{"id":64694,"date":"2024-03-26T16:53:29","date_gmt":"2024-03-26T15:53:29","guid":{"rendered":"https:\/\/blog.brand-architecture.at\/2024\/03\/26\/alltron-distribuisce-il-drone-da-carico-flycart-30-di-dji-in-svizzera\/"},"modified":"2024-03-26T16:53:29","modified_gmt":"2024-03-26T15:53:29","slug":"alltron-distribuisce-il-drone-da-carico-flycart-30-di-dji-in-svizzera","status":"publish","type":"post","link":"https:\/\/loginfo24.com\/it\/2024\/03\/26\/alltron-distribuisce-il-drone-da-carico-flycart-30-di-dji-in-svizzera\/","title":{"rendered":"Alltron distribuisce il drone da carico \u00abFlyCart 30\u00bb di DJI in Svizzera"},"content":{"rendered":"<div class=\"article-block article-block__p viewport-section in-viewport\">\n<h5><strong>Alltron ha ricevuto da DJI, il leader mondiale nella produzione di multicotteri industriali, l&#8217;incarico per la distribuzione in Svizzera del drone da carico \u00abFlyCart 30\u00bb. Il FlyCart 30, largo 3,2 metri, \u00e8 dotato di un multirotore a quattro assi con otto eliche e batterie di volo doppie in configurazione ridondante. Il carico utile pu\u00f2 essere trasportato tramite una cassa di carico con ottimizzazione automatica della distribuzione del peso o un verricello con rilascio di cavo d&#8217;emergenza.<\/strong><\/h5>\n<\/div>\n<div class=\"article-block article-block__p viewport-section in-viewport\">\n<p>(M\u00e4genwil) Per una migliore stabilit\u00e0 di volo e maggiore sicurezza, la \u00abFlyCart 30\u00bb \u00e8 dotata di sistemi come l&#8217;intelligente evitamento degli ostacoli tramite sistemi ottici e radar, un paracadute integrato, un ricevitore ADS-B per i dati di posizione degli aeromobili e proiezione in realt\u00e0 aumentata. Il pilota controlla il sistema \u2013 Remote \u00abBeyond Visual Line of Sight\u00bb \u2013 su un percorso programmato. Naturalmente, \u00e8 possibile anche volare direttamente a vista tramite il telecomando.<\/p>\n<div class=\"article-block article-block__h2 viewport-section in-viewport\">\n<h5>Operazione soggetta a autorizzazione<\/h5>\n<\/div>\n<div class=\"article-block article-block__p viewport-section in-viewport\">\n<p>Il DJI FlyCart 30 pu\u00f2 trasportare un carico utile fino a 30 chilogrammi per distanze fino a 16 chilometri in condizioni ottimali. In Cina, ad esempio, viene utilizzato per le consegne da terra a navi cargo che operano sul fiume Yangtze, sostituendo cos\u00ec i trasporti in barca o i voli in elicottero. Alltron prevede scenari di utilizzo in Svizzera, come operazioni con droni in alta montagna, per raggiungere cantieri isolati, rifugi di montagna o impianti di produzione di energia. Sono possibili anche interventi in situazioni di emergenza, per fornire aiuti a zone isolate. L&#8217;operazione di tali droni da carico \u00e8 ovviamente rigorosamente regolamentata e soggetta ad autorizzazione. Come spiega il distributore argoviese, non solo fornisce la soluzione drone, ma pianifica \u2013 in collaborazione con uno specialista per la sicurezza e la conformit\u00e0 legale dei voli con droni \u2013 anche servizi di accompagnamento adeguati per guidare i partner interessati attraverso le procedure di autorizzazione \u00abSpecific Operations Risk Assessment\u00bb per le operazioni con droni. Uno studio di fattibilit\u00e0 ha attestato le possibilit\u00e0 di successo del progetto, e ci sono gi\u00e0 i primi interessati per applicazioni di trasporto con droni, afferma da M\u00e4genwil.<\/p>\n<div class=\"article-block article-block__h2 viewport-section in-viewport\">\n<h5>Espansione della collaborazione<\/h5>\n<\/div>\n<div class=\"article-block article-block__p viewport-section in-viewport\">\n<p>Alltron collabora con DJI Enterprise a livello di distribuzione dal 2020 e ha gi\u00e0 venduto un numero a quattro cifre di droni per utilizzi professionali\/industriali. Questa collaborazione di successo costituisce anche la base per cui Alltron ha potuto vincere l&#8217;appalto per la distribuzione dei nuovi droni per consegne di DJI. \u00abRingraziamo DJI Enterprise per la fiducia, che i partner attraverso Alltron siano supportati al meglio per realizzare operazioni con droni sicure, conformi e di successo\u00bb, afferma Andrea Savoca, responsabile delle soluzioni ICT di Alltron. La nicchia di mercato non \u00e8 particolarmente grande, ma \u00e8 comunque interessante, risponde Savoca alla domanda se valga la pena economicamente per Alltron. A differenza delle soluzioni su misura, il FlyCart 30 \u00e8 una soluzione praticamente pronta all&#8217;uso a livello tecnico, afferma Savoca. Rispetto ai voli con elicotteri per carichi leggeri, i costi di acquisto e di esercizio sono relativamente bassi, grazie al funzionamento a batteria, l&#8217;operazione con droni \u00e8 praticamente priva di emissioni, e anche il livello di rumore \u00e8 pi\u00f9 gradevole rispetto a un elicottero.<\/p>\n<p>Foto\/Video: \u00a9 Alltron<\/p>\n<\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Alltron ha ricevuto da DJI, il leader mondiale nella produzione di multicotteri industriali, l&#8217;incarico per la distribuzione in Svizzera del drone da carico \u00abFlyCart 30\u00bb. Il<span class=\"excerpt-hellip\"> [\u2026]<\/span><\/p>\n","protected":false},"author":0,"featured_media":6749,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1558,1557,1561],"tags":[],"class_list":["post-64694","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-air-freight","category-forwarding-logistics","category-regions"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Alltron distribuisce il drone da carico \u00abFlyCart 30\u00bb di DJI in Svizzera - Loginfo24<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/loginfo24.com\/it\/2024\/03\/26\/alltron-distribuisce-il-drone-da-carico-flycart-30-di-dji-in-svizzera\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Alltron distribuisce il drone da carico \u00abFlyCart 30\u00bb di DJI in Svizzera - Loginfo24\" \/>\n<meta property=\"og:description\" content=\"Alltron ha ricevuto da DJI, il leader mondiale nella produzione di multicotteri industriali, l&#8217;incarico per la distribuzione in Svizzera del drone da carico \u00abFlyCart 30\u00bb. Il [\u2026]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/loginfo24.com\/it\/2024\/03\/26\/alltron-distribuisce-il-drone-da-carico-flycart-30-di-dji-in-svizzera\/\" \/>\n<meta property=\"og:site_name\" content=\"Loginfo24\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/\" \/>\n<meta property=\"article:published_time\" content=\"2024-03-26T15:53:29+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/alltron_26.3.24.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1202\" \/>\n\t<meta property=\"og:image:height\" content=\"742\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2024\\\/03\\\/26\\\/alltron-distribuisce-il-drone-da-carico-flycart-30-di-dji-in-svizzera\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2024\\\/03\\\/26\\\/alltron-distribuisce-il-drone-da-carico-flycart-30-di-dji-in-svizzera\\\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Alltron distribuisce il drone da carico \u00abFlyCart 30\u00bb di DJI in Svizzera\",\"datePublished\":\"2024-03-26T15:53:29+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2024\\\/03\\\/26\\\/alltron-distribuisce-il-drone-da-carico-flycart-30-di-dji-in-svizzera\\\/\"},\"wordCount\":519,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2024\\\/03\\\/26\\\/alltron-distribuisce-il-drone-da-carico-flycart-30-di-dji-in-svizzera\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/alltron_26.3.24.jpg\",\"articleSection\":[\"Air Freight\",\"Forwarding &amp; Logistics\",\"Regions\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/it\\\/2024\\\/03\\\/26\\\/alltron-distribuisce-il-drone-da-carico-flycart-30-di-dji-in-svizzera\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2024\\\/03\\\/26\\\/alltron-distribuisce-il-drone-da-carico-flycart-30-di-dji-in-svizzera\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2024\\\/03\\\/26\\\/alltron-distribuisce-il-drone-da-carico-flycart-30-di-dji-in-svizzera\\\/\",\"name\":\"Alltron distribuisce il drone da carico \u00abFlyCart 30\u00bb di DJI in Svizzera - Loginfo24\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2024\\\/03\\\/26\\\/alltron-distribuisce-il-drone-da-carico-flycart-30-di-dji-in-svizzera\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2024\\\/03\\\/26\\\/alltron-distribuisce-il-drone-da-carico-flycart-30-di-dji-in-svizzera\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/alltron_26.3.24.jpg\",\"datePublished\":\"2024-03-26T15:53:29+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2024\\\/03\\\/26\\\/alltron-distribuisce-il-drone-da-carico-flycart-30-di-dji-in-svizzera\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/it\\\/2024\\\/03\\\/26\\\/alltron-distribuisce-il-drone-da-carico-flycart-30-di-dji-in-svizzera\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2024\\\/03\\\/26\\\/alltron-distribuisce-il-drone-da-carico-flycart-30-di-dji-in-svizzera\\\/#primaryimage\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/alltron_26.3.24.jpg\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/alltron_26.3.24.jpg\",\"width\":1202,\"height\":742},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2024\\\/03\\\/26\\\/alltron-distribuisce-il-drone-da-carico-flycart-30-di-dji-in-svizzera\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Alltron distribuisce il drone da carico \u00abFlyCart 30\u00bb di DJI in Svizzera\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/\",\"name\":\"Loginfo24\",\"description\":\"Loginfo24 \u00e8 la piattaforma dedicata alla logistica e alle catene di fornitura con informazioni disponibili 24 ore su 24.\",\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#organization\",\"name\":\"Logismedia Group AG\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"width\":938,\"height\":351,\"caption\":\"Logismedia Group AG\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/people\\\/Loginfo24\\\/100057360583332\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/lofinfo24\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Alltron distribuisce il drone da carico \u00abFlyCart 30\u00bb di DJI in Svizzera - Loginfo24","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/loginfo24.com\/it\/2024\/03\/26\/alltron-distribuisce-il-drone-da-carico-flycart-30-di-dji-in-svizzera\/","og_locale":"it_IT","og_type":"article","og_title":"Alltron distribuisce il drone da carico \u00abFlyCart 30\u00bb di DJI in Svizzera - Loginfo24","og_description":"Alltron ha ricevuto da DJI, il leader mondiale nella produzione di multicotteri industriali, l&#8217;incarico per la distribuzione in Svizzera del drone da carico \u00abFlyCart 30\u00bb. Il [\u2026]","og_url":"https:\/\/loginfo24.com\/it\/2024\/03\/26\/alltron-distribuisce-il-drone-da-carico-flycart-30-di-dji-in-svizzera\/","og_site_name":"Loginfo24","article_publisher":"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","article_published_time":"2024-03-26T15:53:29+00:00","og_image":[{"width":1202,"height":742,"url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/alltron_26.3.24.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"3 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/loginfo24.com\/it\/2024\/03\/26\/alltron-distribuisce-il-drone-da-carico-flycart-30-di-dji-in-svizzera\/#article","isPartOf":{"@id":"https:\/\/loginfo24.com\/it\/2024\/03\/26\/alltron-distribuisce-il-drone-da-carico-flycart-30-di-dji-in-svizzera\/"},"author":{"name":"","@id":""},"headline":"Alltron distribuisce il drone da carico \u00abFlyCart 30\u00bb di DJI in Svizzera","datePublished":"2024-03-26T15:53:29+00:00","mainEntityOfPage":{"@id":"https:\/\/loginfo24.com\/it\/2024\/03\/26\/alltron-distribuisce-il-drone-da-carico-flycart-30-di-dji-in-svizzera\/"},"wordCount":519,"commentCount":0,"publisher":{"@id":"https:\/\/loginfo24.com\/it\/#organization"},"image":{"@id":"https:\/\/loginfo24.com\/it\/2024\/03\/26\/alltron-distribuisce-il-drone-da-carico-flycart-30-di-dji-in-svizzera\/#primaryimage"},"thumbnailUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/alltron_26.3.24.jpg","articleSection":["Air Freight","Forwarding &amp; Logistics","Regions"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/loginfo24.com\/it\/2024\/03\/26\/alltron-distribuisce-il-drone-da-carico-flycart-30-di-dji-in-svizzera\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/loginfo24.com\/it\/2024\/03\/26\/alltron-distribuisce-il-drone-da-carico-flycart-30-di-dji-in-svizzera\/","url":"https:\/\/loginfo24.com\/it\/2024\/03\/26\/alltron-distribuisce-il-drone-da-carico-flycart-30-di-dji-in-svizzera\/","name":"Alltron distribuisce il drone da carico \u00abFlyCart 30\u00bb di DJI in Svizzera - Loginfo24","isPartOf":{"@id":"https:\/\/loginfo24.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/loginfo24.com\/it\/2024\/03\/26\/alltron-distribuisce-il-drone-da-carico-flycart-30-di-dji-in-svizzera\/#primaryimage"},"image":{"@id":"https:\/\/loginfo24.com\/it\/2024\/03\/26\/alltron-distribuisce-il-drone-da-carico-flycart-30-di-dji-in-svizzera\/#primaryimage"},"thumbnailUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/alltron_26.3.24.jpg","datePublished":"2024-03-26T15:53:29+00:00","breadcrumb":{"@id":"https:\/\/loginfo24.com\/it\/2024\/03\/26\/alltron-distribuisce-il-drone-da-carico-flycart-30-di-dji-in-svizzera\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/loginfo24.com\/it\/2024\/03\/26\/alltron-distribuisce-il-drone-da-carico-flycart-30-di-dji-in-svizzera\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/loginfo24.com\/it\/2024\/03\/26\/alltron-distribuisce-il-drone-da-carico-flycart-30-di-dji-in-svizzera\/#primaryimage","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/alltron_26.3.24.jpg","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/alltron_26.3.24.jpg","width":1202,"height":742},{"@type":"BreadcrumbList","@id":"https:\/\/loginfo24.com\/it\/2024\/03\/26\/alltron-distribuisce-il-drone-da-carico-flycart-30-di-dji-in-svizzera\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/loginfo24.com\/it\/"},{"@type":"ListItem","position":2,"name":"Alltron distribuisce il drone da carico \u00abFlyCart 30\u00bb di DJI in Svizzera"}]},{"@type":"WebSite","@id":"https:\/\/loginfo24.com\/it\/#website","url":"https:\/\/loginfo24.com\/it\/","name":"Loginfo24","description":"Loginfo24 \u00e8 la piattaforma dedicata alla logistica e alle catene di fornitura con informazioni disponibili 24 ore su 24.","publisher":{"@id":"https:\/\/loginfo24.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/loginfo24.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/loginfo24.com\/it\/#organization","name":"Logismedia Group AG","url":"https:\/\/loginfo24.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/loginfo24.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","width":938,"height":351,"caption":"Logismedia Group AG"},"image":{"@id":"https:\/\/loginfo24.com\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","https:\/\/www.linkedin.com\/company\/lofinfo24\/"]}]}},"_links":{"self":[{"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/posts\/64694","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/comments?post=64694"}],"version-history":[{"count":0,"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/posts\/64694\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/media\/6749"}],"wp:attachment":[{"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/media?parent=64694"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/categories?post=64694"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/tags?post=64694"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}