{"id":63534,"date":"2023-11-28T19:46:02","date_gmt":"2023-11-28T18:46:02","guid":{"rendered":"https:\/\/blog.brand-architecture.at\/2023\/11\/28\/varo-energy-acquisisce-lo-specialista-delle-infrastrutture-di-ricarica-elexon\/"},"modified":"2023-11-28T19:46:02","modified_gmt":"2023-11-28T18:46:02","slug":"varo-energy-acquisisce-lo-specialista-delle-infrastrutture-di-ricarica-elexon","status":"publish","type":"post","link":"https:\/\/loginfo24.com\/it\/2023\/11\/28\/varo-energy-acquisisce-lo-specialista-delle-infrastrutture-di-ricarica-elexon\/","title":{"rendered":"VARO Energy acquisisce lo specialista delle infrastrutture di ricarica elexon"},"content":{"rendered":"<h5><strong>elexon, il principale specialista delle infrastrutture di ricarica nel settore della logistica, continuer\u00e0 il suo percorso di successo con un forte partner <\/strong><strong>VARO Energy, un&#8217;azienda energetica con sede in Svizzera e operante in tutta Europa, ha acquisito il 100% delle azioni di elexon nel novembre di quest&#8217;anno. L&#8217;<\/strong><strong>accordo \u00e8 attualmente soggetto al controllo antitrust da parte dell&#8217;Autorit\u00e0 federale della concorrenza.<\/strong><\/h5>\n<p>(Aquisgrana\/Birsfelden) L&#8217;investimento di VARO in elexon supporta la strategia di trasformazione ONE VARO, presentata a luglio 2022. Nell&#8217;ambito di questa strategia, VARO investir\u00e0 3,5 miliardi di USD in cinque pilastri strategici di crescita: biogas, biocarburanti, idrogeno, rimozione del carbonio basata sulla natura e mobilit\u00e0 elettrica. Il settore esistente di mobilit\u00e0 elettrica di VARO, ROAD, insieme ai punti di forza di elexon, consente a VARO di offrire ai propri clienti una soluzione end-to-end che va dall&#8217;installazione delle infrastrutture di ricarica al pagamento e alla gestione della flotta.<\/p>\n<h5>Leader del settore per le infrastrutture di ricarica nel settore della logistica<\/h5>\n<p>In qualit\u00e0 di leader del settore per le infrastrutture di ricarica nel settore della logistica, elexon conta tra i suoi clienti aziende industriali e commerciali. Dalla sua fondazione nella forma attuale nel 2019 - come joint venture tra SMA Solar Technology AG, AixControl GmbH e aixACCT charging solutions GmbH - elexon ha costantemente posizionato sul mercato prodotti e concetti innovativi, puntando in particolare su sviluppi tecnici orientati al futuro. Come system integrator, elexon \u00e8 considerato un innovatore del settore nei campi della consulenza, installazione, prototipazione, gestione della ricarica e del carico, servizi CPO, soluzioni backend, assistenza e manutenzione, nonch\u00e9 gestione delle quote THG.<\/p>\n<p>Le stazioni di ricarica di elexon dispongono gi\u00e0 oggi di caratteristiche tecniche necessarie per le future infrastrutture di ricarica, ma difficilmente reperibili sul mercato. Parallelamente, elexon sviluppa continuamente nuove soluzioni per supportare il desiderio di molte aziende clienti di diventare energeticamente autonome. Da inizialmente meno di 20 dipendenti, elexon oggi impiega pi\u00f9 di 70 persone, che lavorano sia presso la sede di Aquisgrana che in remoto in tutta la Germania. elexon installa ogni anno circa 8.000 punti di ricarica AC e DC e offre gi\u00e0 oltre 24.000 punti di ricarica ai propri clienti in tutta Europa.<\/p>\n<h5>Felicit\u00e0 per un forte partner<\/h5>\n<p>&#8220;Siamo molto felici di avere VARO come un forte partner al nostro fianco, che contribuisce in modo credibile e deciso alla trasformazione del settore energetico&#8221;, spiega Marcus Scholz, amministratore delegato di elexon GmbH. &#8220;Essere parte del gruppo VARO ci consente di tenere il passo con l&#8217;alta domanda per le nostre soluzioni. Il nostro obiettivo \u00e8 diventare uno dei partner leader, ampliando i nostri servizi, grazie all&#8217;alta qualit\u00e0 dei nostri servizi e ai nostri valori basati sul rispetto e sulla sostenibilit\u00e0.<\/p>\n<p>Foto: \u00a9 elexon \/ <em><strong>Didascalia dell&#8217;immagine:<\/strong> Team tecnico di elexon in azione <\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>elexon, il principale specialista delle infrastrutture di ricarica nel settore della logistica, continuer\u00e0 il suo percorso di successo con un forte partner VARO Energy, un&#8217;azienda energetica<span class=\"excerpt-hellip\"> [\u2026]<\/span><\/p>\n","protected":false},"author":0,"featured_media":7223,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1557,1556,1561],"tags":[],"class_list":["post-63534","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-forwarding-logistics","category-intermodal-road","category-regions"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>VARO Energy acquisisce lo specialista delle infrastrutture di ricarica elexon - Loginfo24<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/loginfo24.com\/it\/2023\/11\/28\/varo-energy-acquisisce-lo-specialista-delle-infrastrutture-di-ricarica-elexon\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"VARO Energy acquisisce lo specialista delle infrastrutture di ricarica elexon - Loginfo24\" \/>\n<meta property=\"og:description\" content=\"elexon, il principale specialista delle infrastrutture di ricarica nel settore della logistica, continuer\u00e0 il suo percorso di successo con un forte partner VARO Energy, un&#8217;azienda energetica [\u2026]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/loginfo24.com\/it\/2023\/11\/28\/varo-energy-acquisisce-lo-specialista-delle-infrastrutture-di-ricarica-elexon\/\" \/>\n<meta property=\"og:site_name\" content=\"Loginfo24\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/\" \/>\n<meta property=\"article:published_time\" content=\"2023-11-28T18:46:02+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/elexon_28.11.23.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1464\" \/>\n\t<meta property=\"og:image:height\" content=\"970\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2023\\\/11\\\/28\\\/varo-energy-acquisisce-lo-specialista-delle-infrastrutture-di-ricarica-elexon\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2023\\\/11\\\/28\\\/varo-energy-acquisisce-lo-specialista-delle-infrastrutture-di-ricarica-elexon\\\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"VARO Energy acquisisce lo specialista delle infrastrutture di ricarica elexon\",\"datePublished\":\"2023-11-28T18:46:02+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2023\\\/11\\\/28\\\/varo-energy-acquisisce-lo-specialista-delle-infrastrutture-di-ricarica-elexon\\\/\"},\"wordCount\":462,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2023\\\/11\\\/28\\\/varo-energy-acquisisce-lo-specialista-delle-infrastrutture-di-ricarica-elexon\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/elexon_28.11.23.jpg\",\"articleSection\":[\"Forwarding &amp; Logistics\",\"Intermodal \\\/ Road\",\"Regions\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/it\\\/2023\\\/11\\\/28\\\/varo-energy-acquisisce-lo-specialista-delle-infrastrutture-di-ricarica-elexon\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2023\\\/11\\\/28\\\/varo-energy-acquisisce-lo-specialista-delle-infrastrutture-di-ricarica-elexon\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2023\\\/11\\\/28\\\/varo-energy-acquisisce-lo-specialista-delle-infrastrutture-di-ricarica-elexon\\\/\",\"name\":\"VARO Energy acquisisce lo specialista delle infrastrutture di ricarica elexon - Loginfo24\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2023\\\/11\\\/28\\\/varo-energy-acquisisce-lo-specialista-delle-infrastrutture-di-ricarica-elexon\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2023\\\/11\\\/28\\\/varo-energy-acquisisce-lo-specialista-delle-infrastrutture-di-ricarica-elexon\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/elexon_28.11.23.jpg\",\"datePublished\":\"2023-11-28T18:46:02+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2023\\\/11\\\/28\\\/varo-energy-acquisisce-lo-specialista-delle-infrastrutture-di-ricarica-elexon\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/it\\\/2023\\\/11\\\/28\\\/varo-energy-acquisisce-lo-specialista-delle-infrastrutture-di-ricarica-elexon\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2023\\\/11\\\/28\\\/varo-energy-acquisisce-lo-specialista-delle-infrastrutture-di-ricarica-elexon\\\/#primaryimage\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/elexon_28.11.23.jpg\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/elexon_28.11.23.jpg\",\"width\":1464,\"height\":970},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2023\\\/11\\\/28\\\/varo-energy-acquisisce-lo-specialista-delle-infrastrutture-di-ricarica-elexon\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"VARO Energy acquisisce lo specialista delle infrastrutture di ricarica elexon\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/\",\"name\":\"Loginfo24\",\"description\":\"Loginfo24 \u00e8 la piattaforma dedicata alla logistica e alle catene di fornitura con informazioni disponibili 24 ore su 24.\",\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#organization\",\"name\":\"Logismedia Group AG\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"width\":938,\"height\":351,\"caption\":\"Logismedia Group AG\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/people\\\/Loginfo24\\\/100057360583332\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/lofinfo24\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"VARO Energy acquisisce lo specialista delle infrastrutture di ricarica elexon - Loginfo24","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/loginfo24.com\/it\/2023\/11\/28\/varo-energy-acquisisce-lo-specialista-delle-infrastrutture-di-ricarica-elexon\/","og_locale":"it_IT","og_type":"article","og_title":"VARO Energy acquisisce lo specialista delle infrastrutture di ricarica elexon - Loginfo24","og_description":"elexon, il principale specialista delle infrastrutture di ricarica nel settore della logistica, continuer\u00e0 il suo percorso di successo con un forte partner VARO Energy, un&#8217;azienda energetica [\u2026]","og_url":"https:\/\/loginfo24.com\/it\/2023\/11\/28\/varo-energy-acquisisce-lo-specialista-delle-infrastrutture-di-ricarica-elexon\/","og_site_name":"Loginfo24","article_publisher":"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","article_published_time":"2023-11-28T18:46:02+00:00","og_image":[{"width":1464,"height":970,"url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/elexon_28.11.23.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"2 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/loginfo24.com\/it\/2023\/11\/28\/varo-energy-acquisisce-lo-specialista-delle-infrastrutture-di-ricarica-elexon\/#article","isPartOf":{"@id":"https:\/\/loginfo24.com\/it\/2023\/11\/28\/varo-energy-acquisisce-lo-specialista-delle-infrastrutture-di-ricarica-elexon\/"},"author":{"name":"","@id":""},"headline":"VARO Energy acquisisce lo specialista delle infrastrutture di ricarica elexon","datePublished":"2023-11-28T18:46:02+00:00","mainEntityOfPage":{"@id":"https:\/\/loginfo24.com\/it\/2023\/11\/28\/varo-energy-acquisisce-lo-specialista-delle-infrastrutture-di-ricarica-elexon\/"},"wordCount":462,"commentCount":0,"publisher":{"@id":"https:\/\/loginfo24.com\/it\/#organization"},"image":{"@id":"https:\/\/loginfo24.com\/it\/2023\/11\/28\/varo-energy-acquisisce-lo-specialista-delle-infrastrutture-di-ricarica-elexon\/#primaryimage"},"thumbnailUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/elexon_28.11.23.jpg","articleSection":["Forwarding &amp; Logistics","Intermodal \/ Road","Regions"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/loginfo24.com\/it\/2023\/11\/28\/varo-energy-acquisisce-lo-specialista-delle-infrastrutture-di-ricarica-elexon\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/loginfo24.com\/it\/2023\/11\/28\/varo-energy-acquisisce-lo-specialista-delle-infrastrutture-di-ricarica-elexon\/","url":"https:\/\/loginfo24.com\/it\/2023\/11\/28\/varo-energy-acquisisce-lo-specialista-delle-infrastrutture-di-ricarica-elexon\/","name":"VARO Energy acquisisce lo specialista delle infrastrutture di ricarica elexon - Loginfo24","isPartOf":{"@id":"https:\/\/loginfo24.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/loginfo24.com\/it\/2023\/11\/28\/varo-energy-acquisisce-lo-specialista-delle-infrastrutture-di-ricarica-elexon\/#primaryimage"},"image":{"@id":"https:\/\/loginfo24.com\/it\/2023\/11\/28\/varo-energy-acquisisce-lo-specialista-delle-infrastrutture-di-ricarica-elexon\/#primaryimage"},"thumbnailUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/elexon_28.11.23.jpg","datePublished":"2023-11-28T18:46:02+00:00","breadcrumb":{"@id":"https:\/\/loginfo24.com\/it\/2023\/11\/28\/varo-energy-acquisisce-lo-specialista-delle-infrastrutture-di-ricarica-elexon\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/loginfo24.com\/it\/2023\/11\/28\/varo-energy-acquisisce-lo-specialista-delle-infrastrutture-di-ricarica-elexon\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/loginfo24.com\/it\/2023\/11\/28\/varo-energy-acquisisce-lo-specialista-delle-infrastrutture-di-ricarica-elexon\/#primaryimage","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/elexon_28.11.23.jpg","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/elexon_28.11.23.jpg","width":1464,"height":970},{"@type":"BreadcrumbList","@id":"https:\/\/loginfo24.com\/it\/2023\/11\/28\/varo-energy-acquisisce-lo-specialista-delle-infrastrutture-di-ricarica-elexon\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/loginfo24.com\/it\/"},{"@type":"ListItem","position":2,"name":"VARO Energy acquisisce lo specialista delle infrastrutture di ricarica elexon"}]},{"@type":"WebSite","@id":"https:\/\/loginfo24.com\/it\/#website","url":"https:\/\/loginfo24.com\/it\/","name":"Loginfo24","description":"Loginfo24 \u00e8 la piattaforma dedicata alla logistica e alle catene di fornitura con informazioni disponibili 24 ore su 24.","publisher":{"@id":"https:\/\/loginfo24.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/loginfo24.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/loginfo24.com\/it\/#organization","name":"Logismedia Group AG","url":"https:\/\/loginfo24.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/loginfo24.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","width":938,"height":351,"caption":"Logismedia Group AG"},"image":{"@id":"https:\/\/loginfo24.com\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","https:\/\/www.linkedin.com\/company\/lofinfo24\/"]}]}},"_links":{"self":[{"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/posts\/63534","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/comments?post=63534"}],"version-history":[{"count":0,"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/posts\/63534\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/media\/7223"}],"wp:attachment":[{"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/media?parent=63534"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/categories?post=63534"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/tags?post=63534"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}