{"id":63365,"date":"2023-11-11T12:21:52","date_gmt":"2023-11-11T11:21:52","guid":{"rendered":"https:\/\/blog.brand-architecture.at\/2023\/11\/11\/sviluppo-del-traffico-marittimo-a-corto-raggio-2022-in-germania\/"},"modified":"2023-11-11T12:21:52","modified_gmt":"2023-11-11T11:21:52","slug":"sviluppo-del-traffico-marittimo-a-corto-raggio-2022-in-germania","status":"publish","type":"post","link":"https:\/\/loginfo24.com\/it\/2023\/11\/11\/sviluppo-del-traffico-marittimo-a-corto-raggio-2022-in-germania\/","title":{"rendered":"Sviluppo del traffico marittimo a corto raggio 2022 in Germania"},"content":{"rendered":"<h5>L&#8217;Ufficio federale per la logistica e la mobilit\u00e0 (BALM) ha esaminato su incarico del Ministero federale per la digitalizzazione e i trasporti (BMDV) lo sviluppo del traffico marittimo a corto raggio nei porti marittimi tedeschi nel 2022. Di conseguenza, il traffico merci nei porti tedeschi nel traffico marittimo a corto raggio \u00e8 diminuito di circa l&#8217;8,3% da circa 180,3 milioni di tonnellate nel 2021 al valore pi\u00f9 basso degli ultimi dieci anni di circa 165,5 milioni di tonnellate nel 2022 (senza i pesi propri dei mezzi di carico).<\/h5>\n<p>(K\u00f6ln) La quota del traffico marittimo a corto raggio sul totale del traffico merci marittimo nei porti tedeschi \u00e8 scesa nello stesso periodo da circa il 62,5% a circa il 59,3%. Il traffico merci nel traffico marittimo a corto raggio \u00e8 stato influenzato in modo significativo dalla guerra di aggressione della Russia contro l&#8217;Ucraina. Le sanzioni imposte alla Federazione Russa, cos\u00ec come altre misure di restrizione commerciale e comportamenti non sanzionati da parte degli operatori di mercato, hanno portato a forti cali del traffico marittimo con la Federazione Russa. Le frizioni persistenti nelle catene di approvvigionamento globali e i cali di produzione nei settori ad alta intensit\u00e0 energetica hanno ostacolato anche il traffico merci marittimo. I principali paesi partner dei porti marittimi tedeschi nel traffico marittimo a corto raggio nel 2022 sono stati Svezia, Norvegia, Finlandia e Danimarca.<\/p>\n<p>Il traffico container nei porti marittimi tedeschi nel traffico marittimo a corto raggio \u00e8 diminuito nel 2022 rispetto all&#8217;anno precedente di circa l&#8217;11,5% a circa 5,15 milioni di TEU. Questo \u00e8 stato anche il valore pi\u00f9 basso degli ultimi 10 anni. I principali paesi partner dei porti container tedeschi nel traffico marittimo a corto raggio nel 2022 sono stati Polonia, Svezia, Finlandia e Regno Unito.<\/p>\n<h5>Traffico container con la Russia diminuito del 74%<\/h5>\n<p>I traffici container con la Federazione Russa sono diminuiti nel periodo di riferimento di circa il 74,0% a circa 0,17 milioni di TEU. I traffici veicolari nei porti marittimi tedeschi nel traffico RoRo sono diminuiti nel 2022 rispetto al 2021 di circa l&#8217;1,3% a circa 2,27 milioni di unit\u00e0. La maggior parte del traffico veicolare \u00e8 avvenuta nei porti del Mar Baltico tedeschi.<\/p>\n<p><a href=\"https:\/\/www.balm.bund.de\/SharedDocs\/Downloads\/DE\/Marktbeobachtung\/Sonderberichte\/SB_Kurzstreckenseeverkehr_2022.html?nn=3290886\" target=\"_blank\" rel=\"noopener\"><strong>Scarica il rapporto completo<\/strong> <\/a><\/p>\n<p>Foto: \u00a9 Loginfo24<\/p>\n","protected":false},"excerpt":{"rendered":"<p>L&#8217;Ufficio federale per la logistica e la mobilit\u00e0 (BALM) ha esaminato su incarico del Ministero federale per la digitalizzazione e i trasporti (BMDV) lo sviluppo del<span class=\"excerpt-hellip\"> [\u2026]<\/span><\/p>\n","protected":false},"author":0,"featured_media":7305,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1557,1560,1561,1559],"tags":[],"class_list":["post-63365","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-forwarding-logistics","category-intralogistics","category-regions","category-shipping-ports"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Sviluppo del traffico marittimo a corto raggio 2022 in Germania - Loginfo24<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/loginfo24.com\/it\/2023\/11\/11\/sviluppo-del-traffico-marittimo-a-corto-raggio-2022-in-germania\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Sviluppo del traffico marittimo a corto raggio 2022 in Germania - Loginfo24\" \/>\n<meta property=\"og:description\" content=\"L&#8217;Ufficio federale per la logistica e la mobilit\u00e0 (BALM) ha esaminato su incarico del Ministero federale per la digitalizzazione e i trasporti (BMDV) lo sviluppo del [\u2026]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/loginfo24.com\/it\/2023\/11\/11\/sviluppo-del-traffico-marittimo-a-corto-raggio-2022-in-germania\/\" \/>\n<meta property=\"og:site_name\" content=\"Loginfo24\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/\" \/>\n<meta property=\"article:published_time\" content=\"2023-11-11T11:21:52+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Hamburg_August_2016-19-scaled-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1920\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2023\\\/11\\\/11\\\/sviluppo-del-traffico-marittimo-a-corto-raggio-2022-in-germania\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2023\\\/11\\\/11\\\/sviluppo-del-traffico-marittimo-a-corto-raggio-2022-in-germania\\\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Sviluppo del traffico marittimo a corto raggio 2022 in Germania\",\"datePublished\":\"2023-11-11T11:21:52+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2023\\\/11\\\/11\\\/sviluppo-del-traffico-marittimo-a-corto-raggio-2022-in-germania\\\/\"},\"wordCount\":357,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2023\\\/11\\\/11\\\/sviluppo-del-traffico-marittimo-a-corto-raggio-2022-in-germania\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/Hamburg_August_2016-19-scaled-1.jpg\",\"articleSection\":[\"Forwarding &amp; Logistics\",\"Intralogistics\",\"Regions\",\"Shipping &amp; Ports\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/it\\\/2023\\\/11\\\/11\\\/sviluppo-del-traffico-marittimo-a-corto-raggio-2022-in-germania\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2023\\\/11\\\/11\\\/sviluppo-del-traffico-marittimo-a-corto-raggio-2022-in-germania\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2023\\\/11\\\/11\\\/sviluppo-del-traffico-marittimo-a-corto-raggio-2022-in-germania\\\/\",\"name\":\"Sviluppo del traffico marittimo a corto raggio 2022 in Germania - Loginfo24\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2023\\\/11\\\/11\\\/sviluppo-del-traffico-marittimo-a-corto-raggio-2022-in-germania\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2023\\\/11\\\/11\\\/sviluppo-del-traffico-marittimo-a-corto-raggio-2022-in-germania\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/Hamburg_August_2016-19-scaled-1.jpg\",\"datePublished\":\"2023-11-11T11:21:52+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2023\\\/11\\\/11\\\/sviluppo-del-traffico-marittimo-a-corto-raggio-2022-in-germania\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/it\\\/2023\\\/11\\\/11\\\/sviluppo-del-traffico-marittimo-a-corto-raggio-2022-in-germania\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2023\\\/11\\\/11\\\/sviluppo-del-traffico-marittimo-a-corto-raggio-2022-in-germania\\\/#primaryimage\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/Hamburg_August_2016-19-scaled-1.jpg\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/Hamburg_August_2016-19-scaled-1.jpg\",\"width\":2560,\"height\":1920},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2023\\\/11\\\/11\\\/sviluppo-del-traffico-marittimo-a-corto-raggio-2022-in-germania\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Sviluppo del traffico marittimo a corto raggio 2022 in Germania\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/\",\"name\":\"Loginfo24\",\"description\":\"Loginfo24 \u00e8 la piattaforma dedicata alla logistica e alle catene di fornitura con informazioni disponibili 24 ore su 24.\",\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#organization\",\"name\":\"Logismedia Group AG\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"width\":938,\"height\":351,\"caption\":\"Logismedia Group AG\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/people\\\/Loginfo24\\\/100057360583332\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/lofinfo24\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Sviluppo del traffico marittimo a corto raggio 2022 in Germania - Loginfo24","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/loginfo24.com\/it\/2023\/11\/11\/sviluppo-del-traffico-marittimo-a-corto-raggio-2022-in-germania\/","og_locale":"it_IT","og_type":"article","og_title":"Sviluppo del traffico marittimo a corto raggio 2022 in Germania - Loginfo24","og_description":"L&#8217;Ufficio federale per la logistica e la mobilit\u00e0 (BALM) ha esaminato su incarico del Ministero federale per la digitalizzazione e i trasporti (BMDV) lo sviluppo del [\u2026]","og_url":"https:\/\/loginfo24.com\/it\/2023\/11\/11\/sviluppo-del-traffico-marittimo-a-corto-raggio-2022-in-germania\/","og_site_name":"Loginfo24","article_publisher":"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","article_published_time":"2023-11-11T11:21:52+00:00","og_image":[{"width":2560,"height":1920,"url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Hamburg_August_2016-19-scaled-1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"2 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/loginfo24.com\/it\/2023\/11\/11\/sviluppo-del-traffico-marittimo-a-corto-raggio-2022-in-germania\/#article","isPartOf":{"@id":"https:\/\/loginfo24.com\/it\/2023\/11\/11\/sviluppo-del-traffico-marittimo-a-corto-raggio-2022-in-germania\/"},"author":{"name":"","@id":""},"headline":"Sviluppo del traffico marittimo a corto raggio 2022 in Germania","datePublished":"2023-11-11T11:21:52+00:00","mainEntityOfPage":{"@id":"https:\/\/loginfo24.com\/it\/2023\/11\/11\/sviluppo-del-traffico-marittimo-a-corto-raggio-2022-in-germania\/"},"wordCount":357,"commentCount":0,"publisher":{"@id":"https:\/\/loginfo24.com\/it\/#organization"},"image":{"@id":"https:\/\/loginfo24.com\/it\/2023\/11\/11\/sviluppo-del-traffico-marittimo-a-corto-raggio-2022-in-germania\/#primaryimage"},"thumbnailUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Hamburg_August_2016-19-scaled-1.jpg","articleSection":["Forwarding &amp; Logistics","Intralogistics","Regions","Shipping &amp; Ports"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/loginfo24.com\/it\/2023\/11\/11\/sviluppo-del-traffico-marittimo-a-corto-raggio-2022-in-germania\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/loginfo24.com\/it\/2023\/11\/11\/sviluppo-del-traffico-marittimo-a-corto-raggio-2022-in-germania\/","url":"https:\/\/loginfo24.com\/it\/2023\/11\/11\/sviluppo-del-traffico-marittimo-a-corto-raggio-2022-in-germania\/","name":"Sviluppo del traffico marittimo a corto raggio 2022 in Germania - Loginfo24","isPartOf":{"@id":"https:\/\/loginfo24.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/loginfo24.com\/it\/2023\/11\/11\/sviluppo-del-traffico-marittimo-a-corto-raggio-2022-in-germania\/#primaryimage"},"image":{"@id":"https:\/\/loginfo24.com\/it\/2023\/11\/11\/sviluppo-del-traffico-marittimo-a-corto-raggio-2022-in-germania\/#primaryimage"},"thumbnailUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Hamburg_August_2016-19-scaled-1.jpg","datePublished":"2023-11-11T11:21:52+00:00","breadcrumb":{"@id":"https:\/\/loginfo24.com\/it\/2023\/11\/11\/sviluppo-del-traffico-marittimo-a-corto-raggio-2022-in-germania\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/loginfo24.com\/it\/2023\/11\/11\/sviluppo-del-traffico-marittimo-a-corto-raggio-2022-in-germania\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/loginfo24.com\/it\/2023\/11\/11\/sviluppo-del-traffico-marittimo-a-corto-raggio-2022-in-germania\/#primaryimage","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Hamburg_August_2016-19-scaled-1.jpg","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Hamburg_August_2016-19-scaled-1.jpg","width":2560,"height":1920},{"@type":"BreadcrumbList","@id":"https:\/\/loginfo24.com\/it\/2023\/11\/11\/sviluppo-del-traffico-marittimo-a-corto-raggio-2022-in-germania\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/loginfo24.com\/it\/"},{"@type":"ListItem","position":2,"name":"Sviluppo del traffico marittimo a corto raggio 2022 in Germania"}]},{"@type":"WebSite","@id":"https:\/\/loginfo24.com\/it\/#website","url":"https:\/\/loginfo24.com\/it\/","name":"Loginfo24","description":"Loginfo24 \u00e8 la piattaforma dedicata alla logistica e alle catene di fornitura con informazioni disponibili 24 ore su 24.","publisher":{"@id":"https:\/\/loginfo24.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/loginfo24.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/loginfo24.com\/it\/#organization","name":"Logismedia Group AG","url":"https:\/\/loginfo24.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/loginfo24.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","width":938,"height":351,"caption":"Logismedia Group AG"},"image":{"@id":"https:\/\/loginfo24.com\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","https:\/\/www.linkedin.com\/company\/lofinfo24\/"]}]}},"_links":{"self":[{"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/posts\/63365","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/comments?post=63365"}],"version-history":[{"count":0,"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/posts\/63365\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/media\/7305"}],"wp:attachment":[{"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/media?parent=63365"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/categories?post=63365"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/tags?post=63365"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}