{"id":62996,"date":"2023-10-10T15:52:04","date_gmt":"2023-10-10T13:52:04","guid":{"rendered":"https:\/\/blog.brand-architecture.at\/2023\/10\/10\/logber-supporta-le-aziende-nel-retrofit-della-logistica-interna\/"},"modified":"2023-10-10T15:52:04","modified_gmt":"2023-10-10T13:52:04","slug":"logber-supporta-le-aziende-nel-retrofit-della-logistica-interna","status":"publish","type":"post","link":"https:\/\/loginfo24.com\/it\/2023\/10\/10\/logber-supporta-le-aziende-nel-retrofit-della-logistica-interna\/","title":{"rendered":"LogBer supporta le aziende nel retrofit della logistica interna"},"content":{"rendered":"<h5><strong>Un magazzino a scaffale alto ben costruito pu\u00f2 soddisfare le esigenze prestazionali dell&#8217;operatore anche dopo 20 anni di utilizzo intensivo praticamente senza limitazioni. Presupponendo una regolare manutenzione e cura di tutti i componenti, la vita utile dei sistemi di movimentazione dei pallet o della tecnologia di trasporto dei pallet pu\u00f2 essere ulteriormente prolungata grazie a un retrofit mirato. Con il supporto di LogBer, \u00e8 possibile evitare investimenti costosi in modo relativamente semplice.<\/strong><\/h5>\n<p> (Ahrensburg) &#8220;Rinnovare i componenti impiantistici invecchiati e modernizzare la tecnologia di controllo e azionamento obsoleta \u00e8 ancora economicamente vantaggioso e sensato per un magazzino a scaffale alto anche dopo un periodo operativo di oltre 30 anni&#8221;, afferma Gerhard Keller, amministratore delegato di LogBer GmbH. &#8220;Di norma, un tale investimento viene ammortizzato in 15-20 anni, ma nella pratica anche i magazzini a scaffale alto con tempi di utilizzo 24\/7 e alte richieste prestazionali funzionano spesso ben oltre questo periodo.&#8221; Gerhard Keller cita come esempio un impianto costruito nel 1980, che 15 anni fa \u00e8 stato sottoposto a un retrofit mirato secondo un concetto sviluppato da LogBer e che \u00e8 ancora in uso invariato dopo oltre quattro decenni. <\/p>\n<h5>\u00c8 stata necessaria una preparazione approfondita<\/h5>\n<p> Tuttavia, per avere successo nel retrofit del magazzino a scaffale alto, sono necessarie ampie preparazioni e pianificatori logistici esperti che sappiano affrontare le incertezze di un progetto del genere. Nel caso specifico, LogBer ha accompagnato il rinnovamento dell&#8217;intera tecnologia di controllo sia dei sistemi di movimentazione dei pallet che della tecnologia di trasporto dei pallet. Tutti gli azionamenti dei sistemi di movimentazione sono stati sostituiti con azionamenti ad alta efficienza energetica e facili da avviare. Le guide di corsa usurate dovevano essere levigate e un sistema di movimentazione danneggiato a causa delle alte forze dinamiche doveva essere completamente rinnovato, poich\u00e9 si erano formate significative fessure di saldatura nel carrello e nel montante. <\/p>\n<h5>\u00c8 stato necessario superare alcune difficolt\u00e0<\/h5>\n<p> Tuttavia, prima \u00e8 stato necessario superare alcune difficolt\u00e0, riporta l&#8217;amministratore delegato di LogBer, Gerhard Keller: &#8220;Il produttore e l&#8217;installatore del magazzino a scaffale alto non esistevano pi\u00f9. Tuttavia, abbiamo trovato nel mercato della logistica tre aziende specializzate nel retrofit di impianti di terzi per un primo sopralluogo e valutazione dei costi potenziali.&#8221; Infine, gli impianti sono stati modernizzati corsia per corsia durante il funzionamento: i controlli (PLC, sensori, ecc.) sono stati portati allo stato dell&#8217;arte, la tecnologia di azionamento \u00e8 stata sostituita con sistemi pi\u00f9 efficienti dal punto di vista energetico e facili da avviare, le guide di corsa e di guida sono state nuovamente regolate, le guide di corsa sono state levigate, le ruote di corsa sono state rinnovate e infine anche la gestione del magazzino e il controllo del flusso dei materiali sono stati adattati alle moderne esigenze logistiche. Nonostante ci\u00f2, Gerhard Keller osserva: &#8220;La preparazione, la pianificazione e l&#8217;esecuzione di un progetto di retrofit\/reingegnerizzazione \u00e8 complessivamente molto impegnativa e le misure necessarie sono difficili da calcolare in anticipo.&#8221; Per poter comunque stimare il lavoro in modo il pi\u00f9 preciso possibile, LogBer suddivide il processo in quattro fasi: all&#8217;analisi della situazione attuale e delle esigenze operative segue lo sviluppo del concetto di retrofit, poi si passa alla pianificazione dettagliata e alla gara d&#8217;appalto per i lavori necessari, infine seguono realizzazione, test e messa in servizio. <\/p>\n<h5>Un grande impegno ripaga<\/h5>\n<p> &#8220;Sebbene l&#8217;impegno sia piuttosto grande, alla fine ne vale sicuramente la pena&#8221;, riassume Gerhard Keller. Il retrofit dell&#8217;impianto costruito nel 1980, realizzato con il supporto di LogBer, ha reso superflua la costruzione di un nuovo magazzino a scaffale alto e ha ridotto i costi a solo il 20% degli investimenti necessari per un nuovo impianto. <br \/> Foto: \u00a9 LogBer<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Un magazzino a scaffale alto ben costruito pu\u00f2 soddisfare le esigenze prestazionali dell&#8217;operatore anche dopo 20 anni di utilizzo intensivo praticamente senza limitazioni. Presupponendo una regolare<span class=\"excerpt-hellip\"> [\u2026]<\/span><\/p>\n","protected":false},"author":0,"featured_media":7459,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1560,1561],"tags":[],"class_list":["post-62996","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-intralogistics","category-regions"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>LogBer supporta le aziende nel retrofit della logistica interna - Loginfo24<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/loginfo24.com\/it\/2023\/10\/10\/logber-supporta-le-aziende-nel-retrofit-della-logistica-interna\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"LogBer supporta le aziende nel retrofit della logistica interna - Loginfo24\" \/>\n<meta property=\"og:description\" content=\"Un magazzino a scaffale alto ben costruito pu\u00f2 soddisfare le esigenze prestazionali dell&#8217;operatore anche dopo 20 anni di utilizzo intensivo praticamente senza limitazioni. Presupponendo una regolare [\u2026]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/loginfo24.com\/it\/2023\/10\/10\/logber-supporta-le-aziende-nel-retrofit-della-logistica-interna\/\" \/>\n<meta property=\"og:site_name\" content=\"Loginfo24\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/\" \/>\n<meta property=\"article:published_time\" content=\"2023-10-10T13:52:04+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/LogBer_10.10.23.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1317\" \/>\n\t<meta property=\"og:image:height\" content=\"774\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2023\\\/10\\\/10\\\/logber-supporta-le-aziende-nel-retrofit-della-logistica-interna\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2023\\\/10\\\/10\\\/logber-supporta-le-aziende-nel-retrofit-della-logistica-interna\\\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"LogBer supporta le aziende nel retrofit della logistica interna\",\"datePublished\":\"2023-10-10T13:52:04+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2023\\\/10\\\/10\\\/logber-supporta-le-aziende-nel-retrofit-della-logistica-interna\\\/\"},\"wordCount\":604,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2023\\\/10\\\/10\\\/logber-supporta-le-aziende-nel-retrofit-della-logistica-interna\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/LogBer_10.10.23.jpg\",\"articleSection\":[\"Intralogistics\",\"Regions\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/it\\\/2023\\\/10\\\/10\\\/logber-supporta-le-aziende-nel-retrofit-della-logistica-interna\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2023\\\/10\\\/10\\\/logber-supporta-le-aziende-nel-retrofit-della-logistica-interna\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2023\\\/10\\\/10\\\/logber-supporta-le-aziende-nel-retrofit-della-logistica-interna\\\/\",\"name\":\"LogBer supporta le aziende nel retrofit della logistica interna - Loginfo24\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2023\\\/10\\\/10\\\/logber-supporta-le-aziende-nel-retrofit-della-logistica-interna\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2023\\\/10\\\/10\\\/logber-supporta-le-aziende-nel-retrofit-della-logistica-interna\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/LogBer_10.10.23.jpg\",\"datePublished\":\"2023-10-10T13:52:04+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2023\\\/10\\\/10\\\/logber-supporta-le-aziende-nel-retrofit-della-logistica-interna\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/it\\\/2023\\\/10\\\/10\\\/logber-supporta-le-aziende-nel-retrofit-della-logistica-interna\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2023\\\/10\\\/10\\\/logber-supporta-le-aziende-nel-retrofit-della-logistica-interna\\\/#primaryimage\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/LogBer_10.10.23.jpg\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/LogBer_10.10.23.jpg\",\"width\":1317,\"height\":774},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2023\\\/10\\\/10\\\/logber-supporta-le-aziende-nel-retrofit-della-logistica-interna\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"LogBer supporta le aziende nel retrofit della logistica interna\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/\",\"name\":\"Loginfo24\",\"description\":\"Loginfo24 \u00e8 la piattaforma dedicata alla logistica e alle catene di fornitura con informazioni disponibili 24 ore su 24.\",\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#organization\",\"name\":\"Logismedia Group AG\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"width\":938,\"height\":351,\"caption\":\"Logismedia Group AG\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/people\\\/Loginfo24\\\/100057360583332\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/lofinfo24\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"LogBer supporta le aziende nel retrofit della logistica interna - Loginfo24","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/loginfo24.com\/it\/2023\/10\/10\/logber-supporta-le-aziende-nel-retrofit-della-logistica-interna\/","og_locale":"it_IT","og_type":"article","og_title":"LogBer supporta le aziende nel retrofit della logistica interna - Loginfo24","og_description":"Un magazzino a scaffale alto ben costruito pu\u00f2 soddisfare le esigenze prestazionali dell&#8217;operatore anche dopo 20 anni di utilizzo intensivo praticamente senza limitazioni. Presupponendo una regolare [\u2026]","og_url":"https:\/\/loginfo24.com\/it\/2023\/10\/10\/logber-supporta-le-aziende-nel-retrofit-della-logistica-interna\/","og_site_name":"Loginfo24","article_publisher":"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","article_published_time":"2023-10-10T13:52:04+00:00","og_image":[{"width":1317,"height":774,"url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/LogBer_10.10.23.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"3 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/loginfo24.com\/it\/2023\/10\/10\/logber-supporta-le-aziende-nel-retrofit-della-logistica-interna\/#article","isPartOf":{"@id":"https:\/\/loginfo24.com\/it\/2023\/10\/10\/logber-supporta-le-aziende-nel-retrofit-della-logistica-interna\/"},"author":{"name":"","@id":""},"headline":"LogBer supporta le aziende nel retrofit della logistica interna","datePublished":"2023-10-10T13:52:04+00:00","mainEntityOfPage":{"@id":"https:\/\/loginfo24.com\/it\/2023\/10\/10\/logber-supporta-le-aziende-nel-retrofit-della-logistica-interna\/"},"wordCount":604,"commentCount":0,"publisher":{"@id":"https:\/\/loginfo24.com\/it\/#organization"},"image":{"@id":"https:\/\/loginfo24.com\/it\/2023\/10\/10\/logber-supporta-le-aziende-nel-retrofit-della-logistica-interna\/#primaryimage"},"thumbnailUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/LogBer_10.10.23.jpg","articleSection":["Intralogistics","Regions"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/loginfo24.com\/it\/2023\/10\/10\/logber-supporta-le-aziende-nel-retrofit-della-logistica-interna\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/loginfo24.com\/it\/2023\/10\/10\/logber-supporta-le-aziende-nel-retrofit-della-logistica-interna\/","url":"https:\/\/loginfo24.com\/it\/2023\/10\/10\/logber-supporta-le-aziende-nel-retrofit-della-logistica-interna\/","name":"LogBer supporta le aziende nel retrofit della logistica interna - Loginfo24","isPartOf":{"@id":"https:\/\/loginfo24.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/loginfo24.com\/it\/2023\/10\/10\/logber-supporta-le-aziende-nel-retrofit-della-logistica-interna\/#primaryimage"},"image":{"@id":"https:\/\/loginfo24.com\/it\/2023\/10\/10\/logber-supporta-le-aziende-nel-retrofit-della-logistica-interna\/#primaryimage"},"thumbnailUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/LogBer_10.10.23.jpg","datePublished":"2023-10-10T13:52:04+00:00","breadcrumb":{"@id":"https:\/\/loginfo24.com\/it\/2023\/10\/10\/logber-supporta-le-aziende-nel-retrofit-della-logistica-interna\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/loginfo24.com\/it\/2023\/10\/10\/logber-supporta-le-aziende-nel-retrofit-della-logistica-interna\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/loginfo24.com\/it\/2023\/10\/10\/logber-supporta-le-aziende-nel-retrofit-della-logistica-interna\/#primaryimage","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/LogBer_10.10.23.jpg","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/LogBer_10.10.23.jpg","width":1317,"height":774},{"@type":"BreadcrumbList","@id":"https:\/\/loginfo24.com\/it\/2023\/10\/10\/logber-supporta-le-aziende-nel-retrofit-della-logistica-interna\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/loginfo24.com\/it\/"},{"@type":"ListItem","position":2,"name":"LogBer supporta le aziende nel retrofit della logistica interna"}]},{"@type":"WebSite","@id":"https:\/\/loginfo24.com\/it\/#website","url":"https:\/\/loginfo24.com\/it\/","name":"Loginfo24","description":"Loginfo24 \u00e8 la piattaforma dedicata alla logistica e alle catene di fornitura con informazioni disponibili 24 ore su 24.","publisher":{"@id":"https:\/\/loginfo24.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/loginfo24.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/loginfo24.com\/it\/#organization","name":"Logismedia Group AG","url":"https:\/\/loginfo24.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/loginfo24.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","width":938,"height":351,"caption":"Logismedia Group AG"},"image":{"@id":"https:\/\/loginfo24.com\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","https:\/\/www.linkedin.com\/company\/lofinfo24\/"]}]}},"_links":{"self":[{"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/posts\/62996","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/comments?post=62996"}],"version-history":[{"count":0,"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/posts\/62996\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/media\/7459"}],"wp:attachment":[{"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/media?parent=62996"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/categories?post=62996"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/tags?post=62996"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}