{"id":61580,"date":"2023-05-29T17:21:26","date_gmt":"2023-05-29T15:21:26","guid":{"rendered":"https:\/\/blog.brand-architecture.at\/2023\/05\/29\/le-ferrovie-merci-chiedono-una-strategia-a-lungo-termine-per-i-prezzi-dellelettricita\/"},"modified":"2023-05-29T17:21:26","modified_gmt":"2023-05-29T15:21:26","slug":"le-ferrovie-merci-chiedono-una-strategia-a-lungo-termine-per-i-prezzi-dellelettricita","status":"publish","type":"post","link":"https:\/\/loginfo24.com\/it\/2023\/05\/29\/le-ferrovie-merci-chiedono-una-strategia-a-lungo-termine-per-i-prezzi-dellelettricita\/","title":{"rendered":"LE FERROVIE MERCI chiedono una strategia a lungo termine per i prezzi dell&#8217;elettricit\u00e0"},"content":{"rendered":"<h5><strong>La seconda &#8220;modifica correttiva&#8221; per la legge sul freno ai prezzi dell&#8217;elettricit\u00e0, che oggi sar\u00e0 presentata dalla coalizione al Bundestag, contiene importanti correzioni per le ferrovie merci, che sono state escluse dai sussidi a causa di lacune nella legge precedente. Gli aumenti a lungo termine dei prezzi dell&#8217;elettricit\u00e0 per le ferrovie, insieme al continuo shock dei prezzi causato dalla guerra, portano comunque a un trasferimento su strada e sollevano richieste per una strategia a lungo termine.<\/strong><\/h5>\n<p>(Berlino) Il freno ai prezzi dell&#8217;elettricit\u00e0 limita dall&#8217;inizio di marzo l&#8217;esplosione dei costi dell&#8217;elettricit\u00e0 per molte aziende ferroviarie a causa della crisi. Tuttavia, finora le aziende che negli ultimi due anni hanno convertito gran parte dei propri veicoli da diesel a una propulsione elettrica pi\u00f9 ecologica non beneficiano quasi affatto del freno ai prezzi dell&#8217;elettricit\u00e0. Il motivo: i pagamenti di sollievo sono legati ai dati del 2021. Questa ingiustizia dovrebbe essere corretta nella modifica correttiva presentata oggi al Bundestag. Sono previste disposizioni speciali per le aziende ferroviarie interessate, affinch\u00e9 i benefici siano equamente distribuiti tra tutti gli attori del mercato. Inoltre, le condizioni per tutte le aziende ferroviarie saranno leggermente migliorate. &#8220;Vediamo le modifiche attese come un&#8217;importante incoraggiamento per il settore, soprattutto per le aziende che hanno investito durante la crisi. Grazie a queste, tutte le ferrovie merci beneficeranno in misura maggiore dei sussidi, creando al contempo condizioni di concorrenza eque sulla ferrovia&#8221;, commenta Ludolf Kerkeling, presidente della G\u00dcTERBAHNEN.<\/p>\n<p>Tuttavia, anche se si creano condizioni eque all&#8217;interno delle ferrovie, manca una strategia per stabilirle anche in concorrenza con il camion. Il prezzo dell&#8217;elettricit\u00e0 ferroviaria con il freno ai prezzi \u00e8 ancora almeno tre volte superiore rispetto al 2021, quando era in media di 6,4 centesimi per kilowattora (o 64 euro per megawattora, ulteriori spiegazioni nell&#8217;INFO qui sotto). Oggi, invece, il prezzo del diesel \u00e8 poco pi\u00f9 alto. Proprio nel segmento del trasporto combinato su ferrovia, particolarmente competitivo, si \u00e8 verificato un crollo di quasi il 14% nel primo trimestre del 2023, un valore simile a quello dei tempi del COVID. &#8220;Per i clienti \u00e8 di nuovo economicamente vantaggioso percorrere l&#8217;intero tragitto in camion. Tuttavia, il trasporto combinato \u00e8 il percorso di crescita per eccellenza, se vogliamo trasferire i trasporti, compresi pacchi e altre merci leggere, sulla ferrovia ecologica&#8221;, spiega Ludolf Kerkeling.<\/p>\n<h5>Paura di un futuro senza freno ai prezzi dell&#8217;elettricit\u00e0<\/h5>\n<p>Le preoccupazioni del settore si rivolgono anche verso un futuro senza freno ai prezzi dell&#8217;elettricit\u00e0: questo \u00e8 limitato fino alla primavera del 2024. La domanda \u00e8 come si pu\u00f2 evitare che proprio la ferrovia ecologica venga esclusa dal mercato se il prezzo dell&#8217;elettricit\u00e0 ferroviaria supera a lungo termine l&#8217;andamento dei prezzi del diesel. Una soluzione potrebbe essere la legge sui prezzi dell&#8217;elettricit\u00e0 industriale del Ministero dell&#8217;Economia, che finora esiste solo come bozza, ma dovrebbe garantire un prezzo fisso e competitivo per l'&#8221;industria energivora&#8221;. Kerkeling: &#8220;Dopo le esperienze positive con il freno ai prezzi dell&#8217;elettricit\u00e0, siamo certi che anche il trasporto ferroviario sar\u00e0 classificato come energivoro e che il prezzo dell&#8217;elettricit\u00e0 industriale contribuir\u00e0 a raggiungere gli obiettivi di protezione climatica nel settore dei trasporti.&#8221;<\/p>\n<blockquote><p>Il freno ai prezzi dell&#8217;elettricit\u00e0 causa spesso malintesi nel trasporto merci ferroviario: il numero significativo di 130 euro per megawattora (o 13 centesimi per kilowattora), che il trasporto elettrico secondo la legge sul freno ai prezzi dell&#8217;elettricit\u00e0 dovrebbe costare, si \u00e8 radicato nella mente della maggior parte dei clienti delle aziende di trasporto ferroviario. Tuttavia, si ignora che solo una parte del fabbisogno di energia elettrica, cio\u00e8 il prezzo di lavoro, \u00e8 soggetta al sollievo. Il prezzo dell&#8217;elettricit\u00e0 ferroviaria in Germania include, oltre ai costi di approvvigionamento, ulteriori componenti che possono aumentare i costi. Questi componenti non sono coperti dal freno ai prezzi dell&#8217;elettricit\u00e0 e quindi non sono ridotti.<\/p>\n<p>Esempio (per il calcolo completo <a href=\"https:\/\/crm.netzwerk-bahnen.de\/civicrm\/mailing\/url?u=507&amp;qid=5686\">qui<\/a>):<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-23171 size-full\" src=\"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/NEE_29.5.23.jpg\" alt=\"\" width=\"570\" height=\"403\" \/><\/p>\n<p>I costi per un megawattora di elettricit\u00e0 si sono cos\u00ec ridotti in modo significativo, ma non a 130 euro, bens\u00ec a 253 euro \u2013 quasi il doppio dei costi frequentemente assunti.<\/p>\n<p>I gravi costi aggiuntivi che le ferrovie merci hanno subito dall&#8217;inizio della crisi energetica non sono quindi stati eliminati dal freno ai prezzi dell&#8217;elettricit\u00e0: lo stesso megawattora di elettricit\u00e0, comprese le tariffe di rete, le tasse e i contributi, nel 2021 sarebbe costato circa 160 euro, solo circa il 63% del prezzo attuale ridotto.<\/p><\/blockquote>\n<p>Foto: \u00a9 LE FERROVIE MERCI<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La seconda &#8220;modifica correttiva&#8221; per la legge sul freno ai prezzi dell&#8217;elettricit\u00e0, che oggi sar\u00e0 presentata dalla coalizione al Bundestag, contiene importanti correzioni per le ferrovie<span class=\"excerpt-hellip\"> [\u2026]<\/span><\/p>\n","protected":false},"author":0,"featured_media":8085,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1559],"tags":[],"class_list":["post-61580","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-shipping-ports"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>LE FERROVIE MERCI chiedono una strategia a lungo termine per i prezzi dell&#039;elettricit\u00e0 - Loginfo24<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/loginfo24.com\/it\/2023\/05\/29\/le-ferrovie-merci-chiedono-una-strategia-a-lungo-termine-per-i-prezzi-dellelettricita\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"LE FERROVIE MERCI chiedono una strategia a lungo termine per i prezzi dell&#039;elettricit\u00e0 - Loginfo24\" \/>\n<meta property=\"og:description\" content=\"La seconda &#8220;modifica correttiva&#8221; per la legge sul freno ai prezzi dell&#8217;elettricit\u00e0, che oggi sar\u00e0 presentata dalla coalizione al Bundestag, contiene importanti correzioni per le ferrovie [\u2026]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/loginfo24.com\/it\/2023\/05\/29\/le-ferrovie-merci-chiedono-una-strategia-a-lungo-termine-per-i-prezzi-dellelettricita\/\" \/>\n<meta property=\"og:site_name\" content=\"Loginfo24\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/\" \/>\n<meta property=\"article:published_time\" content=\"2023-05-29T15:21:26+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/NEE_29.5.23_1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1241\" \/>\n\t<meta property=\"og:image:height\" content=\"644\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2023\\\/05\\\/29\\\/le-ferrovie-merci-chiedono-una-strategia-a-lungo-termine-per-i-prezzi-dellelettricita\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2023\\\/05\\\/29\\\/le-ferrovie-merci-chiedono-una-strategia-a-lungo-termine-per-i-prezzi-dellelettricita\\\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"LE FERROVIE MERCI chiedono una strategia a lungo termine per i prezzi dell&#8217;elettricit\u00e0\",\"datePublished\":\"2023-05-29T15:21:26+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2023\\\/05\\\/29\\\/le-ferrovie-merci-chiedono-una-strategia-a-lungo-termine-per-i-prezzi-dellelettricita\\\/\"},\"wordCount\":731,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2023\\\/05\\\/29\\\/le-ferrovie-merci-chiedono-una-strategia-a-lungo-termine-per-i-prezzi-dellelettricita\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/NEE_29.5.23_1.jpg\",\"articleSection\":[\"Shipping &amp; Ports\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/it\\\/2023\\\/05\\\/29\\\/le-ferrovie-merci-chiedono-una-strategia-a-lungo-termine-per-i-prezzi-dellelettricita\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2023\\\/05\\\/29\\\/le-ferrovie-merci-chiedono-una-strategia-a-lungo-termine-per-i-prezzi-dellelettricita\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2023\\\/05\\\/29\\\/le-ferrovie-merci-chiedono-una-strategia-a-lungo-termine-per-i-prezzi-dellelettricita\\\/\",\"name\":\"LE FERROVIE MERCI chiedono una strategia a lungo termine per i prezzi dell'elettricit\u00e0 - Loginfo24\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2023\\\/05\\\/29\\\/le-ferrovie-merci-chiedono-una-strategia-a-lungo-termine-per-i-prezzi-dellelettricita\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2023\\\/05\\\/29\\\/le-ferrovie-merci-chiedono-una-strategia-a-lungo-termine-per-i-prezzi-dellelettricita\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/NEE_29.5.23_1.jpg\",\"datePublished\":\"2023-05-29T15:21:26+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2023\\\/05\\\/29\\\/le-ferrovie-merci-chiedono-una-strategia-a-lungo-termine-per-i-prezzi-dellelettricita\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/it\\\/2023\\\/05\\\/29\\\/le-ferrovie-merci-chiedono-una-strategia-a-lungo-termine-per-i-prezzi-dellelettricita\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2023\\\/05\\\/29\\\/le-ferrovie-merci-chiedono-una-strategia-a-lungo-termine-per-i-prezzi-dellelettricita\\\/#primaryimage\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/NEE_29.5.23_1.jpg\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/NEE_29.5.23_1.jpg\",\"width\":1241,\"height\":644},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2023\\\/05\\\/29\\\/le-ferrovie-merci-chiedono-una-strategia-a-lungo-termine-per-i-prezzi-dellelettricita\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"LE FERROVIE MERCI chiedono una strategia a lungo termine per i prezzi dell&#8217;elettricit\u00e0\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/\",\"name\":\"Loginfo24\",\"description\":\"Loginfo24 \u00e8 la piattaforma dedicata alla logistica e alle catene di fornitura con informazioni disponibili 24 ore su 24.\",\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#organization\",\"name\":\"Logismedia Group AG\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"width\":938,\"height\":351,\"caption\":\"Logismedia Group AG\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/people\\\/Loginfo24\\\/100057360583332\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/lofinfo24\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"LE FERROVIE MERCI chiedono una strategia a lungo termine per i prezzi dell'elettricit\u00e0 - Loginfo24","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/loginfo24.com\/it\/2023\/05\/29\/le-ferrovie-merci-chiedono-una-strategia-a-lungo-termine-per-i-prezzi-dellelettricita\/","og_locale":"it_IT","og_type":"article","og_title":"LE FERROVIE MERCI chiedono una strategia a lungo termine per i prezzi dell'elettricit\u00e0 - Loginfo24","og_description":"La seconda &#8220;modifica correttiva&#8221; per la legge sul freno ai prezzi dell&#8217;elettricit\u00e0, che oggi sar\u00e0 presentata dalla coalizione al Bundestag, contiene importanti correzioni per le ferrovie [\u2026]","og_url":"https:\/\/loginfo24.com\/it\/2023\/05\/29\/le-ferrovie-merci-chiedono-una-strategia-a-lungo-termine-per-i-prezzi-dellelettricita\/","og_site_name":"Loginfo24","article_publisher":"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","article_published_time":"2023-05-29T15:21:26+00:00","og_image":[{"width":1241,"height":644,"url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/NEE_29.5.23_1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"3 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/loginfo24.com\/it\/2023\/05\/29\/le-ferrovie-merci-chiedono-una-strategia-a-lungo-termine-per-i-prezzi-dellelettricita\/#article","isPartOf":{"@id":"https:\/\/loginfo24.com\/it\/2023\/05\/29\/le-ferrovie-merci-chiedono-una-strategia-a-lungo-termine-per-i-prezzi-dellelettricita\/"},"author":{"name":"","@id":""},"headline":"LE FERROVIE MERCI chiedono una strategia a lungo termine per i prezzi dell&#8217;elettricit\u00e0","datePublished":"2023-05-29T15:21:26+00:00","mainEntityOfPage":{"@id":"https:\/\/loginfo24.com\/it\/2023\/05\/29\/le-ferrovie-merci-chiedono-una-strategia-a-lungo-termine-per-i-prezzi-dellelettricita\/"},"wordCount":731,"commentCount":0,"publisher":{"@id":"https:\/\/loginfo24.com\/it\/#organization"},"image":{"@id":"https:\/\/loginfo24.com\/it\/2023\/05\/29\/le-ferrovie-merci-chiedono-una-strategia-a-lungo-termine-per-i-prezzi-dellelettricita\/#primaryimage"},"thumbnailUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/NEE_29.5.23_1.jpg","articleSection":["Shipping &amp; Ports"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/loginfo24.com\/it\/2023\/05\/29\/le-ferrovie-merci-chiedono-una-strategia-a-lungo-termine-per-i-prezzi-dellelettricita\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/loginfo24.com\/it\/2023\/05\/29\/le-ferrovie-merci-chiedono-una-strategia-a-lungo-termine-per-i-prezzi-dellelettricita\/","url":"https:\/\/loginfo24.com\/it\/2023\/05\/29\/le-ferrovie-merci-chiedono-una-strategia-a-lungo-termine-per-i-prezzi-dellelettricita\/","name":"LE FERROVIE MERCI chiedono una strategia a lungo termine per i prezzi dell'elettricit\u00e0 - Loginfo24","isPartOf":{"@id":"https:\/\/loginfo24.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/loginfo24.com\/it\/2023\/05\/29\/le-ferrovie-merci-chiedono-una-strategia-a-lungo-termine-per-i-prezzi-dellelettricita\/#primaryimage"},"image":{"@id":"https:\/\/loginfo24.com\/it\/2023\/05\/29\/le-ferrovie-merci-chiedono-una-strategia-a-lungo-termine-per-i-prezzi-dellelettricita\/#primaryimage"},"thumbnailUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/NEE_29.5.23_1.jpg","datePublished":"2023-05-29T15:21:26+00:00","breadcrumb":{"@id":"https:\/\/loginfo24.com\/it\/2023\/05\/29\/le-ferrovie-merci-chiedono-una-strategia-a-lungo-termine-per-i-prezzi-dellelettricita\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/loginfo24.com\/it\/2023\/05\/29\/le-ferrovie-merci-chiedono-una-strategia-a-lungo-termine-per-i-prezzi-dellelettricita\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/loginfo24.com\/it\/2023\/05\/29\/le-ferrovie-merci-chiedono-una-strategia-a-lungo-termine-per-i-prezzi-dellelettricita\/#primaryimage","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/NEE_29.5.23_1.jpg","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/NEE_29.5.23_1.jpg","width":1241,"height":644},{"@type":"BreadcrumbList","@id":"https:\/\/loginfo24.com\/it\/2023\/05\/29\/le-ferrovie-merci-chiedono-una-strategia-a-lungo-termine-per-i-prezzi-dellelettricita\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/loginfo24.com\/it\/"},{"@type":"ListItem","position":2,"name":"LE FERROVIE MERCI chiedono una strategia a lungo termine per i prezzi dell&#8217;elettricit\u00e0"}]},{"@type":"WebSite","@id":"https:\/\/loginfo24.com\/it\/#website","url":"https:\/\/loginfo24.com\/it\/","name":"Loginfo24","description":"Loginfo24 \u00e8 la piattaforma dedicata alla logistica e alle catene di fornitura con informazioni disponibili 24 ore su 24.","publisher":{"@id":"https:\/\/loginfo24.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/loginfo24.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/loginfo24.com\/it\/#organization","name":"Logismedia Group AG","url":"https:\/\/loginfo24.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/loginfo24.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","width":938,"height":351,"caption":"Logismedia Group AG"},"image":{"@id":"https:\/\/loginfo24.com\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","https:\/\/www.linkedin.com\/company\/lofinfo24\/"]}]}},"_links":{"self":[{"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/posts\/61580","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/comments?post=61580"}],"version-history":[{"count":0,"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/posts\/61580\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/media\/8085"}],"wp:attachment":[{"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/media?parent=61580"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/categories?post=61580"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/tags?post=61580"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}