{"id":61496,"date":"2023-05-22T17:13:09","date_gmt":"2023-05-22T15:13:09","guid":{"rendered":"https:\/\/blog.brand-architecture.at\/2023\/05\/22\/la-lubecker-hafen-gesellschaft-presenta-un-nuovo-marchio\/"},"modified":"2023-05-22T17:13:09","modified_gmt":"2023-05-22T15:13:09","slug":"la-lubecker-hafen-gesellschaft-presenta-un-nuovo-marchio","status":"publish","type":"post","link":"https:\/\/loginfo24.com\/it\/2023\/05\/22\/la-lubecker-hafen-gesellschaft-presenta-un-nuovo-marchio\/","title":{"rendered":"La L\u00fcbecker Hafen-Gesellschaft presenta un nuovo marchio"},"content":{"rendered":"<h5>Novanta anni compir\u00e0 la L\u00fcbecker Hafen-Gesellschaft (LHG) il prossimo anno, e ora ha ricevuto un nuovo look. Alla fiera &#8220;transport logistic&#8221; di Monaco, l&#8217;azienda ha recentemente presentato il nuovo outfit. Colori vivaci sostituiscono il vecchio logo, il riquadro grigio argento con le tre lettere. Il design include anche il claim &#8220;Your TransPort&#8221;.<\/h5>\n<p>(L\u00fcbeck) Il nuovo logo si distingue per la sua forma chiara e semplice. I suoi tre elementi riflettono la trimodalit\u00e0 delle strutture portuali. Al centro si trova il punto di concentrazione, circondato dalle frecce indicatrici. Queste rappresentano sia una nave che mani che custodiscono con cura le merci dei partner e dei clienti.<\/p>\n<p>I colori aziendali attuali della LHG non sono una reinvenzione, ma piuttosto un&#8217;evoluzione dinamica del look precedente. La tonalit\u00e0 &#8220;Port Orange&#8221;, ad esempio, riprende consapevolmente l&#8217;arancione noto della LHG e gli conferisce maggiore profondit\u00e0. L&#8217;arancione \u00e8 il colore dell&#8217;abbigliamento da lavoro all&#8217;aperto nei terminal \u2013 e quindi una parte immensamente importante dell&#8217;identit\u00e0 dell&#8217;operatore portuale. Il &#8220;Baltic Blue&#8221;, il blu profondo del mare, esprime il legame con l&#8217;acqua.<\/p>\n<h5>Il nuovo marchio \u00e8 molto ben accolto<\/h5>\n<p>Negli ultimi 90 anni, la LHG si \u00e8 gradualmente evoluta in un&#8217;azienda di logistica moderna. Sia in ufficio che al molo, i dipendenti affrontano insieme ogni sfida e portano a termine i progetti pi\u00f9 diversi. Il direttore generale Ortwin Harms spiega: &#8220;Questo &#8216;spirito di squadra&#8217; lo abbiamo tradotto in una sorta di canone di valori a supporto della nuova identit\u00e0 del marchio. Descrive la filosofia dell&#8217;azienda, come pensiamo e agiamo, e per cosa esattamente ci battiamo.&#8221; Il nuovo marchio \u00e8 stato molto ben accolto, ci sono stati molti elogi sia alla fiera che dopo per il &#8220;nuovo look fresco&#8221;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Novanta anni compir\u00e0 la L\u00fcbecker Hafen-Gesellschaft (LHG) il prossimo anno, e ora ha ricevuto un nuovo look. Alla fiera &#8220;transport logistic&#8221; di Monaco, l&#8217;azienda ha recentemente<span class=\"excerpt-hellip\"> [\u2026]<\/span><\/p>\n","protected":false},"author":0,"featured_media":8123,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1557,1561,1559],"tags":[],"class_list":["post-61496","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-forwarding-logistics","category-regions","category-shipping-ports"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La L\u00fcbecker Hafen-Gesellschaft presenta un nuovo marchio - Loginfo24<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/loginfo24.com\/it\/2023\/05\/22\/la-lubecker-hafen-gesellschaft-presenta-un-nuovo-marchio\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La L\u00fcbecker Hafen-Gesellschaft presenta un nuovo marchio - Loginfo24\" \/>\n<meta property=\"og:description\" content=\"Novanta anni compir\u00e0 la L\u00fcbecker Hafen-Gesellschaft (LHG) il prossimo anno, e ora ha ricevuto un nuovo look. Alla fiera &#8220;transport logistic&#8221; di Monaco, l&#8217;azienda ha recentemente [\u2026]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/loginfo24.com\/it\/2023\/05\/22\/la-lubecker-hafen-gesellschaft-presenta-un-nuovo-marchio\/\" \/>\n<meta property=\"og:site_name\" content=\"Loginfo24\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/\" \/>\n<meta property=\"article:published_time\" content=\"2023-05-22T15:13:09+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/LHG_22.5.23.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1350\" \/>\n\t<meta property=\"og:image:height\" content=\"750\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2023\\\/05\\\/22\\\/la-lubecker-hafen-gesellschaft-presenta-un-nuovo-marchio\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2023\\\/05\\\/22\\\/la-lubecker-hafen-gesellschaft-presenta-un-nuovo-marchio\\\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"La L\u00fcbecker Hafen-Gesellschaft presenta un nuovo marchio\",\"datePublished\":\"2023-05-22T15:13:09+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2023\\\/05\\\/22\\\/la-lubecker-hafen-gesellschaft-presenta-un-nuovo-marchio\\\/\"},\"wordCount\":293,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2023\\\/05\\\/22\\\/la-lubecker-hafen-gesellschaft-presenta-un-nuovo-marchio\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/LHG_22.5.23.jpg\",\"articleSection\":[\"Forwarding &amp; Logistics\",\"Regions\",\"Shipping &amp; Ports\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/it\\\/2023\\\/05\\\/22\\\/la-lubecker-hafen-gesellschaft-presenta-un-nuovo-marchio\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2023\\\/05\\\/22\\\/la-lubecker-hafen-gesellschaft-presenta-un-nuovo-marchio\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2023\\\/05\\\/22\\\/la-lubecker-hafen-gesellschaft-presenta-un-nuovo-marchio\\\/\",\"name\":\"La L\u00fcbecker Hafen-Gesellschaft presenta un nuovo marchio - Loginfo24\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2023\\\/05\\\/22\\\/la-lubecker-hafen-gesellschaft-presenta-un-nuovo-marchio\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2023\\\/05\\\/22\\\/la-lubecker-hafen-gesellschaft-presenta-un-nuovo-marchio\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/LHG_22.5.23.jpg\",\"datePublished\":\"2023-05-22T15:13:09+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2023\\\/05\\\/22\\\/la-lubecker-hafen-gesellschaft-presenta-un-nuovo-marchio\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/it\\\/2023\\\/05\\\/22\\\/la-lubecker-hafen-gesellschaft-presenta-un-nuovo-marchio\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2023\\\/05\\\/22\\\/la-lubecker-hafen-gesellschaft-presenta-un-nuovo-marchio\\\/#primaryimage\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/LHG_22.5.23.jpg\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/LHG_22.5.23.jpg\",\"width\":1350,\"height\":750},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2023\\\/05\\\/22\\\/la-lubecker-hafen-gesellschaft-presenta-un-nuovo-marchio\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La L\u00fcbecker Hafen-Gesellschaft presenta un nuovo marchio\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/\",\"name\":\"Loginfo24\",\"description\":\"Loginfo24 \u00e8 la piattaforma dedicata alla logistica e alle catene di fornitura con informazioni disponibili 24 ore su 24.\",\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#organization\",\"name\":\"Logismedia Group AG\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"width\":938,\"height\":351,\"caption\":\"Logismedia Group AG\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/people\\\/Loginfo24\\\/100057360583332\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/lofinfo24\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La L\u00fcbecker Hafen-Gesellschaft presenta un nuovo marchio - Loginfo24","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/loginfo24.com\/it\/2023\/05\/22\/la-lubecker-hafen-gesellschaft-presenta-un-nuovo-marchio\/","og_locale":"it_IT","og_type":"article","og_title":"La L\u00fcbecker Hafen-Gesellschaft presenta un nuovo marchio - Loginfo24","og_description":"Novanta anni compir\u00e0 la L\u00fcbecker Hafen-Gesellschaft (LHG) il prossimo anno, e ora ha ricevuto un nuovo look. Alla fiera &#8220;transport logistic&#8221; di Monaco, l&#8217;azienda ha recentemente [\u2026]","og_url":"https:\/\/loginfo24.com\/it\/2023\/05\/22\/la-lubecker-hafen-gesellschaft-presenta-un-nuovo-marchio\/","og_site_name":"Loginfo24","article_publisher":"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","article_published_time":"2023-05-22T15:13:09+00:00","og_image":[{"width":1350,"height":750,"url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/LHG_22.5.23.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/loginfo24.com\/it\/2023\/05\/22\/la-lubecker-hafen-gesellschaft-presenta-un-nuovo-marchio\/#article","isPartOf":{"@id":"https:\/\/loginfo24.com\/it\/2023\/05\/22\/la-lubecker-hafen-gesellschaft-presenta-un-nuovo-marchio\/"},"author":{"name":"","@id":""},"headline":"La L\u00fcbecker Hafen-Gesellschaft presenta un nuovo marchio","datePublished":"2023-05-22T15:13:09+00:00","mainEntityOfPage":{"@id":"https:\/\/loginfo24.com\/it\/2023\/05\/22\/la-lubecker-hafen-gesellschaft-presenta-un-nuovo-marchio\/"},"wordCount":293,"commentCount":0,"publisher":{"@id":"https:\/\/loginfo24.com\/it\/#organization"},"image":{"@id":"https:\/\/loginfo24.com\/it\/2023\/05\/22\/la-lubecker-hafen-gesellschaft-presenta-un-nuovo-marchio\/#primaryimage"},"thumbnailUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/LHG_22.5.23.jpg","articleSection":["Forwarding &amp; Logistics","Regions","Shipping &amp; Ports"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/loginfo24.com\/it\/2023\/05\/22\/la-lubecker-hafen-gesellschaft-presenta-un-nuovo-marchio\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/loginfo24.com\/it\/2023\/05\/22\/la-lubecker-hafen-gesellschaft-presenta-un-nuovo-marchio\/","url":"https:\/\/loginfo24.com\/it\/2023\/05\/22\/la-lubecker-hafen-gesellschaft-presenta-un-nuovo-marchio\/","name":"La L\u00fcbecker Hafen-Gesellschaft presenta un nuovo marchio - Loginfo24","isPartOf":{"@id":"https:\/\/loginfo24.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/loginfo24.com\/it\/2023\/05\/22\/la-lubecker-hafen-gesellschaft-presenta-un-nuovo-marchio\/#primaryimage"},"image":{"@id":"https:\/\/loginfo24.com\/it\/2023\/05\/22\/la-lubecker-hafen-gesellschaft-presenta-un-nuovo-marchio\/#primaryimage"},"thumbnailUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/LHG_22.5.23.jpg","datePublished":"2023-05-22T15:13:09+00:00","breadcrumb":{"@id":"https:\/\/loginfo24.com\/it\/2023\/05\/22\/la-lubecker-hafen-gesellschaft-presenta-un-nuovo-marchio\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/loginfo24.com\/it\/2023\/05\/22\/la-lubecker-hafen-gesellschaft-presenta-un-nuovo-marchio\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/loginfo24.com\/it\/2023\/05\/22\/la-lubecker-hafen-gesellschaft-presenta-un-nuovo-marchio\/#primaryimage","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/LHG_22.5.23.jpg","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/LHG_22.5.23.jpg","width":1350,"height":750},{"@type":"BreadcrumbList","@id":"https:\/\/loginfo24.com\/it\/2023\/05\/22\/la-lubecker-hafen-gesellschaft-presenta-un-nuovo-marchio\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/loginfo24.com\/it\/"},{"@type":"ListItem","position":2,"name":"La L\u00fcbecker Hafen-Gesellschaft presenta un nuovo marchio"}]},{"@type":"WebSite","@id":"https:\/\/loginfo24.com\/it\/#website","url":"https:\/\/loginfo24.com\/it\/","name":"Loginfo24","description":"Loginfo24 \u00e8 la piattaforma dedicata alla logistica e alle catene di fornitura con informazioni disponibili 24 ore su 24.","publisher":{"@id":"https:\/\/loginfo24.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/loginfo24.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/loginfo24.com\/it\/#organization","name":"Logismedia Group AG","url":"https:\/\/loginfo24.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/loginfo24.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","width":938,"height":351,"caption":"Logismedia Group AG"},"image":{"@id":"https:\/\/loginfo24.com\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","https:\/\/www.linkedin.com\/company\/lofinfo24\/"]}]}},"_links":{"self":[{"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/posts\/61496","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/comments?post=61496"}],"version-history":[{"count":0,"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/posts\/61496\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/media\/8123"}],"wp:attachment":[{"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/media?parent=61496"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/categories?post=61496"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/tags?post=61496"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}