{"id":61008,"date":"2023-03-21T16:40:31","date_gmt":"2023-03-21T15:40:31","guid":{"rendered":"https:\/\/blog.brand-architecture.at\/2023\/03\/21\/nuovi-motivi-contro-la-carenza-di-professionisti\/"},"modified":"2023-03-21T16:40:31","modified_gmt":"2023-03-21T15:40:31","slug":"nuovi-motivi-contro-la-carenza-di-professionisti","status":"publish","type":"post","link":"https:\/\/loginfo24.com\/it\/2023\/03\/21\/nuovi-motivi-contro-la-carenza-di-professionisti\/","title":{"rendered":"Nuovi motivi contro la carenza di professionisti"},"content":{"rendered":"<h5><strong>\u201eCosa succede quando la logistica smette di funzionare?\u201d La risposta a questa domanda \u00e8 fornita da \u201eDie Wirtschaftsmacher\u201d nella loro nuova campagna pubblicitaria. I motivi rivelano l&#8217;influenza del settore economico sulla nostra vita. Con la campagna, l&#8217;iniziativa si collega a un&#8217;azione di successo dell&#8217;anno scorso con stimoli di pensiero simili. Il tema principale per il 2023 \u00e8 l&#8217;impegno per la promozione dei giovani nel terzo settore economico pi\u00f9 grande della Germania, su cui l&#8217;iniziativa fa riferimento ai suoi ambiti lavorativi interessanti e significativi. Il motto annuale \u00e8: \u201eIl tuo futuro nella logistica. Ha senso!\u201d<\/strong><\/h5>\n<p>(Francoforte\/Milano) Tra le maggiori sfide per la logistica ci sono, alla luce della carenza di professionisti, problemi di immagine ben noti. I lavoratori sottovalutano la variet\u00e0, la spinta all&#8217;innovazione e l&#8217;attrattiva delle professioni logistiche, mentre il ruolo fondamentale della societ\u00e0 e le prestazioni del settore economico non diventano sufficientemente visibili. Per questo motivo, \u201eDie Wirtschaftsmacher\u201d punta strategicamente e con successo sul lavoro di sensibilizzazione, offrendo sguardi e intuizioni autentiche sul ruolo della logistica.<\/p>\n<h5><strong>Senzo logistica manca tutto \u2013 a tutti, sempre e ovunque!<\/strong><\/h5>\n<p>Con nuovi motivi, l&#8217;iniziativa dipinge l&#8217;immagine di un mondo senza logistica. Diventa evidente che la maggior parte delle cose quotidiane della nostra vita non sarebbero disponibili senza logistica. La campagna porta quindi alla consapevolezza: la vita quotidiana che conosciamo non esisterebbe semplicemente senza la logistica. Alla pizza mancherebbe il salame, all&#8217;immagine la cornice, alla nuova costruzione il materiale, al musicista lo strumento e al malato il medicinale. In breve: mancava tutto, e a tutti, sempre e ovunque.<\/p>\n<h5><strong>Contro i vecchi pregiudizi sulla logistica<\/strong><\/h5>\n<p>La carenza di professionisti \u00e8 una delle maggiori sfide per la logistica. Con lo slogan \u201eIl tuo futuro nella logistica. Ha senso!\u201d i Wirtschaftsmacher si dedicano quest&#8217;anno alla promozione dei giovani e vogliono combattere in particolare i pregiudizi. I pi\u00f9 comuni stereotipi sulla logistica servono da base per la campagna contro i pregiudizi riproposta. Spesso pensato e raramente verificato \u00e8, ad esempio, che si tratti esclusivamente di lavori come quello di carrellista. Oppure il pregiudizio che la logistica non offra attivit\u00e0 interessanti. Inoltre, non sarebbe sostenibile, non innovativa e non adatta a giovani ambiziosi. I Wirtschaftsmacher dimostrano con i loro nuovi motivi che si tratta di pregiudizi e che spesso \u00e8 addirittura il contrario.<\/p>\n<p>\u201eI pregiudizi nei confronti del nostro settore economico sono, secondo le persone che lavorano nella logistica, altrettanto ostinati quanto distaccati dalla realt\u00e0. Che ci siano compiti interessanti con rilevanza sociale e vere prospettive di carriera, sar\u00e0 evidente a chiunque ottenga i primi sguardi\u201d, spiega Frauke Heistermann, portavoce dei Wirtschaftsmacher. \u201eCome iniziativa logistica, vogliamo quindi invitare in particolare i giovani ad aprirsi a questo tema, per poter prendere decisioni professionali informate.\u201d<\/p>\n<p>Un&#8217;analisi pi\u00f9 approfondita dei pregiudizi contro la logistica \u00e8 disponibile anche nel fascicolo tematico \u201ePregiudizi sulla logistica rapidamente sfatati\u201d, disponibile per il download gratuito.<\/p>\n<p><a href=\"https:\/\/www.die-wirtschaftsmacher.de\/themenhefte\/logistik-vorurteile\">www.die-wirtschaftsmacher.de\/themenhefte\/logistik-vorurteile<\/a><\/p>\n<p>Foto: \u00a9 Die Wirtschaftsmacher \/ <strong><em>Didascalia dell&#8217;immagine:<\/em><\/strong> <em>La nuova campagna dei Wirtschaftsmacher \u00e8 sotto lo slogan \u201eIl tuo futuro nella logistica. Ha senso!\u201d<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u201eCosa succede quando la logistica smette di funzionare?\u201d La risposta a questa domanda \u00e8 fornita da \u201eDie Wirtschaftsmacher\u201d nella loro nuova campagna pubblicitaria. I motivi rivelano<span class=\"excerpt-hellip\"> [\u2026]<\/span><\/p>\n","protected":false},"author":0,"featured_media":8341,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1665,1561],"tags":[],"class_list":["post-61008","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-categories","category-regions"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Nuovi motivi contro la carenza di professionisti - Loginfo24<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/loginfo24.com\/it\/2023\/03\/21\/nuovi-motivi-contro-la-carenza-di-professionisti\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Nuovi motivi contro la carenza di professionisti - Loginfo24\" \/>\n<meta property=\"og:description\" content=\"\u201eCosa succede quando la logistica smette di funzionare?\u201d La risposta a questa domanda \u00e8 fornita da \u201eDie Wirtschaftsmacher\u201d nella loro nuova campagna pubblicitaria. I motivi rivelano [\u2026]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/loginfo24.com\/it\/2023\/03\/21\/nuovi-motivi-contro-la-carenza-di-professionisti\/\" \/>\n<meta property=\"og:site_name\" content=\"Loginfo24\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/\" \/>\n<meta property=\"article:published_time\" content=\"2023-03-21T15:40:31+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Wirtschaftsmacher_21.03.2023.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"974\" \/>\n\t<meta property=\"og:image:height\" content=\"882\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2023\\\/03\\\/21\\\/nuovi-motivi-contro-la-carenza-di-professionisti\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2023\\\/03\\\/21\\\/nuovi-motivi-contro-la-carenza-di-professionisti\\\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Nuovi motivi contro la carenza di professionisti\",\"datePublished\":\"2023-03-21T15:40:31+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2023\\\/03\\\/21\\\/nuovi-motivi-contro-la-carenza-di-professionisti\\\/\"},\"wordCount\":506,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2023\\\/03\\\/21\\\/nuovi-motivi-contro-la-carenza-di-professionisti\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/Wirtschaftsmacher_21.03.2023.jpg\",\"articleSection\":[\"Categories\",\"Regions\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/it\\\/2023\\\/03\\\/21\\\/nuovi-motivi-contro-la-carenza-di-professionisti\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2023\\\/03\\\/21\\\/nuovi-motivi-contro-la-carenza-di-professionisti\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2023\\\/03\\\/21\\\/nuovi-motivi-contro-la-carenza-di-professionisti\\\/\",\"name\":\"Nuovi motivi contro la carenza di professionisti - Loginfo24\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2023\\\/03\\\/21\\\/nuovi-motivi-contro-la-carenza-di-professionisti\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2023\\\/03\\\/21\\\/nuovi-motivi-contro-la-carenza-di-professionisti\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/Wirtschaftsmacher_21.03.2023.jpg\",\"datePublished\":\"2023-03-21T15:40:31+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2023\\\/03\\\/21\\\/nuovi-motivi-contro-la-carenza-di-professionisti\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/it\\\/2023\\\/03\\\/21\\\/nuovi-motivi-contro-la-carenza-di-professionisti\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2023\\\/03\\\/21\\\/nuovi-motivi-contro-la-carenza-di-professionisti\\\/#primaryimage\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/Wirtschaftsmacher_21.03.2023.jpg\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/Wirtschaftsmacher_21.03.2023.jpg\",\"width\":974,\"height\":882},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2023\\\/03\\\/21\\\/nuovi-motivi-contro-la-carenza-di-professionisti\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Nuovi motivi contro la carenza di professionisti\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/\",\"name\":\"Loginfo24\",\"description\":\"Loginfo24 \u00e8 la piattaforma dedicata alla logistica e alle catene di fornitura con informazioni disponibili 24 ore su 24.\",\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#organization\",\"name\":\"Logismedia Group AG\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"width\":938,\"height\":351,\"caption\":\"Logismedia Group AG\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/people\\\/Loginfo24\\\/100057360583332\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/lofinfo24\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Nuovi motivi contro la carenza di professionisti - Loginfo24","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/loginfo24.com\/it\/2023\/03\/21\/nuovi-motivi-contro-la-carenza-di-professionisti\/","og_locale":"it_IT","og_type":"article","og_title":"Nuovi motivi contro la carenza di professionisti - Loginfo24","og_description":"\u201eCosa succede quando la logistica smette di funzionare?\u201d La risposta a questa domanda \u00e8 fornita da \u201eDie Wirtschaftsmacher\u201d nella loro nuova campagna pubblicitaria. I motivi rivelano [\u2026]","og_url":"https:\/\/loginfo24.com\/it\/2023\/03\/21\/nuovi-motivi-contro-la-carenza-di-professionisti\/","og_site_name":"Loginfo24","article_publisher":"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","article_published_time":"2023-03-21T15:40:31+00:00","og_image":[{"width":974,"height":882,"url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Wirtschaftsmacher_21.03.2023.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"2 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/loginfo24.com\/it\/2023\/03\/21\/nuovi-motivi-contro-la-carenza-di-professionisti\/#article","isPartOf":{"@id":"https:\/\/loginfo24.com\/it\/2023\/03\/21\/nuovi-motivi-contro-la-carenza-di-professionisti\/"},"author":{"name":"","@id":""},"headline":"Nuovi motivi contro la carenza di professionisti","datePublished":"2023-03-21T15:40:31+00:00","mainEntityOfPage":{"@id":"https:\/\/loginfo24.com\/it\/2023\/03\/21\/nuovi-motivi-contro-la-carenza-di-professionisti\/"},"wordCount":506,"commentCount":0,"publisher":{"@id":"https:\/\/loginfo24.com\/it\/#organization"},"image":{"@id":"https:\/\/loginfo24.com\/it\/2023\/03\/21\/nuovi-motivi-contro-la-carenza-di-professionisti\/#primaryimage"},"thumbnailUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Wirtschaftsmacher_21.03.2023.jpg","articleSection":["Categories","Regions"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/loginfo24.com\/it\/2023\/03\/21\/nuovi-motivi-contro-la-carenza-di-professionisti\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/loginfo24.com\/it\/2023\/03\/21\/nuovi-motivi-contro-la-carenza-di-professionisti\/","url":"https:\/\/loginfo24.com\/it\/2023\/03\/21\/nuovi-motivi-contro-la-carenza-di-professionisti\/","name":"Nuovi motivi contro la carenza di professionisti - Loginfo24","isPartOf":{"@id":"https:\/\/loginfo24.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/loginfo24.com\/it\/2023\/03\/21\/nuovi-motivi-contro-la-carenza-di-professionisti\/#primaryimage"},"image":{"@id":"https:\/\/loginfo24.com\/it\/2023\/03\/21\/nuovi-motivi-contro-la-carenza-di-professionisti\/#primaryimage"},"thumbnailUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Wirtschaftsmacher_21.03.2023.jpg","datePublished":"2023-03-21T15:40:31+00:00","breadcrumb":{"@id":"https:\/\/loginfo24.com\/it\/2023\/03\/21\/nuovi-motivi-contro-la-carenza-di-professionisti\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/loginfo24.com\/it\/2023\/03\/21\/nuovi-motivi-contro-la-carenza-di-professionisti\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/loginfo24.com\/it\/2023\/03\/21\/nuovi-motivi-contro-la-carenza-di-professionisti\/#primaryimage","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Wirtschaftsmacher_21.03.2023.jpg","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Wirtschaftsmacher_21.03.2023.jpg","width":974,"height":882},{"@type":"BreadcrumbList","@id":"https:\/\/loginfo24.com\/it\/2023\/03\/21\/nuovi-motivi-contro-la-carenza-di-professionisti\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/loginfo24.com\/it\/"},{"@type":"ListItem","position":2,"name":"Nuovi motivi contro la carenza di professionisti"}]},{"@type":"WebSite","@id":"https:\/\/loginfo24.com\/it\/#website","url":"https:\/\/loginfo24.com\/it\/","name":"Loginfo24","description":"Loginfo24 \u00e8 la piattaforma dedicata alla logistica e alle catene di fornitura con informazioni disponibili 24 ore su 24.","publisher":{"@id":"https:\/\/loginfo24.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/loginfo24.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/loginfo24.com\/it\/#organization","name":"Logismedia Group AG","url":"https:\/\/loginfo24.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/loginfo24.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","width":938,"height":351,"caption":"Logismedia Group AG"},"image":{"@id":"https:\/\/loginfo24.com\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","https:\/\/www.linkedin.com\/company\/lofinfo24\/"]}]}},"_links":{"self":[{"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/posts\/61008","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/comments?post=61008"}],"version-history":[{"count":0,"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/posts\/61008\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/media\/8341"}],"wp:attachment":[{"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/media?parent=61008"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/categories?post=61008"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/tags?post=61008"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}