{"id":60978,"date":"2023-03-19T11:26:10","date_gmt":"2023-03-19T10:26:10","guid":{"rendered":"https:\/\/blog.brand-architecture.at\/2023\/03\/19\/craiss-presenta-lazienda-espressa-slynx-a-logimat\/"},"modified":"2023-03-19T11:26:10","modified_gmt":"2023-03-19T10:26:10","slug":"craiss-presenta-lazienda-espressa-slynx-a-logimat","status":"publish","type":"post","link":"https:\/\/loginfo24.com\/it\/2023\/03\/19\/craiss-presenta-lazienda-espressa-slynx-a-logimat\/","title":{"rendered":"CRAISS presenta l&#8217;azienda espressa SLYNX a LogiMAT"},"content":{"rendered":"<h5><strong>La Craiss Generation Logistik GmbH &amp; Co. KG si presenta per la prima volta alla LogiMAT di quest&#8217;anno, che si svolger\u00e0 dal 25 al 27 aprile 2023, con il suo Corporate Start-up SLYNX Spedition.Digital. La premiata piattaforma online promuove ulteriormente la digitalizzazione nel settore dei trasporti speciali e espressi, consentendo l&#8217;assegnazione sostenibile ed efficiente degli ordini.<\/strong><\/h5>\n<p>(M\u00fchlacker\/Stuttgart) I visitatori della fiera specializzata di Stoccarda per soluzioni di intralogistica possono inoltre aspettarsi l&#8217;ampia gamma di servizi offerti da Craiss, tra cui servizi a valore aggiunto per le aziende manifatturiere e soluzioni specifiche per la logistica di magazzino e la preparazione degli ordini.<\/p>\n<p>&#8220;SLYNX \u00e8 il futuro del settore logistico e consente di rendere i trasporti e la rete logistica pi\u00f9 trasparenti, collegando digitalmente i caricatori con le aziende di trasporto&#8221;, afferma Valerie Boden, responsabile del dipartimento presso SLYNX GmbH &amp; Co. KG. L&#8217;impulso per la soluzione universale \u00e8 nato dalla piattaforma online interna &#8220;Sonderfahrten 4.0&#8221;. Un&#8217;idea che ripaga: nel 2022, Craiss ha vinto con SLYNX il &#8220;Leone Nero&#8221;, il pi\u00f9 grande premio economico per le aziende in Baden-W\u00fcrttemberg, nella categoria &#8220;Trasformazione Digitale&#8221;.<\/p>\n<p>SLYNX consente di rappresentare digitalmente ordini e trasporti per la logistica espressa e i trasporti speciali. La piattaforma garantisce una connessione automatica e diretta con i partner di trasporto appropriati, con la gestione e la documentazione che avvengono online. In questo modo, tutte le informazioni sono visibili in modo trasparente a tutti gli attori coinvolti. Anche le consegne critiche in termini di tempo possono essere facilmente ordinate tramite browser. Alla LogiMAT, gli interessati possono conoscere per la prima volta l&#8217;innovativa azienda e scambiare idee direttamente con gli esperti sul posto.<\/p>\n<h5>Presentazione dell&#8217;intero spettro di servizi<\/h5>\n<p>Inoltre, lo specialista della logistica presenta alla fiera il suo intero spettro di servizi, dalla gestione dei trasporti alla logistica contrattuale. Michael Craiss, amministratore delegato della Craiss Generation Logistik GmbH &amp; Co. KG: &#8220;Grazie al nostro ampio portafoglio, possiamo influenzare positivamente la supply chain delle aziende in vari punti. Sulla base delle esigenze dei nostri clienti, sviluppiamo concetti logistici personalizzati e li implementiamo in modo professionale.&#8221; Oltre ai servizi di logistica di magazzino e trasporto, l&#8217;azienda familiare offre anche vari servizi a valore aggiunto come controlli di qualit\u00e0 in entrata, la gestione di piccoli errori, lavori di verniciatura o imballaggio marittimo.<\/p>\n<p>Foto: \u00a9 SLYNX \/\u00a0<em><strong> Legenda dell&#8217;immagine:<\/strong> SLYNX ha ricevuto il premio economico del Baden-W\u00fcrttemberg &#8220;Leone Nero&#8221; per l&#8217;ottimizzazione dei processi di trasporti speciali ed espressi. Lo hanno ricevuto (da sinistra a destra): il direttore di Craiss Matthias Diehm e Michael Craiss, la responsabile del dipartimento Valerie Boden, il Product Owner Christoph Steller e la responsabile del marketing online Pooja Srinath.<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Craiss Generation Logistik GmbH &amp; Co. KG si presenta per la prima volta alla LogiMAT di quest&#8217;anno, che si svolger\u00e0 dal 25 al 27 aprile<span class=\"excerpt-hellip\"> [\u2026]<\/span><\/p>\n","protected":false},"author":0,"featured_media":8351,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1665,1561],"tags":[],"class_list":["post-60978","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-categories","category-regions"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>CRAISS presenta l&#039;azienda espressa SLYNX a LogiMAT - Loginfo24<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/loginfo24.com\/it\/2023\/03\/19\/craiss-presenta-lazienda-espressa-slynx-a-logimat\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"CRAISS presenta l&#039;azienda espressa SLYNX a LogiMAT - Loginfo24\" \/>\n<meta property=\"og:description\" content=\"La Craiss Generation Logistik GmbH &amp; Co. KG si presenta per la prima volta alla LogiMAT di quest&#8217;anno, che si svolger\u00e0 dal 25 al 27 aprile [\u2026]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/loginfo24.com\/it\/2023\/03\/19\/craiss-presenta-lazienda-espressa-slynx-a-logimat\/\" \/>\n<meta property=\"og:site_name\" content=\"Loginfo24\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/\" \/>\n<meta property=\"article:published_time\" content=\"2023-03-19T10:26:10+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/SLYNX_19.3.23.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1577\" \/>\n\t<meta property=\"og:image:height\" content=\"973\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2023\\\/03\\\/19\\\/craiss-presenta-lazienda-espressa-slynx-a-logimat\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2023\\\/03\\\/19\\\/craiss-presenta-lazienda-espressa-slynx-a-logimat\\\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"CRAISS presenta l&#8217;azienda espressa SLYNX a LogiMAT\",\"datePublished\":\"2023-03-19T10:26:10+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2023\\\/03\\\/19\\\/craiss-presenta-lazienda-espressa-slynx-a-logimat\\\/\"},\"wordCount\":451,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2023\\\/03\\\/19\\\/craiss-presenta-lazienda-espressa-slynx-a-logimat\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/SLYNX_19.3.23.jpg\",\"articleSection\":[\"Categories\",\"Regions\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/it\\\/2023\\\/03\\\/19\\\/craiss-presenta-lazienda-espressa-slynx-a-logimat\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2023\\\/03\\\/19\\\/craiss-presenta-lazienda-espressa-slynx-a-logimat\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2023\\\/03\\\/19\\\/craiss-presenta-lazienda-espressa-slynx-a-logimat\\\/\",\"name\":\"CRAISS presenta l'azienda espressa SLYNX a LogiMAT - Loginfo24\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2023\\\/03\\\/19\\\/craiss-presenta-lazienda-espressa-slynx-a-logimat\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2023\\\/03\\\/19\\\/craiss-presenta-lazienda-espressa-slynx-a-logimat\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/SLYNX_19.3.23.jpg\",\"datePublished\":\"2023-03-19T10:26:10+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2023\\\/03\\\/19\\\/craiss-presenta-lazienda-espressa-slynx-a-logimat\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/it\\\/2023\\\/03\\\/19\\\/craiss-presenta-lazienda-espressa-slynx-a-logimat\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2023\\\/03\\\/19\\\/craiss-presenta-lazienda-espressa-slynx-a-logimat\\\/#primaryimage\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/SLYNX_19.3.23.jpg\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/SLYNX_19.3.23.jpg\",\"width\":1577,\"height\":973},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2023\\\/03\\\/19\\\/craiss-presenta-lazienda-espressa-slynx-a-logimat\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"CRAISS presenta l&#8217;azienda espressa SLYNX a LogiMAT\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/\",\"name\":\"Loginfo24\",\"description\":\"Loginfo24 \u00e8 la piattaforma dedicata alla logistica e alle catene di fornitura con informazioni disponibili 24 ore su 24.\",\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#organization\",\"name\":\"Logismedia Group AG\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"width\":938,\"height\":351,\"caption\":\"Logismedia Group AG\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/people\\\/Loginfo24\\\/100057360583332\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/lofinfo24\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"CRAISS presenta l'azienda espressa SLYNX a LogiMAT - Loginfo24","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/loginfo24.com\/it\/2023\/03\/19\/craiss-presenta-lazienda-espressa-slynx-a-logimat\/","og_locale":"it_IT","og_type":"article","og_title":"CRAISS presenta l'azienda espressa SLYNX a LogiMAT - Loginfo24","og_description":"La Craiss Generation Logistik GmbH &amp; Co. KG si presenta per la prima volta alla LogiMAT di quest&#8217;anno, che si svolger\u00e0 dal 25 al 27 aprile [\u2026]","og_url":"https:\/\/loginfo24.com\/it\/2023\/03\/19\/craiss-presenta-lazienda-espressa-slynx-a-logimat\/","og_site_name":"Loginfo24","article_publisher":"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","article_published_time":"2023-03-19T10:26:10+00:00","og_image":[{"width":1577,"height":973,"url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/SLYNX_19.3.23.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"2 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/loginfo24.com\/it\/2023\/03\/19\/craiss-presenta-lazienda-espressa-slynx-a-logimat\/#article","isPartOf":{"@id":"https:\/\/loginfo24.com\/it\/2023\/03\/19\/craiss-presenta-lazienda-espressa-slynx-a-logimat\/"},"author":{"name":"","@id":""},"headline":"CRAISS presenta l&#8217;azienda espressa SLYNX a LogiMAT","datePublished":"2023-03-19T10:26:10+00:00","mainEntityOfPage":{"@id":"https:\/\/loginfo24.com\/it\/2023\/03\/19\/craiss-presenta-lazienda-espressa-slynx-a-logimat\/"},"wordCount":451,"commentCount":0,"publisher":{"@id":"https:\/\/loginfo24.com\/it\/#organization"},"image":{"@id":"https:\/\/loginfo24.com\/it\/2023\/03\/19\/craiss-presenta-lazienda-espressa-slynx-a-logimat\/#primaryimage"},"thumbnailUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/SLYNX_19.3.23.jpg","articleSection":["Categories","Regions"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/loginfo24.com\/it\/2023\/03\/19\/craiss-presenta-lazienda-espressa-slynx-a-logimat\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/loginfo24.com\/it\/2023\/03\/19\/craiss-presenta-lazienda-espressa-slynx-a-logimat\/","url":"https:\/\/loginfo24.com\/it\/2023\/03\/19\/craiss-presenta-lazienda-espressa-slynx-a-logimat\/","name":"CRAISS presenta l'azienda espressa SLYNX a LogiMAT - Loginfo24","isPartOf":{"@id":"https:\/\/loginfo24.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/loginfo24.com\/it\/2023\/03\/19\/craiss-presenta-lazienda-espressa-slynx-a-logimat\/#primaryimage"},"image":{"@id":"https:\/\/loginfo24.com\/it\/2023\/03\/19\/craiss-presenta-lazienda-espressa-slynx-a-logimat\/#primaryimage"},"thumbnailUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/SLYNX_19.3.23.jpg","datePublished":"2023-03-19T10:26:10+00:00","breadcrumb":{"@id":"https:\/\/loginfo24.com\/it\/2023\/03\/19\/craiss-presenta-lazienda-espressa-slynx-a-logimat\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/loginfo24.com\/it\/2023\/03\/19\/craiss-presenta-lazienda-espressa-slynx-a-logimat\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/loginfo24.com\/it\/2023\/03\/19\/craiss-presenta-lazienda-espressa-slynx-a-logimat\/#primaryimage","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/SLYNX_19.3.23.jpg","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/SLYNX_19.3.23.jpg","width":1577,"height":973},{"@type":"BreadcrumbList","@id":"https:\/\/loginfo24.com\/it\/2023\/03\/19\/craiss-presenta-lazienda-espressa-slynx-a-logimat\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/loginfo24.com\/it\/"},{"@type":"ListItem","position":2,"name":"CRAISS presenta l&#8217;azienda espressa SLYNX a LogiMAT"}]},{"@type":"WebSite","@id":"https:\/\/loginfo24.com\/it\/#website","url":"https:\/\/loginfo24.com\/it\/","name":"Loginfo24","description":"Loginfo24 \u00e8 la piattaforma dedicata alla logistica e alle catene di fornitura con informazioni disponibili 24 ore su 24.","publisher":{"@id":"https:\/\/loginfo24.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/loginfo24.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/loginfo24.com\/it\/#organization","name":"Logismedia Group AG","url":"https:\/\/loginfo24.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/loginfo24.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","width":938,"height":351,"caption":"Logismedia Group AG"},"image":{"@id":"https:\/\/loginfo24.com\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","https:\/\/www.linkedin.com\/company\/lofinfo24\/"]}]}},"_links":{"self":[{"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/posts\/60978","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/comments?post=60978"}],"version-history":[{"count":0,"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/posts\/60978\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/media\/8351"}],"wp:attachment":[{"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/media?parent=60978"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/categories?post=60978"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/tags?post=60978"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}