{"id":60509,"date":"2023-02-09T16:50:49","date_gmt":"2023-02-09T15:50:49","guid":{"rendered":"https:\/\/blog.brand-architecture.at\/2023\/02\/09\/designwerk-amplia-la-dirigenza-e-rafforza-le-vendite\/"},"modified":"2023-02-09T16:50:49","modified_gmt":"2023-02-09T15:50:49","slug":"designwerk-amplia-la-dirigenza-e-rafforza-le-vendite","status":"publish","type":"post","link":"https:\/\/loginfo24.com\/it\/2023\/02\/09\/designwerk-amplia-la-dirigenza-e-rafforza-le-vendite\/","title":{"rendered":"Designwerk amplia la dirigenza e rafforza le vendite"},"content":{"rendered":"<h5><strong>Il specialista svizzero della mobilit\u00e0 elettrica Designwerk Technologies AG amplia il proprio consiglio di amministrazione e rafforza il team vendite e produzione nella sede di Winterthur.<\/strong><\/h5>\n<p>(Winterthur) Thomas R\u00fccker inizia il 13 febbraio nella nuova posizione di Direttore Generale Vendite E-LKW, Ingegneria Vendite, Vendite interne e Post-vendita. In questo ruolo, il nativo svizzero guider\u00e0 l&#8217;espansione degli E-LKW in Europa e allo stesso tempo diriger\u00e0 il settore dei servizi post-vendita.<\/p>\n<p>Thomas R\u00fccker vanta un&#8217;esperienza pluriennale nelle vendite, tra cui presso General Motors e Iveco Svizzera. Negli ultimi anni ha ricoperto il ruolo di Managing Director.<\/p>\n<p>\u00abSiamo lieti di dare il benvenuto a Thomas R\u00fccker come nuovo membro della famiglia Designwerk e nel consiglio di amministrazione. Continueremo la nostra crescita attraverso l&#8217;espansione in altri paesi.\u00bb, afferma Adrian Melliger, CEO e co-proprietario di Designwerk Technologies AG.<\/p>\n<p>Foto: \u00a9 Designwerk<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il specialista svizzero della mobilit\u00e0 elettrica Designwerk Technologies AG amplia il proprio consiglio di amministrazione e rafforza il team vendite e produzione nella sede di Winterthur.<span class=\"excerpt-hellip\"> [\u2026]<\/span><\/p>\n","protected":false},"author":0,"featured_media":8532,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1557,1561],"tags":[],"class_list":["post-60509","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-forwarding-logistics","category-regions"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Designwerk amplia la dirigenza e rafforza le vendite - Loginfo24<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/loginfo24.com\/it\/2023\/02\/09\/designwerk-amplia-la-dirigenza-e-rafforza-le-vendite\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Designwerk amplia la dirigenza e rafforza le vendite - Loginfo24\" \/>\n<meta property=\"og:description\" content=\"Il specialista svizzero della mobilit\u00e0 elettrica Designwerk Technologies AG amplia il proprio consiglio di amministrazione e rafforza il team vendite e produzione nella sede di Winterthur. [\u2026]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/loginfo24.com\/it\/2023\/02\/09\/designwerk-amplia-la-dirigenza-e-rafforza-le-vendite\/\" \/>\n<meta property=\"og:site_name\" content=\"Loginfo24\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/\" \/>\n<meta property=\"article:published_time\" content=\"2023-02-09T15:50:49+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Designwerk_09.02.23.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"861\" \/>\n\t<meta property=\"og:image:height\" content=\"429\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2023\\\/02\\\/09\\\/designwerk-amplia-la-dirigenza-e-rafforza-le-vendite\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2023\\\/02\\\/09\\\/designwerk-amplia-la-dirigenza-e-rafforza-le-vendite\\\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Designwerk amplia la dirigenza e rafforza le vendite\",\"datePublished\":\"2023-02-09T15:50:49+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2023\\\/02\\\/09\\\/designwerk-amplia-la-dirigenza-e-rafforza-le-vendite\\\/\"},\"wordCount\":148,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2023\\\/02\\\/09\\\/designwerk-amplia-la-dirigenza-e-rafforza-le-vendite\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/Designwerk_09.02.23.jpg\",\"articleSection\":[\"Forwarding &amp; Logistics\",\"Regions\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/it\\\/2023\\\/02\\\/09\\\/designwerk-amplia-la-dirigenza-e-rafforza-le-vendite\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2023\\\/02\\\/09\\\/designwerk-amplia-la-dirigenza-e-rafforza-le-vendite\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2023\\\/02\\\/09\\\/designwerk-amplia-la-dirigenza-e-rafforza-le-vendite\\\/\",\"name\":\"Designwerk amplia la dirigenza e rafforza le vendite - Loginfo24\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2023\\\/02\\\/09\\\/designwerk-amplia-la-dirigenza-e-rafforza-le-vendite\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2023\\\/02\\\/09\\\/designwerk-amplia-la-dirigenza-e-rafforza-le-vendite\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/Designwerk_09.02.23.jpg\",\"datePublished\":\"2023-02-09T15:50:49+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2023\\\/02\\\/09\\\/designwerk-amplia-la-dirigenza-e-rafforza-le-vendite\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/it\\\/2023\\\/02\\\/09\\\/designwerk-amplia-la-dirigenza-e-rafforza-le-vendite\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2023\\\/02\\\/09\\\/designwerk-amplia-la-dirigenza-e-rafforza-le-vendite\\\/#primaryimage\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/Designwerk_09.02.23.jpg\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/Designwerk_09.02.23.jpg\",\"width\":861,\"height\":429},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2023\\\/02\\\/09\\\/designwerk-amplia-la-dirigenza-e-rafforza-le-vendite\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Designwerk amplia la dirigenza e rafforza le vendite\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/\",\"name\":\"Loginfo24\",\"description\":\"Loginfo24 \u00e8 la piattaforma dedicata alla logistica e alle catene di fornitura con informazioni disponibili 24 ore su 24.\",\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#organization\",\"name\":\"Logismedia Group AG\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"width\":938,\"height\":351,\"caption\":\"Logismedia Group AG\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/people\\\/Loginfo24\\\/100057360583332\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/lofinfo24\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Designwerk amplia la dirigenza e rafforza le vendite - Loginfo24","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/loginfo24.com\/it\/2023\/02\/09\/designwerk-amplia-la-dirigenza-e-rafforza-le-vendite\/","og_locale":"it_IT","og_type":"article","og_title":"Designwerk amplia la dirigenza e rafforza le vendite - Loginfo24","og_description":"Il specialista svizzero della mobilit\u00e0 elettrica Designwerk Technologies AG amplia il proprio consiglio di amministrazione e rafforza il team vendite e produzione nella sede di Winterthur. [\u2026]","og_url":"https:\/\/loginfo24.com\/it\/2023\/02\/09\/designwerk-amplia-la-dirigenza-e-rafforza-le-vendite\/","og_site_name":"Loginfo24","article_publisher":"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","article_published_time":"2023-02-09T15:50:49+00:00","og_image":[{"width":861,"height":429,"url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Designwerk_09.02.23.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/loginfo24.com\/it\/2023\/02\/09\/designwerk-amplia-la-dirigenza-e-rafforza-le-vendite\/#article","isPartOf":{"@id":"https:\/\/loginfo24.com\/it\/2023\/02\/09\/designwerk-amplia-la-dirigenza-e-rafforza-le-vendite\/"},"author":{"name":"","@id":""},"headline":"Designwerk amplia la dirigenza e rafforza le vendite","datePublished":"2023-02-09T15:50:49+00:00","mainEntityOfPage":{"@id":"https:\/\/loginfo24.com\/it\/2023\/02\/09\/designwerk-amplia-la-dirigenza-e-rafforza-le-vendite\/"},"wordCount":148,"commentCount":0,"publisher":{"@id":"https:\/\/loginfo24.com\/it\/#organization"},"image":{"@id":"https:\/\/loginfo24.com\/it\/2023\/02\/09\/designwerk-amplia-la-dirigenza-e-rafforza-le-vendite\/#primaryimage"},"thumbnailUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Designwerk_09.02.23.jpg","articleSection":["Forwarding &amp; Logistics","Regions"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/loginfo24.com\/it\/2023\/02\/09\/designwerk-amplia-la-dirigenza-e-rafforza-le-vendite\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/loginfo24.com\/it\/2023\/02\/09\/designwerk-amplia-la-dirigenza-e-rafforza-le-vendite\/","url":"https:\/\/loginfo24.com\/it\/2023\/02\/09\/designwerk-amplia-la-dirigenza-e-rafforza-le-vendite\/","name":"Designwerk amplia la dirigenza e rafforza le vendite - Loginfo24","isPartOf":{"@id":"https:\/\/loginfo24.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/loginfo24.com\/it\/2023\/02\/09\/designwerk-amplia-la-dirigenza-e-rafforza-le-vendite\/#primaryimage"},"image":{"@id":"https:\/\/loginfo24.com\/it\/2023\/02\/09\/designwerk-amplia-la-dirigenza-e-rafforza-le-vendite\/#primaryimage"},"thumbnailUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Designwerk_09.02.23.jpg","datePublished":"2023-02-09T15:50:49+00:00","breadcrumb":{"@id":"https:\/\/loginfo24.com\/it\/2023\/02\/09\/designwerk-amplia-la-dirigenza-e-rafforza-le-vendite\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/loginfo24.com\/it\/2023\/02\/09\/designwerk-amplia-la-dirigenza-e-rafforza-le-vendite\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/loginfo24.com\/it\/2023\/02\/09\/designwerk-amplia-la-dirigenza-e-rafforza-le-vendite\/#primaryimage","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Designwerk_09.02.23.jpg","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Designwerk_09.02.23.jpg","width":861,"height":429},{"@type":"BreadcrumbList","@id":"https:\/\/loginfo24.com\/it\/2023\/02\/09\/designwerk-amplia-la-dirigenza-e-rafforza-le-vendite\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/loginfo24.com\/it\/"},{"@type":"ListItem","position":2,"name":"Designwerk amplia la dirigenza e rafforza le vendite"}]},{"@type":"WebSite","@id":"https:\/\/loginfo24.com\/it\/#website","url":"https:\/\/loginfo24.com\/it\/","name":"Loginfo24","description":"Loginfo24 \u00e8 la piattaforma dedicata alla logistica e alle catene di fornitura con informazioni disponibili 24 ore su 24.","publisher":{"@id":"https:\/\/loginfo24.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/loginfo24.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/loginfo24.com\/it\/#organization","name":"Logismedia Group AG","url":"https:\/\/loginfo24.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/loginfo24.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","width":938,"height":351,"caption":"Logismedia Group AG"},"image":{"@id":"https:\/\/loginfo24.com\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","https:\/\/www.linkedin.com\/company\/lofinfo24\/"]}]}},"_links":{"self":[{"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/posts\/60509","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/comments?post=60509"}],"version-history":[{"count":0,"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/posts\/60509\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/media\/8532"}],"wp:attachment":[{"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/media?parent=60509"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/categories?post=60509"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/tags?post=60509"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}