{"id":58282,"date":"2022-09-06T15:37:25","date_gmt":"2022-09-06T13:37:25","guid":{"rendered":"https:\/\/blog.brand-architecture.at\/2022\/09\/06\/rhenus-home-e-special-delivery-con-una-nuova-sede-a-hilden\/"},"modified":"2022-09-06T15:37:25","modified_gmt":"2022-09-06T13:37:25","slug":"rhenus-home-e-special-delivery-con-una-nuova-sede-a-hilden","status":"publish","type":"post","link":"https:\/\/loginfo24.com\/it\/2022\/09\/06\/rhenus-home-e-special-delivery-con-una-nuova-sede-a-hilden\/","title":{"rendered":"Rhenus Home e Special Delivery con una nuova sede a Hilden"},"content":{"rendered":"<h5><strong>La filiale di Rhenus Home Delivery a D\u00fcsseldorf si \u00e8 trasferita a Hilden nell&#8217;agosto 2022. In totale, la superficie utile della nuova sede \u00e8 di circa 15.000 metri quadrati. Il nuovo edificio \u00e8 stato progettato e costruito secondo gli standard pi\u00f9 moderni. Rhenus Home Delivery pone particolare attenzione al tema della sostenibilit\u00e0.<\/strong><\/h5>\n<p>(Holzwickede\/Hilden) La nuova filiale delle divisioni Rhenus a Hilden ha ricevuto la certificazione Gold della Deutsche Gesellschaft f\u00fcr nachhaltiges Bauen (DGNB). La sede \u00e8 alimentata da un impianto fotovoltaico con una potenza di 750 kilovolt-ampere (kVA). All&#8217;inizio sono disponibili dieci punti di ricarica per veicoli elettrici e veicoli commerciali elettrici. Grazie a un concetto di tubazioni vuote e a un trasformatore aggiuntivo, le capacit\u00e0 di ricarica possono essere ulteriormente ampliate in futuro. Gli edifici sono riscaldati e raffreddati anche tramite pompe di calore. Una facciata verde sul lato est e ampie terrazze con aree verdi per i dipendenti completano l&#8217;immagine di un moderno e sostenibile nuovo edificio.<\/p>\n<h5><strong>Il complesso si chiama &#8220;Hildener Tor&#8221;<\/strong><\/h5>\n<p>La filiale di Hilden, che \u00e8 stata chiamata &#8220;Hildener Tor&#8221; a causa della sua posizione alle porte di Hilden, comprende oltre 12.000 metri quadrati di superficie di magazzino e di transito, che incorniciano tre complessi per uffici di circa 3.000 metri quadrati in totale. Nel complesso amministrativo, anch&#8217;esso all&#8217;avanguardia, si insedieranno la direzione e l&#8217;amministrazione di Rhenus Special Delivery. I dipendenti del magazzino beneficiano in particolare delle aree di cross-docking pi\u00f9 efficienti con aree opposte per l&#8217;ingresso e l&#8217;uscita delle merci. Particolarmente vantaggiosa \u00e8 la quantit\u00e0 di 20 porte di carico, significativamente superiore rispetto alla precedente sede di D\u00fcsseldorf. &#8220;Rispetto agli immobili standard, beneficiamo delle numerose porte di carico, il che rappresenta un assoluto vantaggio data l&#8217;elevata rotazione delle merci&#8221;, spiega Ronny Sassen, CEO di Rhenus Home Delivery.<\/p>\n<h5><strong>Buona connessione ai trasporti<\/strong><\/h5>\n<p>Da Hilden vengono forniti ampie parti della Renania Settentrionale-Vestfalia, la Renania e parti della Ruhr e del M\u00fcnsterland. A tal fine, il collegamento diretto della sede con le autostrade A3 e A46 offre una base ideale. I servizi offerti dalle filiali includono consegna con due persone, incluso il servizio di montaggio, logistica di magazzino e transito, nonch\u00e9 preparazione dei resi e piccole stoccaggi di commissione. Le merci da trattare riguardano in particolare prodotti ingombranti come grandi elettrodomestici, mobili e biciclette elettriche.<\/p>\n<p>Foto: \u00a9 Rhenus<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La filiale di Rhenus Home Delivery a D\u00fcsseldorf si \u00e8 trasferita a Hilden nell&#8217;agosto 2022. In totale, la superficie utile della nuova sede \u00e8 di circa<span class=\"excerpt-hellip\"> [\u2026]<\/span><\/p>\n","protected":false},"author":0,"featured_media":9459,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1557,1560,1561],"tags":[],"class_list":["post-58282","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-forwarding-logistics","category-intralogistics","category-regions"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Rhenus Home e Special Delivery con una nuova sede a Hilden - Loginfo24<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/loginfo24.com\/it\/2022\/09\/06\/rhenus-home-e-special-delivery-con-una-nuova-sede-a-hilden\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Rhenus Home e Special Delivery con una nuova sede a Hilden - Loginfo24\" \/>\n<meta property=\"og:description\" content=\"La filiale di Rhenus Home Delivery a D\u00fcsseldorf si \u00e8 trasferita a Hilden nell&#8217;agosto 2022. In totale, la superficie utile della nuova sede \u00e8 di circa [\u2026]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/loginfo24.com\/it\/2022\/09\/06\/rhenus-home-e-special-delivery-con-una-nuova-sede-a-hilden\/\" \/>\n<meta property=\"og:site_name\" content=\"Loginfo24\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/\" \/>\n<meta property=\"article:published_time\" content=\"2022-09-06T13:37:25+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Rhenus_6.9.22.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1300\" \/>\n\t<meta property=\"og:image:height\" content=\"777\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2022\\\/09\\\/06\\\/rhenus-home-e-special-delivery-con-una-nuova-sede-a-hilden\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2022\\\/09\\\/06\\\/rhenus-home-e-special-delivery-con-una-nuova-sede-a-hilden\\\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Rhenus Home e Special Delivery con una nuova sede a Hilden\",\"datePublished\":\"2022-09-06T13:37:25+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2022\\\/09\\\/06\\\/rhenus-home-e-special-delivery-con-una-nuova-sede-a-hilden\\\/\"},\"wordCount\":393,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2022\\\/09\\\/06\\\/rhenus-home-e-special-delivery-con-una-nuova-sede-a-hilden\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/Rhenus_6.9.22.jpg\",\"articleSection\":[\"Forwarding &amp; Logistics\",\"Intralogistics\",\"Regions\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/it\\\/2022\\\/09\\\/06\\\/rhenus-home-e-special-delivery-con-una-nuova-sede-a-hilden\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2022\\\/09\\\/06\\\/rhenus-home-e-special-delivery-con-una-nuova-sede-a-hilden\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2022\\\/09\\\/06\\\/rhenus-home-e-special-delivery-con-una-nuova-sede-a-hilden\\\/\",\"name\":\"Rhenus Home e Special Delivery con una nuova sede a Hilden - Loginfo24\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2022\\\/09\\\/06\\\/rhenus-home-e-special-delivery-con-una-nuova-sede-a-hilden\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2022\\\/09\\\/06\\\/rhenus-home-e-special-delivery-con-una-nuova-sede-a-hilden\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/Rhenus_6.9.22.jpg\",\"datePublished\":\"2022-09-06T13:37:25+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2022\\\/09\\\/06\\\/rhenus-home-e-special-delivery-con-una-nuova-sede-a-hilden\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/it\\\/2022\\\/09\\\/06\\\/rhenus-home-e-special-delivery-con-una-nuova-sede-a-hilden\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2022\\\/09\\\/06\\\/rhenus-home-e-special-delivery-con-una-nuova-sede-a-hilden\\\/#primaryimage\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/Rhenus_6.9.22.jpg\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/Rhenus_6.9.22.jpg\",\"width\":1300,\"height\":777},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2022\\\/09\\\/06\\\/rhenus-home-e-special-delivery-con-una-nuova-sede-a-hilden\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Rhenus Home e Special Delivery con una nuova sede a Hilden\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/\",\"name\":\"Loginfo24\",\"description\":\"Loginfo24 \u00e8 la piattaforma dedicata alla logistica e alle catene di fornitura con informazioni disponibili 24 ore su 24.\",\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#organization\",\"name\":\"Logismedia Group AG\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"width\":938,\"height\":351,\"caption\":\"Logismedia Group AG\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/people\\\/Loginfo24\\\/100057360583332\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/lofinfo24\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Rhenus Home e Special Delivery con una nuova sede a Hilden - Loginfo24","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/loginfo24.com\/it\/2022\/09\/06\/rhenus-home-e-special-delivery-con-una-nuova-sede-a-hilden\/","og_locale":"it_IT","og_type":"article","og_title":"Rhenus Home e Special Delivery con una nuova sede a Hilden - Loginfo24","og_description":"La filiale di Rhenus Home Delivery a D\u00fcsseldorf si \u00e8 trasferita a Hilden nell&#8217;agosto 2022. In totale, la superficie utile della nuova sede \u00e8 di circa [\u2026]","og_url":"https:\/\/loginfo24.com\/it\/2022\/09\/06\/rhenus-home-e-special-delivery-con-una-nuova-sede-a-hilden\/","og_site_name":"Loginfo24","article_publisher":"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","article_published_time":"2022-09-06T13:37:25+00:00","og_image":[{"width":1300,"height":777,"url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Rhenus_6.9.22.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"2 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/loginfo24.com\/it\/2022\/09\/06\/rhenus-home-e-special-delivery-con-una-nuova-sede-a-hilden\/#article","isPartOf":{"@id":"https:\/\/loginfo24.com\/it\/2022\/09\/06\/rhenus-home-e-special-delivery-con-una-nuova-sede-a-hilden\/"},"author":{"name":"","@id":""},"headline":"Rhenus Home e Special Delivery con una nuova sede a Hilden","datePublished":"2022-09-06T13:37:25+00:00","mainEntityOfPage":{"@id":"https:\/\/loginfo24.com\/it\/2022\/09\/06\/rhenus-home-e-special-delivery-con-una-nuova-sede-a-hilden\/"},"wordCount":393,"commentCount":0,"publisher":{"@id":"https:\/\/loginfo24.com\/it\/#organization"},"image":{"@id":"https:\/\/loginfo24.com\/it\/2022\/09\/06\/rhenus-home-e-special-delivery-con-una-nuova-sede-a-hilden\/#primaryimage"},"thumbnailUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Rhenus_6.9.22.jpg","articleSection":["Forwarding &amp; Logistics","Intralogistics","Regions"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/loginfo24.com\/it\/2022\/09\/06\/rhenus-home-e-special-delivery-con-una-nuova-sede-a-hilden\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/loginfo24.com\/it\/2022\/09\/06\/rhenus-home-e-special-delivery-con-una-nuova-sede-a-hilden\/","url":"https:\/\/loginfo24.com\/it\/2022\/09\/06\/rhenus-home-e-special-delivery-con-una-nuova-sede-a-hilden\/","name":"Rhenus Home e Special Delivery con una nuova sede a Hilden - Loginfo24","isPartOf":{"@id":"https:\/\/loginfo24.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/loginfo24.com\/it\/2022\/09\/06\/rhenus-home-e-special-delivery-con-una-nuova-sede-a-hilden\/#primaryimage"},"image":{"@id":"https:\/\/loginfo24.com\/it\/2022\/09\/06\/rhenus-home-e-special-delivery-con-una-nuova-sede-a-hilden\/#primaryimage"},"thumbnailUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Rhenus_6.9.22.jpg","datePublished":"2022-09-06T13:37:25+00:00","breadcrumb":{"@id":"https:\/\/loginfo24.com\/it\/2022\/09\/06\/rhenus-home-e-special-delivery-con-una-nuova-sede-a-hilden\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/loginfo24.com\/it\/2022\/09\/06\/rhenus-home-e-special-delivery-con-una-nuova-sede-a-hilden\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/loginfo24.com\/it\/2022\/09\/06\/rhenus-home-e-special-delivery-con-una-nuova-sede-a-hilden\/#primaryimage","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Rhenus_6.9.22.jpg","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Rhenus_6.9.22.jpg","width":1300,"height":777},{"@type":"BreadcrumbList","@id":"https:\/\/loginfo24.com\/it\/2022\/09\/06\/rhenus-home-e-special-delivery-con-una-nuova-sede-a-hilden\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/loginfo24.com\/it\/"},{"@type":"ListItem","position":2,"name":"Rhenus Home e Special Delivery con una nuova sede a Hilden"}]},{"@type":"WebSite","@id":"https:\/\/loginfo24.com\/it\/#website","url":"https:\/\/loginfo24.com\/it\/","name":"Loginfo24","description":"Loginfo24 \u00e8 la piattaforma dedicata alla logistica e alle catene di fornitura con informazioni disponibili 24 ore su 24.","publisher":{"@id":"https:\/\/loginfo24.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/loginfo24.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/loginfo24.com\/it\/#organization","name":"Logismedia Group AG","url":"https:\/\/loginfo24.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/loginfo24.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","width":938,"height":351,"caption":"Logismedia Group AG"},"image":{"@id":"https:\/\/loginfo24.com\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","https:\/\/www.linkedin.com\/company\/lofinfo24\/"]}]}},"_links":{"self":[{"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/posts\/58282","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/comments?post=58282"}],"version-history":[{"count":0,"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/posts\/58282\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/media\/9459"}],"wp:attachment":[{"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/media?parent=58282"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/categories?post=58282"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/tags?post=58282"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}