{"id":58060,"date":"2022-08-28T12:40:53","date_gmt":"2022-08-28T10:40:53","guid":{"rendered":"https:\/\/blog.brand-architecture.at\/2022\/08\/28\/onorificenze-e-promozioni-presso-acito-logistics-gmbh\/"},"modified":"2022-08-28T12:40:53","modified_gmt":"2022-08-28T10:40:53","slug":"onorificenze-e-promozioni-presso-acito-logistics-gmbh","status":"publish","type":"post","link":"https:\/\/loginfo24.com\/it\/2022\/08\/28\/onorificenze-e-promozioni-presso-acito-logistics-gmbh\/","title":{"rendered":"Onorificenze e promozioni presso Acito Logistics GmbH"},"content":{"rendered":"<h5><strong>Dopo due anni di interruzione, Acito Logistics GmbH ha finalmente potuto svolgere di nuovo la tradizionale festa estiva per i dipendenti. Cosa c&#8217;era di meglio che organizzare questo evento come sponsor e partner logistico ufficiale della LGS 2022 Fiera dei Giardini a Neuenburg, presso il meraviglioso sito della fiera? Nell&#8217;ambito della festa estiva, sono stati anche premiati dipendenti meritevoli e di lunga data.<\/strong><\/h5>\n<p>(Weil am Rhein) Nella frenesia dei tempi moderni, i dipendenti di lunga data non sono una cosa scontata, ma qualcosa di speciale. Pertanto, un decennio di fedelt\u00e0 all&#8217;azienda presso Acito Logistics GmbH \u00e8 un&#8217;importante e gradita occasione, che la direzione ha potuto onorare per ben dieci dipendenti. A causa del COVID, l&#8217;azienda ha dovuto rinunciare negli ultimi due anni a una celebrazione dei festeggiati durante una festa per i dipendenti. In occasione della festa annuale presso il sito della Fiera dei Giardini di Neuenburg, la direzione ha colto l&#8217;opportunit\u00e0 per ringraziare le colleghe e i colleghi per la loro fedelt\u00e0 all&#8217;azienda e il loro instancabile impegno. Questi sono Rudolf Schmidt, Walter Schneider, Stefan Kurz, Oliver Schleu\u00df, Anita Sautter, Ralf Albrecht, Sarah Saller, Marcos Azevedo, Oliver Sch\u00f6llhorn, Patric Galley.<\/p>\n<p>Con un team in continua crescita, attualmente 85 dipendenti nei due siti di Weil am Rhein ed Efringen-Kirchen, e con requisiti sempre pi\u00f9 elevati per l&#8217;azienda e l&#8217;ambiente imprenditoriale, \u00e8 necessario delegare compiti a mani responsabili. Pertanto, la promozione di Michael Wagner a procuratore \u00e8 stata una logica conseguenza delle sue azioni e del suo operato per Acito Logistics. Michael Wagner \u00e8 in Acito Logistics dal 2014 e, grazie alla sua lunga esperienza professionale, ha gi\u00e0 lavorato in diversi reparti dell&#8217;azienda. Con la nomina a procuratore, prosegue il suo percorso professionale. \u00c8 responsabile dell&#8217;area contabilit\u00e0 \/ finanze e, come responsabile della formazione, segue attualmente 14 apprendisti nell&#8217;azienda. La promozione dei giovani talenti \u00e8 per lui una questione di cuore, infatti \u00e8 gi\u00e0 da anni insegnante a tempo parziale presso la scuola commerciale di L\u00f6rrach e da pi\u00f9 di un decennio membro della commissione d&#8217;esame della IHK Hochrhein-Bodensee. Come coautore della raccolta di testi sul diritto della spedizione, del trasporto e della logistica, \u00e8 stato anche attivo nella formazione interaziendale.<\/p>\n<p>Il 22.07.2022, Alexander Polnau ha concluso la sua formazione come commerciante per servizi di spedizione e logistica con risultati eccellenti davanti alla Camera di Commercio e Industria di Schopfheim. Per la sua straordinaria prestazione \u00e8 stato premiato anche dall&#8217;Associazione Speditori VSL Baden-W\u00fcrttemberg. Dopo il suo successo formativo, Alexander Polnau punta a conseguire il diploma di scuola superiore professionale a tempo pieno. L&#8217;intero team di Acito lo congratula di cuore e gli augura tanto successo nella sua nuova sfida scolastica.<\/p>\n<p>Il 1\u00b0 settembre 2022, cinque ulteriori apprendisti inizieranno la loro formazione presso Acito.<\/p>\n<p>Per l&#8217;anno formativo 2023, l&#8217;azienda di logistica offre nuovamente posti di apprendistato nei settori delle professioni specializzate per la logistica di magazzino, gestione d&#8217;ufficio e commercianti per servizi di spedizione e logistica. Maggiori informazioni e opportunit\u00e0 di candidatura possono essere trovate sul sito web dell&#8217;azienda: <a href=\"https:\/\/www.acito-logistics.eu\/jobs\/ausbildung\">www.acito-logistics.eu\/jobs\/ausbildung<\/a><\/p>\n<p>Acito Logistics sar\u00e0 nuovamente presente alla fiera di formazione di Weil. Questa si svolger\u00e0 sabato 24.09.2022. Qui gli interessati possono informarsi personalmente sui singoli mestieri di apprendistato.<\/p>\n<p>Foto: \u00a9 Acito Logistics GmbH \/ <strong><em>Didascalia dell&#8217;immagine:<\/em><\/strong><em> Michael Wagner<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dopo due anni di interruzione, Acito Logistics GmbH ha finalmente potuto svolgere di nuovo la tradizionale festa estiva per i dipendenti. Cosa c&#8217;era di meglio che<span class=\"excerpt-hellip\"> [\u2026]<\/span><\/p>\n","protected":false},"author":0,"featured_media":9549,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1557,1561],"tags":[],"class_list":["post-58060","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-forwarding-logistics","category-regions"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Onorificenze e promozioni presso Acito Logistics GmbH - Loginfo24<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/loginfo24.com\/it\/2022\/08\/28\/onorificenze-e-promozioni-presso-acito-logistics-gmbh\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Onorificenze e promozioni presso Acito Logistics GmbH - Loginfo24\" \/>\n<meta property=\"og:description\" content=\"Dopo due anni di interruzione, Acito Logistics GmbH ha finalmente potuto svolgere di nuovo la tradizionale festa estiva per i dipendenti. Cosa c&#8217;era di meglio che [\u2026]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/loginfo24.com\/it\/2022\/08\/28\/onorificenze-e-promozioni-presso-acito-logistics-gmbh\/\" \/>\n<meta property=\"og:site_name\" content=\"Loginfo24\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/\" \/>\n<meta property=\"article:published_time\" content=\"2022-08-28T10:40:53+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Acito_28.08.2022.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1082\" \/>\n\t<meta property=\"og:image:height\" content=\"671\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2022\\\/08\\\/28\\\/onorificenze-e-promozioni-presso-acito-logistics-gmbh\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2022\\\/08\\\/28\\\/onorificenze-e-promozioni-presso-acito-logistics-gmbh\\\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Onorificenze e promozioni presso Acito Logistics GmbH\",\"datePublished\":\"2022-08-28T10:40:53+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2022\\\/08\\\/28\\\/onorificenze-e-promozioni-presso-acito-logistics-gmbh\\\/\"},\"wordCount\":548,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2022\\\/08\\\/28\\\/onorificenze-e-promozioni-presso-acito-logistics-gmbh\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/Acito_28.08.2022.jpg\",\"articleSection\":[\"Forwarding &amp; Logistics\",\"Regions\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/it\\\/2022\\\/08\\\/28\\\/onorificenze-e-promozioni-presso-acito-logistics-gmbh\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2022\\\/08\\\/28\\\/onorificenze-e-promozioni-presso-acito-logistics-gmbh\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2022\\\/08\\\/28\\\/onorificenze-e-promozioni-presso-acito-logistics-gmbh\\\/\",\"name\":\"Onorificenze e promozioni presso Acito Logistics GmbH - Loginfo24\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2022\\\/08\\\/28\\\/onorificenze-e-promozioni-presso-acito-logistics-gmbh\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2022\\\/08\\\/28\\\/onorificenze-e-promozioni-presso-acito-logistics-gmbh\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/Acito_28.08.2022.jpg\",\"datePublished\":\"2022-08-28T10:40:53+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2022\\\/08\\\/28\\\/onorificenze-e-promozioni-presso-acito-logistics-gmbh\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/it\\\/2022\\\/08\\\/28\\\/onorificenze-e-promozioni-presso-acito-logistics-gmbh\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2022\\\/08\\\/28\\\/onorificenze-e-promozioni-presso-acito-logistics-gmbh\\\/#primaryimage\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/Acito_28.08.2022.jpg\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/Acito_28.08.2022.jpg\",\"width\":1082,\"height\":671},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2022\\\/08\\\/28\\\/onorificenze-e-promozioni-presso-acito-logistics-gmbh\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Onorificenze e promozioni presso Acito Logistics GmbH\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/\",\"name\":\"Loginfo24\",\"description\":\"Loginfo24 \u00e8 la piattaforma dedicata alla logistica e alle catene di fornitura con informazioni disponibili 24 ore su 24.\",\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#organization\",\"name\":\"Logismedia Group AG\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"width\":938,\"height\":351,\"caption\":\"Logismedia Group AG\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/people\\\/Loginfo24\\\/100057360583332\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/lofinfo24\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Onorificenze e promozioni presso Acito Logistics GmbH - Loginfo24","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/loginfo24.com\/it\/2022\/08\/28\/onorificenze-e-promozioni-presso-acito-logistics-gmbh\/","og_locale":"it_IT","og_type":"article","og_title":"Onorificenze e promozioni presso Acito Logistics GmbH - Loginfo24","og_description":"Dopo due anni di interruzione, Acito Logistics GmbH ha finalmente potuto svolgere di nuovo la tradizionale festa estiva per i dipendenti. Cosa c&#8217;era di meglio che [\u2026]","og_url":"https:\/\/loginfo24.com\/it\/2022\/08\/28\/onorificenze-e-promozioni-presso-acito-logistics-gmbh\/","og_site_name":"Loginfo24","article_publisher":"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","article_published_time":"2022-08-28T10:40:53+00:00","og_image":[{"width":1082,"height":671,"url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Acito_28.08.2022.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"3 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/loginfo24.com\/it\/2022\/08\/28\/onorificenze-e-promozioni-presso-acito-logistics-gmbh\/#article","isPartOf":{"@id":"https:\/\/loginfo24.com\/it\/2022\/08\/28\/onorificenze-e-promozioni-presso-acito-logistics-gmbh\/"},"author":{"name":"","@id":""},"headline":"Onorificenze e promozioni presso Acito Logistics GmbH","datePublished":"2022-08-28T10:40:53+00:00","mainEntityOfPage":{"@id":"https:\/\/loginfo24.com\/it\/2022\/08\/28\/onorificenze-e-promozioni-presso-acito-logistics-gmbh\/"},"wordCount":548,"commentCount":0,"publisher":{"@id":"https:\/\/loginfo24.com\/it\/#organization"},"image":{"@id":"https:\/\/loginfo24.com\/it\/2022\/08\/28\/onorificenze-e-promozioni-presso-acito-logistics-gmbh\/#primaryimage"},"thumbnailUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Acito_28.08.2022.jpg","articleSection":["Forwarding &amp; Logistics","Regions"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/loginfo24.com\/it\/2022\/08\/28\/onorificenze-e-promozioni-presso-acito-logistics-gmbh\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/loginfo24.com\/it\/2022\/08\/28\/onorificenze-e-promozioni-presso-acito-logistics-gmbh\/","url":"https:\/\/loginfo24.com\/it\/2022\/08\/28\/onorificenze-e-promozioni-presso-acito-logistics-gmbh\/","name":"Onorificenze e promozioni presso Acito Logistics GmbH - Loginfo24","isPartOf":{"@id":"https:\/\/loginfo24.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/loginfo24.com\/it\/2022\/08\/28\/onorificenze-e-promozioni-presso-acito-logistics-gmbh\/#primaryimage"},"image":{"@id":"https:\/\/loginfo24.com\/it\/2022\/08\/28\/onorificenze-e-promozioni-presso-acito-logistics-gmbh\/#primaryimage"},"thumbnailUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Acito_28.08.2022.jpg","datePublished":"2022-08-28T10:40:53+00:00","breadcrumb":{"@id":"https:\/\/loginfo24.com\/it\/2022\/08\/28\/onorificenze-e-promozioni-presso-acito-logistics-gmbh\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/loginfo24.com\/it\/2022\/08\/28\/onorificenze-e-promozioni-presso-acito-logistics-gmbh\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/loginfo24.com\/it\/2022\/08\/28\/onorificenze-e-promozioni-presso-acito-logistics-gmbh\/#primaryimage","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Acito_28.08.2022.jpg","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Acito_28.08.2022.jpg","width":1082,"height":671},{"@type":"BreadcrumbList","@id":"https:\/\/loginfo24.com\/it\/2022\/08\/28\/onorificenze-e-promozioni-presso-acito-logistics-gmbh\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/loginfo24.com\/it\/"},{"@type":"ListItem","position":2,"name":"Onorificenze e promozioni presso Acito Logistics GmbH"}]},{"@type":"WebSite","@id":"https:\/\/loginfo24.com\/it\/#website","url":"https:\/\/loginfo24.com\/it\/","name":"Loginfo24","description":"Loginfo24 \u00e8 la piattaforma dedicata alla logistica e alle catene di fornitura con informazioni disponibili 24 ore su 24.","publisher":{"@id":"https:\/\/loginfo24.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/loginfo24.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/loginfo24.com\/it\/#organization","name":"Logismedia Group AG","url":"https:\/\/loginfo24.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/loginfo24.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","width":938,"height":351,"caption":"Logismedia Group AG"},"image":{"@id":"https:\/\/loginfo24.com\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","https:\/\/www.linkedin.com\/company\/lofinfo24\/"]}]}},"_links":{"self":[{"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/posts\/58060","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/comments?post=58060"}],"version-history":[{"count":0,"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/posts\/58060\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/media\/9549"}],"wp:attachment":[{"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/media?parent=58060"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/categories?post=58060"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/tags?post=58060"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}