{"id":58024,"date":"2022-08-24T16:31:24","date_gmt":"2022-08-24T14:31:24","guid":{"rendered":"https:\/\/blog.brand-architecture.at\/2022\/08\/24\/fachpack-con-nuovi-impulsi-per-lindustria-del-packaging\/"},"modified":"2022-08-24T16:31:24","modified_gmt":"2022-08-24T14:31:24","slug":"fachpack-con-nuovi-impulsi-per-lindustria-del-packaging","status":"publish","type":"post","link":"https:\/\/loginfo24.com\/it\/2022\/08\/24\/fachpack-con-nuovi-impulsi-per-lindustria-del-packaging\/","title":{"rendered":"FACHPACK con nuovi impulsi per l&#8217;industria del packaging"},"content":{"rendered":"<h5><strong>Dal 27 al 29 settembre 2022 \u00e8 di nuovo il momento. Allora apre la FACHPACK, fiera specializzata per imballaggio, tecnologia e processi, presso il centro fieristico di Norimberga. Sotto il tema guida &#8220;Transizione nel Packaging&#8221;, oltre 1100 espositori presentano nei nove padiglioni fieristici i loro prodotti e soluzioni innovativi per l&#8217;imballaggio del futuro. La FACHPACK si propone come guida e fonte di ispirazione per il settore. Come tale, oltre alla parte espositiva, organizza nuovamente un ampio programma di conferenze nei forum PACKBOX \/(Padiglione 9), TECHBOX (Padiglione 3C) e nel forum degli espositori INNOVATIONBOX (Padiglione 5). Temi e relatori interessanti sono in programma.<\/strong><\/h5>\n<p>(Norimberga) I forum della FACHPACK sono sempre un&#8217;attrazione per il pubblico: circa 9.500 partecipanti hanno preso parte a PACKBOX e TECHBOX lo scorso anno. La particolarit\u00e0: rinomati partner del settore del packaging contribuiscono al programma e invitano gli interessati non solo ad ascoltare, ma anche a partecipare attivamente alla discussione. Temi attuali del settore come sostenibilit\u00e0, digitalizzazione, carenza di personale qualificato, colli di bottiglia nella catena di approvvigionamento, crisi energetica, gestione della catena di approvvigionamento, prezzi delle materie prime, e molto altro vengono affrontati.<\/p>\n<h5><strong>Un tema al giorno<\/strong><\/h5>\n<p>I forum PACKBOX e TECHBOX sono suddivisi per temi giornalieri. Nella PACKBOX, dove si parla di imballaggio, stampa e finitura degli imballaggi, si discuter\u00e0 di &#8220;Esperienza di mercato &amp; Aspettativa di mercato&#8221; (27.9.), &#8220;Design sostenibile &amp; Materiale&#8221; (28.9.) e &#8220;Packaging digitale &amp; intelligente&#8221; (29.9.). Partecipano: bayern design, Berndt + Partner, Deutsches Verpackungsinstitut, DFTA Flexodruck Fachverband, epda European Brand &amp; Packaging Design Association, Fachverband Faltschachtel-Industrie e.V.\/ ProCarton, FuturePackLab\/ popular packaging, Horv\u00e1th &amp; Partners, Industrievereinigung Kunststoffverpackungen, K&amp;A BrandResearch, Packaging Europe LTD, Packaging Journal, PAHNKE, taste, WPO World Packaging Organisation, Zukunftsinstitut.<\/p>\n<p>Nella TECHBOX, dove si concentra sulla tecnologia di imballaggio e logistica, sono in programma &#8220;Innovazione &amp; Strategia climatica&#8221; (27.9.), &#8220;NEW WORK I modelli di lavoro futuri nel packaging \/ The future working models in packaging&#8221; (28.9.) e &#8220;Efficienza &amp; Digitalizzazione&#8221; (29.9.). Questo programma \u00e8 curato da: AIM-D e.V., BayStartUp, BGH Consulting, Bund Deutscher Verpackungsingenieure (bdvi), Deutsche Bank AG | Research \/ Economics, Fachagentur f\u00fcr Nachwachsende Rohstoffe (FNR), FH Campus Wien, Fraunhofer Institut f\u00fcr Materialfluss und Logistik (IML), Fraunhofer Institut f\u00fcr Verfahrenstechnik und Verpackung (IVV), Institut f\u00fcr Generationenforschung, Logistik heute\/ Huss Verlag, neue verpackung\/ H\u00fcthig Verlag, Packaging Journal, Packaging Valley Germany, TILISCO, TU Dresden, Verein zur F\u00f6rderung innovativer Verfahren in der Logistik (VVL) e.V.<\/p>\n<p>Oltre ai forum PACKBOX e TECHBOX, c&#8217;\u00e8 il forum degli espositori, l&#8217;INNOVATIONBOX nel Padiglione 5. Qui gli espositori registrati possono presentare le loro innovazioni e i punti salienti dei prodotti ai visitatori professionali in presentazioni di 30 minuti.<\/p>\n<p>Il programma completo della FACHPACK 2022 \u00e8 disponibile su: <a href=\"https:\/\/www.fachpack.de\/programm\" target=\"_blank\" rel=\"noopener\"><strong>www.fachpack.de\/programm<\/strong><\/a><\/p>\n<p>Alcuni interventi selezionati di seguito:<\/p>\n<h5><strong>Pensieri audaci sulla Supply Chain<\/strong><\/h5>\n<p>Si inizia il primo giorno della fiera alle 10:00 nel Breakfast Club della PACKBOX con una keynote di Gunhard Keil del rinomato Zukunftsinstitut. L&#8217;imprenditore viennese e consulente di lunga data per l&#8217;industria del packaging svela &#8220;Pensieri audaci sul futuro della Supply Chain&#8221; nella sua presentazione &#8220;Structure follows strategy o Customer follows packaging?&#8221;. Vede, ad esempio, i centri urbani come New York, Pechino o Francoforte come i centri delle materie prime del futuro. Anche nel tema della logistica e del trasporto merci, molte cose cambieranno in futuro, simile a quanto accade per gli imballaggi di trasporto.<\/p>\n<h5><strong>New Work: Bella nuova realt\u00e0 lavorativa<\/strong><\/h5>\n<p>Il secondo giorno della fiera (28.9.2022) \u00e8 dedicato nella TECHBOX al tema &#8220;New Work&#8221;. Nella crescente competizione per i migliori talenti, il cosiddetto &#8220;war for talents&#8221;, le aziende devono offrire modelli di lavoro attraenti. Sette slot di conferenze si dedicano dalle 10:00 alle 17:00 al tema da diverse prospettive.<\/p>\n<p>Ad esempio, il futurista Hartwin Maas dell&#8217;Istituto per la ricerca sulle generazioni confronta i baby boomer con la giovent\u00f9 digitale e spiega quali competenze e capacit\u00e0 tecnologiche sono richieste nel nuovo mondo del lavoro (12:00-13:00). Richard Clemens, amministratore delegato del VDMA Fachverband Nahrungsmittelmaschinen und Verpackungsmaschinen, si interroga: &#8220;Tra digitalizzazione e sostenibilit\u00e0: campo di tensione o sfida per i giovani talenti?&#8221; (16:00-17:00). Il tavolo rotondo di BGH-Consulting si concentra sui pro e contro dei nuovi rispetto ai vecchi metodi di reclutamento e fidelizzazione del personale e sul ruolo particolare del management interinale (14:00-15:00). Esempi di successo del reclutamento di personale vengono presentati dal Packaging Valley Germany e.V. con il titolo &#8220;NEW WORK mittendrin! La valle delle opportunit\u00e0 di carriera per i top talent \u2013 Come le aziende del Packaging Valley stanno gi\u00e0 oggi reclutando i professionisti di domani!&#8221; (10:00-11:00).<\/p>\n<h5><strong>Un cambiamento epocale nel Packaging<\/strong><\/h5>\n<p>Senza piet\u00e0 e senza compromessi \u00e8 la presentazione &#8220;Il cambiamento epocale e le sue sfide per il globo e il packaging&#8221; di Eric Heymann della Deutsche Bank nell&#8217;ultimo giorno della fiera, il 29 settembre, nella TECHBOX (13:00-13:30). Il direttore e senior economist offre uno sguardo macroeconomico nella sfera di cristallo e si interroga su cosa significano le nuove realt\u00e0 riguardo energia, colli di bottiglia e carenza di personale per gli sviluppi nei prossimi anni.<\/p>\n<h5><strong>myFACHPACK: Conferenze in live streaming<\/strong><\/h5>\n<p>Anche quest&#8217;anno c&#8217;\u00e8 di nuovo l&#8217;estensione digitale myFACHPACK per il matchmaking e il trasferimento di conoscenze tra espositori, partner, relatori e visitatori. myFACHPACK estende la fiera in loco nel mondo virtuale. Gi\u00e0 prima della fiera, a partire dal 16 settembre, il nuovo strumento offre ai visitatori la possibilit\u00e0 di connettersi con espositori, partner e relatori. Durante il periodo della fiera, il programma dei forum di conferenze PACKBOX, TECHBOX e INNOVATIONSBOX sar\u00e0 trasmesso in diretta su myFACHPACK e sar\u00e0 disponibile anche successivamente. myFACHPACK pu\u00f2 essere utilizzato su desktop e, soprattutto, in mobilit\u00e0 tramite un&#8217;app:<\/p>\n<p><a href=\"https:\/\/www.fachpack.de\/myFACHPACK\" target=\"_blank\" rel=\"noopener\"><strong>www.fachpack.de\/myFACHPACK<\/strong><\/a><\/p>\n<h5><strong>Informazioni sulla FACHPACK<\/strong><\/h5>\n<p>La FACHPACK (27-29.9.2022, Norimberga) \u00e8 la fiera europea specializzata per imballaggio, tecnologia e processi. Gli espositori presentano la loro offerta lungo la catena di processo dell&#8217;imballaggio per beni industriali e di consumo. Vengono mostrati: materiali e mezzi ausiliari per imballaggio, macchine per riempimento e imballaggio, tecnologie di etichettatura, marcatura e identificazione, macchine e dispositivi nella periferia dell&#8217;imballaggio, stampa e finitura degli imballaggi, tecnologia di pallettizzazione, intralogistica e servizi. Con il nuovo slogan &#8220;Noi costruiamo il futuro&#8221;, la FACHPACK 2022 si dedica al tema attuale &#8220;Transizione nel Packaging&#8221;. Come punto di incontro del mercato europeo del packaging, la FACHPACK attira visitatori professionali da tutti i settori ad alta intensit\u00e0 di imballaggio: alimenti \/ bevande \/ prodotti di consumo, farmaceutico \/ cosmetico \/ chimico \/ salute, non alimentari \/ alimenti per animali \/ altri beni di consumo, nonch\u00e9 automotive \/ articoli tecnici \/ tecnologia medica e altri beni industriali.<\/p>\n<p><a href=\"https:\/\/www.fachpack.de\" target=\"_blank\" rel=\"noopener\">www.fachpack.de<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dal 27 al 29 settembre 2022 \u00e8 di nuovo il momento. Allora apre la FACHPACK, fiera specializzata per imballaggio, tecnologia e processi, presso il centro fieristico<span class=\"excerpt-hellip\"> [\u2026]<\/span><\/p>\n","protected":false},"author":0,"featured_media":9563,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1557,1561],"tags":[],"class_list":["post-58024","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-forwarding-logistics","category-regions"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>FACHPACK con nuovi impulsi per l&#039;industria del packaging - Loginfo24<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/loginfo24.com\/it\/2022\/08\/24\/fachpack-con-nuovi-impulsi-per-lindustria-del-packaging\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"FACHPACK con nuovi impulsi per l&#039;industria del packaging - Loginfo24\" \/>\n<meta property=\"og:description\" content=\"Dal 27 al 29 settembre 2022 \u00e8 di nuovo il momento. Allora apre la FACHPACK, fiera specializzata per imballaggio, tecnologia e processi, presso il centro fieristico [\u2026]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/loginfo24.com\/it\/2022\/08\/24\/fachpack-con-nuovi-impulsi-per-lindustria-del-packaging\/\" \/>\n<meta property=\"og:site_name\" content=\"Loginfo24\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/\" \/>\n<meta property=\"article:published_time\" content=\"2022-08-24T14:31:24+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Fachpack_24.8.22_3.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1336\" \/>\n\t<meta property=\"og:image:height\" content=\"836\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"5 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2022\\\/08\\\/24\\\/fachpack-con-nuovi-impulsi-per-lindustria-del-packaging\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2022\\\/08\\\/24\\\/fachpack-con-nuovi-impulsi-per-lindustria-del-packaging\\\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"FACHPACK con nuovi impulsi per l&#8217;industria del packaging\",\"datePublished\":\"2022-08-24T14:31:24+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2022\\\/08\\\/24\\\/fachpack-con-nuovi-impulsi-per-lindustria-del-packaging\\\/\"},\"wordCount\":1065,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2022\\\/08\\\/24\\\/fachpack-con-nuovi-impulsi-per-lindustria-del-packaging\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/Fachpack_24.8.22_3.jpg\",\"articleSection\":[\"Forwarding &amp; Logistics\",\"Regions\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/it\\\/2022\\\/08\\\/24\\\/fachpack-con-nuovi-impulsi-per-lindustria-del-packaging\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2022\\\/08\\\/24\\\/fachpack-con-nuovi-impulsi-per-lindustria-del-packaging\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2022\\\/08\\\/24\\\/fachpack-con-nuovi-impulsi-per-lindustria-del-packaging\\\/\",\"name\":\"FACHPACK con nuovi impulsi per l'industria del packaging - Loginfo24\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2022\\\/08\\\/24\\\/fachpack-con-nuovi-impulsi-per-lindustria-del-packaging\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2022\\\/08\\\/24\\\/fachpack-con-nuovi-impulsi-per-lindustria-del-packaging\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/Fachpack_24.8.22_3.jpg\",\"datePublished\":\"2022-08-24T14:31:24+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2022\\\/08\\\/24\\\/fachpack-con-nuovi-impulsi-per-lindustria-del-packaging\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/it\\\/2022\\\/08\\\/24\\\/fachpack-con-nuovi-impulsi-per-lindustria-del-packaging\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2022\\\/08\\\/24\\\/fachpack-con-nuovi-impulsi-per-lindustria-del-packaging\\\/#primaryimage\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/Fachpack_24.8.22_3.jpg\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/Fachpack_24.8.22_3.jpg\",\"width\":1336,\"height\":836},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2022\\\/08\\\/24\\\/fachpack-con-nuovi-impulsi-per-lindustria-del-packaging\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"FACHPACK con nuovi impulsi per l&#8217;industria del packaging\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/\",\"name\":\"Loginfo24\",\"description\":\"Loginfo24 \u00e8 la piattaforma dedicata alla logistica e alle catene di fornitura con informazioni disponibili 24 ore su 24.\",\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#organization\",\"name\":\"Logismedia Group AG\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"width\":938,\"height\":351,\"caption\":\"Logismedia Group AG\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/people\\\/Loginfo24\\\/100057360583332\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/lofinfo24\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"FACHPACK con nuovi impulsi per l'industria del packaging - Loginfo24","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/loginfo24.com\/it\/2022\/08\/24\/fachpack-con-nuovi-impulsi-per-lindustria-del-packaging\/","og_locale":"it_IT","og_type":"article","og_title":"FACHPACK con nuovi impulsi per l'industria del packaging - Loginfo24","og_description":"Dal 27 al 29 settembre 2022 \u00e8 di nuovo il momento. Allora apre la FACHPACK, fiera specializzata per imballaggio, tecnologia e processi, presso il centro fieristico [\u2026]","og_url":"https:\/\/loginfo24.com\/it\/2022\/08\/24\/fachpack-con-nuovi-impulsi-per-lindustria-del-packaging\/","og_site_name":"Loginfo24","article_publisher":"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","article_published_time":"2022-08-24T14:31:24+00:00","og_image":[{"width":1336,"height":836,"url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Fachpack_24.8.22_3.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"5 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/loginfo24.com\/it\/2022\/08\/24\/fachpack-con-nuovi-impulsi-per-lindustria-del-packaging\/#article","isPartOf":{"@id":"https:\/\/loginfo24.com\/it\/2022\/08\/24\/fachpack-con-nuovi-impulsi-per-lindustria-del-packaging\/"},"author":{"name":"","@id":""},"headline":"FACHPACK con nuovi impulsi per l&#8217;industria del packaging","datePublished":"2022-08-24T14:31:24+00:00","mainEntityOfPage":{"@id":"https:\/\/loginfo24.com\/it\/2022\/08\/24\/fachpack-con-nuovi-impulsi-per-lindustria-del-packaging\/"},"wordCount":1065,"commentCount":0,"publisher":{"@id":"https:\/\/loginfo24.com\/it\/#organization"},"image":{"@id":"https:\/\/loginfo24.com\/it\/2022\/08\/24\/fachpack-con-nuovi-impulsi-per-lindustria-del-packaging\/#primaryimage"},"thumbnailUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Fachpack_24.8.22_3.jpg","articleSection":["Forwarding &amp; Logistics","Regions"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/loginfo24.com\/it\/2022\/08\/24\/fachpack-con-nuovi-impulsi-per-lindustria-del-packaging\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/loginfo24.com\/it\/2022\/08\/24\/fachpack-con-nuovi-impulsi-per-lindustria-del-packaging\/","url":"https:\/\/loginfo24.com\/it\/2022\/08\/24\/fachpack-con-nuovi-impulsi-per-lindustria-del-packaging\/","name":"FACHPACK con nuovi impulsi per l'industria del packaging - Loginfo24","isPartOf":{"@id":"https:\/\/loginfo24.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/loginfo24.com\/it\/2022\/08\/24\/fachpack-con-nuovi-impulsi-per-lindustria-del-packaging\/#primaryimage"},"image":{"@id":"https:\/\/loginfo24.com\/it\/2022\/08\/24\/fachpack-con-nuovi-impulsi-per-lindustria-del-packaging\/#primaryimage"},"thumbnailUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Fachpack_24.8.22_3.jpg","datePublished":"2022-08-24T14:31:24+00:00","breadcrumb":{"@id":"https:\/\/loginfo24.com\/it\/2022\/08\/24\/fachpack-con-nuovi-impulsi-per-lindustria-del-packaging\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/loginfo24.com\/it\/2022\/08\/24\/fachpack-con-nuovi-impulsi-per-lindustria-del-packaging\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/loginfo24.com\/it\/2022\/08\/24\/fachpack-con-nuovi-impulsi-per-lindustria-del-packaging\/#primaryimage","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Fachpack_24.8.22_3.jpg","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Fachpack_24.8.22_3.jpg","width":1336,"height":836},{"@type":"BreadcrumbList","@id":"https:\/\/loginfo24.com\/it\/2022\/08\/24\/fachpack-con-nuovi-impulsi-per-lindustria-del-packaging\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/loginfo24.com\/it\/"},{"@type":"ListItem","position":2,"name":"FACHPACK con nuovi impulsi per l&#8217;industria del packaging"}]},{"@type":"WebSite","@id":"https:\/\/loginfo24.com\/it\/#website","url":"https:\/\/loginfo24.com\/it\/","name":"Loginfo24","description":"Loginfo24 \u00e8 la piattaforma dedicata alla logistica e alle catene di fornitura con informazioni disponibili 24 ore su 24.","publisher":{"@id":"https:\/\/loginfo24.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/loginfo24.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/loginfo24.com\/it\/#organization","name":"Logismedia Group AG","url":"https:\/\/loginfo24.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/loginfo24.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","width":938,"height":351,"caption":"Logismedia Group AG"},"image":{"@id":"https:\/\/loginfo24.com\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","https:\/\/www.linkedin.com\/company\/lofinfo24\/"]}]}},"_links":{"self":[{"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/posts\/58024","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/comments?post=58024"}],"version-history":[{"count":0,"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/posts\/58024\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/media\/9563"}],"wp:attachment":[{"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/media?parent=58024"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/categories?post=58024"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/tags?post=58024"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}