{"id":57161,"date":"2022-06-26T16:00:19","date_gmt":"2022-06-26T14:00:19","guid":{"rendered":"https:\/\/blog.brand-architecture.at\/2022\/06\/26\/networcx-digitalizza-i-processi-aziendali-nella-logistica\/"},"modified":"2022-06-26T16:00:19","modified_gmt":"2022-06-26T14:00:19","slug":"networcx-digitalizza-i-processi-aziendali-nella-logistica","status":"publish","type":"post","link":"https:\/\/loginfo24.com\/it\/2022\/06\/26\/networcx-digitalizza-i-processi-aziendali-nella-logistica\/","title":{"rendered":"Networcx digitalizza i processi aziendali nella logistica"},"content":{"rendered":"<h5><strong>La piattaforma Networcx offre un&#8217;unica soluzione per gestire tutti i punti di contatto con i clienti nella logistica. Le abitudini lavorative e di acquisto stanno cambiando rapidamente. Non a causa del Covid-19, anche se questa crisi ha accelerato il processo digitale, ma ad esempio attraverso videochiamate con colleghi e soprattutto con clienti. Tuttavia, la necessit\u00e0 di diventare pi\u00f9 efficienti ed efficaci nel mondo del lavoro era gi\u00e0 presente prima e crescer\u00e0 giorno dopo giorno.<\/strong><\/h5>\n<p>(Wilen b. Wollerau) Le interazioni digitali, insieme alla crescente pressione sui costi e sui margini, rendono importante essere pronti o addirittura avere un vantaggio in termini di strumenti tecnici e digitali. Il dialogo \u00e8 fondamentale e mostra come possiamo sfruttare e modellare al meglio la digitalizzazione a nostro favore - per i clienti, i dipendenti e l&#8217;intera organizzazione. Vediamo la digitalizzazione come la chiave per diventare pi\u00f9 efficaci ed efficienti e per creare opportunit\u00e0 di crescita nel settore della logistica.<\/p>\n<p>Affrontare le sfide e le opportunit\u00e0 descritte sopra richiede alcuni principi guida chiari che devono essere applicati in modo coerente nell&#8217;introduzione di nuovi strumenti e servizi digitali. Consideriamo i seguenti principi come particolarmente critici.<\/p>\n<h5><strong>Era dei sistemi chiusi finita<\/strong><\/h5>\n<p>L&#8217;era dei sistemi chiusi \u00e8 finita. La realt\u00e0 nella nostra vita lavorativa \u00e8 diversa. Immaginate che le informazioni su tariffe, dettagli di spedizione, reclami e documenti di prenotazione vengano automaticamente inserite nei vostri sistemi. Ma anche per i fornitori, un approccio multicanale significa essere sempre presenti dove si trovano i clienti. Per raggiungere il vostro pubblico target, dovete adattarvi al canale scelto dal pubblico stesso.<\/p>\n<h5><strong>Settore dei trasporti e della logistica in ritardo nella digitalizzazione<\/strong><\/h5>\n<p>A prima vista, la visibilit\u00e0 sembra semplice, ma il settore dei trasporti e della logistica \u00e8 ancora in ritardo quando si tratta di integrazione dei dati e trasparenza. Si \u00e8 verificato un cambiamento di paradigma riguardo alle aspettative dei clienti e all&#8217;esperienza finale del cliente. Pertanto, vediamo l&#8217;integrazione e la trasparenza dei dati come un elemento chiave nel vostro percorso di crescita.<\/p>\n<h5><strong>Flussi di lavoro automatizzati e digitali<\/strong><\/h5>\n<p>L&#8217;automazione e la gestione dei flussi di lavoro sottostanti riguardano il conseguimento di guadagni in termini di efficienza e produttivit\u00e0 che contribuiscono all&#8217;ottimizzazione dei vostri costi e processi. In questo modo, potete ridurre significativamente il numero di passaggi di lavoro non necessari nella vostra azienda. L&#8217;automazione e la digitalizzazione consentono processi pi\u00f9 rapidi e migliori e offrono infine una base migliore per le interazioni con i clienti.<\/p>\n<h5>Tutti i sistemi vengono uniti<\/h5>\n<p>La maggior parte delle soluzioni disponibili oggi sul mercato sono troppo tecniche e costose. Dispongono di una variet\u00e0 di funzionalit\u00e0 che non sono necessarie o addirittura non utilizzate. L&#8217;esperienza end-to-end per utenti e clienti \u00e8 molto difficile da raggiungere a causa della crescente complessit\u00e0 e del superamento dei budget. Networcx \u00e8 stato progettato per affrontare esattamente queste sfide. Non \u00e8 pi\u00f9 necessario acquistare e integrare pi\u00f9 sistemi (vedi grafico) per gestire e controllare i canali e i punti di contatto con i clienti.<\/p>\n<h5><strong><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-19842 size-full\" src=\"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Networcx_25.6.22_1.jpg\" alt=\"\" width=\"817\" height=\"512\" \/><\/strong><\/h5>\n<h5><strong>Su Networcx <\/strong><\/h5>\n<p>Networcx \u00e8 un&#8217;applicazione all-in-one per la gestione di clienti, partner e vendite, che consente di gestire i propri processi aziendali dalla A alla Z. Networcx offre un&#8217;unica piattaforma digitale che consente a un&#8217;azienda di interagire con diversi gruppi target: clienti, partner e tutti i dipendenti all&#8217;interno dell&#8217;organizzazione attraverso funzioni e reparti.<\/p>\n<p>Possono essere utilizzati anche singoli moduli come ad esempio offerte e gare (Quotes\/Tenders) o gestione delle prestazioni e delle compensazioni (Performance and Compensation Management). La soluzione Networcx offre standard e modelli logistici pronti all&#8217;uso e supporta le aziende nella gestione delle interazioni personali e digitali con clienti e partner (ad es. agenti).<\/p>\n<p>Networcx AG ha sede a Wilen presso Wollerau, in Svizzera.<\/p>\n<p><a href=\"https:\/\/www.networcx.io\" target=\"_blank\" rel=\"noopener\">www.networcx.io<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La piattaforma Networcx offre un&#8217;unica soluzione per gestire tutti i punti di contatto con i clienti nella logistica. Le abitudini lavorative e di acquisto stanno cambiando<span class=\"excerpt-hellip\"> [\u2026]<\/span><\/p>\n","protected":false},"author":0,"featured_media":9947,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1665,1557,1561],"tags":[],"class_list":["post-57161","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-categories","category-forwarding-logistics","category-regions"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Networcx digitalizza i processi aziendali nella logistica - Loginfo24<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/loginfo24.com\/it\/2022\/06\/26\/networcx-digitalizza-i-processi-aziendali-nella-logistica\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Networcx digitalizza i processi aziendali nella logistica - Loginfo24\" \/>\n<meta property=\"og:description\" content=\"La piattaforma Networcx offre un&#8217;unica soluzione per gestire tutti i punti di contatto con i clienti nella logistica. Le abitudini lavorative e di acquisto stanno cambiando [\u2026]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/loginfo24.com\/it\/2022\/06\/26\/networcx-digitalizza-i-processi-aziendali-nella-logistica\/\" \/>\n<meta property=\"og:site_name\" content=\"Loginfo24\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/\" \/>\n<meta property=\"article:published_time\" content=\"2022-06-26T14:00:19+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Networcx_Titel_25.6.22.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1392\" \/>\n\t<meta property=\"og:image:height\" content=\"903\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2022\\\/06\\\/26\\\/networcx-digitalizza-i-processi-aziendali-nella-logistica\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2022\\\/06\\\/26\\\/networcx-digitalizza-i-processi-aziendali-nella-logistica\\\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Networcx digitalizza i processi aziendali nella logistica\",\"datePublished\":\"2022-06-26T14:00:19+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2022\\\/06\\\/26\\\/networcx-digitalizza-i-processi-aziendali-nella-logistica\\\/\"},\"wordCount\":624,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2022\\\/06\\\/26\\\/networcx-digitalizza-i-processi-aziendali-nella-logistica\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/Networcx_Titel_25.6.22.jpg\",\"articleSection\":[\"Categories\",\"Forwarding &amp; Logistics\",\"Regions\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/it\\\/2022\\\/06\\\/26\\\/networcx-digitalizza-i-processi-aziendali-nella-logistica\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2022\\\/06\\\/26\\\/networcx-digitalizza-i-processi-aziendali-nella-logistica\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2022\\\/06\\\/26\\\/networcx-digitalizza-i-processi-aziendali-nella-logistica\\\/\",\"name\":\"Networcx digitalizza i processi aziendali nella logistica - Loginfo24\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2022\\\/06\\\/26\\\/networcx-digitalizza-i-processi-aziendali-nella-logistica\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2022\\\/06\\\/26\\\/networcx-digitalizza-i-processi-aziendali-nella-logistica\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/Networcx_Titel_25.6.22.jpg\",\"datePublished\":\"2022-06-26T14:00:19+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2022\\\/06\\\/26\\\/networcx-digitalizza-i-processi-aziendali-nella-logistica\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/it\\\/2022\\\/06\\\/26\\\/networcx-digitalizza-i-processi-aziendali-nella-logistica\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2022\\\/06\\\/26\\\/networcx-digitalizza-i-processi-aziendali-nella-logistica\\\/#primaryimage\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/Networcx_Titel_25.6.22.jpg\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/Networcx_Titel_25.6.22.jpg\",\"width\":1392,\"height\":903},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2022\\\/06\\\/26\\\/networcx-digitalizza-i-processi-aziendali-nella-logistica\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Networcx digitalizza i processi aziendali nella logistica\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/\",\"name\":\"Loginfo24\",\"description\":\"Loginfo24 \u00e8 la piattaforma dedicata alla logistica e alle catene di fornitura con informazioni disponibili 24 ore su 24.\",\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#organization\",\"name\":\"Logismedia Group AG\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"width\":938,\"height\":351,\"caption\":\"Logismedia Group AG\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/people\\\/Loginfo24\\\/100057360583332\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/lofinfo24\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Networcx digitalizza i processi aziendali nella logistica - Loginfo24","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/loginfo24.com\/it\/2022\/06\/26\/networcx-digitalizza-i-processi-aziendali-nella-logistica\/","og_locale":"it_IT","og_type":"article","og_title":"Networcx digitalizza i processi aziendali nella logistica - Loginfo24","og_description":"La piattaforma Networcx offre un&#8217;unica soluzione per gestire tutti i punti di contatto con i clienti nella logistica. Le abitudini lavorative e di acquisto stanno cambiando [\u2026]","og_url":"https:\/\/loginfo24.com\/it\/2022\/06\/26\/networcx-digitalizza-i-processi-aziendali-nella-logistica\/","og_site_name":"Loginfo24","article_publisher":"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","article_published_time":"2022-06-26T14:00:19+00:00","og_image":[{"width":1392,"height":903,"url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Networcx_Titel_25.6.22.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"3 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/loginfo24.com\/it\/2022\/06\/26\/networcx-digitalizza-i-processi-aziendali-nella-logistica\/#article","isPartOf":{"@id":"https:\/\/loginfo24.com\/it\/2022\/06\/26\/networcx-digitalizza-i-processi-aziendali-nella-logistica\/"},"author":{"name":"","@id":""},"headline":"Networcx digitalizza i processi aziendali nella logistica","datePublished":"2022-06-26T14:00:19+00:00","mainEntityOfPage":{"@id":"https:\/\/loginfo24.com\/it\/2022\/06\/26\/networcx-digitalizza-i-processi-aziendali-nella-logistica\/"},"wordCount":624,"commentCount":0,"publisher":{"@id":"https:\/\/loginfo24.com\/it\/#organization"},"image":{"@id":"https:\/\/loginfo24.com\/it\/2022\/06\/26\/networcx-digitalizza-i-processi-aziendali-nella-logistica\/#primaryimage"},"thumbnailUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Networcx_Titel_25.6.22.jpg","articleSection":["Categories","Forwarding &amp; Logistics","Regions"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/loginfo24.com\/it\/2022\/06\/26\/networcx-digitalizza-i-processi-aziendali-nella-logistica\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/loginfo24.com\/it\/2022\/06\/26\/networcx-digitalizza-i-processi-aziendali-nella-logistica\/","url":"https:\/\/loginfo24.com\/it\/2022\/06\/26\/networcx-digitalizza-i-processi-aziendali-nella-logistica\/","name":"Networcx digitalizza i processi aziendali nella logistica - Loginfo24","isPartOf":{"@id":"https:\/\/loginfo24.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/loginfo24.com\/it\/2022\/06\/26\/networcx-digitalizza-i-processi-aziendali-nella-logistica\/#primaryimage"},"image":{"@id":"https:\/\/loginfo24.com\/it\/2022\/06\/26\/networcx-digitalizza-i-processi-aziendali-nella-logistica\/#primaryimage"},"thumbnailUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Networcx_Titel_25.6.22.jpg","datePublished":"2022-06-26T14:00:19+00:00","breadcrumb":{"@id":"https:\/\/loginfo24.com\/it\/2022\/06\/26\/networcx-digitalizza-i-processi-aziendali-nella-logistica\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/loginfo24.com\/it\/2022\/06\/26\/networcx-digitalizza-i-processi-aziendali-nella-logistica\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/loginfo24.com\/it\/2022\/06\/26\/networcx-digitalizza-i-processi-aziendali-nella-logistica\/#primaryimage","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Networcx_Titel_25.6.22.jpg","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Networcx_Titel_25.6.22.jpg","width":1392,"height":903},{"@type":"BreadcrumbList","@id":"https:\/\/loginfo24.com\/it\/2022\/06\/26\/networcx-digitalizza-i-processi-aziendali-nella-logistica\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/loginfo24.com\/it\/"},{"@type":"ListItem","position":2,"name":"Networcx digitalizza i processi aziendali nella logistica"}]},{"@type":"WebSite","@id":"https:\/\/loginfo24.com\/it\/#website","url":"https:\/\/loginfo24.com\/it\/","name":"Loginfo24","description":"Loginfo24 \u00e8 la piattaforma dedicata alla logistica e alle catene di fornitura con informazioni disponibili 24 ore su 24.","publisher":{"@id":"https:\/\/loginfo24.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/loginfo24.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/loginfo24.com\/it\/#organization","name":"Logismedia Group AG","url":"https:\/\/loginfo24.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/loginfo24.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","width":938,"height":351,"caption":"Logismedia Group AG"},"image":{"@id":"https:\/\/loginfo24.com\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","https:\/\/www.linkedin.com\/company\/lofinfo24\/"]}]}},"_links":{"self":[{"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/posts\/57161","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/comments?post=57161"}],"version-history":[{"count":0,"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/posts\/57161\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/media\/9947"}],"wp:attachment":[{"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/media?parent=57161"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/categories?post=57161"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/tags?post=57161"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}