{"id":56877,"date":"2022-06-12T16:55:22","date_gmt":"2022-06-12T14:55:22","guid":{"rendered":"https:\/\/blog.brand-architecture.at\/2022\/06\/12\/astag-dati-sul-traffico-in-svizzera-2021\/"},"modified":"2022-06-12T16:55:22","modified_gmt":"2022-06-12T14:55:22","slug":"astag-dati-sul-traffico-in-svizzera-2021","status":"publish","type":"post","link":"https:\/\/loginfo24.com\/it\/2022\/06\/12\/astag-dati-sul-traffico-in-svizzera-2021\/","title":{"rendered":"ASTAG \u2013 Dati sul traffico in Svizzera 2021"},"content":{"rendered":"<h5><strong>Il forte sovraccarico delle infrastrutture stradali ha notevolmente limitato il flusso del traffico sulle strade nazionali nell&#8217;anno passato, portando a un aumento massiccio delle ore di congestione. L&#8217;Associazione svizzera dei veicoli commerciali ASTAG chiede un ulteriore sviluppo delle infrastrutture per garantire un approvvigionamento e smaltimento senza intoppi in Svizzera. Solo in questo modo possono essere evitate deviazioni e costi aggiuntivi massicci - a beneficio dell&#8217;economia e dell&#8217;ambiente.<\/strong><\/h5>\n<p> (Berna) L&#8217;associazione dei veicoli commerciali ASTAG si mostra preoccupata per l&#8217;aumento sproporzionato delle ore di congestione rispetto al chilometraggio. Nel 2021, il traffico si \u00e8 bloccato per un totale di 32.481 ore sulle strade svizzere, raggiungendo nuovamente un livello paragonabile a quello precedente alla pandemia. Rispetto all&#8217;anno precedente (22.575 ore di congestione), ci\u00f2 corrisponde a un aumento del +43,9%. La causa dell&#8217;aumento delle ore di congestione \u00e8 nella maggior parte dei casi il sovraccarico del traffico (89%). Questo evidenzia la necessit\u00e0 di un immediato ampliamento delle infrastrutture stradali. Pertanto, l&#8217;ASTAG continua a richiedere una revisione sistematica degli assi principali in coordinamento con l&#8217;ampliamento degli assi secondari. Solo in questo modo pu\u00f2 essere garantito il flusso del traffico.<\/p>\n<h5><strong>Doppio carico durante le ore di punta<\/strong><\/h5>\n<p> Il problema dell&#8217;aumento massiccio delle ore di congestione \u00e8 grave per il settore del trasporto su strada, come dimostra uno sguardo al nuovo andamento settimanale e giornaliero del volume di traffico: al mattino, il traffico lavorativo e alla sera il traffico per acquisti e tempo libero portano a un aumento del volume di traffico. In questi due intervalli di tempo, anche la domanda di merci da parte dell&#8217;economia e dei consumatori raggiunge il suo picco. Al mattino, deve essere garantita la consegna di beni e merci. Alla sera avviene il ritiro per la consegna puntuale delle merci per il giorno successivo. &#8220;L&#8217;aumento delle ore di congestione minaccia questo processo sistemico&#8221;, avverte il presidente centrale dell&#8217;ASTAG Thierry Burkart. Ci\u00f2 provoca alti costi aggiuntivi a causa delle perdite di produttivit\u00e0 sia per il settore dei trasporti che per l&#8217;economia e la popolazione. Inoltre, il traffico stop-and-go non ecologico ha conseguenze sul consumo di carburante e sull&#8217;ambiente. Tuttavia, il rapporto ASTRA sullo sviluppo del traffico e sul flusso del traffico 2021 mette in luce anche un punto positivo: nonostante l&#8217;aumento della domanda di servizi di trasporto, i chilometri percorsi dai veicoli nel trasporto pesante sono cambiati poco. &#8220;La bassa percentuale di veicoli pesanti sul totale del volume di traffico, pari solo al 5,9%, sottolinea l&#8217;efficienza raggiunta dal settore del trasporto su strada&#8221;, si rallegrano Thierry Burkart. Foto: \u00a9 Loginfo24 \/ Adobe Stock<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il forte sovraccarico delle infrastrutture stradali ha notevolmente limitato il flusso del traffico sulle strade nazionali nell&#8217;anno passato, portando a un aumento massiccio delle ore di<span class=\"excerpt-hellip\"> [\u2026]<\/span><\/p>\n","protected":false},"author":0,"featured_media":10070,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1557,1556,1561],"tags":[],"class_list":["post-56877","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-forwarding-logistics","category-intermodal-road","category-regions"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>ASTAG \u2013 Dati sul traffico in Svizzera 2021 - Loginfo24<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/loginfo24.com\/it\/2022\/06\/12\/astag-dati-sul-traffico-in-svizzera-2021\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"ASTAG \u2013 Dati sul traffico in Svizzera 2021 - Loginfo24\" \/>\n<meta property=\"og:description\" content=\"Il forte sovraccarico delle infrastrutture stradali ha notevolmente limitato il flusso del traffico sulle strade nazionali nell&#8217;anno passato, portando a un aumento massiccio delle ore di [\u2026]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/loginfo24.com\/it\/2022\/06\/12\/astag-dati-sul-traffico-in-svizzera-2021\/\" \/>\n<meta property=\"og:site_name\" content=\"Loginfo24\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/\" \/>\n<meta property=\"article:published_time\" content=\"2022-06-12T14:55:22+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/ASTAG_12.6.22.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1484\" \/>\n\t<meta property=\"og:image:height\" content=\"726\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2022\\\/06\\\/12\\\/astag-dati-sul-traffico-in-svizzera-2021\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2022\\\/06\\\/12\\\/astag-dati-sul-traffico-in-svizzera-2021\\\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"ASTAG \u2013 Dati sul traffico in Svizzera 2021\",\"datePublished\":\"2022-06-12T14:55:22+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2022\\\/06\\\/12\\\/astag-dati-sul-traffico-in-svizzera-2021\\\/\"},\"wordCount\":432,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2022\\\/06\\\/12\\\/astag-dati-sul-traffico-in-svizzera-2021\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/ASTAG_12.6.22.jpg\",\"articleSection\":[\"Forwarding &amp; Logistics\",\"Intermodal \\\/ Road\",\"Regions\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/it\\\/2022\\\/06\\\/12\\\/astag-dati-sul-traffico-in-svizzera-2021\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2022\\\/06\\\/12\\\/astag-dati-sul-traffico-in-svizzera-2021\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2022\\\/06\\\/12\\\/astag-dati-sul-traffico-in-svizzera-2021\\\/\",\"name\":\"ASTAG \u2013 Dati sul traffico in Svizzera 2021 - Loginfo24\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2022\\\/06\\\/12\\\/astag-dati-sul-traffico-in-svizzera-2021\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2022\\\/06\\\/12\\\/astag-dati-sul-traffico-in-svizzera-2021\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/ASTAG_12.6.22.jpg\",\"datePublished\":\"2022-06-12T14:55:22+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2022\\\/06\\\/12\\\/astag-dati-sul-traffico-in-svizzera-2021\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/it\\\/2022\\\/06\\\/12\\\/astag-dati-sul-traffico-in-svizzera-2021\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2022\\\/06\\\/12\\\/astag-dati-sul-traffico-in-svizzera-2021\\\/#primaryimage\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/ASTAG_12.6.22.jpg\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/ASTAG_12.6.22.jpg\",\"width\":1484,\"height\":726},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2022\\\/06\\\/12\\\/astag-dati-sul-traffico-in-svizzera-2021\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"ASTAG \u2013 Dati sul traffico in Svizzera 2021\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/\",\"name\":\"Loginfo24\",\"description\":\"Loginfo24 \u00e8 la piattaforma dedicata alla logistica e alle catene di fornitura con informazioni disponibili 24 ore su 24.\",\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#organization\",\"name\":\"Logismedia Group AG\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"width\":938,\"height\":351,\"caption\":\"Logismedia Group AG\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/people\\\/Loginfo24\\\/100057360583332\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/lofinfo24\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"ASTAG \u2013 Dati sul traffico in Svizzera 2021 - Loginfo24","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/loginfo24.com\/it\/2022\/06\/12\/astag-dati-sul-traffico-in-svizzera-2021\/","og_locale":"it_IT","og_type":"article","og_title":"ASTAG \u2013 Dati sul traffico in Svizzera 2021 - Loginfo24","og_description":"Il forte sovraccarico delle infrastrutture stradali ha notevolmente limitato il flusso del traffico sulle strade nazionali nell&#8217;anno passato, portando a un aumento massiccio delle ore di [\u2026]","og_url":"https:\/\/loginfo24.com\/it\/2022\/06\/12\/astag-dati-sul-traffico-in-svizzera-2021\/","og_site_name":"Loginfo24","article_publisher":"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","article_published_time":"2022-06-12T14:55:22+00:00","og_image":[{"width":1484,"height":726,"url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/ASTAG_12.6.22.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"2 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/loginfo24.com\/it\/2022\/06\/12\/astag-dati-sul-traffico-in-svizzera-2021\/#article","isPartOf":{"@id":"https:\/\/loginfo24.com\/it\/2022\/06\/12\/astag-dati-sul-traffico-in-svizzera-2021\/"},"author":{"name":"","@id":""},"headline":"ASTAG \u2013 Dati sul traffico in Svizzera 2021","datePublished":"2022-06-12T14:55:22+00:00","mainEntityOfPage":{"@id":"https:\/\/loginfo24.com\/it\/2022\/06\/12\/astag-dati-sul-traffico-in-svizzera-2021\/"},"wordCount":432,"commentCount":0,"publisher":{"@id":"https:\/\/loginfo24.com\/it\/#organization"},"image":{"@id":"https:\/\/loginfo24.com\/it\/2022\/06\/12\/astag-dati-sul-traffico-in-svizzera-2021\/#primaryimage"},"thumbnailUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/ASTAG_12.6.22.jpg","articleSection":["Forwarding &amp; Logistics","Intermodal \/ Road","Regions"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/loginfo24.com\/it\/2022\/06\/12\/astag-dati-sul-traffico-in-svizzera-2021\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/loginfo24.com\/it\/2022\/06\/12\/astag-dati-sul-traffico-in-svizzera-2021\/","url":"https:\/\/loginfo24.com\/it\/2022\/06\/12\/astag-dati-sul-traffico-in-svizzera-2021\/","name":"ASTAG \u2013 Dati sul traffico in Svizzera 2021 - Loginfo24","isPartOf":{"@id":"https:\/\/loginfo24.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/loginfo24.com\/it\/2022\/06\/12\/astag-dati-sul-traffico-in-svizzera-2021\/#primaryimage"},"image":{"@id":"https:\/\/loginfo24.com\/it\/2022\/06\/12\/astag-dati-sul-traffico-in-svizzera-2021\/#primaryimage"},"thumbnailUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/ASTAG_12.6.22.jpg","datePublished":"2022-06-12T14:55:22+00:00","breadcrumb":{"@id":"https:\/\/loginfo24.com\/it\/2022\/06\/12\/astag-dati-sul-traffico-in-svizzera-2021\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/loginfo24.com\/it\/2022\/06\/12\/astag-dati-sul-traffico-in-svizzera-2021\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/loginfo24.com\/it\/2022\/06\/12\/astag-dati-sul-traffico-in-svizzera-2021\/#primaryimage","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/ASTAG_12.6.22.jpg","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/ASTAG_12.6.22.jpg","width":1484,"height":726},{"@type":"BreadcrumbList","@id":"https:\/\/loginfo24.com\/it\/2022\/06\/12\/astag-dati-sul-traffico-in-svizzera-2021\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/loginfo24.com\/it\/"},{"@type":"ListItem","position":2,"name":"ASTAG \u2013 Dati sul traffico in Svizzera 2021"}]},{"@type":"WebSite","@id":"https:\/\/loginfo24.com\/it\/#website","url":"https:\/\/loginfo24.com\/it\/","name":"Loginfo24","description":"Loginfo24 \u00e8 la piattaforma dedicata alla logistica e alle catene di fornitura con informazioni disponibili 24 ore su 24.","publisher":{"@id":"https:\/\/loginfo24.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/loginfo24.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/loginfo24.com\/it\/#organization","name":"Logismedia Group AG","url":"https:\/\/loginfo24.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/loginfo24.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","width":938,"height":351,"caption":"Logismedia Group AG"},"image":{"@id":"https:\/\/loginfo24.com\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","https:\/\/www.linkedin.com\/company\/lofinfo24\/"]}]}},"_links":{"self":[{"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/posts\/56877","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/comments?post=56877"}],"version-history":[{"count":0,"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/posts\/56877\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/media\/10070"}],"wp:attachment":[{"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/media?parent=56877"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/categories?post=56877"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/tags?post=56877"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}