{"id":56847,"date":"2022-06-09T20:15:00","date_gmt":"2022-06-09T18:15:00","guid":{"rendered":"https:\/\/blog.brand-architecture.at\/2022\/06\/09\/posta-austriaca-fusione-di-4-filiali\/"},"modified":"2022-06-09T20:15:00","modified_gmt":"2022-06-09T18:15:00","slug":"posta-austriaca-fusione-di-4-filiali","status":"publish","type":"post","link":"https:\/\/loginfo24.com\/it\/2022\/06\/09\/posta-austriaca-fusione-di-4-filiali\/","title":{"rendered":"Posta austriaca: fusione di 4 filiali"},"content":{"rendered":"<h5><strong>La Post Business Solutions GmbH, una filiale della Posta austriaca AG, riunisce tutte le soluzioni nel campo dei processi informativi e aziendali sotto un&#8217;unica nuova marca. Grazie alla fusione delle quattro precedenti filiali Scanpoint, EMD, D2D e sendhybrid, i clienti aziendali potranno ora ricevere tutti i servizi integrati e da un&#8217;unica fonte. In questo modo, la Post Business Solutions cresce fino a diventare uno dei pi\u00f9 grandi attori nel settore dell&#8217;outsourcing documentale in Austria.<\/strong><\/h5>\n<p>(Wien) Quattro filiali della Posta austriaca AG \u2013 Scanpoint, EMD, D2D e sendhybrid \u2013 elaborano ogni giorno 1,6 milioni di pagine per 450 clienti aziendali provenienti da otto paesi, principalmente nei settori della pubblica amministrazione, banche, assicurazioni, telecomunicazioni e aziende industriali. Per accompagnare i clienti aziendali in modo pi\u00f9 efficace verso un futuro competitivo, i quattro marchi esistenti sono stati uniti sotto il marchio comune &#8220;Post Business Solutions&#8221;. In questo modo, la Posta consolida la sua posizione nel mercato austriaco come partner esperto e affidabile per le aziende nell&#8217;analisi, outsourcing e automazione dei processi informativi e aziendali.<\/p>\n<h5><strong>\u00abOne Face to the Customer\u201d<\/strong><\/h5>\n<p>Un&#8217;immagine di marca unificata sotto il motto &#8220;One Face to the Customer&#8221; garantisce che pi\u00f9 di 30 soluzioni fisiche e digitali in questo settore siano integrate e offerte da un&#8217;unica fonte. La competenza combinata e il nuovo marchio si riflettono anche in un nuovo logo sotto l&#8217;egida della Posta austriaca AG. &#8220;Sotto il nuovo marchio Post Business Solutions, uniamo le nostre soluzioni per i processi aziendali e diventiamo cos\u00ec uno dei pi\u00f9 grandi fornitori di outsourcing documentale nel mercato austriaco. Invece di quattro filiali, la Post Business Solutions ora offre una piattaforma unificata per i nostri clienti, che combina know-how di processo, tecnologia all&#8217;avanguardia e l&#8217;affidabilit\u00e0 della Posta&#8221;, afferma DI Walter Oblin, direttore generale aggiunto e membro del consiglio per la corrispondenza e le finanze della Posta austriaca AG.<\/p>\n<h5><strong>Utilizzare le risorse in modo efficiente<\/strong><\/h5>\n<p>Circa 30 soluzioni della Post Business Solutions coprono l&#8217;intero ciclo di utilizzo delle informazioni dall&#8217;interno verso l&#8217;esterno e all&#8217;interno di un&#8217;azienda. Questo ciclo viene attuato in quattro fasi: 1) raccolta e consegna di lettere e invii postali nell&#8217;ambito della gestione degli sportelli postali (&#8220;Collect your data&#8221;), 2) trasformazione digitale dei documenti (&#8220;Transform your data&#8221;), 3) gestione dei documenti (&#8220;Manage your data&#8221;) e 4) ottimizzazione della comunicazione con i clienti (&#8220;Communicate your data&#8221;). In questo settore, la Post Business Solutions occupa gi\u00e0 una delle posizioni di leadership nel mercato austriaco in termini di capacit\u00e0 produttiva: ogni anno vengono stampate 500 milioni di pagine \u2013 fatture, lettere, comunicazioni e molto altro. Attraverso diverse soluzioni, vengono digitalizzate complessivamente 80 milioni di pagine all&#8217;anno. Ad esempio, le fatture possono essere elaborate con l&#8217;ausilio dell&#8217;intelligenza artificiale e attraverso la verifica da parte di personale esperto della Post Business Solutions entro 24 ore, garantendo una qualit\u00e0 dei dati al 100%. Inoltre, 4,2 milioni di documenti aziendali vengono consegnati digitalmente ogni anno tramite l&#8217;E-Brief. Inoltre, la Post Business Solutions utilizza tecnologie innovative come l&#8217;automazione dei processi robotici (RPA) e adotta i pi\u00f9 elevati standard europei in materia di protezione dei dati. &#8220;Attraverso l&#8217;outsourcing alla Post Business Solutions, le aziende possono liberare risorse importanti per le loro attivit\u00e0 principali e sfruttare potenziali di miglioramento della qualit\u00e0 e risparmio sui costi. Come partner per i processi aziendali, offriamo ai nostri clienti tutti i servizi da un&#8217;unica fonte e li accompagniamo verso un futuro digitale e sostenibile&#8221;, spiega Mag. George Wallner, M.Sc., responsabile del settore Post Business Solutions nella Posta austriaca AG.<\/p>\n<p>Grazie alla fusione delle quattro precedenti filiali nella Post Business Solutions GmbH, gli attuali stabilimenti di produzione a Graz, Haid presso Linz, Vienna e Nitra, cos\u00ec come tutti i posti di lavoro dei complessivi 520 dipendenti, rimarranno intatti. Allo stesso tempo, attraverso la strategia di crescita pianificata, nei prossimi anni si prevede di creare fino a 70 nuovi posti di lavoro.<\/p>\n<p>Foto: \u00a9 Posta austriaca AG \/ <strong><em>Didascalia dell&#8217;immagine:<\/em><\/strong><em> da sinistra: DI Walter Oblin, direttore generale aggiunto e membro del consiglio per la corrispondenza e le finanze della Posta austriaca AG, Mag. George Wallner, M.Sc., responsabile del settore Post Business Solutions nella Posta austriaca AG<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Post Business Solutions GmbH, una filiale della Posta austriaca AG, riunisce tutte le soluzioni nel campo dei processi informativi e aziendali sotto un&#8217;unica nuova marca.<span class=\"excerpt-hellip\"> [\u2026]<\/span><\/p>\n","protected":false},"author":0,"featured_media":10080,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1557,1561],"tags":[],"class_list":["post-56847","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-forwarding-logistics","category-regions"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Posta austriaca: fusione di 4 filiali - Loginfo24<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/loginfo24.com\/it\/2022\/06\/09\/posta-austriaca-fusione-di-4-filiali\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Posta austriaca: fusione di 4 filiali - Loginfo24\" \/>\n<meta property=\"og:description\" content=\"La Post Business Solutions GmbH, una filiale della Posta austriaca AG, riunisce tutte le soluzioni nel campo dei processi informativi e aziendali sotto un&#8217;unica nuova marca. [\u2026]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/loginfo24.com\/it\/2022\/06\/09\/posta-austriaca-fusione-di-4-filiali\/\" \/>\n<meta property=\"og:site_name\" content=\"Loginfo24\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/\" \/>\n<meta property=\"article:published_time\" content=\"2022-06-09T18:15:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Post_AT_10.06.2022-scaled-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1698\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2022\\\/06\\\/09\\\/posta-austriaca-fusione-di-4-filiali\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2022\\\/06\\\/09\\\/posta-austriaca-fusione-di-4-filiali\\\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Posta austriaca: fusione di 4 filiali\",\"datePublished\":\"2022-06-09T18:15:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2022\\\/06\\\/09\\\/posta-austriaca-fusione-di-4-filiali\\\/\"},\"wordCount\":690,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2022\\\/06\\\/09\\\/posta-austriaca-fusione-di-4-filiali\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/Post_AT_10.06.2022-scaled-1.jpg\",\"articleSection\":[\"Forwarding &amp; Logistics\",\"Regions\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/it\\\/2022\\\/06\\\/09\\\/posta-austriaca-fusione-di-4-filiali\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2022\\\/06\\\/09\\\/posta-austriaca-fusione-di-4-filiali\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2022\\\/06\\\/09\\\/posta-austriaca-fusione-di-4-filiali\\\/\",\"name\":\"Posta austriaca: fusione di 4 filiali - Loginfo24\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2022\\\/06\\\/09\\\/posta-austriaca-fusione-di-4-filiali\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2022\\\/06\\\/09\\\/posta-austriaca-fusione-di-4-filiali\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/Post_AT_10.06.2022-scaled-1.jpg\",\"datePublished\":\"2022-06-09T18:15:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2022\\\/06\\\/09\\\/posta-austriaca-fusione-di-4-filiali\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/it\\\/2022\\\/06\\\/09\\\/posta-austriaca-fusione-di-4-filiali\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2022\\\/06\\\/09\\\/posta-austriaca-fusione-di-4-filiali\\\/#primaryimage\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/Post_AT_10.06.2022-scaled-1.jpg\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/Post_AT_10.06.2022-scaled-1.jpg\",\"width\":2560,\"height\":1698},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2022\\\/06\\\/09\\\/posta-austriaca-fusione-di-4-filiali\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Posta austriaca: fusione di 4 filiali\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/\",\"name\":\"Loginfo24\",\"description\":\"Loginfo24 \u00e8 la piattaforma dedicata alla logistica e alle catene di fornitura con informazioni disponibili 24 ore su 24.\",\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#organization\",\"name\":\"Logismedia Group AG\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"width\":938,\"height\":351,\"caption\":\"Logismedia Group AG\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/people\\\/Loginfo24\\\/100057360583332\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/lofinfo24\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Posta austriaca: fusione di 4 filiali - Loginfo24","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/loginfo24.com\/it\/2022\/06\/09\/posta-austriaca-fusione-di-4-filiali\/","og_locale":"it_IT","og_type":"article","og_title":"Posta austriaca: fusione di 4 filiali - Loginfo24","og_description":"La Post Business Solutions GmbH, una filiale della Posta austriaca AG, riunisce tutte le soluzioni nel campo dei processi informativi e aziendali sotto un&#8217;unica nuova marca. [\u2026]","og_url":"https:\/\/loginfo24.com\/it\/2022\/06\/09\/posta-austriaca-fusione-di-4-filiali\/","og_site_name":"Loginfo24","article_publisher":"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","article_published_time":"2022-06-09T18:15:00+00:00","og_image":[{"width":2560,"height":1698,"url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Post_AT_10.06.2022-scaled-1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"3 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/loginfo24.com\/it\/2022\/06\/09\/posta-austriaca-fusione-di-4-filiali\/#article","isPartOf":{"@id":"https:\/\/loginfo24.com\/it\/2022\/06\/09\/posta-austriaca-fusione-di-4-filiali\/"},"author":{"name":"","@id":""},"headline":"Posta austriaca: fusione di 4 filiali","datePublished":"2022-06-09T18:15:00+00:00","mainEntityOfPage":{"@id":"https:\/\/loginfo24.com\/it\/2022\/06\/09\/posta-austriaca-fusione-di-4-filiali\/"},"wordCount":690,"commentCount":0,"publisher":{"@id":"https:\/\/loginfo24.com\/it\/#organization"},"image":{"@id":"https:\/\/loginfo24.com\/it\/2022\/06\/09\/posta-austriaca-fusione-di-4-filiali\/#primaryimage"},"thumbnailUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Post_AT_10.06.2022-scaled-1.jpg","articleSection":["Forwarding &amp; Logistics","Regions"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/loginfo24.com\/it\/2022\/06\/09\/posta-austriaca-fusione-di-4-filiali\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/loginfo24.com\/it\/2022\/06\/09\/posta-austriaca-fusione-di-4-filiali\/","url":"https:\/\/loginfo24.com\/it\/2022\/06\/09\/posta-austriaca-fusione-di-4-filiali\/","name":"Posta austriaca: fusione di 4 filiali - Loginfo24","isPartOf":{"@id":"https:\/\/loginfo24.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/loginfo24.com\/it\/2022\/06\/09\/posta-austriaca-fusione-di-4-filiali\/#primaryimage"},"image":{"@id":"https:\/\/loginfo24.com\/it\/2022\/06\/09\/posta-austriaca-fusione-di-4-filiali\/#primaryimage"},"thumbnailUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Post_AT_10.06.2022-scaled-1.jpg","datePublished":"2022-06-09T18:15:00+00:00","breadcrumb":{"@id":"https:\/\/loginfo24.com\/it\/2022\/06\/09\/posta-austriaca-fusione-di-4-filiali\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/loginfo24.com\/it\/2022\/06\/09\/posta-austriaca-fusione-di-4-filiali\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/loginfo24.com\/it\/2022\/06\/09\/posta-austriaca-fusione-di-4-filiali\/#primaryimage","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Post_AT_10.06.2022-scaled-1.jpg","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Post_AT_10.06.2022-scaled-1.jpg","width":2560,"height":1698},{"@type":"BreadcrumbList","@id":"https:\/\/loginfo24.com\/it\/2022\/06\/09\/posta-austriaca-fusione-di-4-filiali\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/loginfo24.com\/it\/"},{"@type":"ListItem","position":2,"name":"Posta austriaca: fusione di 4 filiali"}]},{"@type":"WebSite","@id":"https:\/\/loginfo24.com\/it\/#website","url":"https:\/\/loginfo24.com\/it\/","name":"Loginfo24","description":"Loginfo24 \u00e8 la piattaforma dedicata alla logistica e alle catene di fornitura con informazioni disponibili 24 ore su 24.","publisher":{"@id":"https:\/\/loginfo24.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/loginfo24.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/loginfo24.com\/it\/#organization","name":"Logismedia Group AG","url":"https:\/\/loginfo24.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/loginfo24.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","width":938,"height":351,"caption":"Logismedia Group AG"},"image":{"@id":"https:\/\/loginfo24.com\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","https:\/\/www.linkedin.com\/company\/lofinfo24\/"]}]}},"_links":{"self":[{"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/posts\/56847","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/comments?post=56847"}],"version-history":[{"count":0,"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/posts\/56847\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/media\/10080"}],"wp:attachment":[{"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/media?parent=56847"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/categories?post=56847"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/tags?post=56847"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}