{"id":56561,"date":"2022-05-24T18:45:37","date_gmt":"2022-05-24T16:45:37","guid":{"rendered":"https:\/\/blog.brand-architecture.at\/2022\/05\/24\/hapag-lloyd-compie-175-anni\/"},"modified":"2022-05-24T18:45:37","modified_gmt":"2022-05-24T16:45:37","slug":"hapag-lloyd-compie-175-anni","status":"publish","type":"post","link":"https:\/\/loginfo24.com\/it\/2022\/05\/24\/hapag-lloyd-compie-175-anni\/","title":{"rendered":"Hapag-Lloyd compie 175 anni"},"content":{"rendered":"<h5><strong>Il 27 maggio di 175 anni fa, armatori e commercianti fondarono la Hamburg-Amerikanische Packetfahrt-Actien-Gesellschaft (Hapag). La Hapag-Lloyd AG \u00e8 nata solo nel 1970 dalla fusione con il Norddeutschen Lloyd di Brema. Sono seguite ulteriori acquisizioni, come Canadian Pacific (2005), CSAV (2014), UASC (2017), NileDutch (2021) e l&#8217;acquisizione prevista della divisione container di DAL (2022). Oggi Hapag-Lloyd \u00e8 la quinta compagnia di navigazione container al mondo e la pi\u00f9 grande compagnia di navigazione della Germania.<\/strong><\/h5>\n<p>(Hamburgo) &#8220;Il nostro anniversario ci riempie di grande orgoglio&#8221;, afferma Rolf Habben Jansen, CEO di Hapag-Lloyd AG. &#8220;Perch\u00e9, come per molte aziende tradizionali, anche la nostra storia \u00e8 caratterizzata da un continuo cambiamento e innovazione. Dalla Hapag, che dal 1848 navigava inizialmente attraverso l&#8217;Atlantico con una sola nave a vela, \u00e8 diventata oggi un&#8217;azienda logistica rinomata e operante a livello internazionale, che serve quasi tutti i grandi porti del mondo.&#8221;<\/p>\n<p>Con la fondazione nel 1847, l&#8217;attivit\u00e0 principale dell&#8217;azienda era il trasporto di posta e passeggeri, in particolare emigranti. Il trasporto merci inizialmente aveva un ruolo secondario. Il direttore generale Albert Ballin (1857-1918) trasform\u00f2 Hapag nella pi\u00f9 grande compagnia di navigazione del mondo, invent\u00f2 la crociera e port\u00f2 il business dell&#8217;emigrazione a un grande successo ad Amburgo. Sebbene la compagnia di navigazione avesse perso praticamente tutte le navi a causa delle due guerre mondiali, riusc\u00ec a risollevarsi ogni volta.<\/p>\n<p>L&#8217;azienda ricorda il cambiamento avvenuto in 175 anni con diverse attivit\u00e0 nel corso dell&#8217;anno, tra cui un convegno scientifico, una festa per i dipendenti ad Amburgo e un congresso. &#8220;Hapag-Lloyd ha tutti i motivi per festeggiare, ma anche per essere grata&#8221;, afferma Rolf Habben Jansen. &#8220;Il nostro ringraziamento va ai nostri oltre 14.000 dipendenti in tutto il mondo, ai nostri clienti, ai nostri proprietari e a tutti coloro che, negli ultimi 175 anni, hanno contribuito a mantenere Hapag-Lloyd sulla giusta rotta e a superare con successo anche i periodi pi\u00f9 difficili.&#8221;<\/p>\n<p>Immagine: \u00a9 Hapag-Lloyd<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il 27 maggio di 175 anni fa, armatori e commercianti fondarono la Hamburg-Amerikanische Packetfahrt-Actien-Gesellschaft (Hapag). La Hapag-Lloyd AG \u00e8 nata solo nel 1970 dalla fusione con<span class=\"excerpt-hellip\"> [\u2026]<\/span><\/p>\n","protected":false},"author":0,"featured_media":10184,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1557,1561,1559],"tags":[],"class_list":["post-56561","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-forwarding-logistics","category-regions","category-shipping-ports"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Hapag-Lloyd compie 175 anni - Loginfo24<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/loginfo24.com\/it\/2022\/05\/24\/hapag-lloyd-compie-175-anni\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Hapag-Lloyd compie 175 anni - Loginfo24\" \/>\n<meta property=\"og:description\" content=\"Il 27 maggio di 175 anni fa, armatori e commercianti fondarono la Hamburg-Amerikanische Packetfahrt-Actien-Gesellschaft (Hapag). La Hapag-Lloyd AG \u00e8 nata solo nel 1970 dalla fusione con [\u2026]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/loginfo24.com\/it\/2022\/05\/24\/hapag-lloyd-compie-175-anni\/\" \/>\n<meta property=\"og:site_name\" content=\"Loginfo24\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/\" \/>\n<meta property=\"article:published_time\" content=\"2022-05-24T16:45:37+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Hapag_25.05.2022.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1964\" \/>\n\t<meta property=\"og:image:height\" content=\"1395\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2022\\\/05\\\/24\\\/hapag-lloyd-compie-175-anni\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2022\\\/05\\\/24\\\/hapag-lloyd-compie-175-anni\\\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Hapag-Lloyd compie 175 anni\",\"datePublished\":\"2022-05-24T16:45:37+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2022\\\/05\\\/24\\\/hapag-lloyd-compie-175-anni\\\/\"},\"wordCount\":309,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2022\\\/05\\\/24\\\/hapag-lloyd-compie-175-anni\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/Hapag_25.05.2022.jpg\",\"articleSection\":[\"Forwarding &amp; Logistics\",\"Regions\",\"Shipping &amp; Ports\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/it\\\/2022\\\/05\\\/24\\\/hapag-lloyd-compie-175-anni\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2022\\\/05\\\/24\\\/hapag-lloyd-compie-175-anni\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2022\\\/05\\\/24\\\/hapag-lloyd-compie-175-anni\\\/\",\"name\":\"Hapag-Lloyd compie 175 anni - Loginfo24\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2022\\\/05\\\/24\\\/hapag-lloyd-compie-175-anni\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2022\\\/05\\\/24\\\/hapag-lloyd-compie-175-anni\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/Hapag_25.05.2022.jpg\",\"datePublished\":\"2022-05-24T16:45:37+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2022\\\/05\\\/24\\\/hapag-lloyd-compie-175-anni\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/it\\\/2022\\\/05\\\/24\\\/hapag-lloyd-compie-175-anni\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2022\\\/05\\\/24\\\/hapag-lloyd-compie-175-anni\\\/#primaryimage\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/Hapag_25.05.2022.jpg\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/Hapag_25.05.2022.jpg\",\"width\":1964,\"height\":1395},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2022\\\/05\\\/24\\\/hapag-lloyd-compie-175-anni\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Hapag-Lloyd compie 175 anni\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/\",\"name\":\"Loginfo24\",\"description\":\"Loginfo24 \u00e8 la piattaforma dedicata alla logistica e alle catene di fornitura con informazioni disponibili 24 ore su 24.\",\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#organization\",\"name\":\"Logismedia Group AG\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"width\":938,\"height\":351,\"caption\":\"Logismedia Group AG\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/people\\\/Loginfo24\\\/100057360583332\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/lofinfo24\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Hapag-Lloyd compie 175 anni - Loginfo24","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/loginfo24.com\/it\/2022\/05\/24\/hapag-lloyd-compie-175-anni\/","og_locale":"it_IT","og_type":"article","og_title":"Hapag-Lloyd compie 175 anni - Loginfo24","og_description":"Il 27 maggio di 175 anni fa, armatori e commercianti fondarono la Hamburg-Amerikanische Packetfahrt-Actien-Gesellschaft (Hapag). La Hapag-Lloyd AG \u00e8 nata solo nel 1970 dalla fusione con [\u2026]","og_url":"https:\/\/loginfo24.com\/it\/2022\/05\/24\/hapag-lloyd-compie-175-anni\/","og_site_name":"Loginfo24","article_publisher":"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","article_published_time":"2022-05-24T16:45:37+00:00","og_image":[{"width":1964,"height":1395,"url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Hapag_25.05.2022.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/loginfo24.com\/it\/2022\/05\/24\/hapag-lloyd-compie-175-anni\/#article","isPartOf":{"@id":"https:\/\/loginfo24.com\/it\/2022\/05\/24\/hapag-lloyd-compie-175-anni\/"},"author":{"name":"","@id":""},"headline":"Hapag-Lloyd compie 175 anni","datePublished":"2022-05-24T16:45:37+00:00","mainEntityOfPage":{"@id":"https:\/\/loginfo24.com\/it\/2022\/05\/24\/hapag-lloyd-compie-175-anni\/"},"wordCount":309,"commentCount":0,"publisher":{"@id":"https:\/\/loginfo24.com\/it\/#organization"},"image":{"@id":"https:\/\/loginfo24.com\/it\/2022\/05\/24\/hapag-lloyd-compie-175-anni\/#primaryimage"},"thumbnailUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Hapag_25.05.2022.jpg","articleSection":["Forwarding &amp; Logistics","Regions","Shipping &amp; Ports"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/loginfo24.com\/it\/2022\/05\/24\/hapag-lloyd-compie-175-anni\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/loginfo24.com\/it\/2022\/05\/24\/hapag-lloyd-compie-175-anni\/","url":"https:\/\/loginfo24.com\/it\/2022\/05\/24\/hapag-lloyd-compie-175-anni\/","name":"Hapag-Lloyd compie 175 anni - Loginfo24","isPartOf":{"@id":"https:\/\/loginfo24.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/loginfo24.com\/it\/2022\/05\/24\/hapag-lloyd-compie-175-anni\/#primaryimage"},"image":{"@id":"https:\/\/loginfo24.com\/it\/2022\/05\/24\/hapag-lloyd-compie-175-anni\/#primaryimage"},"thumbnailUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Hapag_25.05.2022.jpg","datePublished":"2022-05-24T16:45:37+00:00","breadcrumb":{"@id":"https:\/\/loginfo24.com\/it\/2022\/05\/24\/hapag-lloyd-compie-175-anni\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/loginfo24.com\/it\/2022\/05\/24\/hapag-lloyd-compie-175-anni\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/loginfo24.com\/it\/2022\/05\/24\/hapag-lloyd-compie-175-anni\/#primaryimage","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Hapag_25.05.2022.jpg","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Hapag_25.05.2022.jpg","width":1964,"height":1395},{"@type":"BreadcrumbList","@id":"https:\/\/loginfo24.com\/it\/2022\/05\/24\/hapag-lloyd-compie-175-anni\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/loginfo24.com\/it\/"},{"@type":"ListItem","position":2,"name":"Hapag-Lloyd compie 175 anni"}]},{"@type":"WebSite","@id":"https:\/\/loginfo24.com\/it\/#website","url":"https:\/\/loginfo24.com\/it\/","name":"Loginfo24","description":"Loginfo24 \u00e8 la piattaforma dedicata alla logistica e alle catene di fornitura con informazioni disponibili 24 ore su 24.","publisher":{"@id":"https:\/\/loginfo24.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/loginfo24.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/loginfo24.com\/it\/#organization","name":"Logismedia Group AG","url":"https:\/\/loginfo24.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/loginfo24.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","width":938,"height":351,"caption":"Logismedia Group AG"},"image":{"@id":"https:\/\/loginfo24.com\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","https:\/\/www.linkedin.com\/company\/lofinfo24\/"]}]}},"_links":{"self":[{"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/posts\/56561","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/comments?post=56561"}],"version-history":[{"count":0,"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/posts\/56561\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/media\/10184"}],"wp:attachment":[{"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/media?parent=56561"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/categories?post=56561"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/tags?post=56561"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}