{"id":56443,"date":"2022-05-18T20:34:40","date_gmt":"2022-05-18T18:34:40","guid":{"rendered":"https:\/\/blog.brand-architecture.at\/2022\/05\/18\/la-posta-svizzera-con-un-buon-primo-trimestre-2022\/"},"modified":"2022-05-18T20:34:40","modified_gmt":"2022-05-18T18:34:40","slug":"la-posta-svizzera-con-un-buon-primo-trimestre-2022","status":"publish","type":"post","link":"https:\/\/loginfo24.com\/it\/2022\/05\/18\/la-posta-svizzera-con-un-buon-primo-trimestre-2022\/","title":{"rendered":"La Posta Svizzera con un buon primo trimestre 2022"},"content":{"rendered":"<h5><strong>Il risultato del primo trimestre del 2022 della Posta Svizzera \u00e8 migliore rispetto all&#8217;anno precedente. Una parte significativa del miglioramento \u00e8 attribuibile in particolare a PostFinance. Il settore dei servizi logistici ha contribuito maggiormente al risultato del gruppo, nonostante il volume dei pacchi sia diminuito di circa il 10% rispetto all&#8217;anno precedente.<\/strong><\/h5>\n<p>(Berna) La Posta Svizzera \u00e8 complessivamente sulla buona strada e continua a promuovere l&#8217;espansione pianificata delle infrastrutture logistiche e delle competenze digitali. Osserva con grande attenzione l&#8217;attuale contesto, caratterizzato da numerose incertezze e sfide.<\/p>\n<p>Nel primo trimestre del 2022, la Posta Svizzera ha realizzato un utile di gruppo di 159 milioni di franchi, con un incremento di 68 milioni di franchi rispetto allo stesso periodo dell&#8217;anno precedente. Il risultato operativo (EBIT) \u00e8 stato di 145 milioni di franchi, superiore di 64 milioni di franchi rispetto all&#8217;anno precedente. Il fatturato (entrate operative) ha raggiunto 1749 milioni di franchi, ovvero 58 milioni di franchi in pi\u00f9 rispetto a un anno fa. &#8220;La Posta ha iniziato bene l&#8217;anno con il primo trimestre, siamo finanziariamente e strategicamente sulla buona strada&#8221;, afferma Alex Glanzmann, CFO della Posta. &#8220;Tuttavia, il buon risultato non deve farci dimenticare che ci troviamo di fronte a compiti impegnativi.&#8221;<\/p>\n<p>Il buon avvio \u00e8 stato principalmente sostenuto da PostFinance. Sebbene i proventi da interessi sugli investimenti finanziari siano continuati a diminuire a causa del mercato, sono stati compensati da un aumento delle attivit\u00e0 nel mercato interbancario e da commissioni pi\u00f9 elevate sui saldi. Di conseguenza, i proventi da interessi sono stati complessivamente superiori rispetto all&#8217;anno precedente. Anche le commissioni e i servizi hanno registrato un successo maggiore per PostFinance, grazie anche a nuovi prodotti di investimento digitale come la gestione patrimoniale elettronica.<\/p>\n<h5><strong>Il mercato dei pacchi cresce - ma pi\u00f9 lentamente<\/strong><\/h5>\n<p>Mentre il numero di lettere, pari a 471,8 milioni, ha registrato un calo del -1,8% meno marcato rispetto all&#8217;anno precedente, i volumi dei pacchi sono diminuiti significativamente nel primo trimestre rispetto all&#8217;anno precedente. La Posta ha gestito 47,2 milioni di pacchi nel primo trimestre di quest&#8217;anno, il 9,6% in meno rispetto allo stesso periodo del 2021, quando l&#8217;effetto lockdown aveva portato a volumi molto elevati nel commercio online. Le misure contro il COVID-19 sono state per lo pi\u00f9 revocate e le persone tornano a fare acquisti nei negozi. Inoltre, le difficolt\u00e0 di approvvigionamento in Asia e un clima di consumo depresso a causa della guerra in Ucraina hanno contribuito al calo dei volumi dei pacchi. Pertanto, la Posta si aspetta che il mercato dei pacchi si sviluppi pi\u00f9 lentamente nel 2022 rispetto a quanto previsto in precedenza. Nonostante la curva di crescita appiattita, l&#8217;aumento dei volumi continua a lungo termine. La Posta sta quindi continuando a espandere la propria infrastruttura nella lavorazione dei pacchi come pianificato. &#8220;Le capacit\u00e0 aggiuntive sono necessarie affinch\u00e9 possiamo elaborare e consegnare in modo efficiente e sostenibile i volumi di pacchi in crescita a lungo termine&#8221;, afferma il CFO Alex Glanzmann. &#8220;Le fluttuazioni nei volumi e le previsioni incerte riguardo all&#8217;evoluzione economica richiedono una gestione proattiva delle capacit\u00e0 e dei costi.&#8221;<\/p>\n<p>Con un risultato di 109 milioni di franchi, il settore dei servizi logistici ha contribuito maggiormente al risultato positivo del gruppo. Rispetto all&#8217;anno precedente, tuttavia, \u00e8 stato inferiore di 11 milioni di franchi. PostNetz \u00e8 riuscita a mantenere stabile il risultato nonostante il continuo calo delle operazioni allo sportello, mentre i servizi di mobilit\u00e0 hanno aumentato il risultato di 5 milioni di franchi. In PostAuto, si \u00e8 registrata una netta ripresa della domanda, che \u00e8 aumentata a 33,7 milioni di passeggeri, un incremento del 18% rispetto all&#8217;anno precedente. L&#8217;attivit\u00e0 del settore dei servizi di comunicazione \u00e8 ancora in fase di sviluppo e procede come pianificato.<\/p>\n<h5><strong>La Posta si sente confermata nel percorso intrapreso<\/strong><\/h5>\n<p>La sua strategia &#8220;Posta del domani&#8221; viene perseguita con coerenza dalla Posta. Si concentra sullo sviluppo del core business nella logistica e nella comunicazione. Inoltre, punta su partnership, partecipazioni e acquisizioni per ampliare le competenze necessarie. La Posta intende guadagnare autonomamente il denaro necessario per gli investimenti futuri. &#8220;L&#8217;impatto degli investimenti attuali si rifletter\u00e0 con un certo ritardo nei risultati finanziari. Siamo molto fiduciosi di poter raggiungere i nostri obiettivi anche dal punto di vista finanziario entro la fine del periodo strategico&#8221;, afferma il CFO Alex Glanzmann.<\/p>\n<p>L&#8217;ambiente per l&#8217;attuazione della strategia rimane molto impegnativo. Sviluppo del mercato e dei volumi, iniziative politiche, livello dei tassi d&#8217;interesse, prezzi dell&#8217;energia, rischio di inflazione, clima di consumo o catene di approvvigionamento: numerose incertezze caratterizzano attualmente la situazione. L&#8217;agilit\u00e0 e una pianificazione proattiva sono quindi di fondamentale importanza per la Posta. &#8220;Osserviamo l&#8217;ambiente con grande attenzione per poter reagire rapidamente a nuovi sviluppi&#8221;, afferma il CFO Alex Glanzmann.<\/p>\n<p>Foto: \u00a9 Posta Svizzera<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il risultato del primo trimestre del 2022 della Posta Svizzera \u00e8 migliore rispetto all&#8217;anno precedente. Una parte significativa del miglioramento \u00e8 attribuibile in particolare a PostFinance.<span class=\"excerpt-hellip\"> [\u2026]<\/span><\/p>\n","protected":false},"author":0,"featured_media":10228,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1557,1561],"tags":[],"class_list":["post-56443","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-forwarding-logistics","category-regions"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La Posta Svizzera con un buon primo trimestre 2022 - Loginfo24<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/loginfo24.com\/it\/2022\/05\/18\/la-posta-svizzera-con-un-buon-primo-trimestre-2022\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La Posta Svizzera con un buon primo trimestre 2022 - Loginfo24\" \/>\n<meta property=\"og:description\" content=\"Il risultato del primo trimestre del 2022 della Posta Svizzera \u00e8 migliore rispetto all&#8217;anno precedente. Una parte significativa del miglioramento \u00e8 attribuibile in particolare a PostFinance. [\u2026]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/loginfo24.com\/it\/2022\/05\/18\/la-posta-svizzera-con-un-buon-primo-trimestre-2022\/\" \/>\n<meta property=\"og:site_name\" content=\"Loginfo24\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/\" \/>\n<meta property=\"article:published_time\" content=\"2022-05-18T18:34:40+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Post_CH_18.5.22.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1369\" \/>\n\t<meta property=\"og:image:height\" content=\"709\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2022\\\/05\\\/18\\\/la-posta-svizzera-con-un-buon-primo-trimestre-2022\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2022\\\/05\\\/18\\\/la-posta-svizzera-con-un-buon-primo-trimestre-2022\\\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"La Posta Svizzera con un buon primo trimestre 2022\",\"datePublished\":\"2022-05-18T18:34:40+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2022\\\/05\\\/18\\\/la-posta-svizzera-con-un-buon-primo-trimestre-2022\\\/\"},\"wordCount\":780,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2022\\\/05\\\/18\\\/la-posta-svizzera-con-un-buon-primo-trimestre-2022\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/Post_CH_18.5.22.jpg\",\"articleSection\":[\"Forwarding &amp; Logistics\",\"Regions\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/it\\\/2022\\\/05\\\/18\\\/la-posta-svizzera-con-un-buon-primo-trimestre-2022\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2022\\\/05\\\/18\\\/la-posta-svizzera-con-un-buon-primo-trimestre-2022\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2022\\\/05\\\/18\\\/la-posta-svizzera-con-un-buon-primo-trimestre-2022\\\/\",\"name\":\"La Posta Svizzera con un buon primo trimestre 2022 - Loginfo24\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2022\\\/05\\\/18\\\/la-posta-svizzera-con-un-buon-primo-trimestre-2022\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2022\\\/05\\\/18\\\/la-posta-svizzera-con-un-buon-primo-trimestre-2022\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/Post_CH_18.5.22.jpg\",\"datePublished\":\"2022-05-18T18:34:40+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2022\\\/05\\\/18\\\/la-posta-svizzera-con-un-buon-primo-trimestre-2022\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/it\\\/2022\\\/05\\\/18\\\/la-posta-svizzera-con-un-buon-primo-trimestre-2022\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2022\\\/05\\\/18\\\/la-posta-svizzera-con-un-buon-primo-trimestre-2022\\\/#primaryimage\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/Post_CH_18.5.22.jpg\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/Post_CH_18.5.22.jpg\",\"width\":1369,\"height\":709},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2022\\\/05\\\/18\\\/la-posta-svizzera-con-un-buon-primo-trimestre-2022\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La Posta Svizzera con un buon primo trimestre 2022\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/\",\"name\":\"Loginfo24\",\"description\":\"Loginfo24 \u00e8 la piattaforma dedicata alla logistica e alle catene di fornitura con informazioni disponibili 24 ore su 24.\",\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#organization\",\"name\":\"Logismedia Group AG\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"width\":938,\"height\":351,\"caption\":\"Logismedia Group AG\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/people\\\/Loginfo24\\\/100057360583332\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/lofinfo24\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La Posta Svizzera con un buon primo trimestre 2022 - Loginfo24","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/loginfo24.com\/it\/2022\/05\/18\/la-posta-svizzera-con-un-buon-primo-trimestre-2022\/","og_locale":"it_IT","og_type":"article","og_title":"La Posta Svizzera con un buon primo trimestre 2022 - Loginfo24","og_description":"Il risultato del primo trimestre del 2022 della Posta Svizzera \u00e8 migliore rispetto all&#8217;anno precedente. Una parte significativa del miglioramento \u00e8 attribuibile in particolare a PostFinance. [\u2026]","og_url":"https:\/\/loginfo24.com\/it\/2022\/05\/18\/la-posta-svizzera-con-un-buon-primo-trimestre-2022\/","og_site_name":"Loginfo24","article_publisher":"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","article_published_time":"2022-05-18T18:34:40+00:00","og_image":[{"width":1369,"height":709,"url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Post_CH_18.5.22.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"4 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/loginfo24.com\/it\/2022\/05\/18\/la-posta-svizzera-con-un-buon-primo-trimestre-2022\/#article","isPartOf":{"@id":"https:\/\/loginfo24.com\/it\/2022\/05\/18\/la-posta-svizzera-con-un-buon-primo-trimestre-2022\/"},"author":{"name":"","@id":""},"headline":"La Posta Svizzera con un buon primo trimestre 2022","datePublished":"2022-05-18T18:34:40+00:00","mainEntityOfPage":{"@id":"https:\/\/loginfo24.com\/it\/2022\/05\/18\/la-posta-svizzera-con-un-buon-primo-trimestre-2022\/"},"wordCount":780,"commentCount":0,"publisher":{"@id":"https:\/\/loginfo24.com\/it\/#organization"},"image":{"@id":"https:\/\/loginfo24.com\/it\/2022\/05\/18\/la-posta-svizzera-con-un-buon-primo-trimestre-2022\/#primaryimage"},"thumbnailUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Post_CH_18.5.22.jpg","articleSection":["Forwarding &amp; Logistics","Regions"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/loginfo24.com\/it\/2022\/05\/18\/la-posta-svizzera-con-un-buon-primo-trimestre-2022\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/loginfo24.com\/it\/2022\/05\/18\/la-posta-svizzera-con-un-buon-primo-trimestre-2022\/","url":"https:\/\/loginfo24.com\/it\/2022\/05\/18\/la-posta-svizzera-con-un-buon-primo-trimestre-2022\/","name":"La Posta Svizzera con un buon primo trimestre 2022 - Loginfo24","isPartOf":{"@id":"https:\/\/loginfo24.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/loginfo24.com\/it\/2022\/05\/18\/la-posta-svizzera-con-un-buon-primo-trimestre-2022\/#primaryimage"},"image":{"@id":"https:\/\/loginfo24.com\/it\/2022\/05\/18\/la-posta-svizzera-con-un-buon-primo-trimestre-2022\/#primaryimage"},"thumbnailUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Post_CH_18.5.22.jpg","datePublished":"2022-05-18T18:34:40+00:00","breadcrumb":{"@id":"https:\/\/loginfo24.com\/it\/2022\/05\/18\/la-posta-svizzera-con-un-buon-primo-trimestre-2022\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/loginfo24.com\/it\/2022\/05\/18\/la-posta-svizzera-con-un-buon-primo-trimestre-2022\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/loginfo24.com\/it\/2022\/05\/18\/la-posta-svizzera-con-un-buon-primo-trimestre-2022\/#primaryimage","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Post_CH_18.5.22.jpg","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Post_CH_18.5.22.jpg","width":1369,"height":709},{"@type":"BreadcrumbList","@id":"https:\/\/loginfo24.com\/it\/2022\/05\/18\/la-posta-svizzera-con-un-buon-primo-trimestre-2022\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/loginfo24.com\/it\/"},{"@type":"ListItem","position":2,"name":"La Posta Svizzera con un buon primo trimestre 2022"}]},{"@type":"WebSite","@id":"https:\/\/loginfo24.com\/it\/#website","url":"https:\/\/loginfo24.com\/it\/","name":"Loginfo24","description":"Loginfo24 \u00e8 la piattaforma dedicata alla logistica e alle catene di fornitura con informazioni disponibili 24 ore su 24.","publisher":{"@id":"https:\/\/loginfo24.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/loginfo24.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/loginfo24.com\/it\/#organization","name":"Logismedia Group AG","url":"https:\/\/loginfo24.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/loginfo24.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","width":938,"height":351,"caption":"Logismedia Group AG"},"image":{"@id":"https:\/\/loginfo24.com\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","https:\/\/www.linkedin.com\/company\/lofinfo24\/"]}]}},"_links":{"self":[{"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/posts\/56443","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/comments?post=56443"}],"version-history":[{"count":0,"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/posts\/56443\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/media\/10228"}],"wp:attachment":[{"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/media?parent=56443"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/categories?post=56443"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/tags?post=56443"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}