{"id":56359,"date":"2022-05-15T21:20:30","date_gmt":"2022-05-15T19:20:30","guid":{"rendered":"https:\/\/blog.brand-architecture.at\/2022\/05\/15\/il-ministro-federale-wissing-si-confronta-con-traton-group\/"},"modified":"2022-05-15T21:20:30","modified_gmt":"2022-05-15T19:20:30","slug":"il-ministro-federale-wissing-si-confronta-con-traton-group","status":"publish","type":"post","link":"https:\/\/loginfo24.com\/it\/2022\/05\/15\/il-ministro-federale-wissing-si-confronta-con-traton-group\/","title":{"rendered":"Il Ministro Federale Wissing si confronta con TRATON GROUP"},"content":{"rendered":"<p><strong>Il Dr. Volker Wissing, Ministro Federale per la Digitalizzazione e i Trasporti, e Bernd Osterloh, Direttore delle Risorse Umane di TRATON GROUP, si sono confrontati a Berlino in occasione di un evento sul trasporto del futuro e sulla necessit\u00e0 di un rapido sviluppo dell&#8217;infrastruttura di ricarica per i veicoli commerciali. Wissing e Osterloh hanno concordato che la creazione di una rete di ricarica a livello europeo ha un&#8217;alta priorit\u00e0 per il raggiungimento degli obiettivi di protezione climatica dell&#8217;Unione Europea.<\/strong> <\/p>\n<p> (Berlino) &#8220;I camion elettrici a batteria per il trasporto a lungo raggio offrono grandi opportunit\u00e0 per il raggiungimento degli obiettivi di protezione climatica nel settore dei trasporti e per l&#8217;indipendenza dai combustibili fossili. Gi\u00e0 i primi 100.000 camion elettrici potrebbero risparmiare circa dieci milioni di tonnellate di CO2 all&#8217;anno&#8221;, ha dichiarato Osterloh durante il confronto con il Ministro Federale. Osterloh ha spiegato che TRATON GROUP, con i suoi marchi Scania, MAN Truck &amp; Bus, Navistar e Volkswagen Caminh\u00f5es e \u00d4nibus, offre gi\u00e0 a livello mondiale camion, autobus e furgoni elettrici a batteria in serie. I progressi nella tecnologia delle batterie consentiranno, secondo le stime di TRATON GROUP, di raggiungere gi\u00e0 nei prossimi anni autonomie fino a 1.000 chilometri con una sola carica. I tempi di ricarica sono significativamente inferiori a un&#8217;ora, rendendo possibile la ricarica durante le pause obbligatorie previste dalla legge in Europa. &#8220;In questo modo, la mobilit\u00e0 elettrica diventa finalmente adatta per il trasporto a lungo raggio e anche per il mercato di massa&#8221;, ha affermato Osterloh. <\/p>\n<p> <strong>Joint Venture per l&#8217;espansione dell&#8217;infrastruttura di ricarica<\/strong> <\/p>\n<p> Finora manca in Europa l&#8217;infrastruttura di ricarica necessaria per i veicoli commerciali elettrici a lungo raggio. Per dare una spinta iniziale, TRATON GROUP, insieme a Volvo Group e Daimler Truck, sta pianificando una joint venture che, entro cinque anni dalla sua fondazione, intende costruire e gestire almeno 1.700 punti di ricarica ad alta potenza per energia verde in prossimit\u00e0 delle autostrade, nonch\u00e9 presso hub logistici e punti di scarico. Per la joint venture \u00e8 necessaria ancora l&#8217;approvazione delle autorit\u00e0 antitrust. &#8220;Speriamo in una conclusione rapida delle verifiche da parte delle autorit\u00e0, in modo da poter finalmente avviare la joint venture&#8221;, ha dichiarato Osterloh. Con un investimento di 500 milioni di euro, i tre produttori di veicoli commerciali intendono anticipare i costi per la costruzione dell&#8217;infrastruttura nella joint venture. <\/p>\n<p> <strong>Richiesta di supporto dalla politica<\/strong> <\/p>\n<p> Osterloh ha sottolineato che, oltre alla rete pianificata dalla joint venture, \u00e8 necessaria anche un&#8217;assistenza statale e un chiaro segnale da parte della politica, non da ultimo per costruire fiducia con altri Stati membri dell&#8217;UE e con i trasportatori. Questo dovrebbe includere, ad esempio, l&#8217;annuncio del governo federale per la creazione di una rete di ricarica per camion in Germania, analogamente alla rete gi\u00e0 approvata per le auto. &#8220;Lo Stato ha un ruolo particolare, poich\u00e9 molte delle aree necessarie lungo le autostrade non possono essere riconvertite per la costruzione di punti di ricarica per camion senza un intervento statale&#8221;, ha affermato il membro del consiglio di TRATON, Osterloh, aggiungendo: &#8220;Ora \u00e8 la politica a dover promuovere l&#8217;espansione dell&#8217;infrastruttura di ricarica necessaria per garantire il successo della mobilit\u00e0 elettrica anche per i camion pesanti.&#8221; <\/p>\n<p> Il confronto tra Wissing e Osterloh si \u00e8 svolto prima di un evento presso il vecchio aeroporto di Berlino-Tempelhof. Qui, il marchio TRATON MAN Truck &amp; Bus presenter\u00e0 il primo prototipo di camion elettrico a batteria per il trasporto a lungo raggio, il MAN eTGX, che dovrebbe arrivare sul mercato all&#8217;inizio del 2024. <\/p>\n<p> <strong>MAN e ABB in prima linea<\/strong> <\/p>\n<p> In una discussione con il Ministro dei Trasporti Wissing e Kristin Kahl, il cui trasportatore Contargo ha gi\u00e0 accumulato esperienze nell&#8217;uso di camion elettrici, i CEO di MAN Truck &amp; Bus SE, Alexander Vlaskamp, e ABB E-mobility, Frank M\u00fchlon, hanno sottolineato che l&#8217;industria \u00e8 pronta per la trasformazione verso i camion elettrici. MAN, come produttore di veicoli commerciali, e ABB E-mobility, come fornitore di stazioni di ricarica, hanno gi\u00e0 preso le loro decisioni di investimento in veicoli elettrici a batteria e reti di ricarica, ora servono linee guida politiche. <\/p>\n<p> Il CEO di MAN, Alexander Vlaskamp: &#8220;Siamo pronti. Ma la trasformazione verso tecnologie a zero emissioni avverr\u00e0 solo se la politica investir\u00e0 massicciamente nella costruzione di una rete di infrastrutture di ricarica affidabile per veicoli commerciali pesanti. L&#8217;accelerazione dell&#8217;espansione dell&#8217;infrastruttura di ricarica \u00e8 l&#8217;unico modo per realizzare la transizione dei trasporti e raggiungere gli obiettivi climatici.&#8221; <\/p>\n<p> <strong>Decarbonizzazione del trasporto merci su strada<\/strong> <\/p>\n<p> Il Ministro Federale Wissing si \u00e8 detto impressionato dall&#8217;evento: &#8220;Per raggiungere i nostri obiettivi climatici, dobbiamo decarbonizzare il trasporto merci su strada. Puntiamo soprattutto sulla crescita del mercato di veicoli commerciali ecologici e sulla costruzione di un&#8217;infrastruttura di ricarica ad alta potenza corrispondente. \u00c8 importante ora portare rapidamente pi\u00f9 camion elettrici sulle strade. La cooperazione tra MAN e ABB dimostra che siamo sulla buona strada.&#8221; <\/p>\n<p> Foto: \u00a9 Traton \/ <strong>Didascalia:<\/strong> <em>Alexander Vlaskamp, CEO di MAN, Dr. Volker Wissing, Ministro Federale dei Trasporti, Frank M\u00fchlon, CEO di ABB E-mobility, Bernd Osterloh, Direttore delle Risorse Umane di TRATON e Dr. Frederik Zohm, membro del consiglio per Ricerca e Sviluppo di MAN.<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il Dr. Volker Wissing, Ministro Federale per la Digitalizzazione e i Trasporti, e Bernd Osterloh, Direttore delle Risorse Umane di TRATON GROUP, si sono confrontati a<span class=\"excerpt-hellip\"> [\u2026]<\/span><\/p>\n","protected":false},"author":0,"featured_media":10261,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1665,1557,1556,1561],"tags":[],"class_list":["post-56359","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-categories","category-forwarding-logistics","category-intermodal-road","category-regions"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Il Ministro Federale Wissing si confronta con TRATON GROUP - Loginfo24<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/loginfo24.com\/it\/2022\/05\/15\/il-ministro-federale-wissing-si-confronta-con-traton-group\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Il Ministro Federale Wissing si confronta con TRATON GROUP - Loginfo24\" \/>\n<meta property=\"og:description\" content=\"Il Dr. Volker Wissing, Ministro Federale per la Digitalizzazione e i Trasporti, e Bernd Osterloh, Direttore delle Risorse Umane di TRATON GROUP, si sono confrontati a [\u2026]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/loginfo24.com\/it\/2022\/05\/15\/il-ministro-federale-wissing-si-confronta-con-traton-group\/\" \/>\n<meta property=\"og:site_name\" content=\"Loginfo24\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/\" \/>\n<meta property=\"article:published_time\" content=\"2022-05-15T19:20:30+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Traton_16.05.2022.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1478\" \/>\n\t<meta property=\"og:image:height\" content=\"1014\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2022\\\/05\\\/15\\\/il-ministro-federale-wissing-si-confronta-con-traton-group\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2022\\\/05\\\/15\\\/il-ministro-federale-wissing-si-confronta-con-traton-group\\\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Il Ministro Federale Wissing si confronta con TRATON GROUP\",\"datePublished\":\"2022-05-15T19:20:30+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2022\\\/05\\\/15\\\/il-ministro-federale-wissing-si-confronta-con-traton-group\\\/\"},\"wordCount\":862,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2022\\\/05\\\/15\\\/il-ministro-federale-wissing-si-confronta-con-traton-group\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/Traton_16.05.2022.jpg\",\"articleSection\":[\"Categories\",\"Forwarding &amp; Logistics\",\"Intermodal \\\/ Road\",\"Regions\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/it\\\/2022\\\/05\\\/15\\\/il-ministro-federale-wissing-si-confronta-con-traton-group\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2022\\\/05\\\/15\\\/il-ministro-federale-wissing-si-confronta-con-traton-group\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2022\\\/05\\\/15\\\/il-ministro-federale-wissing-si-confronta-con-traton-group\\\/\",\"name\":\"Il Ministro Federale Wissing si confronta con TRATON GROUP - Loginfo24\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2022\\\/05\\\/15\\\/il-ministro-federale-wissing-si-confronta-con-traton-group\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2022\\\/05\\\/15\\\/il-ministro-federale-wissing-si-confronta-con-traton-group\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/Traton_16.05.2022.jpg\",\"datePublished\":\"2022-05-15T19:20:30+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2022\\\/05\\\/15\\\/il-ministro-federale-wissing-si-confronta-con-traton-group\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/it\\\/2022\\\/05\\\/15\\\/il-ministro-federale-wissing-si-confronta-con-traton-group\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2022\\\/05\\\/15\\\/il-ministro-federale-wissing-si-confronta-con-traton-group\\\/#primaryimage\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/Traton_16.05.2022.jpg\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/Traton_16.05.2022.jpg\",\"width\":1478,\"height\":1014},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2022\\\/05\\\/15\\\/il-ministro-federale-wissing-si-confronta-con-traton-group\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Il Ministro Federale Wissing si confronta con TRATON GROUP\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/\",\"name\":\"Loginfo24\",\"description\":\"Loginfo24 \u00e8 la piattaforma dedicata alla logistica e alle catene di fornitura con informazioni disponibili 24 ore su 24.\",\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#organization\",\"name\":\"Logismedia Group AG\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"width\":938,\"height\":351,\"caption\":\"Logismedia Group AG\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/people\\\/Loginfo24\\\/100057360583332\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/lofinfo24\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Il Ministro Federale Wissing si confronta con TRATON GROUP - Loginfo24","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/loginfo24.com\/it\/2022\/05\/15\/il-ministro-federale-wissing-si-confronta-con-traton-group\/","og_locale":"it_IT","og_type":"article","og_title":"Il Ministro Federale Wissing si confronta con TRATON GROUP - Loginfo24","og_description":"Il Dr. Volker Wissing, Ministro Federale per la Digitalizzazione e i Trasporti, e Bernd Osterloh, Direttore delle Risorse Umane di TRATON GROUP, si sono confrontati a [\u2026]","og_url":"https:\/\/loginfo24.com\/it\/2022\/05\/15\/il-ministro-federale-wissing-si-confronta-con-traton-group\/","og_site_name":"Loginfo24","article_publisher":"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","article_published_time":"2022-05-15T19:20:30+00:00","og_image":[{"width":1478,"height":1014,"url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Traton_16.05.2022.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"4 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/loginfo24.com\/it\/2022\/05\/15\/il-ministro-federale-wissing-si-confronta-con-traton-group\/#article","isPartOf":{"@id":"https:\/\/loginfo24.com\/it\/2022\/05\/15\/il-ministro-federale-wissing-si-confronta-con-traton-group\/"},"author":{"name":"","@id":""},"headline":"Il Ministro Federale Wissing si confronta con TRATON GROUP","datePublished":"2022-05-15T19:20:30+00:00","mainEntityOfPage":{"@id":"https:\/\/loginfo24.com\/it\/2022\/05\/15\/il-ministro-federale-wissing-si-confronta-con-traton-group\/"},"wordCount":862,"commentCount":0,"publisher":{"@id":"https:\/\/loginfo24.com\/it\/#organization"},"image":{"@id":"https:\/\/loginfo24.com\/it\/2022\/05\/15\/il-ministro-federale-wissing-si-confronta-con-traton-group\/#primaryimage"},"thumbnailUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Traton_16.05.2022.jpg","articleSection":["Categories","Forwarding &amp; Logistics","Intermodal \/ Road","Regions"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/loginfo24.com\/it\/2022\/05\/15\/il-ministro-federale-wissing-si-confronta-con-traton-group\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/loginfo24.com\/it\/2022\/05\/15\/il-ministro-federale-wissing-si-confronta-con-traton-group\/","url":"https:\/\/loginfo24.com\/it\/2022\/05\/15\/il-ministro-federale-wissing-si-confronta-con-traton-group\/","name":"Il Ministro Federale Wissing si confronta con TRATON GROUP - Loginfo24","isPartOf":{"@id":"https:\/\/loginfo24.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/loginfo24.com\/it\/2022\/05\/15\/il-ministro-federale-wissing-si-confronta-con-traton-group\/#primaryimage"},"image":{"@id":"https:\/\/loginfo24.com\/it\/2022\/05\/15\/il-ministro-federale-wissing-si-confronta-con-traton-group\/#primaryimage"},"thumbnailUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Traton_16.05.2022.jpg","datePublished":"2022-05-15T19:20:30+00:00","breadcrumb":{"@id":"https:\/\/loginfo24.com\/it\/2022\/05\/15\/il-ministro-federale-wissing-si-confronta-con-traton-group\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/loginfo24.com\/it\/2022\/05\/15\/il-ministro-federale-wissing-si-confronta-con-traton-group\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/loginfo24.com\/it\/2022\/05\/15\/il-ministro-federale-wissing-si-confronta-con-traton-group\/#primaryimage","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Traton_16.05.2022.jpg","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Traton_16.05.2022.jpg","width":1478,"height":1014},{"@type":"BreadcrumbList","@id":"https:\/\/loginfo24.com\/it\/2022\/05\/15\/il-ministro-federale-wissing-si-confronta-con-traton-group\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/loginfo24.com\/it\/"},{"@type":"ListItem","position":2,"name":"Il Ministro Federale Wissing si confronta con TRATON GROUP"}]},{"@type":"WebSite","@id":"https:\/\/loginfo24.com\/it\/#website","url":"https:\/\/loginfo24.com\/it\/","name":"Loginfo24","description":"Loginfo24 \u00e8 la piattaforma dedicata alla logistica e alle catene di fornitura con informazioni disponibili 24 ore su 24.","publisher":{"@id":"https:\/\/loginfo24.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/loginfo24.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/loginfo24.com\/it\/#organization","name":"Logismedia Group AG","url":"https:\/\/loginfo24.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/loginfo24.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","width":938,"height":351,"caption":"Logismedia Group AG"},"image":{"@id":"https:\/\/loginfo24.com\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","https:\/\/www.linkedin.com\/company\/lofinfo24\/"]}]}},"_links":{"self":[{"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/posts\/56359","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/comments?post=56359"}],"version-history":[{"count":0,"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/posts\/56359\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/media\/10261"}],"wp:attachment":[{"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/media?parent=56359"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/categories?post=56359"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/tags?post=56359"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}