{"id":56295,"date":"2022-05-11T18:48:20","date_gmt":"2022-05-11T16:48:20","guid":{"rendered":"https:\/\/blog.brand-architecture.at\/2022\/05\/11\/efrexx-e-magic-software-enterprises-concordano-una-cooperazione\/"},"modified":"2022-05-11T18:48:20","modified_gmt":"2022-05-11T16:48:20","slug":"efrexx-e-magic-software-enterprises-concordano-una-cooperazione","status":"publish","type":"post","link":"https:\/\/loginfo24.com\/it\/2022\/05\/11\/efrexx-e-magic-software-enterprises-concordano-una-cooperazione\/","title":{"rendered":"eFrexx e Magic Software Enterprises concordano una cooperazione"},"content":{"rendered":"<h5><strong>La eFrexx GmbH di D\u00fcsseldorf amplia il proprio portafoglio di soluzioni nell&#8217;ambito di una partnership con la Magic Software Enterprises (Deutschland) GmbH, introducendo una piattaforma di integrazione e digitalizzazione. I clienti della piattaforma cloud personalizzata per i servizi di trasporto beneficiano dell&#8217;integrazione senza soluzione di continuit\u00e0 dei loro sistemi aziendali.<\/strong><\/h5>\n<p>(Ratingen) &#8220;Nella logistica si ricorre spesso all&#8217;approccio cosiddetto Best-of-Breed: viene acquisito il software pi\u00f9 adatto per il rispettivo caso d&#8217;uso. Se la comunicazione senza perdite con gli altri sistemi in azienda sia garantita, gioca un ruolo secondario&#8221;, afferma Achim Quaken, fondatore e CEO di eFrexx. Ne derivano incompatibilit\u00e0 che creano silos di dati e, in ultima analisi, complicano o addirittura bloccano i processi lavorativi.<\/p>\n<p>Per poter sfruttare appieno le potenzialit\u00e0 della digitalizzazione, sono quindi necessarie soluzioni di integrazione su misura. \u00c8 a questo punto che si inserisce la nuova partnership tra eFrexx e Magic Software Enterprises (MSE). I clienti della piattaforma di gara possono ora allineare i flussi di dati dei loro sistemi grazie alla piattaforma di digitalizzazione Magic xpi. Lo strumento di integrazione si distingue non solo per un elevato grado di connettivit\u00e0, ma supporta anche soluzioni basate su cloud e server, nonch\u00e9 implementazioni ibride. Cos\u00ec come in eFrexx, il controllo dei dati rimane nelle mani dei committenti, in modo che possano essere rispettati tutti i requisiti relativi alla protezione dei dati e alle normative di conformit\u00e0.<\/p>\n<div id=\"attachment_19162\" style=\"width: 1349px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-19162\" class=\"wp-image-19162 size-full\" src=\"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/eFrexx_11.5.22_1.jpg\" alt=\"\" width=\"1339\" height=\"977\" \/><p id=\"caption-attachment-19162\" class=\"wp-caption-text\">Soluzioni di integrazione su misura: \u00c8 a questo punto che si inserisce la nuova partnership tra eFrexx e MSE (\u00a9 MSE)<\/p><\/div>\n<h5><strong>Le piattaforme si completano a vicenda<\/strong><\/h5>\n<p>Stephan Romeder, amministratore delegato di Magic Software Enterprises (Deutschland) GmbH &amp; VP Global Business Development: &#8220;Siamo molto felici della partnership con eFrexx \u2013 un esperto cos\u00ec competente ed esperto nel settore della logistica. La piattaforma cloud per i servizi di trasporto di eFrexx e la nostra piattaforma di digitalizzazione Magic xpi si completano a vicenda e offriranno ai nostri clienti comuni vantaggi competitivi rilevanti grazie allo scambio di dati fluido e ai processi automatizzati.&#8221;<\/p>\n<h5><strong>Creare un paesaggio sistemico su misura<\/strong><\/h5>\n<p>In particolare, le PMI saranno in grado di creare un paesaggio sistemico tecnicamente su misura a costi relativamente contenuti grazie alla collaborazione tra le due aziende. Quaken: &#8220;La programmazione complessa delle interfacce appartiene ormai al passato. Questo allevia i reparti IT e fa risparmiare denaro.&#8221;<\/p>\n<p>Foto: \u00a9 eFrexx \/ <strong><em>Didascalia dell&#8217;immagine:<\/em> <\/strong><em>La eFrexx GmbH collaborer\u00e0 in futuro con la Magic Software Enterprises (Deutschland) GmbH. I clienti di eFrexx beneficiano dell&#8217;integrazione senza soluzione di continuit\u00e0 dei loro sistemi aziendali e dell&#8217;automazione di tutti i processi aziendali necessari.<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La eFrexx GmbH di D\u00fcsseldorf amplia il proprio portafoglio di soluzioni nell&#8217;ambito di una partnership con la Magic Software Enterprises (Deutschland) GmbH, introducendo una piattaforma di<span class=\"excerpt-hellip\"> [\u2026]<\/span><\/p>\n","protected":false},"author":0,"featured_media":10293,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1665,1557,1561],"tags":[],"class_list":["post-56295","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-categories","category-forwarding-logistics","category-regions"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>eFrexx e Magic Software Enterprises concordano una cooperazione - Loginfo24<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/loginfo24.com\/it\/2022\/05\/11\/efrexx-e-magic-software-enterprises-concordano-una-cooperazione\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"eFrexx e Magic Software Enterprises concordano una cooperazione - Loginfo24\" \/>\n<meta property=\"og:description\" content=\"La eFrexx GmbH di D\u00fcsseldorf amplia il proprio portafoglio di soluzioni nell&#8217;ambito di una partnership con la Magic Software Enterprises (Deutschland) GmbH, introducendo una piattaforma di [\u2026]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/loginfo24.com\/it\/2022\/05\/11\/efrexx-e-magic-software-enterprises-concordano-una-cooperazione\/\" \/>\n<meta property=\"og:site_name\" content=\"Loginfo24\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/\" \/>\n<meta property=\"article:published_time\" content=\"2022-05-11T16:48:20+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/eFrexx_11.5.22.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1231\" \/>\n\t<meta property=\"og:image:height\" content=\"779\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2022\\\/05\\\/11\\\/efrexx-e-magic-software-enterprises-concordano-una-cooperazione\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2022\\\/05\\\/11\\\/efrexx-e-magic-software-enterprises-concordano-una-cooperazione\\\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"eFrexx e Magic Software Enterprises concordano una cooperazione\",\"datePublished\":\"2022-05-11T16:48:20+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2022\\\/05\\\/11\\\/efrexx-e-magic-software-enterprises-concordano-una-cooperazione\\\/\"},\"wordCount\":438,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2022\\\/05\\\/11\\\/efrexx-e-magic-software-enterprises-concordano-una-cooperazione\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/eFrexx_11.5.22.jpg\",\"articleSection\":[\"Categories\",\"Forwarding &amp; Logistics\",\"Regions\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/it\\\/2022\\\/05\\\/11\\\/efrexx-e-magic-software-enterprises-concordano-una-cooperazione\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2022\\\/05\\\/11\\\/efrexx-e-magic-software-enterprises-concordano-una-cooperazione\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2022\\\/05\\\/11\\\/efrexx-e-magic-software-enterprises-concordano-una-cooperazione\\\/\",\"name\":\"eFrexx e Magic Software Enterprises concordano una cooperazione - Loginfo24\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2022\\\/05\\\/11\\\/efrexx-e-magic-software-enterprises-concordano-una-cooperazione\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2022\\\/05\\\/11\\\/efrexx-e-magic-software-enterprises-concordano-una-cooperazione\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/eFrexx_11.5.22.jpg\",\"datePublished\":\"2022-05-11T16:48:20+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2022\\\/05\\\/11\\\/efrexx-e-magic-software-enterprises-concordano-una-cooperazione\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/it\\\/2022\\\/05\\\/11\\\/efrexx-e-magic-software-enterprises-concordano-una-cooperazione\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2022\\\/05\\\/11\\\/efrexx-e-magic-software-enterprises-concordano-una-cooperazione\\\/#primaryimage\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/eFrexx_11.5.22.jpg\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/eFrexx_11.5.22.jpg\",\"width\":1231,\"height\":779},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2022\\\/05\\\/11\\\/efrexx-e-magic-software-enterprises-concordano-una-cooperazione\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"eFrexx e Magic Software Enterprises concordano una cooperazione\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/\",\"name\":\"Loginfo24\",\"description\":\"Loginfo24 \u00e8 la piattaforma dedicata alla logistica e alle catene di fornitura con informazioni disponibili 24 ore su 24.\",\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#organization\",\"name\":\"Logismedia Group AG\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"width\":938,\"height\":351,\"caption\":\"Logismedia Group AG\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/people\\\/Loginfo24\\\/100057360583332\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/lofinfo24\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"eFrexx e Magic Software Enterprises concordano una cooperazione - Loginfo24","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/loginfo24.com\/it\/2022\/05\/11\/efrexx-e-magic-software-enterprises-concordano-una-cooperazione\/","og_locale":"it_IT","og_type":"article","og_title":"eFrexx e Magic Software Enterprises concordano una cooperazione - Loginfo24","og_description":"La eFrexx GmbH di D\u00fcsseldorf amplia il proprio portafoglio di soluzioni nell&#8217;ambito di una partnership con la Magic Software Enterprises (Deutschland) GmbH, introducendo una piattaforma di [\u2026]","og_url":"https:\/\/loginfo24.com\/it\/2022\/05\/11\/efrexx-e-magic-software-enterprises-concordano-una-cooperazione\/","og_site_name":"Loginfo24","article_publisher":"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","article_published_time":"2022-05-11T16:48:20+00:00","og_image":[{"width":1231,"height":779,"url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/eFrexx_11.5.22.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"2 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/loginfo24.com\/it\/2022\/05\/11\/efrexx-e-magic-software-enterprises-concordano-una-cooperazione\/#article","isPartOf":{"@id":"https:\/\/loginfo24.com\/it\/2022\/05\/11\/efrexx-e-magic-software-enterprises-concordano-una-cooperazione\/"},"author":{"name":"","@id":""},"headline":"eFrexx e Magic Software Enterprises concordano una cooperazione","datePublished":"2022-05-11T16:48:20+00:00","mainEntityOfPage":{"@id":"https:\/\/loginfo24.com\/it\/2022\/05\/11\/efrexx-e-magic-software-enterprises-concordano-una-cooperazione\/"},"wordCount":438,"commentCount":0,"publisher":{"@id":"https:\/\/loginfo24.com\/it\/#organization"},"image":{"@id":"https:\/\/loginfo24.com\/it\/2022\/05\/11\/efrexx-e-magic-software-enterprises-concordano-una-cooperazione\/#primaryimage"},"thumbnailUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/eFrexx_11.5.22.jpg","articleSection":["Categories","Forwarding &amp; Logistics","Regions"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/loginfo24.com\/it\/2022\/05\/11\/efrexx-e-magic-software-enterprises-concordano-una-cooperazione\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/loginfo24.com\/it\/2022\/05\/11\/efrexx-e-magic-software-enterprises-concordano-una-cooperazione\/","url":"https:\/\/loginfo24.com\/it\/2022\/05\/11\/efrexx-e-magic-software-enterprises-concordano-una-cooperazione\/","name":"eFrexx e Magic Software Enterprises concordano una cooperazione - Loginfo24","isPartOf":{"@id":"https:\/\/loginfo24.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/loginfo24.com\/it\/2022\/05\/11\/efrexx-e-magic-software-enterprises-concordano-una-cooperazione\/#primaryimage"},"image":{"@id":"https:\/\/loginfo24.com\/it\/2022\/05\/11\/efrexx-e-magic-software-enterprises-concordano-una-cooperazione\/#primaryimage"},"thumbnailUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/eFrexx_11.5.22.jpg","datePublished":"2022-05-11T16:48:20+00:00","breadcrumb":{"@id":"https:\/\/loginfo24.com\/it\/2022\/05\/11\/efrexx-e-magic-software-enterprises-concordano-una-cooperazione\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/loginfo24.com\/it\/2022\/05\/11\/efrexx-e-magic-software-enterprises-concordano-una-cooperazione\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/loginfo24.com\/it\/2022\/05\/11\/efrexx-e-magic-software-enterprises-concordano-una-cooperazione\/#primaryimage","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/eFrexx_11.5.22.jpg","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/eFrexx_11.5.22.jpg","width":1231,"height":779},{"@type":"BreadcrumbList","@id":"https:\/\/loginfo24.com\/it\/2022\/05\/11\/efrexx-e-magic-software-enterprises-concordano-una-cooperazione\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/loginfo24.com\/it\/"},{"@type":"ListItem","position":2,"name":"eFrexx e Magic Software Enterprises concordano una cooperazione"}]},{"@type":"WebSite","@id":"https:\/\/loginfo24.com\/it\/#website","url":"https:\/\/loginfo24.com\/it\/","name":"Loginfo24","description":"Loginfo24 \u00e8 la piattaforma dedicata alla logistica e alle catene di fornitura con informazioni disponibili 24 ore su 24.","publisher":{"@id":"https:\/\/loginfo24.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/loginfo24.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/loginfo24.com\/it\/#organization","name":"Logismedia Group AG","url":"https:\/\/loginfo24.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/loginfo24.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","width":938,"height":351,"caption":"Logismedia Group AG"},"image":{"@id":"https:\/\/loginfo24.com\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","https:\/\/www.linkedin.com\/company\/lofinfo24\/"]}]}},"_links":{"self":[{"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/posts\/56295","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/comments?post=56295"}],"version-history":[{"count":0,"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/posts\/56295\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/media\/10293"}],"wp:attachment":[{"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/media?parent=56295"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/categories?post=56295"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/tags?post=56295"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}