{"id":56228,"date":"2022-05-09T21:25:58","date_gmt":"2022-05-09T19:25:58","guid":{"rendered":"https:\/\/blog.brand-architecture.at\/2022\/05\/09\/dpd-svizzera-consegna-a-basilea-lultima-miglio-in-modo-sostenibile\/"},"modified":"2022-05-09T21:25:58","modified_gmt":"2022-05-09T19:25:58","slug":"dpd-svizzera-consegna-a-basilea-lultima-miglio-in-modo-sostenibile","status":"publish","type":"post","link":"https:\/\/loginfo24.com\/it\/2022\/05\/09\/dpd-svizzera-consegna-a-basilea-lultima-miglio-in-modo-sostenibile\/","title":{"rendered":"DPD Svizzera consegna a Basilea l&#8217;ultima miglio in modo sostenibile"},"content":{"rendered":"<h5><strong>Marted\u00ec DPD Svizzera ha inaugurato il primo Green CityHub presso il Smart City Lab di Basilea, nell&#8217;area Wolf. Questo fornisce alla regione di Basilea un fornitore di servizi di consegna che si basa al 100% su veicoli elettrici per l&#8217;ultima miglio e riduce le emissioni. Presso la sede di Basilea Wolf, DPD Svizzera beneficia di sinergie con i partner dello Smart City Lab di Basilea.<\/strong><\/h5>\n<p>(Buchs\/Basilea) Il volume di pacchi in costante aumento, in particolare nei centri urbani, rappresenta un problema sempre pi\u00f9 grande per l&#8217;ambiente e la popolazione urbana. Il carico delle citt\u00e0 con traffico ed emissioni da un lato e la gestione dell&#8217;aumento del volume dall&#8217;altro pongono una grande sfida alle aziende di logistica. Il Green CityHub di Basilea non solo rende pi\u00f9 flessibile la consegna dell&#8217;ultima miglio, ma crea anche un valore aggiunto per le persone e l&#8217;ambiente.<\/p>\n<p>Grazie al nuovo Green CityHub nello Smart City Lab di Basilea, DPD Svizzera fornisce un&#8217;altra citt\u00e0 con consegne completamente sostenibili, oltre alle citt\u00e0 di Sciaffusa e Ginevra. In questo modo, DPD Svizzera si avvicina all&#8217;obiettivo di offrire un trasporto completamente verde in 10 citt\u00e0 svizzere entro il 2025.<\/p>\n<h5>Green CityHub Basilea ufficialmente operativo<\/h5>\n<p>Durante la cerimonia di inaugurazione del 3 maggio 2022, il Green CityHub \u00e8 stato ufficialmente messo in funzione. Sono stati invitati i partner dello Smart City Lab di Basilea e altri partner. Dopo un breve discorso di apertura, \u00e8 stata simbolicamente tagliata la fascia di inaugurazione. Un rappresentante della partner DPD Manor AG ha dichiarato: \u00abUna consegna di pacchi CO2-neutrale dovrebbe essere promossa in ogni citt\u00e0&#8230; Continuate cos\u00ec!\u00bb. Un dipendente dell&#8217;amministrazione comunale di Basilea ha aggiunto: \u00abLa posizione al Wolf \u00e8 ideale per una consegna verde nella citt\u00e0 di Basilea. La sede \u00e8 centralmente importante per il futuro.\u00bb.<\/p>\n<p>Lo Smart City Lab di Basilea promuove innovazioni nei settori degli edifici, della mobilit\u00e0, della logistica urbana e oltre, per una Svizzera sostenibile, vivibile e competitiva del futuro. Offre spazi e formati per connettere gli attori, sviluppare soluzioni, testare idee e vivere soluzioni intelligenti.<\/p>\n<h5>Collaborazione con diversi partner<\/h5>\n<p>DPD Svizzera collabora localmente con diversi partner dello Smart City Lab di Basilea. Oltre ai propri e-Van per la consegna direttamente a casa, i pacchi vengono anche consegnati in Parcel Lockers nel centro di Basilea, gestiti dall&#8217;operatore di armadietti per pacchi \u00abSchlaueBox\u00bb. In questo modo, i destinatari possono ritirare il loro pacco quando \u00e8 pi\u00f9 comodo per loro. Grazie alla collaborazione con l&#8217;azienda UpVolt, gli e-Van vengono caricati con energia elettrica ecologica.<\/p>\n<p>La consegna elettrificata riduce le emissioni di CO2 del 70%. Grazie al Green CityHub, vengono risparmiati circa 11&#8217;000 km di percorsi mensili. I pacchi vengono pre-selezionati di notte nel deposito di M\u00f6hlin e trasportati con il camion al Green CityHub Wolf. L\u00ec, gli e-Van vengono caricati e le spedizioni vengono consegnate.<\/p>\n<h5>Fatti e cifre Green CityHub Basilea Wolf:<\/h5>\n<ul>\n<li>Numero previsto di pacchi al mese per la consegna: 26&#8217;000<\/li>\n<li>Dimensione del Green CityHub: 300 m2 di superficie interna pi\u00f9 290 m2 di area esterna<\/li>\n<li>10 e-Van<\/li>\n<li>8 tour e 2 tour di emergenza<\/li>\n<\/ul>\n<p>Per DPD Svizzera, la responsabilit\u00e0 nei confronti dell&#8217;ambiente \u00e8 un dovere. Il fornitore di servizi di consegna consegna ogni pacco in modo CO2 neutrale dal 2012 - senza costi aggiuntivi per i clienti. Questo avviene misurando le proprie emissioni di CO2, riducendole costantemente e compensando tutte le emissioni di CO2 residue.<\/p>\n<p>Foto: \u00a9 DPD<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Marted\u00ec DPD Svizzera ha inaugurato il primo Green CityHub presso il Smart City Lab di Basilea, nell&#8217;area Wolf. Questo fornisce alla regione di Basilea un fornitore<span class=\"excerpt-hellip\"> [\u2026]<\/span><\/p>\n","protected":false},"author":0,"featured_media":10321,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1665,1557,1556,1561],"tags":[],"class_list":["post-56228","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-categories","category-forwarding-logistics","category-intermodal-road","category-regions"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>DPD Svizzera consegna a Basilea l&#039;ultima miglio in modo sostenibile - Loginfo24<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/loginfo24.com\/it\/2022\/05\/09\/dpd-svizzera-consegna-a-basilea-lultima-miglio-in-modo-sostenibile\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"DPD Svizzera consegna a Basilea l&#039;ultima miglio in modo sostenibile - Loginfo24\" \/>\n<meta property=\"og:description\" content=\"Marted\u00ec DPD Svizzera ha inaugurato il primo Green CityHub presso il Smart City Lab di Basilea, nell&#8217;area Wolf. Questo fornisce alla regione di Basilea un fornitore [\u2026]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/loginfo24.com\/it\/2022\/05\/09\/dpd-svizzera-consegna-a-basilea-lultima-miglio-in-modo-sostenibile\/\" \/>\n<meta property=\"og:site_name\" content=\"Loginfo24\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/\" \/>\n<meta property=\"article:published_time\" content=\"2022-05-09T19:25:58+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/DPD_9.5.22.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1164\" \/>\n\t<meta property=\"og:image:height\" content=\"592\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2022\\\/05\\\/09\\\/dpd-svizzera-consegna-a-basilea-lultima-miglio-in-modo-sostenibile\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2022\\\/05\\\/09\\\/dpd-svizzera-consegna-a-basilea-lultima-miglio-in-modo-sostenibile\\\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"DPD Svizzera consegna a Basilea l&#8217;ultima miglio in modo sostenibile\",\"datePublished\":\"2022-05-09T19:25:58+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2022\\\/05\\\/09\\\/dpd-svizzera-consegna-a-basilea-lultima-miglio-in-modo-sostenibile\\\/\"},\"wordCount\":564,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2022\\\/05\\\/09\\\/dpd-svizzera-consegna-a-basilea-lultima-miglio-in-modo-sostenibile\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/DPD_9.5.22.jpg\",\"articleSection\":[\"Categories\",\"Forwarding &amp; Logistics\",\"Intermodal \\\/ Road\",\"Regions\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/it\\\/2022\\\/05\\\/09\\\/dpd-svizzera-consegna-a-basilea-lultima-miglio-in-modo-sostenibile\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2022\\\/05\\\/09\\\/dpd-svizzera-consegna-a-basilea-lultima-miglio-in-modo-sostenibile\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2022\\\/05\\\/09\\\/dpd-svizzera-consegna-a-basilea-lultima-miglio-in-modo-sostenibile\\\/\",\"name\":\"DPD Svizzera consegna a Basilea l'ultima miglio in modo sostenibile - Loginfo24\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2022\\\/05\\\/09\\\/dpd-svizzera-consegna-a-basilea-lultima-miglio-in-modo-sostenibile\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2022\\\/05\\\/09\\\/dpd-svizzera-consegna-a-basilea-lultima-miglio-in-modo-sostenibile\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/DPD_9.5.22.jpg\",\"datePublished\":\"2022-05-09T19:25:58+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2022\\\/05\\\/09\\\/dpd-svizzera-consegna-a-basilea-lultima-miglio-in-modo-sostenibile\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/it\\\/2022\\\/05\\\/09\\\/dpd-svizzera-consegna-a-basilea-lultima-miglio-in-modo-sostenibile\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2022\\\/05\\\/09\\\/dpd-svizzera-consegna-a-basilea-lultima-miglio-in-modo-sostenibile\\\/#primaryimage\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/DPD_9.5.22.jpg\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/DPD_9.5.22.jpg\",\"width\":1164,\"height\":592},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2022\\\/05\\\/09\\\/dpd-svizzera-consegna-a-basilea-lultima-miglio-in-modo-sostenibile\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"DPD Svizzera consegna a Basilea l&#8217;ultima miglio in modo sostenibile\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/\",\"name\":\"Loginfo24\",\"description\":\"Loginfo24 \u00e8 la piattaforma dedicata alla logistica e alle catene di fornitura con informazioni disponibili 24 ore su 24.\",\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#organization\",\"name\":\"Logismedia Group AG\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"width\":938,\"height\":351,\"caption\":\"Logismedia Group AG\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/people\\\/Loginfo24\\\/100057360583332\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/lofinfo24\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"DPD Svizzera consegna a Basilea l'ultima miglio in modo sostenibile - Loginfo24","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/loginfo24.com\/it\/2022\/05\/09\/dpd-svizzera-consegna-a-basilea-lultima-miglio-in-modo-sostenibile\/","og_locale":"it_IT","og_type":"article","og_title":"DPD Svizzera consegna a Basilea l'ultima miglio in modo sostenibile - Loginfo24","og_description":"Marted\u00ec DPD Svizzera ha inaugurato il primo Green CityHub presso il Smart City Lab di Basilea, nell&#8217;area Wolf. Questo fornisce alla regione di Basilea un fornitore [\u2026]","og_url":"https:\/\/loginfo24.com\/it\/2022\/05\/09\/dpd-svizzera-consegna-a-basilea-lultima-miglio-in-modo-sostenibile\/","og_site_name":"Loginfo24","article_publisher":"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","article_published_time":"2022-05-09T19:25:58+00:00","og_image":[{"width":1164,"height":592,"url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/DPD_9.5.22.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"3 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/loginfo24.com\/it\/2022\/05\/09\/dpd-svizzera-consegna-a-basilea-lultima-miglio-in-modo-sostenibile\/#article","isPartOf":{"@id":"https:\/\/loginfo24.com\/it\/2022\/05\/09\/dpd-svizzera-consegna-a-basilea-lultima-miglio-in-modo-sostenibile\/"},"author":{"name":"","@id":""},"headline":"DPD Svizzera consegna a Basilea l&#8217;ultima miglio in modo sostenibile","datePublished":"2022-05-09T19:25:58+00:00","mainEntityOfPage":{"@id":"https:\/\/loginfo24.com\/it\/2022\/05\/09\/dpd-svizzera-consegna-a-basilea-lultima-miglio-in-modo-sostenibile\/"},"wordCount":564,"commentCount":0,"publisher":{"@id":"https:\/\/loginfo24.com\/it\/#organization"},"image":{"@id":"https:\/\/loginfo24.com\/it\/2022\/05\/09\/dpd-svizzera-consegna-a-basilea-lultima-miglio-in-modo-sostenibile\/#primaryimage"},"thumbnailUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/DPD_9.5.22.jpg","articleSection":["Categories","Forwarding &amp; Logistics","Intermodal \/ Road","Regions"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/loginfo24.com\/it\/2022\/05\/09\/dpd-svizzera-consegna-a-basilea-lultima-miglio-in-modo-sostenibile\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/loginfo24.com\/it\/2022\/05\/09\/dpd-svizzera-consegna-a-basilea-lultima-miglio-in-modo-sostenibile\/","url":"https:\/\/loginfo24.com\/it\/2022\/05\/09\/dpd-svizzera-consegna-a-basilea-lultima-miglio-in-modo-sostenibile\/","name":"DPD Svizzera consegna a Basilea l'ultima miglio in modo sostenibile - Loginfo24","isPartOf":{"@id":"https:\/\/loginfo24.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/loginfo24.com\/it\/2022\/05\/09\/dpd-svizzera-consegna-a-basilea-lultima-miglio-in-modo-sostenibile\/#primaryimage"},"image":{"@id":"https:\/\/loginfo24.com\/it\/2022\/05\/09\/dpd-svizzera-consegna-a-basilea-lultima-miglio-in-modo-sostenibile\/#primaryimage"},"thumbnailUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/DPD_9.5.22.jpg","datePublished":"2022-05-09T19:25:58+00:00","breadcrumb":{"@id":"https:\/\/loginfo24.com\/it\/2022\/05\/09\/dpd-svizzera-consegna-a-basilea-lultima-miglio-in-modo-sostenibile\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/loginfo24.com\/it\/2022\/05\/09\/dpd-svizzera-consegna-a-basilea-lultima-miglio-in-modo-sostenibile\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/loginfo24.com\/it\/2022\/05\/09\/dpd-svizzera-consegna-a-basilea-lultima-miglio-in-modo-sostenibile\/#primaryimage","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/DPD_9.5.22.jpg","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/DPD_9.5.22.jpg","width":1164,"height":592},{"@type":"BreadcrumbList","@id":"https:\/\/loginfo24.com\/it\/2022\/05\/09\/dpd-svizzera-consegna-a-basilea-lultima-miglio-in-modo-sostenibile\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/loginfo24.com\/it\/"},{"@type":"ListItem","position":2,"name":"DPD Svizzera consegna a Basilea l&#8217;ultima miglio in modo sostenibile"}]},{"@type":"WebSite","@id":"https:\/\/loginfo24.com\/it\/#website","url":"https:\/\/loginfo24.com\/it\/","name":"Loginfo24","description":"Loginfo24 \u00e8 la piattaforma dedicata alla logistica e alle catene di fornitura con informazioni disponibili 24 ore su 24.","publisher":{"@id":"https:\/\/loginfo24.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/loginfo24.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/loginfo24.com\/it\/#organization","name":"Logismedia Group AG","url":"https:\/\/loginfo24.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/loginfo24.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","width":938,"height":351,"caption":"Logismedia Group AG"},"image":{"@id":"https:\/\/loginfo24.com\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","https:\/\/www.linkedin.com\/company\/lofinfo24\/"]}]}},"_links":{"self":[{"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/posts\/56228","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/comments?post=56228"}],"version-history":[{"count":0,"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/posts\/56228\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/media\/10321"}],"wp:attachment":[{"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/media?parent=56228"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/categories?post=56228"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/tags?post=56228"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}