{"id":55981,"date":"2022-04-28T19:26:30","date_gmt":"2022-04-28T17:26:30","guid":{"rendered":"https:\/\/blog.brand-architecture.at\/2022\/04\/28\/green-logistics-enabler-gle-per-una-flotta-sostenibile\/"},"modified":"2022-04-28T19:26:30","modified_gmt":"2022-04-28T17:26:30","slug":"green-logistics-enabler-gle-per-una-flotta-sostenibile","status":"publish","type":"post","link":"https:\/\/loginfo24.com\/it\/2022\/04\/28\/green-logistics-enabler-gle-per-una-flotta-sostenibile\/","title":{"rendered":"Green Logistics Enabler GLE per una flotta sostenibile"},"content":{"rendered":"<h5><strong>La consulenza logistica Green Logistics Enabler (GLE) di Berlino avvia un nuovo modello di business nel settore della gestione sostenibile delle flotte. L&#8217;approccio innovativo di GLE prevede la conversione mirata delle flotte di camion tradizionali a fonti di energia verde e a sistemi di propulsione alternativi come elettrico, biogas e idrogeno.<\/strong><\/h5>\n<p>(Berlino) Come target, il fondatore e proprietario di GLE, Bruno Lukas, ha definito le aziende di trasporto e le industrie con una propria flotta di camion. L&#8217;attenzione iniziale \u00e8 rivolta alla logistica distributiva nel traffico regionale e alla logistica urbana.<\/p>\n<p>L&#8217;approccio olistico di GLE per l&#8217;introduzione di una flotta sostenibile comprende tre fasi. Per prima cosa, sulla base di studi di mercato per tecnologie di propulsione alternative, viene effettuata un&#8217;analisi dettagliata delle condizioni e delle necessit\u00e0 della flotta. Nella seconda fase, GLE sviluppa insieme al cliente soluzioni di trasporto sostenibili su misura, per preparare la flotta di camion e la logistica distributiva alle esigenze future. La terza fase prevede la conversione graduale della flotta di veicoli a veicoli a basse emissioni o privi di emissioni - spesso in combinazione con un&#8217;ottimizzazione dei percorsi di trasporto.<\/p>\n<h5><strong>Mercato energetico teso come motore per soluzioni alternative<\/strong><\/h5>\n<p>&#8220;Le richieste della politica e dell&#8217;economia per soluzioni di trasporto climaticamente neutre e al contempo economiche stanno portando gli operatori di flotte di camion a un ripensamento su larga scala&#8221;, afferma Lukas. La situazione attuale tesa nel mercato energetico mostra quanto sia volatile e sensibile questo settore. &#8220;L&#8217;aumento vertiginoso dei prezzi del diesel e il crescente divieto di circolazione dei veicoli a diesel nei centri urbani costringono gli operatori di flotte a occuparsi tempestivamente di alternative di propulsione sostenibili.&#8221; \u00c8 fondamentale trovare soluzioni tecniche sostenibili che siano anche accessibili - un punto importante soprattutto per il settore della logistica caratterizzato da piccole e medie imprese. &#8220;Valutare gli sviluppi di mercato e prendere le decisioni giuste per la propria flotta \u00e8 difficile da gestire come attivit\u00e0 secondaria&#8221;, sa Lukas.<\/p>\n<h5><strong>Stabilire un processo olistico si basa su molteplici pilastri<\/strong><\/h5>\n<p>Per una realizzazione mirata \u00e8 necessaria una strategia di flotta olistica che tenga conto di tutti i fattori influenti. Questi includono i costi di acquisto finanziabili dallo stato, la selezione di sistemi di propulsione adeguati, le condizioni di acquisto e l&#8217;evoluzione dei prezzi dell&#8217;energia. Proprio questi ambiti sono trattati dalla consulenza logistica GLE. Un servizio di base centrale \u00e8 la creazione di analisi di mercato regolari e specifiche per il cliente sui sistemi di propulsione alternativi per camion e sui programmi di finanziamento - se necessario con un database tecnico complementare. Il campo di attivit\u00e0 di GLE che si basa su questo \u00e8 la consulenza strategica per l&#8217;implementazione della logistica distributiva &#8220;verde&#8221;. Questo comprende l&#8217;intero processo. Si estende dall&#8217;analisi delle condizioni e delle necessit\u00e0 della flotta di camion, allo sviluppo di concetti di veicolo e alla selezione dei fornitori, fino al supporto nelle gare d&#8217;appalto e nei test dei veicoli. In questo contesto, l&#8217;analisi di mercato di GLE serve come base decisionale fondata per la conversione graduale a una flotta &#8220;verde&#8221;.<\/p>\n<h5><strong>Le conversioni delle flotte richiedono pazienza<\/strong><\/h5>\n<p>Un accompagnamento continuo e professionalmente fondato \u00e8, per il proprietario di GLE Lukas, la chiave per una conversione di successo a una flotta di camion sostenibile. La sua motivazione: &#8220;Questo trasferimento richiede, a causa dei tipici processi di approvvigionamento per flotte a partire da 20 camion, diversi anni. Infatti, a causa delle durate di leasing e dei modelli di finanziamento a lungo termine, le flotte possono essere convertite solo gradualmente.&#8221; A causa dei costi di investimento elevati, delle innovazioni agili e delle influenze di mercato volatili, \u00e8 necessario un project management rigoroso. &#8220;Solo chi persegue in modo coerente la conversione a sistemi di propulsione alternativi potr\u00e0 operare con successo sul mercato a lungo termine&#8221;, conclude Lukas.<\/p>\n<p>Foto: \u00a9 Matthias Gottwald \/ <strong><em>Didascalia foto:<\/em><\/strong> <em>Il proprietario di GLE Bruno Lukas (a destra) durante un colloquio con un cliente<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La consulenza logistica Green Logistics Enabler (GLE) di Berlino avvia un nuovo modello di business nel settore della gestione sostenibile delle flotte. L&#8217;approccio innovativo di GLE<span class=\"excerpt-hellip\"> [\u2026]<\/span><\/p>\n","protected":false},"author":0,"featured_media":10429,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1665,1557,1561],"tags":[],"class_list":["post-55981","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-categories","category-forwarding-logistics","category-regions"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Green Logistics Enabler GLE per una flotta sostenibile - Loginfo24<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/loginfo24.com\/it\/2022\/04\/28\/green-logistics-enabler-gle-per-una-flotta-sostenibile\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Green Logistics Enabler GLE per una flotta sostenibile - Loginfo24\" \/>\n<meta property=\"og:description\" content=\"La consulenza logistica Green Logistics Enabler (GLE) di Berlino avvia un nuovo modello di business nel settore della gestione sostenibile delle flotte. L&#8217;approccio innovativo di GLE [\u2026]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/loginfo24.com\/it\/2022\/04\/28\/green-logistics-enabler-gle-per-una-flotta-sostenibile\/\" \/>\n<meta property=\"og:site_name\" content=\"Loginfo24\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/\" \/>\n<meta property=\"article:published_time\" content=\"2022-04-28T17:26:30+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/GLE_28.4.22.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1492\" \/>\n\t<meta property=\"og:image:height\" content=\"988\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2022\\\/04\\\/28\\\/green-logistics-enabler-gle-per-una-flotta-sostenibile\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2022\\\/04\\\/28\\\/green-logistics-enabler-gle-per-una-flotta-sostenibile\\\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Green Logistics Enabler GLE per una flotta sostenibile\",\"datePublished\":\"2022-04-28T17:26:30+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2022\\\/04\\\/28\\\/green-logistics-enabler-gle-per-una-flotta-sostenibile\\\/\"},\"wordCount\":657,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2022\\\/04\\\/28\\\/green-logistics-enabler-gle-per-una-flotta-sostenibile\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/GLE_28.4.22.jpg\",\"articleSection\":[\"Categories\",\"Forwarding &amp; Logistics\",\"Regions\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/it\\\/2022\\\/04\\\/28\\\/green-logistics-enabler-gle-per-una-flotta-sostenibile\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2022\\\/04\\\/28\\\/green-logistics-enabler-gle-per-una-flotta-sostenibile\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2022\\\/04\\\/28\\\/green-logistics-enabler-gle-per-una-flotta-sostenibile\\\/\",\"name\":\"Green Logistics Enabler GLE per una flotta sostenibile - Loginfo24\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2022\\\/04\\\/28\\\/green-logistics-enabler-gle-per-una-flotta-sostenibile\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2022\\\/04\\\/28\\\/green-logistics-enabler-gle-per-una-flotta-sostenibile\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/GLE_28.4.22.jpg\",\"datePublished\":\"2022-04-28T17:26:30+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2022\\\/04\\\/28\\\/green-logistics-enabler-gle-per-una-flotta-sostenibile\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/it\\\/2022\\\/04\\\/28\\\/green-logistics-enabler-gle-per-una-flotta-sostenibile\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2022\\\/04\\\/28\\\/green-logistics-enabler-gle-per-una-flotta-sostenibile\\\/#primaryimage\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/GLE_28.4.22.jpg\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/GLE_28.4.22.jpg\",\"width\":1492,\"height\":988},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2022\\\/04\\\/28\\\/green-logistics-enabler-gle-per-una-flotta-sostenibile\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Green Logistics Enabler GLE per una flotta sostenibile\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/\",\"name\":\"Loginfo24\",\"description\":\"Loginfo24 \u00e8 la piattaforma dedicata alla logistica e alle catene di fornitura con informazioni disponibili 24 ore su 24.\",\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#organization\",\"name\":\"Logismedia Group AG\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"width\":938,\"height\":351,\"caption\":\"Logismedia Group AG\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/people\\\/Loginfo24\\\/100057360583332\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/lofinfo24\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Green Logistics Enabler GLE per una flotta sostenibile - Loginfo24","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/loginfo24.com\/it\/2022\/04\/28\/green-logistics-enabler-gle-per-una-flotta-sostenibile\/","og_locale":"it_IT","og_type":"article","og_title":"Green Logistics Enabler GLE per una flotta sostenibile - Loginfo24","og_description":"La consulenza logistica Green Logistics Enabler (GLE) di Berlino avvia un nuovo modello di business nel settore della gestione sostenibile delle flotte. L&#8217;approccio innovativo di GLE [\u2026]","og_url":"https:\/\/loginfo24.com\/it\/2022\/04\/28\/green-logistics-enabler-gle-per-una-flotta-sostenibile\/","og_site_name":"Loginfo24","article_publisher":"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","article_published_time":"2022-04-28T17:26:30+00:00","og_image":[{"width":1492,"height":988,"url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/GLE_28.4.22.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"3 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/loginfo24.com\/it\/2022\/04\/28\/green-logistics-enabler-gle-per-una-flotta-sostenibile\/#article","isPartOf":{"@id":"https:\/\/loginfo24.com\/it\/2022\/04\/28\/green-logistics-enabler-gle-per-una-flotta-sostenibile\/"},"author":{"name":"","@id":""},"headline":"Green Logistics Enabler GLE per una flotta sostenibile","datePublished":"2022-04-28T17:26:30+00:00","mainEntityOfPage":{"@id":"https:\/\/loginfo24.com\/it\/2022\/04\/28\/green-logistics-enabler-gle-per-una-flotta-sostenibile\/"},"wordCount":657,"commentCount":0,"publisher":{"@id":"https:\/\/loginfo24.com\/it\/#organization"},"image":{"@id":"https:\/\/loginfo24.com\/it\/2022\/04\/28\/green-logistics-enabler-gle-per-una-flotta-sostenibile\/#primaryimage"},"thumbnailUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/GLE_28.4.22.jpg","articleSection":["Categories","Forwarding &amp; Logistics","Regions"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/loginfo24.com\/it\/2022\/04\/28\/green-logistics-enabler-gle-per-una-flotta-sostenibile\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/loginfo24.com\/it\/2022\/04\/28\/green-logistics-enabler-gle-per-una-flotta-sostenibile\/","url":"https:\/\/loginfo24.com\/it\/2022\/04\/28\/green-logistics-enabler-gle-per-una-flotta-sostenibile\/","name":"Green Logistics Enabler GLE per una flotta sostenibile - Loginfo24","isPartOf":{"@id":"https:\/\/loginfo24.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/loginfo24.com\/it\/2022\/04\/28\/green-logistics-enabler-gle-per-una-flotta-sostenibile\/#primaryimage"},"image":{"@id":"https:\/\/loginfo24.com\/it\/2022\/04\/28\/green-logistics-enabler-gle-per-una-flotta-sostenibile\/#primaryimage"},"thumbnailUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/GLE_28.4.22.jpg","datePublished":"2022-04-28T17:26:30+00:00","breadcrumb":{"@id":"https:\/\/loginfo24.com\/it\/2022\/04\/28\/green-logistics-enabler-gle-per-una-flotta-sostenibile\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/loginfo24.com\/it\/2022\/04\/28\/green-logistics-enabler-gle-per-una-flotta-sostenibile\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/loginfo24.com\/it\/2022\/04\/28\/green-logistics-enabler-gle-per-una-flotta-sostenibile\/#primaryimage","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/GLE_28.4.22.jpg","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/GLE_28.4.22.jpg","width":1492,"height":988},{"@type":"BreadcrumbList","@id":"https:\/\/loginfo24.com\/it\/2022\/04\/28\/green-logistics-enabler-gle-per-una-flotta-sostenibile\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/loginfo24.com\/it\/"},{"@type":"ListItem","position":2,"name":"Green Logistics Enabler GLE per una flotta sostenibile"}]},{"@type":"WebSite","@id":"https:\/\/loginfo24.com\/it\/#website","url":"https:\/\/loginfo24.com\/it\/","name":"Loginfo24","description":"Loginfo24 \u00e8 la piattaforma dedicata alla logistica e alle catene di fornitura con informazioni disponibili 24 ore su 24.","publisher":{"@id":"https:\/\/loginfo24.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/loginfo24.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/loginfo24.com\/it\/#organization","name":"Logismedia Group AG","url":"https:\/\/loginfo24.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/loginfo24.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","width":938,"height":351,"caption":"Logismedia Group AG"},"image":{"@id":"https:\/\/loginfo24.com\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","https:\/\/www.linkedin.com\/company\/lofinfo24\/"]}]}},"_links":{"self":[{"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/posts\/55981","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/comments?post=55981"}],"version-history":[{"count":0,"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/posts\/55981\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/media\/10429"}],"wp:attachment":[{"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/media?parent=55981"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/categories?post=55981"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/tags?post=55981"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}