{"id":55773,"date":"2022-04-19T19:01:42","date_gmt":"2022-04-19T17:01:42","guid":{"rendered":"https:\/\/blog.brand-architecture.at\/2022\/04\/19\/zeitfracht-amplia-i-servizi-di-stampa-su-richiesta-per-gli-editori\/"},"modified":"2022-04-19T19:01:42","modified_gmt":"2022-04-19T17:01:42","slug":"zeitfracht-amplia-i-servizi-di-stampa-su-richiesta-per-gli-editori","status":"publish","type":"post","link":"https:\/\/loginfo24.com\/it\/2022\/04\/19\/zeitfracht-amplia-i-servizi-di-stampa-su-richiesta-per-gli-editori\/","title":{"rendered":"Zeitfracht amplia i servizi di stampa su richiesta per gli editori"},"content":{"rendered":"<h5><strong>Zeitfracht stampa in collaborazione con l&#8217;azienda di servizi di stampa CPI da subito anche libri con copertina rigida nella logistica di Erfurt. In questo modo, l&#8217;azienda pu\u00f2 gestire gli ordini di stampa su richiesta (PoD) in modo ancora pi\u00f9 rapido e sostenibile. L&#8217;offerta ampliata ha portato immediatamente a nuovi clienti.<\/strong><\/h5>\n<p>(Erfurt) Tra i nuovi clienti, due grandi editori scientifici, Springer Nature e De Gruyter, si affideranno in futuro al servizio PoD di Zeitfracht. Con i due editori, circa 1,3 milioni di titoli PoD saranno offerti sul mercato tramite Zeitfracht.<\/p>\n<p>\u201eSiamo molto felici per i nuovi ingressi di prestigio e per l&#8217;interesse complessivo crescente verso il nostro servizio di stampa su richiesta. Soprattutto in tempi di mercati delle materie prime tesi, una produzione su richiesta e senza rischi \u00e8 estremamente importante. Continueremo a espandere e ottimizzare questo settore, aumentando cos\u00ec notevolmente la disponibilit\u00e0 di titoli per i nostri clienti, la cui produzione in stock e stoccaggio non \u00e8 pi\u00f9 economicamente sensata\u201c, afferma Thomas Raff, membro del consiglio di amministrazione del gruppo Zeitfracht e portavoce della direzione di Zeitfracht GmbH. Mentre in precedenza venivano prodotti solo libri con copertina morbida a Erfurt, il sito di stampa PoD consolidato nella capitale della Turingia consente di ridurre i costi di trasporto. In questo modo, le risorse possono essere risparmiate e la grande velocit\u00e0 della logistica di Zeitfracht pu\u00f2 essere utilizzata direttamente.<\/p>\n<h5><strong>Numero di titoli significativamente maggiore<\/strong><\/h5>\n<p>\u201eSiamo lieti che grazie alla collaborazione ampliata un numero significativamente maggiore di titoli del nostro programma editoriale sia disponibile tramite Zeitfracht e che i clienti possano riceverli molto pi\u00f9 rapidamente\u201c, afferma Alexander Faust, Direttore della Produzione e delle Operazioni Interne di De Gruyter. Eric Schmitt, Vice Presidente Esecutivo degli Acquisti Centrali di Springer Nature: \u201eSiamo molto contenti che i nostri titoli possano ora essere resi disponibili ai clienti in Germania tramite Zeitfracht attraverso PoD. Oltre alla disponibilit\u00e0 costante, \u00e8 per noi molto importante contribuire ulteriormente alla sostenibilit\u00e0 della produzione fisica.\u201c<\/p>\n<h5><strong>Utilizzo di una tecnologia unica<\/strong><\/h5>\n<p>Dal gennaio 2022, Zeitfracht GmbH collabora con CPI \u2013 il principale fornitore di servizi di stampa di libri in Germania. Zeitfracht e CPI offrono ai clienti editoriali una transizione senza soluzione di continuit\u00e0 tra la stampa tradizionale e la \u201estampa su ordinazione\u201c nell&#8217;assortimento di Zeitfracht o nella distribuzione editoriale. Nella produzione, CPI e Zeitfracht utilizzano una tecnologia finora unica in Germania, che produce copertine morbide e rigide senza interruzione di attrezzaggio su una macchina in-house.<\/p>\n<p>Foto: \u00a9 Zeitfracht<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Zeitfracht stampa in collaborazione con l&#8217;azienda di servizi di stampa CPI da subito anche libri con copertina rigida nella logistica di Erfurt. In questo modo, l&#8217;azienda<span class=\"excerpt-hellip\"> [\u2026]<\/span><\/p>\n","protected":false},"author":0,"featured_media":10515,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1557,1556,1560,1561],"tags":[],"class_list":["post-55773","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-forwarding-logistics","category-intermodal-road","category-intralogistics","category-regions"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Zeitfracht amplia i servizi di stampa su richiesta per gli editori - Loginfo24<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/loginfo24.com\/it\/2022\/04\/19\/zeitfracht-amplia-i-servizi-di-stampa-su-richiesta-per-gli-editori\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Zeitfracht amplia i servizi di stampa su richiesta per gli editori - Loginfo24\" \/>\n<meta property=\"og:description\" content=\"Zeitfracht stampa in collaborazione con l&#8217;azienda di servizi di stampa CPI da subito anche libri con copertina rigida nella logistica di Erfurt. In questo modo, l&#8217;azienda [\u2026]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/loginfo24.com\/it\/2022\/04\/19\/zeitfracht-amplia-i-servizi-di-stampa-su-richiesta-per-gli-editori\/\" \/>\n<meta property=\"og:site_name\" content=\"Loginfo24\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/\" \/>\n<meta property=\"article:published_time\" content=\"2022-04-19T17:01:42+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Zeitfracht_19.4.22.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1234\" \/>\n\t<meta property=\"og:image:height\" content=\"726\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2022\\\/04\\\/19\\\/zeitfracht-amplia-i-servizi-di-stampa-su-richiesta-per-gli-editori\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2022\\\/04\\\/19\\\/zeitfracht-amplia-i-servizi-di-stampa-su-richiesta-per-gli-editori\\\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Zeitfracht amplia i servizi di stampa su richiesta per gli editori\",\"datePublished\":\"2022-04-19T17:01:42+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2022\\\/04\\\/19\\\/zeitfracht-amplia-i-servizi-di-stampa-su-richiesta-per-gli-editori\\\/\"},\"wordCount\":414,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2022\\\/04\\\/19\\\/zeitfracht-amplia-i-servizi-di-stampa-su-richiesta-per-gli-editori\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/Zeitfracht_19.4.22.jpg\",\"articleSection\":[\"Forwarding &amp; Logistics\",\"Intermodal \\\/ Road\",\"Intralogistics\",\"Regions\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/it\\\/2022\\\/04\\\/19\\\/zeitfracht-amplia-i-servizi-di-stampa-su-richiesta-per-gli-editori\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2022\\\/04\\\/19\\\/zeitfracht-amplia-i-servizi-di-stampa-su-richiesta-per-gli-editori\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2022\\\/04\\\/19\\\/zeitfracht-amplia-i-servizi-di-stampa-su-richiesta-per-gli-editori\\\/\",\"name\":\"Zeitfracht amplia i servizi di stampa su richiesta per gli editori - Loginfo24\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2022\\\/04\\\/19\\\/zeitfracht-amplia-i-servizi-di-stampa-su-richiesta-per-gli-editori\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2022\\\/04\\\/19\\\/zeitfracht-amplia-i-servizi-di-stampa-su-richiesta-per-gli-editori\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/Zeitfracht_19.4.22.jpg\",\"datePublished\":\"2022-04-19T17:01:42+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2022\\\/04\\\/19\\\/zeitfracht-amplia-i-servizi-di-stampa-su-richiesta-per-gli-editori\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/it\\\/2022\\\/04\\\/19\\\/zeitfracht-amplia-i-servizi-di-stampa-su-richiesta-per-gli-editori\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2022\\\/04\\\/19\\\/zeitfracht-amplia-i-servizi-di-stampa-su-richiesta-per-gli-editori\\\/#primaryimage\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/Zeitfracht_19.4.22.jpg\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/Zeitfracht_19.4.22.jpg\",\"width\":1234,\"height\":726},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2022\\\/04\\\/19\\\/zeitfracht-amplia-i-servizi-di-stampa-su-richiesta-per-gli-editori\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Zeitfracht amplia i servizi di stampa su richiesta per gli editori\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/\",\"name\":\"Loginfo24\",\"description\":\"Loginfo24 \u00e8 la piattaforma dedicata alla logistica e alle catene di fornitura con informazioni disponibili 24 ore su 24.\",\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#organization\",\"name\":\"Logismedia Group AG\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"width\":938,\"height\":351,\"caption\":\"Logismedia Group AG\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/people\\\/Loginfo24\\\/100057360583332\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/lofinfo24\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Zeitfracht amplia i servizi di stampa su richiesta per gli editori - Loginfo24","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/loginfo24.com\/it\/2022\/04\/19\/zeitfracht-amplia-i-servizi-di-stampa-su-richiesta-per-gli-editori\/","og_locale":"it_IT","og_type":"article","og_title":"Zeitfracht amplia i servizi di stampa su richiesta per gli editori - Loginfo24","og_description":"Zeitfracht stampa in collaborazione con l&#8217;azienda di servizi di stampa CPI da subito anche libri con copertina rigida nella logistica di Erfurt. In questo modo, l&#8217;azienda [\u2026]","og_url":"https:\/\/loginfo24.com\/it\/2022\/04\/19\/zeitfracht-amplia-i-servizi-di-stampa-su-richiesta-per-gli-editori\/","og_site_name":"Loginfo24","article_publisher":"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","article_published_time":"2022-04-19T17:01:42+00:00","og_image":[{"width":1234,"height":726,"url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Zeitfracht_19.4.22.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"2 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/loginfo24.com\/it\/2022\/04\/19\/zeitfracht-amplia-i-servizi-di-stampa-su-richiesta-per-gli-editori\/#article","isPartOf":{"@id":"https:\/\/loginfo24.com\/it\/2022\/04\/19\/zeitfracht-amplia-i-servizi-di-stampa-su-richiesta-per-gli-editori\/"},"author":{"name":"","@id":""},"headline":"Zeitfracht amplia i servizi di stampa su richiesta per gli editori","datePublished":"2022-04-19T17:01:42+00:00","mainEntityOfPage":{"@id":"https:\/\/loginfo24.com\/it\/2022\/04\/19\/zeitfracht-amplia-i-servizi-di-stampa-su-richiesta-per-gli-editori\/"},"wordCount":414,"commentCount":0,"publisher":{"@id":"https:\/\/loginfo24.com\/it\/#organization"},"image":{"@id":"https:\/\/loginfo24.com\/it\/2022\/04\/19\/zeitfracht-amplia-i-servizi-di-stampa-su-richiesta-per-gli-editori\/#primaryimage"},"thumbnailUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Zeitfracht_19.4.22.jpg","articleSection":["Forwarding &amp; Logistics","Intermodal \/ Road","Intralogistics","Regions"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/loginfo24.com\/it\/2022\/04\/19\/zeitfracht-amplia-i-servizi-di-stampa-su-richiesta-per-gli-editori\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/loginfo24.com\/it\/2022\/04\/19\/zeitfracht-amplia-i-servizi-di-stampa-su-richiesta-per-gli-editori\/","url":"https:\/\/loginfo24.com\/it\/2022\/04\/19\/zeitfracht-amplia-i-servizi-di-stampa-su-richiesta-per-gli-editori\/","name":"Zeitfracht amplia i servizi di stampa su richiesta per gli editori - Loginfo24","isPartOf":{"@id":"https:\/\/loginfo24.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/loginfo24.com\/it\/2022\/04\/19\/zeitfracht-amplia-i-servizi-di-stampa-su-richiesta-per-gli-editori\/#primaryimage"},"image":{"@id":"https:\/\/loginfo24.com\/it\/2022\/04\/19\/zeitfracht-amplia-i-servizi-di-stampa-su-richiesta-per-gli-editori\/#primaryimage"},"thumbnailUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Zeitfracht_19.4.22.jpg","datePublished":"2022-04-19T17:01:42+00:00","breadcrumb":{"@id":"https:\/\/loginfo24.com\/it\/2022\/04\/19\/zeitfracht-amplia-i-servizi-di-stampa-su-richiesta-per-gli-editori\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/loginfo24.com\/it\/2022\/04\/19\/zeitfracht-amplia-i-servizi-di-stampa-su-richiesta-per-gli-editori\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/loginfo24.com\/it\/2022\/04\/19\/zeitfracht-amplia-i-servizi-di-stampa-su-richiesta-per-gli-editori\/#primaryimage","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Zeitfracht_19.4.22.jpg","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Zeitfracht_19.4.22.jpg","width":1234,"height":726},{"@type":"BreadcrumbList","@id":"https:\/\/loginfo24.com\/it\/2022\/04\/19\/zeitfracht-amplia-i-servizi-di-stampa-su-richiesta-per-gli-editori\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/loginfo24.com\/it\/"},{"@type":"ListItem","position":2,"name":"Zeitfracht amplia i servizi di stampa su richiesta per gli editori"}]},{"@type":"WebSite","@id":"https:\/\/loginfo24.com\/it\/#website","url":"https:\/\/loginfo24.com\/it\/","name":"Loginfo24","description":"Loginfo24 \u00e8 la piattaforma dedicata alla logistica e alle catene di fornitura con informazioni disponibili 24 ore su 24.","publisher":{"@id":"https:\/\/loginfo24.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/loginfo24.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/loginfo24.com\/it\/#organization","name":"Logismedia Group AG","url":"https:\/\/loginfo24.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/loginfo24.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","width":938,"height":351,"caption":"Logismedia Group AG"},"image":{"@id":"https:\/\/loginfo24.com\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","https:\/\/www.linkedin.com\/company\/lofinfo24\/"]}]}},"_links":{"self":[{"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/posts\/55773","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/comments?post=55773"}],"version-history":[{"count":0,"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/posts\/55773\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/media\/10515"}],"wp:attachment":[{"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/media?parent=55773"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/categories?post=55773"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/tags?post=55773"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}