{"id":55271,"date":"2022-03-22T16:07:54","date_gmt":"2022-03-22T15:07:54","guid":{"rendered":"https:\/\/blog.brand-architecture.at\/2022\/03\/22\/seed-group-e-nexxiot-come-partner-in-medio-oriente-e-nord-africa\/"},"modified":"2022-03-22T16:07:54","modified_gmt":"2022-03-22T15:07:54","slug":"seed-group-e-nexxiot-come-partner-in-medio-oriente-e-nord-africa","status":"publish","type":"post","link":"https:\/\/loginfo24.com\/it\/2022\/03\/22\/seed-group-e-nexxiot-come-partner-in-medio-oriente-e-nord-africa\/","title":{"rendered":"Seed Group e Nexxiot come partner in Medio Oriente e Nord Africa"},"content":{"rendered":"<h5><strong>Il Medio Oriente e il Nord Africa stanno diventando sempre pi\u00f9 un importante hub logistico per il commercio globale. Il potenziale della regione MENA e GCC attira ogni anno nuovi investitori nei settori del commercio e della logistica. La collaborazione tra Seed Group e Nexxiot mira a fornire servizi digitali innovativi per le catene di approvvigionamento nella regione, rafforzando cos\u00ec anche la loro sostenibilit\u00e0<\/strong><strong>.<\/strong><\/h5>\n<p>(Dubai\/Zurigo) Seed Group, un&#8217;azienda dell&#8217;ufficio privato di Sheikh Saeed bin Ahmed Al Maktoum, ha annunciato oggi una partnership strategica con Nexxiot, il pioniere svizzero del TradeTech. Le due aziende intendono promuovere insieme l&#8217;adozione di servizi basati sui dati per la logistica in Medio Oriente e Nord Africa, rafforzando cos\u00ec il commercio globale e rendendo i processi pi\u00f9 sostenibili. Nexxiot sar\u00e0 supportata da Seed Group nell&#8217;espansione delle sue attivit\u00e0 negli Emirati Arabi Uniti (EAU) e in altri paesi della regione MENA.<\/p>\n<p>I paesi della regione MENA stanno guadagnando posizioni nel Logistics Performance Index (LPI), lo strumento di benchmarking interattivo della Banca Mondiale. Nell&#8217;ultimo LPI pubblicato, gli EAU si sono classificati all&#8217;11\u00b0 posto nella classifica globale. Da allora, l&#8217;importanza della regione come hub logistico per il commercio mondiale \u00e8 aumentata ulteriormente. L&#8217;aumento del traffico mette anche in evidenza il tema della sostenibilit\u00e0.<\/p>\n<p>\u00c8 qui che si inserisce la partnership annunciata tra Seed Group e Nexxiot. Come motore della digitalizzazione, Nexxiot ha puntato sull&#8217;uso delle tecnologie pi\u00f9 avanzate sin dalla sua fondazione, per rendere il settore della logistica sostenibile attraverso soluzioni digitali. Nell&#8217;ambito della collaborazione con Seed Group, entrambe le aziende intendono ora implementare questa strategia anche in Nord Africa e Medio Oriente.<\/p>\n<p>Hisham Al Gurg, CEO di Seed Group e dell&#8217;ufficio privato di Sheikh Saeed bin Ahmed Al Maktoum, ha dichiarato a questo proposito: &#8220;Data l&#8217;importanza crescente della regione MENA come centro commerciale globale, l&#8217;uso delle tecnologie IoT (Internet of Things) pi\u00f9 avanzate in combinazione con un&#8217;analisi dei dati mirata \u00e8 pi\u00f9 importante che mai. Abbiamo riconosciuto questo megatrend e stiamo cercando partner che ci supportino nel nostro percorso per promuovere ulteriormente questa crescita. La trasparenza \u00e8 un elemento chiave, poich\u00e9 alla fine beneficia tutti gli attori delle catene di approvvigionamento globali. In questo modo, da un lato si possono raggiungere miglioramenti continui e, dall&#8217;altro, si possono generare valore aggiunto sia per i clienti che per i partner. Questo non solo crea prosperit\u00e0, ma ci consente anche di raggiungere i nostri obiettivi di sostenibilit\u00e0.&#8221;<\/p>\n<h5><strong>Il monitoraggio in tempo reale riduce i rischi e aumenta la sostenibilit\u00e0<\/strong><\/h5>\n<p>&#8220;La presenza di Nexxiot in Medio Oriente contribuir\u00e0 in modo significativo alla visione degli EAU per un futuro pi\u00f9 sostenibile. Siamo entusiasti di collaborare con un esperto che promuove soluzioni innovative nel suo settore&#8221;, aggiunge Hisham Al Gurg.<\/p>\n<p>Alla luce della continua crescita, il governo degli EAU sta cercando di creare un futuro pi\u00f9 sostenibile. In linea con l&#8217;iniziativa &#8220;Net-Zero by 2050&#8221; degli EAU, Nexxiot sta lavorando per ridurre le emissioni globali di anidride carbonica nel trasporto merci del cinque percento. Le soluzioni dell&#8217;azienda contribuiscono ad aumentare l&#8217;efficienza nel trasporto merci a livello globale.<\/p>\n<p>L&#8217;uso dell&#8217;IoT industriale funge da apripista. Questo consente di ridurre i costi, migliorare la qualit\u00e0 del carico, aumentare l&#8217;utilizzo della flotta e l&#8217;efficienza dei trasporti, nonch\u00e9 rafforzare la sicurezza e la sostenibilit\u00e0. Nexxiot combina nelle sue soluzioni innovative sensori IoT con software potente e un&#8217;analisi precisa dei Big Data. In questo modo, i clienti e i partner ottengono informazioni utili per ottimizzare le loro operazioni e sviluppare nuovi servizi basati sui dati.<\/p>\n<p>Il portafoglio di Nexxiot comprende prodotti e soluzioni per il monitoraggio di oggetti di trasporto non elettrificati, come container o vagoni merci, per ridurre il rischio di danni durante il trasporto e ottimizzare il loro smistamento. Questo va dal monitoraggio in tempo reale dello stato di carico, al monitoraggio della temperatura per carichi sensibili, come le merci pericolose, fino al monitoraggio completo di tutte le influenze interne ed esterne sul trasporto.<\/p>\n<h5><strong>Un attore importante nella regione<\/strong><\/h5>\n<p>Negli ultimi 16 anni, Seed Group ha accompagnato molte aziende nel loro ingresso nel mercato della regione MENA. Dispone di una vasta rete e di una presenza regionale e promuove come partner di sviluppo la trasformazione digitale in molti settori chiave. Ha stretto numerose partnership strategiche di successo con aziende di tutto il mondo e mira a rivoluzionare i rispettivi settori attraverso l&#8217;uso delle tecnologie pi\u00f9 avanzate e soluzioni innovative.<\/p>\n<p>Anche Nexxiot si concentra su questa strategia. Stefan Kalmund, CEO di Nexxiot, inquadra la partnership: &#8220;L&#8217;analisi dei dati di carico utilizzando algoritmi potenti, intelligenza artificiale e machine learning crea trasparenza e potenziale di automazione su tutti i mezzi di trasporto. La nuova partnership con Seed Group ci aiuta a stabilire le nostre soluzioni TradeTech innovative negli EAU e nella regione MENA.&#8221;<\/p>\n<p>La tecnologia di Nexxiot ha gi\u00e0 dimostrato la sua efficacia a livello globale e consente la massima trasparenza, dalla quale beneficiano tutti i partecipanti alla catena di approvvigionamento. Questa trasparenza genera maggiore fiducia e supporta l&#8217;automazione di processi chiave nella logistica.<\/p>\n<h5><strong>Informazioni su Seed Group<\/strong><\/h5>\n<p>Negli ultimi 16 anni, Seed Group ha stretto alleanze strategiche con aziende leader a livello mondiale provenienti da diverse regioni e settori. Queste aziende hanno portato avanti con successo i loro interessi economici e obiettivi nella regione del Medio Oriente e Nord Africa grazie al supporto di Seed Group e alla sua forte rete regionale. L&#8217;obiettivo del gruppo aziendale \u00e8 costruire partnership vantaggiose per entrambe le parti con multinazionali e accelerare il loro ingresso e presenza sostenibile nella regione MENA. Seed Group \u00e8 la chiave per il successo di tutti i suoi partner nella regione e li aiuta a raggiungere i loro clienti target e ad espandere le loro attivit\u00e0. L&#8217;ufficio privato \u00e8 stato fondato da Sheikh Saeed bin Ahmed Al Maktoum per investire direttamente in opportunit\u00e0 commerciali potenziali che soddisfano i criteri nella regione o per supportarle.<\/p>\n<p>Foto: \u00a9 Seed Group \/ <strong><em>Didascalia dell&#8217;immagine:<\/em><\/strong><em> Hisham Al Gurg, CEO di Seed Group e dell&#8217;ufficio privato di Sheikh Saeed bin Ahmed Al Maktoum, durante la cerimonia di firma<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il Medio Oriente e il Nord Africa stanno diventando sempre pi\u00f9 un importante hub logistico per il commercio globale. Il potenziale della regione MENA e GCC<span class=\"excerpt-hellip\"> [\u2026]<\/span><\/p>\n","protected":false},"author":0,"featured_media":10705,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1665,1557,1561],"tags":[],"class_list":["post-55271","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-categories","category-forwarding-logistics","category-regions"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Seed Group e Nexxiot come partner in Medio Oriente e Nord Africa - Loginfo24<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/loginfo24.com\/it\/2022\/03\/22\/seed-group-e-nexxiot-come-partner-in-medio-oriente-e-nord-africa\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Seed Group e Nexxiot come partner in Medio Oriente e Nord Africa - Loginfo24\" \/>\n<meta property=\"og:description\" content=\"Il Medio Oriente e il Nord Africa stanno diventando sempre pi\u00f9 un importante hub logistico per il commercio globale. Il potenziale della regione MENA e GCC [\u2026]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/loginfo24.com\/it\/2022\/03\/22\/seed-group-e-nexxiot-come-partner-in-medio-oriente-e-nord-africa\/\" \/>\n<meta property=\"og:site_name\" content=\"Loginfo24\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/\" \/>\n<meta property=\"article:published_time\" content=\"2022-03-22T15:07:54+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Nexxiot_22.3.22.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1494\" \/>\n\t<meta property=\"og:image:height\" content=\"954\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"5 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2022\\\/03\\\/22\\\/seed-group-e-nexxiot-come-partner-in-medio-oriente-e-nord-africa\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2022\\\/03\\\/22\\\/seed-group-e-nexxiot-come-partner-in-medio-oriente-e-nord-africa\\\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Seed Group e Nexxiot come partner in Medio Oriente e Nord Africa\",\"datePublished\":\"2022-03-22T15:07:54+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2022\\\/03\\\/22\\\/seed-group-e-nexxiot-come-partner-in-medio-oriente-e-nord-africa\\\/\"},\"wordCount\":1023,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2022\\\/03\\\/22\\\/seed-group-e-nexxiot-come-partner-in-medio-oriente-e-nord-africa\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/Nexxiot_22.3.22.jpg\",\"articleSection\":[\"Categories\",\"Forwarding &amp; Logistics\",\"Regions\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/it\\\/2022\\\/03\\\/22\\\/seed-group-e-nexxiot-come-partner-in-medio-oriente-e-nord-africa\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2022\\\/03\\\/22\\\/seed-group-e-nexxiot-come-partner-in-medio-oriente-e-nord-africa\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2022\\\/03\\\/22\\\/seed-group-e-nexxiot-come-partner-in-medio-oriente-e-nord-africa\\\/\",\"name\":\"Seed Group e Nexxiot come partner in Medio Oriente e Nord Africa - Loginfo24\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2022\\\/03\\\/22\\\/seed-group-e-nexxiot-come-partner-in-medio-oriente-e-nord-africa\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2022\\\/03\\\/22\\\/seed-group-e-nexxiot-come-partner-in-medio-oriente-e-nord-africa\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/Nexxiot_22.3.22.jpg\",\"datePublished\":\"2022-03-22T15:07:54+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2022\\\/03\\\/22\\\/seed-group-e-nexxiot-come-partner-in-medio-oriente-e-nord-africa\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/it\\\/2022\\\/03\\\/22\\\/seed-group-e-nexxiot-come-partner-in-medio-oriente-e-nord-africa\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2022\\\/03\\\/22\\\/seed-group-e-nexxiot-come-partner-in-medio-oriente-e-nord-africa\\\/#primaryimage\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/Nexxiot_22.3.22.jpg\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/Nexxiot_22.3.22.jpg\",\"width\":1494,\"height\":954},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2022\\\/03\\\/22\\\/seed-group-e-nexxiot-come-partner-in-medio-oriente-e-nord-africa\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Seed Group e Nexxiot come partner in Medio Oriente e Nord Africa\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/\",\"name\":\"Loginfo24\",\"description\":\"Loginfo24 \u00e8 la piattaforma dedicata alla logistica e alle catene di fornitura con informazioni disponibili 24 ore su 24.\",\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#organization\",\"name\":\"Logismedia Group AG\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"width\":938,\"height\":351,\"caption\":\"Logismedia Group AG\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/people\\\/Loginfo24\\\/100057360583332\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/lofinfo24\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Seed Group e Nexxiot come partner in Medio Oriente e Nord Africa - Loginfo24","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/loginfo24.com\/it\/2022\/03\/22\/seed-group-e-nexxiot-come-partner-in-medio-oriente-e-nord-africa\/","og_locale":"it_IT","og_type":"article","og_title":"Seed Group e Nexxiot come partner in Medio Oriente e Nord Africa - Loginfo24","og_description":"Il Medio Oriente e il Nord Africa stanno diventando sempre pi\u00f9 un importante hub logistico per il commercio globale. Il potenziale della regione MENA e GCC [\u2026]","og_url":"https:\/\/loginfo24.com\/it\/2022\/03\/22\/seed-group-e-nexxiot-come-partner-in-medio-oriente-e-nord-africa\/","og_site_name":"Loginfo24","article_publisher":"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","article_published_time":"2022-03-22T15:07:54+00:00","og_image":[{"width":1494,"height":954,"url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Nexxiot_22.3.22.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"5 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/loginfo24.com\/it\/2022\/03\/22\/seed-group-e-nexxiot-come-partner-in-medio-oriente-e-nord-africa\/#article","isPartOf":{"@id":"https:\/\/loginfo24.com\/it\/2022\/03\/22\/seed-group-e-nexxiot-come-partner-in-medio-oriente-e-nord-africa\/"},"author":{"name":"","@id":""},"headline":"Seed Group e Nexxiot come partner in Medio Oriente e Nord Africa","datePublished":"2022-03-22T15:07:54+00:00","mainEntityOfPage":{"@id":"https:\/\/loginfo24.com\/it\/2022\/03\/22\/seed-group-e-nexxiot-come-partner-in-medio-oriente-e-nord-africa\/"},"wordCount":1023,"commentCount":0,"publisher":{"@id":"https:\/\/loginfo24.com\/it\/#organization"},"image":{"@id":"https:\/\/loginfo24.com\/it\/2022\/03\/22\/seed-group-e-nexxiot-come-partner-in-medio-oriente-e-nord-africa\/#primaryimage"},"thumbnailUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Nexxiot_22.3.22.jpg","articleSection":["Categories","Forwarding &amp; Logistics","Regions"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/loginfo24.com\/it\/2022\/03\/22\/seed-group-e-nexxiot-come-partner-in-medio-oriente-e-nord-africa\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/loginfo24.com\/it\/2022\/03\/22\/seed-group-e-nexxiot-come-partner-in-medio-oriente-e-nord-africa\/","url":"https:\/\/loginfo24.com\/it\/2022\/03\/22\/seed-group-e-nexxiot-come-partner-in-medio-oriente-e-nord-africa\/","name":"Seed Group e Nexxiot come partner in Medio Oriente e Nord Africa - Loginfo24","isPartOf":{"@id":"https:\/\/loginfo24.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/loginfo24.com\/it\/2022\/03\/22\/seed-group-e-nexxiot-come-partner-in-medio-oriente-e-nord-africa\/#primaryimage"},"image":{"@id":"https:\/\/loginfo24.com\/it\/2022\/03\/22\/seed-group-e-nexxiot-come-partner-in-medio-oriente-e-nord-africa\/#primaryimage"},"thumbnailUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Nexxiot_22.3.22.jpg","datePublished":"2022-03-22T15:07:54+00:00","breadcrumb":{"@id":"https:\/\/loginfo24.com\/it\/2022\/03\/22\/seed-group-e-nexxiot-come-partner-in-medio-oriente-e-nord-africa\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/loginfo24.com\/it\/2022\/03\/22\/seed-group-e-nexxiot-come-partner-in-medio-oriente-e-nord-africa\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/loginfo24.com\/it\/2022\/03\/22\/seed-group-e-nexxiot-come-partner-in-medio-oriente-e-nord-africa\/#primaryimage","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Nexxiot_22.3.22.jpg","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Nexxiot_22.3.22.jpg","width":1494,"height":954},{"@type":"BreadcrumbList","@id":"https:\/\/loginfo24.com\/it\/2022\/03\/22\/seed-group-e-nexxiot-come-partner-in-medio-oriente-e-nord-africa\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/loginfo24.com\/it\/"},{"@type":"ListItem","position":2,"name":"Seed Group e Nexxiot come partner in Medio Oriente e Nord Africa"}]},{"@type":"WebSite","@id":"https:\/\/loginfo24.com\/it\/#website","url":"https:\/\/loginfo24.com\/it\/","name":"Loginfo24","description":"Loginfo24 \u00e8 la piattaforma dedicata alla logistica e alle catene di fornitura con informazioni disponibili 24 ore su 24.","publisher":{"@id":"https:\/\/loginfo24.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/loginfo24.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/loginfo24.com\/it\/#organization","name":"Logismedia Group AG","url":"https:\/\/loginfo24.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/loginfo24.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","width":938,"height":351,"caption":"Logismedia Group AG"},"image":{"@id":"https:\/\/loginfo24.com\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","https:\/\/www.linkedin.com\/company\/lofinfo24\/"]}]}},"_links":{"self":[{"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/posts\/55271","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/comments?post=55271"}],"version-history":[{"count":0,"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/posts\/55271\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/media\/10705"}],"wp:attachment":[{"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/media?parent=55271"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/categories?post=55271"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/tags?post=55271"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}