{"id":54887,"date":"2022-02-24T17:51:48","date_gmt":"2022-02-24T16:51:48","guid":{"rendered":"https:\/\/blog.brand-architecture.at\/2022\/02\/24\/dhl-express-apre-un-nuovo-sito-a-dortmund\/"},"modified":"2022-02-24T17:51:48","modified_gmt":"2022-02-24T16:51:48","slug":"dhl-express-apre-un-nuovo-sito-a-dortmund","status":"publish","type":"post","link":"https:\/\/loginfo24.com\/it\/2022\/02\/24\/dhl-express-apre-un-nuovo-sito-a-dortmund\/","title":{"rendered":"DHL Express apre un nuovo sito a Dortmund"},"content":{"rendered":"<h5><strong>DHL Express Germania ha avviato con successo il nuovo sito in Germaniastra\u00dfe 56-60 a Dortmund nell&#8217;ambito del suo ampio programma infrastrutturale. Qui, il fornitore leader mondiale di servizi espressi internazionali dispone ora di spazi produttivi e amministrativi di oltre 5.000 m\u00b2 su una superficie totale di oltre 20.000 m\u00b2. La superficie produttiva del precedente sito di Dortmund \u00e8 stata quasi raddoppiata.<\/strong><\/h5>\n<p> &#8220;La nostra nuova sede si distingue rispetto a quella precedente non solo per le sue dimensioni, ma ottimizza anche i nostri processi grazie alle sue attrezzature&#8221;, spiega Markus Reckling, Managing Director di DHL Express Germania, i vantaggi del progetto di investimento da 25 milioni di euro. &#8220;A causa delle tendenze della digitalizzazione e della globalizzazione, anche a seguito della pandemia, i volumi di spedizione continuano a crescere. Grazie all&#8217;espansione della capacit\u00e0 e alla gestione pi\u00f9 efficiente delle spedizioni, siamo ora ben attrezzati a Dortmund per gli anni a venire.&#8221;<\/p>\n<h5><strong>Materiali a risparmio energetico<\/strong><\/h5>\n<p> Inoltre, nella pianificazione dell&#8217;edificio \u00e8 stata prestata particolare attenzione all&#8217;uso di materiali a risparmio energetico e, ad esempio, per l&#8217;illuminazione \u00e8 stata utilizzata la tecnologia LED pi\u00f9 moderna. Inoltre, il sito dispone di un impianto fotovoltaico che genera 100 kW di picco per il funzionamento della tecnologia domestica, dei server e dei computer. All&#8217;esterno, l&#8217;edificio \u00e8 gi\u00e0 predisposto per un massimo di 64 posizioni per veicoli elettrici, di cui inizialmente 12 sono state dotate di wallbox per veicoli elettrici.<\/p>\n<h5><strong>Posti di lavoro ergonomici<\/strong><\/h5>\n<p> Inoltre, i 230 dipendenti del nuovo sito, situato a sette chilometri dalla precedente sede, beneficiano di posti di lavoro ergonomici in ufficio e nel magazzino, oltre che di spazi sociali modernamente attrezzati. La nuova stazione DHL Express soddisfa inoltre i requisiti di sicurezza della Transported Asset Protection Association (TAPA). Pertanto, anche questa stazione dell&#8217;azienda riceve la certificazione TAPA Classe A, riconosciuta a livello mondiale, come il massimo livello di sicurezza nel trasporto aereo.<\/p>\n<h5><strong>Parte di un ampio programma infrastrutturale<\/strong><\/h5>\n<p> Il nuovo edificio a Dortmund fa parte di un ampio programma infrastrutturale con cui DHL Express sta modernizzando e ampliando radicalmente i suoi stabilimenti produttivi in Germania, tra cui Neu-Ulm, Brema e Monaco. L&#8217;area di servizio della stazione di Dortmund comprende tutte le aree postali 44 e 58. Inoltre, vengono servite parti delle aree postali 45 (fino a Ennigerloh) e 59 (fino a Brilon).<br \/>Foto: \u00a9 DHL<\/p>\n","protected":false},"excerpt":{"rendered":"<p>DHL Express Germania ha avviato con successo il nuovo sito in Germaniastra\u00dfe 56-60 a Dortmund nell&#8217;ambito del suo ampio programma infrastrutturale. Qui, il fornitore leader mondiale<span class=\"excerpt-hellip\"> [\u2026]<\/span><\/p>\n","protected":false},"author":0,"featured_media":10889,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1557,1556,1560,1561],"tags":[],"class_list":["post-54887","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-forwarding-logistics","category-intermodal-road","category-intralogistics","category-regions"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>DHL Express apre un nuovo sito a Dortmund - Loginfo24<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/loginfo24.com\/it\/2022\/02\/24\/dhl-express-apre-un-nuovo-sito-a-dortmund\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"DHL Express apre un nuovo sito a Dortmund - Loginfo24\" \/>\n<meta property=\"og:description\" content=\"DHL Express Germania ha avviato con successo il nuovo sito in Germaniastra\u00dfe 56-60 a Dortmund nell&#8217;ambito del suo ampio programma infrastrutturale. Qui, il fornitore leader mondiale [\u2026]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/loginfo24.com\/it\/2022\/02\/24\/dhl-express-apre-un-nuovo-sito-a-dortmund\/\" \/>\n<meta property=\"og:site_name\" content=\"Loginfo24\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/\" \/>\n<meta property=\"article:published_time\" content=\"2022-02-24T16:51:48+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/DHL_24.2.22.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1626\" \/>\n\t<meta property=\"og:image:height\" content=\"805\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2022\\\/02\\\/24\\\/dhl-express-apre-un-nuovo-sito-a-dortmund\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2022\\\/02\\\/24\\\/dhl-express-apre-un-nuovo-sito-a-dortmund\\\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"DHL Express apre un nuovo sito a Dortmund\",\"datePublished\":\"2022-02-24T16:51:48+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2022\\\/02\\\/24\\\/dhl-express-apre-un-nuovo-sito-a-dortmund\\\/\"},\"wordCount\":385,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2022\\\/02\\\/24\\\/dhl-express-apre-un-nuovo-sito-a-dortmund\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/DHL_24.2.22.jpg\",\"articleSection\":[\"Forwarding &amp; Logistics\",\"Intermodal \\\/ Road\",\"Intralogistics\",\"Regions\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/it\\\/2022\\\/02\\\/24\\\/dhl-express-apre-un-nuovo-sito-a-dortmund\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2022\\\/02\\\/24\\\/dhl-express-apre-un-nuovo-sito-a-dortmund\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2022\\\/02\\\/24\\\/dhl-express-apre-un-nuovo-sito-a-dortmund\\\/\",\"name\":\"DHL Express apre un nuovo sito a Dortmund - Loginfo24\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2022\\\/02\\\/24\\\/dhl-express-apre-un-nuovo-sito-a-dortmund\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2022\\\/02\\\/24\\\/dhl-express-apre-un-nuovo-sito-a-dortmund\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/DHL_24.2.22.jpg\",\"datePublished\":\"2022-02-24T16:51:48+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2022\\\/02\\\/24\\\/dhl-express-apre-un-nuovo-sito-a-dortmund\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/it\\\/2022\\\/02\\\/24\\\/dhl-express-apre-un-nuovo-sito-a-dortmund\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2022\\\/02\\\/24\\\/dhl-express-apre-un-nuovo-sito-a-dortmund\\\/#primaryimage\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/DHL_24.2.22.jpg\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/DHL_24.2.22.jpg\",\"width\":1626,\"height\":805},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2022\\\/02\\\/24\\\/dhl-express-apre-un-nuovo-sito-a-dortmund\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"DHL Express apre un nuovo sito a Dortmund\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/\",\"name\":\"Loginfo24\",\"description\":\"Loginfo24 \u00e8 la piattaforma dedicata alla logistica e alle catene di fornitura con informazioni disponibili 24 ore su 24.\",\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#organization\",\"name\":\"Logismedia Group AG\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"width\":938,\"height\":351,\"caption\":\"Logismedia Group AG\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/people\\\/Loginfo24\\\/100057360583332\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/lofinfo24\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"DHL Express apre un nuovo sito a Dortmund - Loginfo24","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/loginfo24.com\/it\/2022\/02\/24\/dhl-express-apre-un-nuovo-sito-a-dortmund\/","og_locale":"it_IT","og_type":"article","og_title":"DHL Express apre un nuovo sito a Dortmund - Loginfo24","og_description":"DHL Express Germania ha avviato con successo il nuovo sito in Germaniastra\u00dfe 56-60 a Dortmund nell&#8217;ambito del suo ampio programma infrastrutturale. Qui, il fornitore leader mondiale [\u2026]","og_url":"https:\/\/loginfo24.com\/it\/2022\/02\/24\/dhl-express-apre-un-nuovo-sito-a-dortmund\/","og_site_name":"Loginfo24","article_publisher":"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","article_published_time":"2022-02-24T16:51:48+00:00","og_image":[{"width":1626,"height":805,"url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/DHL_24.2.22.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"2 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/loginfo24.com\/it\/2022\/02\/24\/dhl-express-apre-un-nuovo-sito-a-dortmund\/#article","isPartOf":{"@id":"https:\/\/loginfo24.com\/it\/2022\/02\/24\/dhl-express-apre-un-nuovo-sito-a-dortmund\/"},"author":{"name":"","@id":""},"headline":"DHL Express apre un nuovo sito a Dortmund","datePublished":"2022-02-24T16:51:48+00:00","mainEntityOfPage":{"@id":"https:\/\/loginfo24.com\/it\/2022\/02\/24\/dhl-express-apre-un-nuovo-sito-a-dortmund\/"},"wordCount":385,"commentCount":0,"publisher":{"@id":"https:\/\/loginfo24.com\/it\/#organization"},"image":{"@id":"https:\/\/loginfo24.com\/it\/2022\/02\/24\/dhl-express-apre-un-nuovo-sito-a-dortmund\/#primaryimage"},"thumbnailUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/DHL_24.2.22.jpg","articleSection":["Forwarding &amp; Logistics","Intermodal \/ Road","Intralogistics","Regions"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/loginfo24.com\/it\/2022\/02\/24\/dhl-express-apre-un-nuovo-sito-a-dortmund\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/loginfo24.com\/it\/2022\/02\/24\/dhl-express-apre-un-nuovo-sito-a-dortmund\/","url":"https:\/\/loginfo24.com\/it\/2022\/02\/24\/dhl-express-apre-un-nuovo-sito-a-dortmund\/","name":"DHL Express apre un nuovo sito a Dortmund - Loginfo24","isPartOf":{"@id":"https:\/\/loginfo24.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/loginfo24.com\/it\/2022\/02\/24\/dhl-express-apre-un-nuovo-sito-a-dortmund\/#primaryimage"},"image":{"@id":"https:\/\/loginfo24.com\/it\/2022\/02\/24\/dhl-express-apre-un-nuovo-sito-a-dortmund\/#primaryimage"},"thumbnailUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/DHL_24.2.22.jpg","datePublished":"2022-02-24T16:51:48+00:00","breadcrumb":{"@id":"https:\/\/loginfo24.com\/it\/2022\/02\/24\/dhl-express-apre-un-nuovo-sito-a-dortmund\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/loginfo24.com\/it\/2022\/02\/24\/dhl-express-apre-un-nuovo-sito-a-dortmund\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/loginfo24.com\/it\/2022\/02\/24\/dhl-express-apre-un-nuovo-sito-a-dortmund\/#primaryimage","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/DHL_24.2.22.jpg","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/DHL_24.2.22.jpg","width":1626,"height":805},{"@type":"BreadcrumbList","@id":"https:\/\/loginfo24.com\/it\/2022\/02\/24\/dhl-express-apre-un-nuovo-sito-a-dortmund\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/loginfo24.com\/it\/"},{"@type":"ListItem","position":2,"name":"DHL Express apre un nuovo sito a Dortmund"}]},{"@type":"WebSite","@id":"https:\/\/loginfo24.com\/it\/#website","url":"https:\/\/loginfo24.com\/it\/","name":"Loginfo24","description":"Loginfo24 \u00e8 la piattaforma dedicata alla logistica e alle catene di fornitura con informazioni disponibili 24 ore su 24.","publisher":{"@id":"https:\/\/loginfo24.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/loginfo24.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/loginfo24.com\/it\/#organization","name":"Logismedia Group AG","url":"https:\/\/loginfo24.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/loginfo24.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","width":938,"height":351,"caption":"Logismedia Group AG"},"image":{"@id":"https:\/\/loginfo24.com\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","https:\/\/www.linkedin.com\/company\/lofinfo24\/"]}]}},"_links":{"self":[{"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/posts\/54887","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/comments?post=54887"}],"version-history":[{"count":0,"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/posts\/54887\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/media\/10889"}],"wp:attachment":[{"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/media?parent=54887"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/categories?post=54887"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/tags?post=54887"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}