{"id":54384,"date":"2022-02-03T18:42:25","date_gmt":"2022-02-03T17:42:25","guid":{"rendered":"https:\/\/blog.brand-architecture.at\/2022\/02\/03\/iaa-veicoli-commerciali-per-la-prima-volta-come-iaa-transportation\/"},"modified":"2022-02-03T18:42:25","modified_gmt":"2022-02-03T17:42:25","slug":"iaa-veicoli-commerciali-per-la-prima-volta-come-iaa-transportation","status":"publish","type":"post","link":"https:\/\/loginfo24.com\/it\/2022\/02\/03\/iaa-veicoli-commerciali-per-la-prima-volta-come-iaa-transportation\/","title":{"rendered":"IAA Veicoli Commerciali per la prima volta come IAA TRANSPORTATION"},"content":{"rendered":"<h5><strong>Sotto il motto &#8220;Persone e merci in movimento&#8221;, l&#8217;IAA TRANSPORTATION si svolger\u00e0 dal 20 al 25 settembre 2022 presso il sito della Deutsche Messe AG a Hannover. Oltre alla presentazione di novit\u00e0 nel settore dei veicoli, al centro ci saranno i settori della logistica, del trasporto e della digitalizzazione del traffico dei veicoli commerciali nel percorso verso la neutralit\u00e0 climatica.<\/strong><\/h5>\n<p>(Berlino\/Hannover) Con questo, l&#8217;attuale IAA Veicoli Commerciali amplia la gamma di temi e espositori e diventa con un nuovo nome l&#8217;IAA TRANSPORTATION, la piattaforma di riferimento internazionale per logistica, veicoli commerciali, autobus e il settore dei trasporti. Con il concetto di evento ampliato, connette i produttori e fornitori rilevanti nei settori dei veicoli commerciali, autobus e logistica con i principali fornitori tecnologici. Un obiettivo importante del nuovo concetto \u00e8 quello di concentrare maggiormente l&#8217;attenzione sulla trasformazione climatica e tecnologica dell&#8217;intero settore dei trasporti come piattaforma internazionale.<\/p>\n<p>&#8220;L&#8217;IAA TRANSPORTATION \u00e8 la fiera leader per trasporti, veicoli commerciali e logistica. Il nostro concetto di successo per una realizzazione sicura della IAA MOBILITY 2021 sar\u00e0 applicato anche all&#8217;IAA TRANSPORTATION di Hannover: L&#8217;attuale stato delle registrazioni dimostra che l&#8217;ampliamento del concetto \u00e8 stato accolto positivamente dal settore. Sono gi\u00e0 arrivate registrazioni di espositori da pi\u00f9 di quaranta paesi. L&#8217;alto numero di registrazioni \u00e8 incoraggiante e sottolinea anche il desiderio degli espositori di offrire nuovamente ai clienti un&#8217;esperienza dal vivo con i nuovi prodotti&#8221;, afferma J\u00fcrgen Mindel, direttore generale del VDA.<\/p>\n<h5><strong>IAA TRANSPORTATION con quattro giorni tematici<\/strong><\/h5>\n<p>Il nuovo concetto dell&#8217;IAA TRANSPORTATION prevede anche una connessione tra presentazione di novit\u00e0, pubblico specializzato e scambio di esperti nell&#8217;ambito della IAA-Conference 2022. Per consentire agli espositori e ai visitatori la migliore presenza possibile del loro pubblico target, in quattro giorni saranno al centro della IAA-Conference diversi temi guida.<\/p>\n<ul>\n<li><strong>FUTURO DELLA LOGISTICA<\/strong>, con i temi delle catene di approvvigionamento, camion, integrazione ferrovia &amp; navigazione, e-mobilit\u00e0 e tecnologia dell&#8217;idrogeno nel trasporto pesante e nei veicoli commerciali leggeri e pesanti, nonch\u00e9 innovazioni tecnologiche e digitali per la catena logistica<\/li>\n<li><strong>COMMERCIO &amp; LOGISTICA<\/strong>, con i temi dell&#8217;ultima miglio, logistica in centro citt\u00e0, furgoni, trasportatori, biciclette cargo, robot di consegna, digitalizzazione e soluzioni innovative per il commercio al dettaglio, e-commerce<\/li>\n<li><strong>INFRASTRUTTURA<\/strong>, con i temi delle infrastrutture di ricarica elettrica e a idrogeno, espansione delle reti dati, gestione dei dati, trasporto in autobus a lunga distanza, collegamento con il trasporto ferroviario<\/li>\n<li><strong>INNOVAZIONI NEL TRASPORTO PUBBLICO<\/strong>, con i temi autobus, elettrificazione, idrogeno, ride-sharing, ride-hailing, MaaS, rete digitale dell&#8217;offerta esistente<\/li>\n<\/ul>\n<p>Le aziende e le associazioni interessate possono contattare l&#8217;organizzatore e presentare i loro concetti.<\/p>\n<h5><strong>&#8220;IAA Last Mile Experience Area&#8221; stabilisce un nuovo standard<\/strong><\/h5>\n<p>L&#8217;IAA TRANSPORTATION presenta con l&#8217;Last Mile Experience Area un innovativo nuovo concetto di padiglione. Per la prima volta in una fiera, verr\u00e0 allestito un intero scenario urbano al coperto, all&#8217;interno del quale verranno presentate le ultime soluzioni per l&#8217;ultima miglio in azione. Saranno mostrati l&#8217;uso di droni per pacchi, robot di consegna, e-transporters, e-cargo-bikes, cos\u00ec come novit\u00e0 dall&#8217;Internet delle Cose, reti dati e tecnologie cloud, piattaforme SaaS e hub decentralizzati.<\/p>\n<p>&#8220;Con il nuovo formato vogliamo mettere in contatto pianificatori urbani, fornitori di tecnologia, dettaglianti di generi alimentari e servizi di consegna con gli attori del settore della logistica, sindaci e politica locale. Solo con soluzioni intelligenti, innovative e socialmente accettate saremo in grado di soddisfare la crescente domanda di logistica in centro citt\u00e0 e di portare avanti la neutralit\u00e0 climatica&#8221;, afferma J\u00fcrgen Mindel, direttore generale del VDA.<\/p>\n<h5><strong>Assegnazione di premi di settore rinomati<\/strong><\/h5>\n<p>All&#8217;IAA TRANSPORTATION verranno inoltre assegnati premi in diversi settori della mobilit\u00e0. I vincitori dei rinomati concorsi &#8220;Bus of the Year&#8221;, &#8220;Coach of the Year&#8221; e per la prima volta &#8220;Cargo Bike of the Year&#8221; saranno presentati e premiati. &#8220;Siamo in buoni colloqui con &#8220;Truck of the Year&#8221;, &#8220;Trailer Innovation Award&#8221; e &#8220;Van of the Year&#8221; e sono ottimista che nel 2022 presenteremo tutti questi premi a Hannover, dando loro la massima visibilit\u00e0. Siamo particolarmente felici di poter accogliere il &#8220;Cargo Bike of the Year&#8221; all&#8217;IAA. Questo dimostra chiaramente quanto sia variegato il nostro portafoglio&#8221;, afferma J\u00fcrgen Mindel.<\/p>\n<p>Foto: \u00a9 IAA TRANSPORTATION<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Sotto il motto &#8220;Persone e merci in movimento&#8221;, l&#8217;IAA TRANSPORTATION si svolger\u00e0 dal 20 al 25 settembre 2022 presso il sito della Deutsche Messe AG a<span class=\"excerpt-hellip\"> [\u2026]<\/span><\/p>\n","protected":false},"author":0,"featured_media":11085,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1557,1561],"tags":[],"class_list":["post-54384","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-forwarding-logistics","category-regions"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>IAA Veicoli Commerciali per la prima volta come IAA TRANSPORTATION - Loginfo24<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/loginfo24.com\/it\/2022\/02\/03\/iaa-veicoli-commerciali-per-la-prima-volta-come-iaa-transportation\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"IAA Veicoli Commerciali per la prima volta come IAA TRANSPORTATION - Loginfo24\" \/>\n<meta property=\"og:description\" content=\"Sotto il motto &#8220;Persone e merci in movimento&#8221;, l&#8217;IAA TRANSPORTATION si svolger\u00e0 dal 20 al 25 settembre 2022 presso il sito della Deutsche Messe AG a [\u2026]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/loginfo24.com\/it\/2022\/02\/03\/iaa-veicoli-commerciali-per-la-prima-volta-come-iaa-transportation\/\" \/>\n<meta property=\"og:site_name\" content=\"Loginfo24\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/\" \/>\n<meta property=\"article:published_time\" content=\"2022-02-03T17:42:25+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/IAA_3.2.22.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1255\" \/>\n\t<meta property=\"og:image:height\" content=\"728\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2022\\\/02\\\/03\\\/iaa-veicoli-commerciali-per-la-prima-volta-come-iaa-transportation\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2022\\\/02\\\/03\\\/iaa-veicoli-commerciali-per-la-prima-volta-come-iaa-transportation\\\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"IAA Veicoli Commerciali per la prima volta come IAA TRANSPORTATION\",\"datePublished\":\"2022-02-03T17:42:25+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2022\\\/02\\\/03\\\/iaa-veicoli-commerciali-per-la-prima-volta-come-iaa-transportation\\\/\"},\"wordCount\":700,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2022\\\/02\\\/03\\\/iaa-veicoli-commerciali-per-la-prima-volta-come-iaa-transportation\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/IAA_3.2.22.jpg\",\"articleSection\":[\"Forwarding &amp; Logistics\",\"Regions\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/it\\\/2022\\\/02\\\/03\\\/iaa-veicoli-commerciali-per-la-prima-volta-come-iaa-transportation\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2022\\\/02\\\/03\\\/iaa-veicoli-commerciali-per-la-prima-volta-come-iaa-transportation\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2022\\\/02\\\/03\\\/iaa-veicoli-commerciali-per-la-prima-volta-come-iaa-transportation\\\/\",\"name\":\"IAA Veicoli Commerciali per la prima volta come IAA TRANSPORTATION - Loginfo24\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2022\\\/02\\\/03\\\/iaa-veicoli-commerciali-per-la-prima-volta-come-iaa-transportation\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2022\\\/02\\\/03\\\/iaa-veicoli-commerciali-per-la-prima-volta-come-iaa-transportation\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/IAA_3.2.22.jpg\",\"datePublished\":\"2022-02-03T17:42:25+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2022\\\/02\\\/03\\\/iaa-veicoli-commerciali-per-la-prima-volta-come-iaa-transportation\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/it\\\/2022\\\/02\\\/03\\\/iaa-veicoli-commerciali-per-la-prima-volta-come-iaa-transportation\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2022\\\/02\\\/03\\\/iaa-veicoli-commerciali-per-la-prima-volta-come-iaa-transportation\\\/#primaryimage\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/IAA_3.2.22.jpg\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/IAA_3.2.22.jpg\",\"width\":1255,\"height\":728},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2022\\\/02\\\/03\\\/iaa-veicoli-commerciali-per-la-prima-volta-come-iaa-transportation\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"IAA Veicoli Commerciali per la prima volta come IAA TRANSPORTATION\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/\",\"name\":\"Loginfo24\",\"description\":\"Loginfo24 \u00e8 la piattaforma dedicata alla logistica e alle catene di fornitura con informazioni disponibili 24 ore su 24.\",\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#organization\",\"name\":\"Logismedia Group AG\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"width\":938,\"height\":351,\"caption\":\"Logismedia Group AG\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/people\\\/Loginfo24\\\/100057360583332\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/lofinfo24\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"IAA Veicoli Commerciali per la prima volta come IAA TRANSPORTATION - Loginfo24","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/loginfo24.com\/it\/2022\/02\/03\/iaa-veicoli-commerciali-per-la-prima-volta-come-iaa-transportation\/","og_locale":"it_IT","og_type":"article","og_title":"IAA Veicoli Commerciali per la prima volta come IAA TRANSPORTATION - Loginfo24","og_description":"Sotto il motto &#8220;Persone e merci in movimento&#8221;, l&#8217;IAA TRANSPORTATION si svolger\u00e0 dal 20 al 25 settembre 2022 presso il sito della Deutsche Messe AG a [\u2026]","og_url":"https:\/\/loginfo24.com\/it\/2022\/02\/03\/iaa-veicoli-commerciali-per-la-prima-volta-come-iaa-transportation\/","og_site_name":"Loginfo24","article_publisher":"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","article_published_time":"2022-02-03T17:42:25+00:00","og_image":[{"width":1255,"height":728,"url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/IAA_3.2.22.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"3 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/loginfo24.com\/it\/2022\/02\/03\/iaa-veicoli-commerciali-per-la-prima-volta-come-iaa-transportation\/#article","isPartOf":{"@id":"https:\/\/loginfo24.com\/it\/2022\/02\/03\/iaa-veicoli-commerciali-per-la-prima-volta-come-iaa-transportation\/"},"author":{"name":"","@id":""},"headline":"IAA Veicoli Commerciali per la prima volta come IAA TRANSPORTATION","datePublished":"2022-02-03T17:42:25+00:00","mainEntityOfPage":{"@id":"https:\/\/loginfo24.com\/it\/2022\/02\/03\/iaa-veicoli-commerciali-per-la-prima-volta-come-iaa-transportation\/"},"wordCount":700,"commentCount":0,"publisher":{"@id":"https:\/\/loginfo24.com\/it\/#organization"},"image":{"@id":"https:\/\/loginfo24.com\/it\/2022\/02\/03\/iaa-veicoli-commerciali-per-la-prima-volta-come-iaa-transportation\/#primaryimage"},"thumbnailUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/IAA_3.2.22.jpg","articleSection":["Forwarding &amp; Logistics","Regions"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/loginfo24.com\/it\/2022\/02\/03\/iaa-veicoli-commerciali-per-la-prima-volta-come-iaa-transportation\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/loginfo24.com\/it\/2022\/02\/03\/iaa-veicoli-commerciali-per-la-prima-volta-come-iaa-transportation\/","url":"https:\/\/loginfo24.com\/it\/2022\/02\/03\/iaa-veicoli-commerciali-per-la-prima-volta-come-iaa-transportation\/","name":"IAA Veicoli Commerciali per la prima volta come IAA TRANSPORTATION - Loginfo24","isPartOf":{"@id":"https:\/\/loginfo24.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/loginfo24.com\/it\/2022\/02\/03\/iaa-veicoli-commerciali-per-la-prima-volta-come-iaa-transportation\/#primaryimage"},"image":{"@id":"https:\/\/loginfo24.com\/it\/2022\/02\/03\/iaa-veicoli-commerciali-per-la-prima-volta-come-iaa-transportation\/#primaryimage"},"thumbnailUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/IAA_3.2.22.jpg","datePublished":"2022-02-03T17:42:25+00:00","breadcrumb":{"@id":"https:\/\/loginfo24.com\/it\/2022\/02\/03\/iaa-veicoli-commerciali-per-la-prima-volta-come-iaa-transportation\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/loginfo24.com\/it\/2022\/02\/03\/iaa-veicoli-commerciali-per-la-prima-volta-come-iaa-transportation\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/loginfo24.com\/it\/2022\/02\/03\/iaa-veicoli-commerciali-per-la-prima-volta-come-iaa-transportation\/#primaryimage","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/IAA_3.2.22.jpg","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/IAA_3.2.22.jpg","width":1255,"height":728},{"@type":"BreadcrumbList","@id":"https:\/\/loginfo24.com\/it\/2022\/02\/03\/iaa-veicoli-commerciali-per-la-prima-volta-come-iaa-transportation\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/loginfo24.com\/it\/"},{"@type":"ListItem","position":2,"name":"IAA Veicoli Commerciali per la prima volta come IAA TRANSPORTATION"}]},{"@type":"WebSite","@id":"https:\/\/loginfo24.com\/it\/#website","url":"https:\/\/loginfo24.com\/it\/","name":"Loginfo24","description":"Loginfo24 \u00e8 la piattaforma dedicata alla logistica e alle catene di fornitura con informazioni disponibili 24 ore su 24.","publisher":{"@id":"https:\/\/loginfo24.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/loginfo24.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/loginfo24.com\/it\/#organization","name":"Logismedia Group AG","url":"https:\/\/loginfo24.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/loginfo24.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","width":938,"height":351,"caption":"Logismedia Group AG"},"image":{"@id":"https:\/\/loginfo24.com\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","https:\/\/www.linkedin.com\/company\/lofinfo24\/"]}]}},"_links":{"self":[{"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/posts\/54384","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/comments?post=54384"}],"version-history":[{"count":0,"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/posts\/54384\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/media\/11085"}],"wp:attachment":[{"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/media?parent=54384"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/categories?post=54384"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/tags?post=54384"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}