{"id":54354,"date":"2022-02-03T18:03:52","date_gmt":"2022-02-03T17:03:52","guid":{"rendered":"https:\/\/blog.brand-architecture.at\/2022\/02\/03\/logivest-media-una-proprieta-logistica-a-westech-solar-energy\/"},"modified":"2022-02-03T18:03:52","modified_gmt":"2022-02-03T17:03:52","slug":"logivest-media-una-proprieta-logistica-a-westech-solar-energy","status":"publish","type":"post","link":"https:\/\/loginfo24.com\/it\/2022\/02\/03\/logivest-media-una-proprieta-logistica-a-westech-solar-energy\/","title":{"rendered":"Logivest media una propriet\u00e0 logistica a Westech-Solar Energy"},"content":{"rendered":"<h4><b><span style=\"font-family: 'Cambria',serif\">A Garching, vicino a Monaco, Logivest ha mediato uno spazio logistico di 1.320 metri quadrati per Westech-Solar Energy GmbH. Lo spazio comprende 1.200 metri quadrati di area di magazzino e 120 metri quadrati di area uffici nell&#8217;area commerciale di Garching-Hochbr\u00fcck.<\/span><\/b><\/h4>\n<p><span style=\"font-family: 'Cambria',serif\">(Monaco\/Garching) Il nuovo inquilino, Westech-Solar Energy GmbH con sede a Planegg, \u00e8 orientato alla vendita, allo sviluppo e alla produzione di prodotti e sistemi innovativi per la produzione di energia rinnovabile ecologica.<\/span><\/p>\n<p><span style=\"font-family: 'Cambria',serif\">Le superfici in affitto consistono in un&#8217;unit\u00e0 seminterrata con una rampa nell&#8217;area commerciale multi-inquilino. L&#8217;azienda ha gi\u00e0 occupato i nuovi spazi nel dicembre 2021 e li utilizza per lo stoccaggio di pannelli solari.<\/span><\/p>\n<p><span style=\"font-family: 'Cambria',serif\">\u00a0\u201eCon la sua posizione nell&#8217;area commerciale di Garching-Hochbr\u00fcck, il sito offre un&#8217;eccellente connessione alle autostrade A 9 e A 92, cos\u00ec come alla tangenziale di Monaco A 99. In particolare, quest&#8217;ultima \u00e8 stata un criterio importante per Westech-Solar Energy, poich\u00e9 consente di raggiungere la sede centrale dell&#8217;azienda a Planegg, dall&#8217;altra parte di Monaco, in un tempo relativamente breve\u201c, afferma Maximilian Hohendorf, Consultant Industrial &amp; Logistics Letting presso Logivest.<\/span><\/p>\n<p><span style=\"font-family: 'Cambria',serif\">Foto: \u00a9 Logivest<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Garching, vicino a Monaco, Logivest ha mediato uno spazio logistico di 1.320 metri quadrati per Westech-Solar Energy GmbH. Lo spazio comprende 1.200 metri quadrati di<span class=\"excerpt-hellip\"> [\u2026]<\/span><\/p>\n","protected":false},"author":0,"featured_media":11095,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1557,1560,1561],"tags":[],"class_list":["post-54354","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-forwarding-logistics","category-intralogistics","category-regions"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Logivest media una propriet\u00e0 logistica a Westech-Solar Energy - Loginfo24<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/loginfo24.com\/it\/2022\/02\/03\/logivest-media-una-proprieta-logistica-a-westech-solar-energy\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Logivest media una propriet\u00e0 logistica a Westech-Solar Energy - Loginfo24\" \/>\n<meta property=\"og:description\" content=\"A Garching, vicino a Monaco, Logivest ha mediato uno spazio logistico di 1.320 metri quadrati per Westech-Solar Energy GmbH. Lo spazio comprende 1.200 metri quadrati di [\u2026]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/loginfo24.com\/it\/2022\/02\/03\/logivest-media-una-proprieta-logistica-a-westech-solar-energy\/\" \/>\n<meta property=\"og:site_name\" content=\"Loginfo24\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/\" \/>\n<meta property=\"article:published_time\" content=\"2022-02-03T17:03:52+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Logivest_3.2.22.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1218\" \/>\n\t<meta property=\"og:image:height\" content=\"806\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2022\\\/02\\\/03\\\/logivest-media-una-proprieta-logistica-a-westech-solar-energy\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2022\\\/02\\\/03\\\/logivest-media-una-proprieta-logistica-a-westech-solar-energy\\\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Logivest media una propriet\u00e0 logistica a Westech-Solar Energy\",\"datePublished\":\"2022-02-03T17:03:52+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2022\\\/02\\\/03\\\/logivest-media-una-proprieta-logistica-a-westech-solar-energy\\\/\"},\"wordCount\":186,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2022\\\/02\\\/03\\\/logivest-media-una-proprieta-logistica-a-westech-solar-energy\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/Logivest_3.2.22.jpg\",\"articleSection\":[\"Forwarding &amp; Logistics\",\"Intralogistics\",\"Regions\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/it\\\/2022\\\/02\\\/03\\\/logivest-media-una-proprieta-logistica-a-westech-solar-energy\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2022\\\/02\\\/03\\\/logivest-media-una-proprieta-logistica-a-westech-solar-energy\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2022\\\/02\\\/03\\\/logivest-media-una-proprieta-logistica-a-westech-solar-energy\\\/\",\"name\":\"Logivest media una propriet\u00e0 logistica a Westech-Solar Energy - Loginfo24\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2022\\\/02\\\/03\\\/logivest-media-una-proprieta-logistica-a-westech-solar-energy\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2022\\\/02\\\/03\\\/logivest-media-una-proprieta-logistica-a-westech-solar-energy\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/Logivest_3.2.22.jpg\",\"datePublished\":\"2022-02-03T17:03:52+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2022\\\/02\\\/03\\\/logivest-media-una-proprieta-logistica-a-westech-solar-energy\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/it\\\/2022\\\/02\\\/03\\\/logivest-media-una-proprieta-logistica-a-westech-solar-energy\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2022\\\/02\\\/03\\\/logivest-media-una-proprieta-logistica-a-westech-solar-energy\\\/#primaryimage\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/Logivest_3.2.22.jpg\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/Logivest_3.2.22.jpg\",\"width\":1218,\"height\":806},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2022\\\/02\\\/03\\\/logivest-media-una-proprieta-logistica-a-westech-solar-energy\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Logivest media una propriet\u00e0 logistica a Westech-Solar Energy\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/\",\"name\":\"Loginfo24\",\"description\":\"Loginfo24 \u00e8 la piattaforma dedicata alla logistica e alle catene di fornitura con informazioni disponibili 24 ore su 24.\",\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#organization\",\"name\":\"Logismedia Group AG\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"width\":938,\"height\":351,\"caption\":\"Logismedia Group AG\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/people\\\/Loginfo24\\\/100057360583332\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/lofinfo24\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Logivest media una propriet\u00e0 logistica a Westech-Solar Energy - Loginfo24","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/loginfo24.com\/it\/2022\/02\/03\/logivest-media-una-proprieta-logistica-a-westech-solar-energy\/","og_locale":"it_IT","og_type":"article","og_title":"Logivest media una propriet\u00e0 logistica a Westech-Solar Energy - Loginfo24","og_description":"A Garching, vicino a Monaco, Logivest ha mediato uno spazio logistico di 1.320 metri quadrati per Westech-Solar Energy GmbH. Lo spazio comprende 1.200 metri quadrati di [\u2026]","og_url":"https:\/\/loginfo24.com\/it\/2022\/02\/03\/logivest-media-una-proprieta-logistica-a-westech-solar-energy\/","og_site_name":"Loginfo24","article_publisher":"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","article_published_time":"2022-02-03T17:03:52+00:00","og_image":[{"width":1218,"height":806,"url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Logivest_3.2.22.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/loginfo24.com\/it\/2022\/02\/03\/logivest-media-una-proprieta-logistica-a-westech-solar-energy\/#article","isPartOf":{"@id":"https:\/\/loginfo24.com\/it\/2022\/02\/03\/logivest-media-una-proprieta-logistica-a-westech-solar-energy\/"},"author":{"name":"","@id":""},"headline":"Logivest media una propriet\u00e0 logistica a Westech-Solar Energy","datePublished":"2022-02-03T17:03:52+00:00","mainEntityOfPage":{"@id":"https:\/\/loginfo24.com\/it\/2022\/02\/03\/logivest-media-una-proprieta-logistica-a-westech-solar-energy\/"},"wordCount":186,"commentCount":0,"publisher":{"@id":"https:\/\/loginfo24.com\/it\/#organization"},"image":{"@id":"https:\/\/loginfo24.com\/it\/2022\/02\/03\/logivest-media-una-proprieta-logistica-a-westech-solar-energy\/#primaryimage"},"thumbnailUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Logivest_3.2.22.jpg","articleSection":["Forwarding &amp; Logistics","Intralogistics","Regions"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/loginfo24.com\/it\/2022\/02\/03\/logivest-media-una-proprieta-logistica-a-westech-solar-energy\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/loginfo24.com\/it\/2022\/02\/03\/logivest-media-una-proprieta-logistica-a-westech-solar-energy\/","url":"https:\/\/loginfo24.com\/it\/2022\/02\/03\/logivest-media-una-proprieta-logistica-a-westech-solar-energy\/","name":"Logivest media una propriet\u00e0 logistica a Westech-Solar Energy - Loginfo24","isPartOf":{"@id":"https:\/\/loginfo24.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/loginfo24.com\/it\/2022\/02\/03\/logivest-media-una-proprieta-logistica-a-westech-solar-energy\/#primaryimage"},"image":{"@id":"https:\/\/loginfo24.com\/it\/2022\/02\/03\/logivest-media-una-proprieta-logistica-a-westech-solar-energy\/#primaryimage"},"thumbnailUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Logivest_3.2.22.jpg","datePublished":"2022-02-03T17:03:52+00:00","breadcrumb":{"@id":"https:\/\/loginfo24.com\/it\/2022\/02\/03\/logivest-media-una-proprieta-logistica-a-westech-solar-energy\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/loginfo24.com\/it\/2022\/02\/03\/logivest-media-una-proprieta-logistica-a-westech-solar-energy\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/loginfo24.com\/it\/2022\/02\/03\/logivest-media-una-proprieta-logistica-a-westech-solar-energy\/#primaryimage","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Logivest_3.2.22.jpg","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Logivest_3.2.22.jpg","width":1218,"height":806},{"@type":"BreadcrumbList","@id":"https:\/\/loginfo24.com\/it\/2022\/02\/03\/logivest-media-una-proprieta-logistica-a-westech-solar-energy\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/loginfo24.com\/it\/"},{"@type":"ListItem","position":2,"name":"Logivest media una propriet\u00e0 logistica a Westech-Solar Energy"}]},{"@type":"WebSite","@id":"https:\/\/loginfo24.com\/it\/#website","url":"https:\/\/loginfo24.com\/it\/","name":"Loginfo24","description":"Loginfo24 \u00e8 la piattaforma dedicata alla logistica e alle catene di fornitura con informazioni disponibili 24 ore su 24.","publisher":{"@id":"https:\/\/loginfo24.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/loginfo24.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/loginfo24.com\/it\/#organization","name":"Logismedia Group AG","url":"https:\/\/loginfo24.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/loginfo24.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","width":938,"height":351,"caption":"Logismedia Group AG"},"image":{"@id":"https:\/\/loginfo24.com\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","https:\/\/www.linkedin.com\/company\/lofinfo24\/"]}]}},"_links":{"self":[{"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/posts\/54354","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/comments?post=54354"}],"version-history":[{"count":0,"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/posts\/54354\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/media\/11095"}],"wp:attachment":[{"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/media?parent=54354"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/categories?post=54354"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/tags?post=54354"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}