{"id":54074,"date":"2021-12-09T19:08:52","date_gmt":"2021-12-09T18:08:52","guid":{"rendered":"https:\/\/blog.brand-architecture.at\/2021\/12\/09\/i-clienti-svizzeri-sono-soddisfatti-del-loro-servizio-postale\/"},"modified":"2021-12-09T19:08:52","modified_gmt":"2021-12-09T18:08:52","slug":"i-clienti-svizzeri-sono-soddisfatti-del-loro-servizio-postale","status":"publish","type":"post","link":"https:\/\/loginfo24.com\/it\/2021\/12\/09\/i-clienti-svizzeri-sono-soddisfatti-del-loro-servizio-postale\/","title":{"rendered":"I clienti svizzeri sono soddisfatti del loro servizio postale"},"content":{"rendered":"<h5><strong>La Posta riceve un buon feedback dai suoi clienti. Nella survey di quest&#8217;anno sulla soddisfazione dei clienti, raggiunge un ottimo risultato di 81 su 100 punti. Questo in un anno ancora segnato dalla pandemia di Corona e dall&#8217;aumento dei volumi di pacchi. Un ringraziamento va ancora una volta ai nostri collaboratori.<\/strong><\/h5>\n<p>(Berna) L&#8217;annuale indagine sulla soddisfazione dei clienti fa parte della tradizione della Posta. Da 22 anni a questa parte, misura la soddisfazione dei suoi clienti privati e aziendali attraverso due istituti di ricerca indipendenti. La Posta e i suoi collaboratori vogliono da un lato sapere quanto siano soddisfatti i loro clienti con la Posta in generale. Dall&#8217;altro lato, ci interessa sapere come viene percepito l&#8217;offerta di servizi, se i prezzi sono adeguati e come i clienti vivono il contatto e la consulenza, in particolare come comunichiamo con loro e come affrontiamo i problemi. Solo con il feedback dei loro clienti la Posta pu\u00f2 ottimizzare la sua offerta di servizi. Allo stesso tempo, vediamo immediatamente dai risultati dell&#8217;indagine come sono stati accolti i provvedimenti di miglioramento. Una parte dei risultati della misurazione della soddisfazione dei clienti viene inoltre inclusa nella relazione annuale al Consiglio federale.<\/p>\n<h5><strong>La maggioranza dei clienti \u00e8 molto soddisfatta anche nel 2021<\/strong><\/h5>\n<p>Per l&#8217;indagine di quest&#8217;anno, la Posta ha intervistato circa 7.800 clienti privati e circa 4.600 clienti aziendali. Il risultato: i clienti sono perlopi\u00f9 molto soddisfatti della Posta, con un punteggio totale di 81 su 100 punti. Il valore rimane invariato rispetto all&#8217;anno precedente. E dimostra che la Posta e i suoi servizi continuano a convincere, nonostante le sfide presentate dalla pandemia di Corona e dall&#8217;aumento dei volumi di pacchi. La Posta deve l&#8217;alta soddisfazione dei clienti all&#8217;impegno dei suoi collaboratori in tutti i settori. Nel 2021 hanno svolto un lavoro straordinario in condizioni ancora difficili.<\/p>\n<h5><strong>I risultati in sintesi<\/strong><\/h5>\n<p>La Posta ha condotto le indagini nel periodo da luglio 2020 a giugno 2021. Per questo motivo, l&#8217;indagine si basa ancora sulla vecchia struttura aziendale con i settori &#8220;PostMail&#8221; e &#8220;PostLogistics&#8221;.<\/p>\n<p>I risultati dell&#8217;indagine sono suddivisi in tre categorie: i clienti con una valutazione tra 80-100 punti sono considerati &#8220;molto soddisfatti&#8221;, tra 65-79 punti &#8220;soddisfatti&#8221; e con meno di 65 punti &#8220;insoddisfatti&#8221;. I valori vanno da 0 a 100 punti tramite la trasformazione della scala decimale nelle indagini sulla soddisfazione dei clienti.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-16215 size-full\" src=\"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Post_CH_9.12.21_1.jpg\" alt=\"\" width=\"1274\" height=\"713\" \/>Foto\/Grafica: \u00a9 Posta Svizzera<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Posta riceve un buon feedback dai suoi clienti. Nella survey di quest&#8217;anno sulla soddisfazione dei clienti, raggiunge un ottimo risultato di 81 su 100 punti.<span class=\"excerpt-hellip\"> [\u2026]<\/span><\/p>\n","protected":false},"author":0,"featured_media":11519,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1557,1561],"tags":[],"class_list":["post-54074","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-forwarding-logistics","category-regions"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>I clienti svizzeri sono soddisfatti del loro servizio postale - Loginfo24<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/loginfo24.com\/it\/2021\/12\/09\/i-clienti-svizzeri-sono-soddisfatti-del-loro-servizio-postale\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"I clienti svizzeri sono soddisfatti del loro servizio postale - Loginfo24\" \/>\n<meta property=\"og:description\" content=\"La Posta riceve un buon feedback dai suoi clienti. Nella survey di quest&#8217;anno sulla soddisfazione dei clienti, raggiunge un ottimo risultato di 81 su 100 punti. [\u2026]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/loginfo24.com\/it\/2021\/12\/09\/i-clienti-svizzeri-sono-soddisfatti-del-loro-servizio-postale\/\" \/>\n<meta property=\"og:site_name\" content=\"Loginfo24\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/\" \/>\n<meta property=\"article:published_time\" content=\"2021-12-09T18:08:52+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Post_CH_9.12.21.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1360\" \/>\n\t<meta property=\"og:image:height\" content=\"840\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2021\\\/12\\\/09\\\/i-clienti-svizzeri-sono-soddisfatti-del-loro-servizio-postale\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2021\\\/12\\\/09\\\/i-clienti-svizzeri-sono-soddisfatti-del-loro-servizio-postale\\\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"I clienti svizzeri sono soddisfatti del loro servizio postale\",\"datePublished\":\"2021-12-09T18:08:52+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2021\\\/12\\\/09\\\/i-clienti-svizzeri-sono-soddisfatti-del-loro-servizio-postale\\\/\"},\"wordCount\":398,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2021\\\/12\\\/09\\\/i-clienti-svizzeri-sono-soddisfatti-del-loro-servizio-postale\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/Post_CH_9.12.21.jpg\",\"articleSection\":[\"Forwarding &amp; Logistics\",\"Regions\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/it\\\/2021\\\/12\\\/09\\\/i-clienti-svizzeri-sono-soddisfatti-del-loro-servizio-postale\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2021\\\/12\\\/09\\\/i-clienti-svizzeri-sono-soddisfatti-del-loro-servizio-postale\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2021\\\/12\\\/09\\\/i-clienti-svizzeri-sono-soddisfatti-del-loro-servizio-postale\\\/\",\"name\":\"I clienti svizzeri sono soddisfatti del loro servizio postale - Loginfo24\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2021\\\/12\\\/09\\\/i-clienti-svizzeri-sono-soddisfatti-del-loro-servizio-postale\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2021\\\/12\\\/09\\\/i-clienti-svizzeri-sono-soddisfatti-del-loro-servizio-postale\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/Post_CH_9.12.21.jpg\",\"datePublished\":\"2021-12-09T18:08:52+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2021\\\/12\\\/09\\\/i-clienti-svizzeri-sono-soddisfatti-del-loro-servizio-postale\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/it\\\/2021\\\/12\\\/09\\\/i-clienti-svizzeri-sono-soddisfatti-del-loro-servizio-postale\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2021\\\/12\\\/09\\\/i-clienti-svizzeri-sono-soddisfatti-del-loro-servizio-postale\\\/#primaryimage\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/Post_CH_9.12.21.jpg\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/Post_CH_9.12.21.jpg\",\"width\":1360,\"height\":840},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2021\\\/12\\\/09\\\/i-clienti-svizzeri-sono-soddisfatti-del-loro-servizio-postale\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"I clienti svizzeri sono soddisfatti del loro servizio postale\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/\",\"name\":\"Loginfo24\",\"description\":\"Loginfo24 \u00e8 la piattaforma dedicata alla logistica e alle catene di fornitura con informazioni disponibili 24 ore su 24.\",\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#organization\",\"name\":\"Logismedia Group AG\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"width\":938,\"height\":351,\"caption\":\"Logismedia Group AG\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/people\\\/Loginfo24\\\/100057360583332\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/lofinfo24\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"I clienti svizzeri sono soddisfatti del loro servizio postale - Loginfo24","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/loginfo24.com\/it\/2021\/12\/09\/i-clienti-svizzeri-sono-soddisfatti-del-loro-servizio-postale\/","og_locale":"it_IT","og_type":"article","og_title":"I clienti svizzeri sono soddisfatti del loro servizio postale - Loginfo24","og_description":"La Posta riceve un buon feedback dai suoi clienti. Nella survey di quest&#8217;anno sulla soddisfazione dei clienti, raggiunge un ottimo risultato di 81 su 100 punti. [\u2026]","og_url":"https:\/\/loginfo24.com\/it\/2021\/12\/09\/i-clienti-svizzeri-sono-soddisfatti-del-loro-servizio-postale\/","og_site_name":"Loginfo24","article_publisher":"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","article_published_time":"2021-12-09T18:08:52+00:00","og_image":[{"width":1360,"height":840,"url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Post_CH_9.12.21.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"2 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/loginfo24.com\/it\/2021\/12\/09\/i-clienti-svizzeri-sono-soddisfatti-del-loro-servizio-postale\/#article","isPartOf":{"@id":"https:\/\/loginfo24.com\/it\/2021\/12\/09\/i-clienti-svizzeri-sono-soddisfatti-del-loro-servizio-postale\/"},"author":{"name":"","@id":""},"headline":"I clienti svizzeri sono soddisfatti del loro servizio postale","datePublished":"2021-12-09T18:08:52+00:00","mainEntityOfPage":{"@id":"https:\/\/loginfo24.com\/it\/2021\/12\/09\/i-clienti-svizzeri-sono-soddisfatti-del-loro-servizio-postale\/"},"wordCount":398,"commentCount":0,"publisher":{"@id":"https:\/\/loginfo24.com\/it\/#organization"},"image":{"@id":"https:\/\/loginfo24.com\/it\/2021\/12\/09\/i-clienti-svizzeri-sono-soddisfatti-del-loro-servizio-postale\/#primaryimage"},"thumbnailUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Post_CH_9.12.21.jpg","articleSection":["Forwarding &amp; Logistics","Regions"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/loginfo24.com\/it\/2021\/12\/09\/i-clienti-svizzeri-sono-soddisfatti-del-loro-servizio-postale\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/loginfo24.com\/it\/2021\/12\/09\/i-clienti-svizzeri-sono-soddisfatti-del-loro-servizio-postale\/","url":"https:\/\/loginfo24.com\/it\/2021\/12\/09\/i-clienti-svizzeri-sono-soddisfatti-del-loro-servizio-postale\/","name":"I clienti svizzeri sono soddisfatti del loro servizio postale - Loginfo24","isPartOf":{"@id":"https:\/\/loginfo24.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/loginfo24.com\/it\/2021\/12\/09\/i-clienti-svizzeri-sono-soddisfatti-del-loro-servizio-postale\/#primaryimage"},"image":{"@id":"https:\/\/loginfo24.com\/it\/2021\/12\/09\/i-clienti-svizzeri-sono-soddisfatti-del-loro-servizio-postale\/#primaryimage"},"thumbnailUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Post_CH_9.12.21.jpg","datePublished":"2021-12-09T18:08:52+00:00","breadcrumb":{"@id":"https:\/\/loginfo24.com\/it\/2021\/12\/09\/i-clienti-svizzeri-sono-soddisfatti-del-loro-servizio-postale\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/loginfo24.com\/it\/2021\/12\/09\/i-clienti-svizzeri-sono-soddisfatti-del-loro-servizio-postale\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/loginfo24.com\/it\/2021\/12\/09\/i-clienti-svizzeri-sono-soddisfatti-del-loro-servizio-postale\/#primaryimage","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Post_CH_9.12.21.jpg","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Post_CH_9.12.21.jpg","width":1360,"height":840},{"@type":"BreadcrumbList","@id":"https:\/\/loginfo24.com\/it\/2021\/12\/09\/i-clienti-svizzeri-sono-soddisfatti-del-loro-servizio-postale\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/loginfo24.com\/it\/"},{"@type":"ListItem","position":2,"name":"I clienti svizzeri sono soddisfatti del loro servizio postale"}]},{"@type":"WebSite","@id":"https:\/\/loginfo24.com\/it\/#website","url":"https:\/\/loginfo24.com\/it\/","name":"Loginfo24","description":"Loginfo24 \u00e8 la piattaforma dedicata alla logistica e alle catene di fornitura con informazioni disponibili 24 ore su 24.","publisher":{"@id":"https:\/\/loginfo24.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/loginfo24.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/loginfo24.com\/it\/#organization","name":"Logismedia Group AG","url":"https:\/\/loginfo24.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/loginfo24.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","width":938,"height":351,"caption":"Logismedia Group AG"},"image":{"@id":"https:\/\/loginfo24.com\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","https:\/\/www.linkedin.com\/company\/lofinfo24\/"]}]}},"_links":{"self":[{"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/posts\/54074","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/comments?post=54074"}],"version-history":[{"count":0,"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/posts\/54074\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/media\/11519"}],"wp:attachment":[{"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/media?parent=54074"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/categories?post=54074"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/tags?post=54074"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}