{"id":53105,"date":"2021-11-01T18:22:17","date_gmt":"2021-11-01T17:22:17","guid":{"rendered":"https:\/\/blog.brand-architecture.at\/2021\/11\/01\/hengstler-con-encoder-robusti-per-sistemi-di-trasporto-senza-conducente\/"},"modified":"2021-11-01T18:22:17","modified_gmt":"2021-11-01T17:22:17","slug":"hengstler-con-encoder-robusti-per-sistemi-di-trasporto-senza-conducente","status":"publish","type":"post","link":"https:\/\/loginfo24.com\/it\/2021\/11\/01\/hengstler-con-encoder-robusti-per-sistemi-di-trasporto-senza-conducente\/","title":{"rendered":"Hengstler con encoder robusti per sistemi di trasporto senza conducente"},"content":{"rendered":"<h5><strong>I sistemi di trasporto senza conducente (FTS) svolgono una funzione centrale nella logistica interna. Gli encoder di Hengstler garantiscono il funzionamento efficiente dei veicoli. Essi misurano la velocit\u00e0, l&#8217;angolo di sterzata e l&#8217;altezza di sollevamento degli FTS. Gli encoder sono robusti, molto compatti e offrono molteplici opzioni di connessione.<\/strong><\/h5>\n<p>(Pressebox; Aldingen) Gli encoder assoluti e incrementali di Hengstler sono utilizzati da molti anni nei sistemi di trasporto senza conducente. I rinomati produttori di FTS apprezzano, tra l&#8217;altro, la precisione e la resistenza agli urti e alle vibrazioni degli encoder. Utilizzano gli encoder provenienti da Aldingen, in Svevia, in vari veicoli di movimentazione automatizzati, come ad esempio carrelli elevatori a contrappeso, carrelli elevatori portali, veicoli a guida inferiore o robot di parcheggio. I veicoli a guida automatica (AGV) non solo si occupano del carico e scarico di merci o materie prime, ma supportano anche la preparazione di prodotti finiti o forniscono componenti per l&#8217;approvvigionamento della produzione Just-in-Time alle linee di montaggio.<\/p>\n<p>Gli encoder di Hengstler consentono un funzionamento rapido e fluido dei sistemi di trasporto autonomi, misurando la velocit\u00e0 di marcia, l&#8217;altezza di sollevamento e l&#8217;angolo di sterzata degli FTS. Grazie agli encoder, i robot di trasporto possono quindi raggiungere la loro destinazione in brevissimo tempo. Per l&#8217;installazione in veicoli di movimentazione automatizzati, sono adatti sia gli encoder assoluti della serie ACURO<sup>\u00ae<\/sup> che gli encoder incrementali ICURO: mentre gli encoder assoluti sono principalmente utilizzati per misurare l&#8217;angolo di sterzata, gli encoder incrementali misurano, tra l&#8217;altro, la velocit\u00e0 dei veicoli.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-large wp-image-15270\" src=\"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Hangstler_1.11.21.jpg\" alt=\"\" width=\"1024\" height=\"574\" \/><\/p>\n<h5><strong>In diverse varianti<\/strong><\/h5>\n<p>Hengstler offre i suoi encoder in diverse varianti e con numerose opzioni di equipaggiamento. Gli encoder assoluti sono disponibili sia in versione Singleturn che Multiturn e alcuni modelli offrono, oltre alle impostazioni standard, una vasta gamma di funzioni programmabili (ACURO<sup>\u00ae<\/sup> AC58\/AC59\/61). Tra gli encoder incrementali, oltre alle versioni per motori BLDC, servo e passo-passo, sono disponibili anche encoder per FTS a batteria, che consumano particolarmente poca energia.<\/p>\n<p>Hengstler produce tutti gli encoder su ordinazione e li adatta, su richiesta, gi\u00e0 a partire dalla quantit\u00e0 di 1 all&#8217;applicazione specifica. In questo modo, il cliente ha la garanzia che le sue esigenze siano soddisfatte fino all&#8217;ultimo dettaglio.<\/p>\n<p>Foto: \u00a9 Hengstler<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>I sistemi di trasporto senza conducente (FTS) svolgono una funzione centrale nella logistica interna. Gli encoder di Hengstler garantiscono il funzionamento efficiente dei veicoli. Essi misurano<span class=\"excerpt-hellip\"> [\u2026]<\/span><\/p>\n","protected":false},"author":0,"featured_media":11932,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1557,1560,1561],"tags":[],"class_list":["post-53105","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-forwarding-logistics","category-intralogistics","category-regions"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Hengstler con encoder robusti per sistemi di trasporto senza conducente - Loginfo24<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/loginfo24.com\/it\/2021\/11\/01\/hengstler-con-encoder-robusti-per-sistemi-di-trasporto-senza-conducente\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Hengstler con encoder robusti per sistemi di trasporto senza conducente - Loginfo24\" \/>\n<meta property=\"og:description\" content=\"I sistemi di trasporto senza conducente (FTS) svolgono una funzione centrale nella logistica interna. Gli encoder di Hengstler garantiscono il funzionamento efficiente dei veicoli. Essi misurano [\u2026]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/loginfo24.com\/it\/2021\/11\/01\/hengstler-con-encoder-robusti-per-sistemi-di-trasporto-senza-conducente\/\" \/>\n<meta property=\"og:site_name\" content=\"Loginfo24\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/\" \/>\n<meta property=\"article:published_time\" content=\"2021-11-01T17:22:17+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Hangstler_1.11.21_2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1300\" \/>\n\t<meta property=\"og:image:height\" content=\"727\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2021\\\/11\\\/01\\\/hengstler-con-encoder-robusti-per-sistemi-di-trasporto-senza-conducente\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2021\\\/11\\\/01\\\/hengstler-con-encoder-robusti-per-sistemi-di-trasporto-senza-conducente\\\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Hengstler con encoder robusti per sistemi di trasporto senza conducente\",\"datePublished\":\"2021-11-01T17:22:17+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2021\\\/11\\\/01\\\/hengstler-con-encoder-robusti-per-sistemi-di-trasporto-senza-conducente\\\/\"},\"wordCount\":380,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2021\\\/11\\\/01\\\/hengstler-con-encoder-robusti-per-sistemi-di-trasporto-senza-conducente\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/Hangstler_1.11.21_2.jpg\",\"articleSection\":[\"Forwarding &amp; Logistics\",\"Intralogistics\",\"Regions\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/it\\\/2021\\\/11\\\/01\\\/hengstler-con-encoder-robusti-per-sistemi-di-trasporto-senza-conducente\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2021\\\/11\\\/01\\\/hengstler-con-encoder-robusti-per-sistemi-di-trasporto-senza-conducente\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2021\\\/11\\\/01\\\/hengstler-con-encoder-robusti-per-sistemi-di-trasporto-senza-conducente\\\/\",\"name\":\"Hengstler con encoder robusti per sistemi di trasporto senza conducente - Loginfo24\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2021\\\/11\\\/01\\\/hengstler-con-encoder-robusti-per-sistemi-di-trasporto-senza-conducente\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2021\\\/11\\\/01\\\/hengstler-con-encoder-robusti-per-sistemi-di-trasporto-senza-conducente\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/Hangstler_1.11.21_2.jpg\",\"datePublished\":\"2021-11-01T17:22:17+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2021\\\/11\\\/01\\\/hengstler-con-encoder-robusti-per-sistemi-di-trasporto-senza-conducente\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/it\\\/2021\\\/11\\\/01\\\/hengstler-con-encoder-robusti-per-sistemi-di-trasporto-senza-conducente\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2021\\\/11\\\/01\\\/hengstler-con-encoder-robusti-per-sistemi-di-trasporto-senza-conducente\\\/#primaryimage\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/Hangstler_1.11.21_2.jpg\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/Hangstler_1.11.21_2.jpg\",\"width\":1300,\"height\":727},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2021\\\/11\\\/01\\\/hengstler-con-encoder-robusti-per-sistemi-di-trasporto-senza-conducente\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Hengstler con encoder robusti per sistemi di trasporto senza conducente\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/\",\"name\":\"Loginfo24\",\"description\":\"Loginfo24 \u00e8 la piattaforma dedicata alla logistica e alle catene di fornitura con informazioni disponibili 24 ore su 24.\",\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#organization\",\"name\":\"Logismedia Group AG\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"width\":938,\"height\":351,\"caption\":\"Logismedia Group AG\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/people\\\/Loginfo24\\\/100057360583332\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/lofinfo24\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Hengstler con encoder robusti per sistemi di trasporto senza conducente - Loginfo24","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/loginfo24.com\/it\/2021\/11\/01\/hengstler-con-encoder-robusti-per-sistemi-di-trasporto-senza-conducente\/","og_locale":"it_IT","og_type":"article","og_title":"Hengstler con encoder robusti per sistemi di trasporto senza conducente - Loginfo24","og_description":"I sistemi di trasporto senza conducente (FTS) svolgono una funzione centrale nella logistica interna. Gli encoder di Hengstler garantiscono il funzionamento efficiente dei veicoli. Essi misurano [\u2026]","og_url":"https:\/\/loginfo24.com\/it\/2021\/11\/01\/hengstler-con-encoder-robusti-per-sistemi-di-trasporto-senza-conducente\/","og_site_name":"Loginfo24","article_publisher":"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","article_published_time":"2021-11-01T17:22:17+00:00","og_image":[{"width":1300,"height":727,"url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Hangstler_1.11.21_2.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"2 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/loginfo24.com\/it\/2021\/11\/01\/hengstler-con-encoder-robusti-per-sistemi-di-trasporto-senza-conducente\/#article","isPartOf":{"@id":"https:\/\/loginfo24.com\/it\/2021\/11\/01\/hengstler-con-encoder-robusti-per-sistemi-di-trasporto-senza-conducente\/"},"author":{"name":"","@id":""},"headline":"Hengstler con encoder robusti per sistemi di trasporto senza conducente","datePublished":"2021-11-01T17:22:17+00:00","mainEntityOfPage":{"@id":"https:\/\/loginfo24.com\/it\/2021\/11\/01\/hengstler-con-encoder-robusti-per-sistemi-di-trasporto-senza-conducente\/"},"wordCount":380,"commentCount":0,"publisher":{"@id":"https:\/\/loginfo24.com\/it\/#organization"},"image":{"@id":"https:\/\/loginfo24.com\/it\/2021\/11\/01\/hengstler-con-encoder-robusti-per-sistemi-di-trasporto-senza-conducente\/#primaryimage"},"thumbnailUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Hangstler_1.11.21_2.jpg","articleSection":["Forwarding &amp; Logistics","Intralogistics","Regions"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/loginfo24.com\/it\/2021\/11\/01\/hengstler-con-encoder-robusti-per-sistemi-di-trasporto-senza-conducente\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/loginfo24.com\/it\/2021\/11\/01\/hengstler-con-encoder-robusti-per-sistemi-di-trasporto-senza-conducente\/","url":"https:\/\/loginfo24.com\/it\/2021\/11\/01\/hengstler-con-encoder-robusti-per-sistemi-di-trasporto-senza-conducente\/","name":"Hengstler con encoder robusti per sistemi di trasporto senza conducente - Loginfo24","isPartOf":{"@id":"https:\/\/loginfo24.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/loginfo24.com\/it\/2021\/11\/01\/hengstler-con-encoder-robusti-per-sistemi-di-trasporto-senza-conducente\/#primaryimage"},"image":{"@id":"https:\/\/loginfo24.com\/it\/2021\/11\/01\/hengstler-con-encoder-robusti-per-sistemi-di-trasporto-senza-conducente\/#primaryimage"},"thumbnailUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Hangstler_1.11.21_2.jpg","datePublished":"2021-11-01T17:22:17+00:00","breadcrumb":{"@id":"https:\/\/loginfo24.com\/it\/2021\/11\/01\/hengstler-con-encoder-robusti-per-sistemi-di-trasporto-senza-conducente\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/loginfo24.com\/it\/2021\/11\/01\/hengstler-con-encoder-robusti-per-sistemi-di-trasporto-senza-conducente\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/loginfo24.com\/it\/2021\/11\/01\/hengstler-con-encoder-robusti-per-sistemi-di-trasporto-senza-conducente\/#primaryimage","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Hangstler_1.11.21_2.jpg","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Hangstler_1.11.21_2.jpg","width":1300,"height":727},{"@type":"BreadcrumbList","@id":"https:\/\/loginfo24.com\/it\/2021\/11\/01\/hengstler-con-encoder-robusti-per-sistemi-di-trasporto-senza-conducente\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/loginfo24.com\/it\/"},{"@type":"ListItem","position":2,"name":"Hengstler con encoder robusti per sistemi di trasporto senza conducente"}]},{"@type":"WebSite","@id":"https:\/\/loginfo24.com\/it\/#website","url":"https:\/\/loginfo24.com\/it\/","name":"Loginfo24","description":"Loginfo24 \u00e8 la piattaforma dedicata alla logistica e alle catene di fornitura con informazioni disponibili 24 ore su 24.","publisher":{"@id":"https:\/\/loginfo24.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/loginfo24.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/loginfo24.com\/it\/#organization","name":"Logismedia Group AG","url":"https:\/\/loginfo24.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/loginfo24.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","width":938,"height":351,"caption":"Logismedia Group AG"},"image":{"@id":"https:\/\/loginfo24.com\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","https:\/\/www.linkedin.com\/company\/lofinfo24\/"]}]}},"_links":{"self":[{"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/posts\/53105","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/comments?post=53105"}],"version-history":[{"count":0,"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/posts\/53105\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/media\/11932"}],"wp:attachment":[{"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/media?parent=53105"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/categories?post=53105"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/tags?post=53105"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}