{"id":51718,"date":"2021-09-07T16:21:07","date_gmt":"2021-09-07T14:21:07","guid":{"rendered":"https:\/\/blog.brand-architecture.at\/2021\/09\/07\/ferrovia-merci-con-elogi-per-la-svizzera-e-richieste-alla-germania\/"},"modified":"2021-09-07T16:21:07","modified_gmt":"2021-09-07T14:21:07","slug":"ferrovia-merci-con-elogi-per-la-svizzera-e-richieste-alla-germania","status":"publish","type":"post","link":"https:\/\/loginfo24.com\/it\/2021\/09\/07\/ferrovia-merci-con-elogi-per-la-svizzera-e-richieste-alla-germania\/","title":{"rendered":"Ferrovia merci con elogi per la Svizzera e richieste alla Germania"},"content":{"rendered":"<p>Il 6 settembre 1996 \u00e8 stato firmato il &#8220;Trattato di Lugano&#8221;. Germania e Svizzera si sono impegnate a creare l&#8217;infrastruttura per un traffico ferroviario efficiente tra i due paesi. Ieri, esattamente 25 anni dopo, \u00e8 stata fatta una valutazione nella stazione ferroviaria tedesca della metropoli di confine svizzera Basilea, che \u00e8 particolarmente imbarazzante per la politica dei trasporti tedesca. Mentre la Svizzera ha completato puntualmente tunnel e linee, in Germania n\u00e9 l&#8217;ampliamento della linea ferroviaria della Valle del Reno n\u00e9 i bypass procedono abbastanza rapidamente. Le ferrovie merci hanno ora formulato le loro aspettative.<\/p>\n<p>(Berlino\/Basilea) Una serie di misure per accelerare il pi\u00f9 possibile la creazione di capacit\u00e0 ferroviaria aggiuntiva nel corridoio Nord-Sud, di importanza europea e regionale, lungo il Reno superiore, \u00e8 richiesta dalla Rete Europea delle Ferrovie. Il presidente del consiglio di amministrazione della NEE, Ludolf Kerkeling, avverte: &#8220;Il nuovo ministro dei trasporti rischia un collasso del traffico nella regione.&#8221; Kerkeling ha chiesto di anticipare di sei-sette anni rispetto alla pianificazione attuale della DB la quadruplicazione promessa nel 1996 e di completarla entro il 2035. &#8220;Le ferrovie merci vogliono, come contributo alla transizione dei trasporti e al programma di protezione climatica, trasportare grossomodo il doppio di quanto fanno oggi. Questo e l&#8217;orario di mezz&#8217;ora desiderato nel trasporto passeggeri a lunga distanza non possiamo semplicemente realizzarli con l&#8217;infrastruttura attuale.&#8221;<\/p>\n<p>A Basilea, l&#8217;ex ministro dei trasporti svizzero e presidente della Confederazione Adolf Ogi ha ricordato che la Svizzera aveva concordato e garantito contrattualmente un compromesso con l&#8217;UE e i paesi vicini per il traffico di transito Nord-Sud. Questo prevedeva in particolare la costruzione di due tunnel ferroviari di grandi dimensioni e numerose altre linee ferroviarie come accessi alla &#8220;Nuova Trasversale Ferroviaria Alpina (NEAT)&#8221;.<\/p>\n<h5><strong>Il ministro lamenta un ampliamento inaccettabilmente lento<\/strong><\/h5>\n<p>Winfried Hermann, ministro dei trasporti del Baden-W\u00fcrttemberg, ha lamentato l&#8217;ampliamento inaccettabilmente lento. Questo avrebbe dovuto essere realizzato pi\u00f9 rapidamente proprio a causa del traffico merci. Il governo federale ha investito troppo poco in passato e ha posto priorit\u00e0 sbagliate - gi\u00e0 per motivi di protezione climatica, il progetto dovrebbe essere accelerato.<\/p>\n<p>25 anni dopo la firma del contratto, sulla linea della Valle del Reno mancano ancora due binari su 96 di circa 180 chilometri - e gli altri vengono continuamente chiusi per lavori di costruzione. La linea della Valle del Reno \u00e8 dal 2010 parte del Corridoio Europeo per il Trasporto Merci Reno-Alpi ed \u00e8 anche una delle connessioni pi\u00f9 importanti in Europa centrale per i treni passeggeri. Gi\u00e0 oggi circolano oltre 200 treni al giorno e la domanda nel trasporto merci e passeggeri continua a crescere. Kerkeling sottolinea: &#8220;Per ridurre il grande divario tra Offenburg e Schliengen a sud di Friburgo e per alleviare un po&#8217; il disastro del tunnel a Rastatt, vogliamo che vengano intraprese misure aggiuntive. Ad esempio, entro il 2023 almeno uno dei due tubi del tunnel a Rastatt dovrebbe essere percorribile.&#8221; \u00c8 inoltre prioritario per le ferrovie merci un utilizzo ottimale della tecnologia di comando e sicurezza ETCS che sar\u00e0 installata a breve, cos\u00ec come l&#8217;ampliamento della linea sulla riva sinistra del Reno tra Strasburgo e W\u00f6rth. Alcune linee come la G\u00e4ubahn devono inoltre essere potenziate per deviazioni necessarie. Allo stesso tempo, \u00e8 necessaria anche una migliore gestione dei cantieri e una collaborazione pi\u00f9 intensa tra gli operatori dell&#8217;infrastruttura ferroviaria. Kerkeling: &#8220;La gestione del corridoio di trasporto merci dovrebbe essere trasferita in Svizzera e, se possibile, anche dirigere il ramo orientale del corridoio sulla riva sinistra del Reno &#8216;Nordsee-Mittelmeer&#8217;.&#8221;<\/p>\n<h5><strong>Critiche a un nuovo accordo<\/strong><\/h5>\n<p>Il nuovo accordo recentemente presentato dal ministro dei trasporti tedesco con la Svizzera non \u00e8, secondo le parole di Kerkeling, &#8220;realmente utile e sufficiente. \u00c8 superfluo abbandonare il Trattato di Lugano a favore di un insieme di accordi pieni di dichiarazioni di intenti non vincolanti, in cui ora non \u00e8 contenuta alcuna affermazione concreta sulla linea della Valle del Reno e si afferma che non ci sono obblighi finanziari per nessuno. In questo modo, il ministro dei trasporti ha la licenza di continuare la mentalit\u00e0 &#8216;vengo oggi, non vengo domani&#8217;, che \u00e8 gi\u00e0 comune, perch\u00e9 siamo gi\u00e0 in ritardo, e rinvia ogni giorno l&#8217;alleggerimento urgente del collo di bottiglia nella regione.&#8221;<\/p>\n<blockquote><p><em><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-14020 size-full\" src=\"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/NEE_7.9.21_3.jpg\" alt=\"\" width=\"1500\" height=\"2123\" \/><br \/>\nSpiegazione del grafico: sulla linea della Valle del Reno, i tratti Karlsruhe-Rastatt e Offenburg-Schliengen, ad eccezione di un breve tratto a Friburgo, non sono ancora quadruplici. La linea \u00e8 completamente elettrificata, a differenza della linea di deviazione Karlsruhe-Strasburgo-Basilea, che nel tratto tra W\u00f6rth am Rhein e Lauterbourg \u00e8 solo a binario unico e fino a Strasburgo non \u00e8 nemmeno elettrificata. A causa dei necessari cambi di locomotiva e delle barriere linguistiche inutili tra gli operatori dell&#8217;infrastruttura, la linea, un tempo significativa, oggi non gioca nemmeno un ruolo rilevante come linea di deviazione. A est della Valle del Reno, la deviazione dei treni attraverso la G\u00e4ubahn \u00e8 ampiamente possibile solo a binario unico e anche attorno a Singen manca l&#8217;infrastruttura. Come alleggerimento continuo della Valle del Reno, non \u00e8 utilizzabile nemmeno a causa delle capacit\u00e0 limitate sul lato svizzero nel nodo di Zurigo.<\/em><\/p><\/blockquote>\n<p>Le immagini dell&#8217;evento &#8220;Ospiti tra amici&#8221; possono essere trovate <strong><a href=\"https:\/\/www.netzwerk-bahnen.de\/news\/bilder-der-veranstaltung-zu-gast-bei-freunden-in-basel-und-videos-der-reden.html\" target=\"_blank\" rel=\"noopener noreferrer\">qui<\/a>.<\/strong> I discorsi di Winfried Hermann, ministro dei trasporti del Baden-W\u00fcrttemberg, Adolf Ogi, ex presidente della Confederazione svizzera e Josef Dittli, presidente dell&#8217;Associazione dell&#8217;industria delle spedizioni (VAP) saranno pubblicati a breve sulla stessa pagina.<\/p>\n<p>Foto\/Grafica: \u00a9 NEE \/ <strong><em>Didascalia foto di copertura:<\/em><\/strong><em> L&#8217;ex consigliere federale svizzero Adolf Ogi ha parlato a Basilea agli ospiti dell&#8217;evento &#8220;Ospiti tra amici&#8221;.<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il 6 settembre 1996 \u00e8 stato firmato il &#8220;Trattato di Lugano&#8221;. Germania e Svizzera si sono impegnate a creare l&#8217;infrastruttura per un traffico ferroviario efficiente tra<span class=\"excerpt-hellip\"> [\u2026]<\/span><\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1557,1556,1561],"tags":[],"class_list":["post-51718","post","type-post","status-publish","format-standard","hentry","category-forwarding-logistics","category-intermodal-road","category-regions"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Ferrovia merci con elogi per la Svizzera e richieste alla Germania - Loginfo24<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/loginfo24.com\/it\/2021\/09\/07\/ferrovia-merci-con-elogi-per-la-svizzera-e-richieste-alla-germania\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ferrovia merci con elogi per la Svizzera e richieste alla Germania - Loginfo24\" \/>\n<meta property=\"og:description\" content=\"Il 6 settembre 1996 \u00e8 stato firmato il &#8220;Trattato di Lugano&#8221;. Germania e Svizzera si sono impegnate a creare l&#8217;infrastruttura per un traffico ferroviario efficiente tra [\u2026]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/loginfo24.com\/it\/2021\/09\/07\/ferrovia-merci-con-elogi-per-la-svizzera-e-richieste-alla-germania\/\" \/>\n<meta property=\"og:site_name\" content=\"Loginfo24\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/\" \/>\n<meta property=\"article:published_time\" content=\"2021-09-07T14:21:07+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/NEE_7.9.21_3.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2021\\\/09\\\/07\\\/ferrovia-merci-con-elogi-per-la-svizzera-e-richieste-alla-germania\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2021\\\/09\\\/07\\\/ferrovia-merci-con-elogi-per-la-svizzera-e-richieste-alla-germania\\\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Ferrovia merci con elogi per la Svizzera e richieste alla Germania\",\"datePublished\":\"2021-09-07T14:21:07+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2021\\\/09\\\/07\\\/ferrovia-merci-con-elogi-per-la-svizzera-e-richieste-alla-germania\\\/\"},\"wordCount\":906,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2021\\\/09\\\/07\\\/ferrovia-merci-con-elogi-per-la-svizzera-e-richieste-alla-germania\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/NEE_7.9.21_3.jpg\",\"articleSection\":[\"Forwarding &amp; Logistics\",\"Intermodal \\\/ Road\",\"Regions\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/it\\\/2021\\\/09\\\/07\\\/ferrovia-merci-con-elogi-per-la-svizzera-e-richieste-alla-germania\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2021\\\/09\\\/07\\\/ferrovia-merci-con-elogi-per-la-svizzera-e-richieste-alla-germania\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2021\\\/09\\\/07\\\/ferrovia-merci-con-elogi-per-la-svizzera-e-richieste-alla-germania\\\/\",\"name\":\"Ferrovia merci con elogi per la Svizzera e richieste alla Germania - Loginfo24\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2021\\\/09\\\/07\\\/ferrovia-merci-con-elogi-per-la-svizzera-e-richieste-alla-germania\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2021\\\/09\\\/07\\\/ferrovia-merci-con-elogi-per-la-svizzera-e-richieste-alla-germania\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/NEE_7.9.21_3.jpg\",\"datePublished\":\"2021-09-07T14:21:07+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2021\\\/09\\\/07\\\/ferrovia-merci-con-elogi-per-la-svizzera-e-richieste-alla-germania\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/it\\\/2021\\\/09\\\/07\\\/ferrovia-merci-con-elogi-per-la-svizzera-e-richieste-alla-germania\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2021\\\/09\\\/07\\\/ferrovia-merci-con-elogi-per-la-svizzera-e-richieste-alla-germania\\\/#primaryimage\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/NEE_7.9.21_3.jpg\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/NEE_7.9.21_3.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2021\\\/09\\\/07\\\/ferrovia-merci-con-elogi-per-la-svizzera-e-richieste-alla-germania\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ferrovia merci con elogi per la Svizzera e richieste alla Germania\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/\",\"name\":\"Loginfo24\",\"description\":\"Loginfo24 \u00e8 la piattaforma dedicata alla logistica e alle catene di fornitura con informazioni disponibili 24 ore su 24.\",\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#organization\",\"name\":\"Logismedia Group AG\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"width\":938,\"height\":351,\"caption\":\"Logismedia Group AG\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/people\\\/Loginfo24\\\/100057360583332\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/lofinfo24\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ferrovia merci con elogi per la Svizzera e richieste alla Germania - Loginfo24","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/loginfo24.com\/it\/2021\/09\/07\/ferrovia-merci-con-elogi-per-la-svizzera-e-richieste-alla-germania\/","og_locale":"it_IT","og_type":"article","og_title":"Ferrovia merci con elogi per la Svizzera e richieste alla Germania - Loginfo24","og_description":"Il 6 settembre 1996 \u00e8 stato firmato il &#8220;Trattato di Lugano&#8221;. Germania e Svizzera si sono impegnate a creare l&#8217;infrastruttura per un traffico ferroviario efficiente tra [\u2026]","og_url":"https:\/\/loginfo24.com\/it\/2021\/09\/07\/ferrovia-merci-con-elogi-per-la-svizzera-e-richieste-alla-germania\/","og_site_name":"Loginfo24","article_publisher":"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","article_published_time":"2021-09-07T14:21:07+00:00","og_image":[{"url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/NEE_7.9.21_3.jpg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"4 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/loginfo24.com\/it\/2021\/09\/07\/ferrovia-merci-con-elogi-per-la-svizzera-e-richieste-alla-germania\/#article","isPartOf":{"@id":"https:\/\/loginfo24.com\/it\/2021\/09\/07\/ferrovia-merci-con-elogi-per-la-svizzera-e-richieste-alla-germania\/"},"author":{"name":"","@id":""},"headline":"Ferrovia merci con elogi per la Svizzera e richieste alla Germania","datePublished":"2021-09-07T14:21:07+00:00","mainEntityOfPage":{"@id":"https:\/\/loginfo24.com\/it\/2021\/09\/07\/ferrovia-merci-con-elogi-per-la-svizzera-e-richieste-alla-germania\/"},"wordCount":906,"commentCount":0,"publisher":{"@id":"https:\/\/loginfo24.com\/it\/#organization"},"image":{"@id":"https:\/\/loginfo24.com\/it\/2021\/09\/07\/ferrovia-merci-con-elogi-per-la-svizzera-e-richieste-alla-germania\/#primaryimage"},"thumbnailUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/NEE_7.9.21_3.jpg","articleSection":["Forwarding &amp; Logistics","Intermodal \/ Road","Regions"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/loginfo24.com\/it\/2021\/09\/07\/ferrovia-merci-con-elogi-per-la-svizzera-e-richieste-alla-germania\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/loginfo24.com\/it\/2021\/09\/07\/ferrovia-merci-con-elogi-per-la-svizzera-e-richieste-alla-germania\/","url":"https:\/\/loginfo24.com\/it\/2021\/09\/07\/ferrovia-merci-con-elogi-per-la-svizzera-e-richieste-alla-germania\/","name":"Ferrovia merci con elogi per la Svizzera e richieste alla Germania - Loginfo24","isPartOf":{"@id":"https:\/\/loginfo24.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/loginfo24.com\/it\/2021\/09\/07\/ferrovia-merci-con-elogi-per-la-svizzera-e-richieste-alla-germania\/#primaryimage"},"image":{"@id":"https:\/\/loginfo24.com\/it\/2021\/09\/07\/ferrovia-merci-con-elogi-per-la-svizzera-e-richieste-alla-germania\/#primaryimage"},"thumbnailUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/NEE_7.9.21_3.jpg","datePublished":"2021-09-07T14:21:07+00:00","breadcrumb":{"@id":"https:\/\/loginfo24.com\/it\/2021\/09\/07\/ferrovia-merci-con-elogi-per-la-svizzera-e-richieste-alla-germania\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/loginfo24.com\/it\/2021\/09\/07\/ferrovia-merci-con-elogi-per-la-svizzera-e-richieste-alla-germania\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/loginfo24.com\/it\/2021\/09\/07\/ferrovia-merci-con-elogi-per-la-svizzera-e-richieste-alla-germania\/#primaryimage","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/NEE_7.9.21_3.jpg","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/NEE_7.9.21_3.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/loginfo24.com\/it\/2021\/09\/07\/ferrovia-merci-con-elogi-per-la-svizzera-e-richieste-alla-germania\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/loginfo24.com\/it\/"},{"@type":"ListItem","position":2,"name":"Ferrovia merci con elogi per la Svizzera e richieste alla Germania"}]},{"@type":"WebSite","@id":"https:\/\/loginfo24.com\/it\/#website","url":"https:\/\/loginfo24.com\/it\/","name":"Loginfo24","description":"Loginfo24 \u00e8 la piattaforma dedicata alla logistica e alle catene di fornitura con informazioni disponibili 24 ore su 24.","publisher":{"@id":"https:\/\/loginfo24.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/loginfo24.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/loginfo24.com\/it\/#organization","name":"Logismedia Group AG","url":"https:\/\/loginfo24.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/loginfo24.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","width":938,"height":351,"caption":"Logismedia Group AG"},"image":{"@id":"https:\/\/loginfo24.com\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","https:\/\/www.linkedin.com\/company\/lofinfo24\/"]}]}},"_links":{"self":[{"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/posts\/51718","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/comments?post=51718"}],"version-history":[{"count":0,"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/posts\/51718\/revisions"}],"wp:attachment":[{"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/media?parent=51718"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/categories?post=51718"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/tags?post=51718"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}