{"id":51592,"date":"2021-09-02T16:07:35","date_gmt":"2021-09-02T14:07:35","guid":{"rendered":"https:\/\/blog.brand-architecture.at\/2021\/09\/02\/fiege-e-lip-avviano-un-ulteriore-multi-user-center\/"},"modified":"2021-09-02T16:07:35","modified_gmt":"2021-09-02T14:07:35","slug":"fiege-e-lip-avviano-un-ulteriore-multi-user-center","status":"publish","type":"post","link":"https:\/\/loginfo24.com\/it\/2021\/09\/02\/fiege-e-lip-avviano-un-ulteriore-multi-user-center\/","title":{"rendered":"Fiege e LIP avviano un ulteriore Multi-User-Center"},"content":{"rendered":"<p>LIP Invest come investitore e il fornitore di servizi logistici Fiege avviano a Gengenbach circa 40.000 metri quadrati di superficie logistica vicino al confine franco-tedesco. Si tratta del secondo accordo di Forward-Funding tra Fiege e LIP. L&#8217;utilizzo del centro sar\u00e0 gestito dall&#8217;unit\u00e0 commerciale Fiege Industria e Pneumatici.<\/p>\n<p>(Gengenbach\/Greven\/Munich) Ci \u00e8 voluto quasi un anno, ma ora il nuovo centro logistico \u00e8 stato completato: il gruppo Fiege avvia il suo Multi-User-Center a Gengenbach, nel Baden-W\u00fcrttemberg. Su un terreno di 73.000 metri quadrati vicino al confine franco-tedesco tra Strasburgo, Friburgo e Stoccarda sono stati realizzati un edificio per uffici di tre piani e quattro sezioni di magazzino, che offrono circa 40.000 metri quadrati di spazio di stoccaggio per diversi clienti, tra cui un grande produttore di pneumatici. L&#8217;avvio operativo \u00e8 previsto per ottobre.<\/p>\n<p>La nuova propriet\u00e0 logistica a Gengenbach soddisfa il Gold Status della Deutsche Gesellschaft f\u00fcr Nachhaltiges Bauen (DGNB). In questo modo, l&#8217;azienda familiare Fiege di Greven, nella Westfalia, sta attuando non solo i suoi obiettivi di crescita, ma anche i suoi obiettivi di sostenibilit\u00e0. &#8220;Oltre all&#8217;illuminazione LED su tutta la superficie, a un impianto fotovoltaico e all&#8217;infrastruttura per la mobilit\u00e0 elettrica, abbiamo pianificato anche un prato fiorito sul sito&#8221;, afferma Jan Fiege, Managing Director Real Estate di Fiege. &#8220;Inoltre, la tecnologia di gestione degli edifici consente una gestione operativa sostenibile e intersettoriale.&#8221;<\/p>\n<h5><strong>Costruzione di alta qualit\u00e0 e moderna<\/strong><\/h5>\n<p>LIP Invest aveva gi\u00e0 acquisito lo sviluppo del progetto come Forward Deal e ha investito oltre 50 milioni di euro nella nuova costruzione. &#8220;Con l&#8217;acquisto del Multi-User-Center possiamo aumentare ulteriormente la nostra allocazione dei siti nel portafoglio. La propriet\u00e0 non si distingue solo per la sua posizione, ma anche per la costruzione di alta qualit\u00e0 e moderna. Con la facile suddivisione del magazzino e il numero elevato di porte di carico, presenta un alto grado di utilizzabilit\u00e0 per terzi&#8221;, afferma Bodo Hollung, socio e amministratore delegato di LIP Invest.<\/p>\n<p>Il progetto di costruzione \u00e8 stato realizzato dal dipartimento Fiege Real Estate in collaborazione con lo studio di architettura Kr\u00fcger Consult e la Bremer AG come appaltatore generale. Il sindaco di Gengenbach, Thorsten Erny, elogia la rapida conclusione della nuova costruzione: &#8220;\u00c8 impressionante vedere che l&#8217;intero nuovo edificio \u00e8 stato realizzato in soli un anno. Ora siamo felici di poter accogliere l&#8217;azienda familiare Fiege a Gengenbach.&#8221;<\/p>\n<h5><strong>Copertura migliore per il sud della Germania, Svizzera e Francia<\/strong><\/h5>\n<p>Il nuovo Multi-User-Center a Gengenbach sar\u00e0 utilizzato dall&#8217;unit\u00e0 commerciale Fiege Industria e Pneumatici. Christian Wierling, Managing Director del dipartimento presso Fiege, spiega: &#8220;Gengenbach \u00e8 per noi una posizione strategicamente estremamente preziosa nella logistica dei pneumatici e offre ai nostri clienti la possibilit\u00e0 di coprire meglio l&#8217;area del sud della Germania, cos\u00ec come la Svizzera e la Francia.&#8221; Inoltre, la posizione a Gengenbach \u00e8 l&#8217;estensione perfetta della sede Fiege a Lahr, a circa 30 chilometri di distanza nella Foresta Nera, afferma Wierling. &#8220;Con il nuovo Multi-User-Center a Gengenbach, non solo soddisfiamo la nostra strategia di crescita, ma soprattutto quella dei nostri clienti.&#8221;<\/p>\n<p>Foto: \u00a9 Fiege<\/p>\n","protected":false},"excerpt":{"rendered":"<p>LIP Invest come investitore e il fornitore di servizi logistici Fiege avviano a Gengenbach circa 40.000 metri quadrati di superficie logistica vicino al confine franco-tedesco. Si<span class=\"excerpt-hellip\"> [\u2026]<\/span><\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1557,1560,1561],"tags":[],"class_list":["post-51592","post","type-post","status-publish","format-standard","hentry","category-forwarding-logistics","category-intralogistics","category-regions"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Fiege e LIP avviano un ulteriore Multi-User-Center - Loginfo24<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/loginfo24.com\/it\/2021\/09\/02\/fiege-e-lip-avviano-un-ulteriore-multi-user-center\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Fiege e LIP avviano un ulteriore Multi-User-Center - Loginfo24\" \/>\n<meta property=\"og:description\" content=\"LIP Invest come investitore e il fornitore di servizi logistici Fiege avviano a Gengenbach circa 40.000 metri quadrati di superficie logistica vicino al confine franco-tedesco. Si [\u2026]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/loginfo24.com\/it\/2021\/09\/02\/fiege-e-lip-avviano-un-ulteriore-multi-user-center\/\" \/>\n<meta property=\"og:site_name\" content=\"Loginfo24\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/\" \/>\n<meta property=\"article:published_time\" content=\"2021-09-02T14:07:35+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2021\\\/09\\\/02\\\/fiege-e-lip-avviano-un-ulteriore-multi-user-center\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2021\\\/09\\\/02\\\/fiege-e-lip-avviano-un-ulteriore-multi-user-center\\\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Fiege e LIP avviano un ulteriore Multi-User-Center\",\"datePublished\":\"2021-09-02T14:07:35+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2021\\\/09\\\/02\\\/fiege-e-lip-avviano-un-ulteriore-multi-user-center\\\/\"},\"wordCount\":507,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#organization\"},\"articleSection\":[\"Forwarding &amp; Logistics\",\"Intralogistics\",\"Regions\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/it\\\/2021\\\/09\\\/02\\\/fiege-e-lip-avviano-un-ulteriore-multi-user-center\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2021\\\/09\\\/02\\\/fiege-e-lip-avviano-un-ulteriore-multi-user-center\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2021\\\/09\\\/02\\\/fiege-e-lip-avviano-un-ulteriore-multi-user-center\\\/\",\"name\":\"Fiege e LIP avviano un ulteriore Multi-User-Center - Loginfo24\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#website\"},\"datePublished\":\"2021-09-02T14:07:35+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2021\\\/09\\\/02\\\/fiege-e-lip-avviano-un-ulteriore-multi-user-center\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/it\\\/2021\\\/09\\\/02\\\/fiege-e-lip-avviano-un-ulteriore-multi-user-center\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2021\\\/09\\\/02\\\/fiege-e-lip-avviano-un-ulteriore-multi-user-center\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Fiege e LIP avviano un ulteriore Multi-User-Center\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/\",\"name\":\"Loginfo24\",\"description\":\"Loginfo24 \u00e8 la piattaforma dedicata alla logistica e alle catene di fornitura con informazioni disponibili 24 ore su 24.\",\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#organization\",\"name\":\"Logismedia Group AG\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"width\":938,\"height\":351,\"caption\":\"Logismedia Group AG\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/people\\\/Loginfo24\\\/100057360583332\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/lofinfo24\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Fiege e LIP avviano un ulteriore Multi-User-Center - Loginfo24","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/loginfo24.com\/it\/2021\/09\/02\/fiege-e-lip-avviano-un-ulteriore-multi-user-center\/","og_locale":"it_IT","og_type":"article","og_title":"Fiege e LIP avviano un ulteriore Multi-User-Center - Loginfo24","og_description":"LIP Invest come investitore e il fornitore di servizi logistici Fiege avviano a Gengenbach circa 40.000 metri quadrati di superficie logistica vicino al confine franco-tedesco. Si [\u2026]","og_url":"https:\/\/loginfo24.com\/it\/2021\/09\/02\/fiege-e-lip-avviano-un-ulteriore-multi-user-center\/","og_site_name":"Loginfo24","article_publisher":"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","article_published_time":"2021-09-02T14:07:35+00:00","twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"2 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/loginfo24.com\/it\/2021\/09\/02\/fiege-e-lip-avviano-un-ulteriore-multi-user-center\/#article","isPartOf":{"@id":"https:\/\/loginfo24.com\/it\/2021\/09\/02\/fiege-e-lip-avviano-un-ulteriore-multi-user-center\/"},"author":{"name":"","@id":""},"headline":"Fiege e LIP avviano un ulteriore Multi-User-Center","datePublished":"2021-09-02T14:07:35+00:00","mainEntityOfPage":{"@id":"https:\/\/loginfo24.com\/it\/2021\/09\/02\/fiege-e-lip-avviano-un-ulteriore-multi-user-center\/"},"wordCount":507,"commentCount":0,"publisher":{"@id":"https:\/\/loginfo24.com\/it\/#organization"},"articleSection":["Forwarding &amp; Logistics","Intralogistics","Regions"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/loginfo24.com\/it\/2021\/09\/02\/fiege-e-lip-avviano-un-ulteriore-multi-user-center\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/loginfo24.com\/it\/2021\/09\/02\/fiege-e-lip-avviano-un-ulteriore-multi-user-center\/","url":"https:\/\/loginfo24.com\/it\/2021\/09\/02\/fiege-e-lip-avviano-un-ulteriore-multi-user-center\/","name":"Fiege e LIP avviano un ulteriore Multi-User-Center - Loginfo24","isPartOf":{"@id":"https:\/\/loginfo24.com\/it\/#website"},"datePublished":"2021-09-02T14:07:35+00:00","breadcrumb":{"@id":"https:\/\/loginfo24.com\/it\/2021\/09\/02\/fiege-e-lip-avviano-un-ulteriore-multi-user-center\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/loginfo24.com\/it\/2021\/09\/02\/fiege-e-lip-avviano-un-ulteriore-multi-user-center\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/loginfo24.com\/it\/2021\/09\/02\/fiege-e-lip-avviano-un-ulteriore-multi-user-center\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/loginfo24.com\/it\/"},{"@type":"ListItem","position":2,"name":"Fiege e LIP avviano un ulteriore Multi-User-Center"}]},{"@type":"WebSite","@id":"https:\/\/loginfo24.com\/it\/#website","url":"https:\/\/loginfo24.com\/it\/","name":"Loginfo24","description":"Loginfo24 \u00e8 la piattaforma dedicata alla logistica e alle catene di fornitura con informazioni disponibili 24 ore su 24.","publisher":{"@id":"https:\/\/loginfo24.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/loginfo24.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/loginfo24.com\/it\/#organization","name":"Logismedia Group AG","url":"https:\/\/loginfo24.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/loginfo24.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","width":938,"height":351,"caption":"Logismedia Group AG"},"image":{"@id":"https:\/\/loginfo24.com\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","https:\/\/www.linkedin.com\/company\/lofinfo24\/"]}]}},"_links":{"self":[{"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/posts\/51592","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/comments?post=51592"}],"version-history":[{"count":0,"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/posts\/51592\/revisions"}],"wp:attachment":[{"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/media?parent=51592"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/categories?post=51592"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/tags?post=51592"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}