{"id":51508,"date":"2021-08-31T17:44:45","date_gmt":"2021-08-31T15:44:45","guid":{"rendered":"https:\/\/blog.brand-architecture.at\/2021\/08\/31\/lip-invest-lancia-il-quarto-fondo-immobiliare-logistico\/"},"modified":"2021-08-31T17:44:45","modified_gmt":"2021-08-31T15:44:45","slug":"lip-invest-lancia-il-quarto-fondo-immobiliare-logistico","status":"publish","type":"post","link":"https:\/\/loginfo24.com\/it\/2021\/08\/31\/lip-invest-lancia-il-quarto-fondo-immobiliare-logistico\/","title":{"rendered":"LIP Invest lancia il quarto fondo immobiliare logistico"},"content":{"rendered":"<p>LIP Invest, principale gestore di investimenti per immobili logistici in Germania, lancia il suo quarto fondo immobiliare logistico. La BaFin ha concesso l&#8217;autorizzazione alla distribuzione per il &#8220;LIP Real Estate Investment Fund \u2013 LOGISTICS GERMANY IV&#8221;. Pertanto, \u00e8 ora aperto alla sottoscrizione da parte di investitori istituzionali.<\/p>\n<p>(Monaco) Il fondo si rivolge principalmente a casse di previdenza, fondi pensione e banche e casse di risparmio. Grazie alla rinnovata collaborazione con il KVG di servizio INREAL, possono essere soddisfatti tutti i requisiti di reporting normativo e bancario.<\/p>\n<p>Numerosi investitori hanno gi\u00e0 confermato la loro partecipazione al fondo. Gli investitori del primo closing possono contare su un rapido richiamo di capitale entro pochi mesi, grazie a un pipeline garantita di oltre 100 milioni di euro.<\/p>\n<p>Con una strategia core, il fondo - come i suoi tre predecessori - si concentrer\u00e0 esclusivamente sulla Germania, il mercato logistico pi\u00f9 grande e importante in Europa. Nell&#8217;ambito di una ampia diversificazione, il fondo si focalizzer\u00e0 su localit\u00e0 consolidate e sostenibili per utilizzi logistici con una domanda di spazio duratura. La concezione del fondo include anche aspetti di sostenibilit\u00e0 ambientale, responsabilit\u00e0 sociale e corporate governance.<\/p>\n<h5><strong>Il portafoglio sale a 1,3 miliardi di euro<\/strong><\/h5>\n<p>\u201cNonostante l&#8217;aumento dei prezzi in molte classi di attivi, gli immobili logistici continuano a offrire un&#8217;opportunit\u00e0 di investimento attraente con flussi di cassa garantiti e la possibilit\u00e0 di aumenti degli affitti a causa di una disponibilit\u00e0 di spazi sempre pi\u00f9 ridotta\u201d, afferma Bodo Hollung, fondatore e amministratore delegato di LIP Invest.<\/p>\n<p>Hollung continua: \u201cNegli immobili specializzati come quelli logistici, sempre pi\u00f9 investitori si affidano a cosiddette boutique di investimento, piccoli gestori patrimoniali specializzati nella loro classe di attivi. Solo negli ultimi tre anni, oltre 50 investitori istituzionali hanno partecipato ai fondi immobiliari logistici LIP con oltre 770 milioni di euro.\u201d<\/p>\n<p>Con un volume di investimento di circa 1,3 miliardi di euro, il portafoglio LIP \u00e8 ora composto da 45 oggetti con una superficie totale affittabile di 930.000 metri quadrati e un reddito da affitto di oltre 55 milioni di euro. Dopo l&#8217;affitto programmato di oggetti acquisiti con quasi 20.000 metri quadrati di parziale vuoto, l&#8217;intero patrimonio immobiliare \u00e8 completamente affittato.<\/p>\n<p>Foto: \u00a9 LIP \/ <strong><em>Didascalia:<\/em><\/strong><em> Bodo Hollung<strong>,<\/strong> fondatore e amministratore delegato di LIP Invest<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>LIP Invest, principale gestore di investimenti per immobili logistici in Germania, lancia il suo quarto fondo immobiliare logistico. La BaFin ha concesso l&#8217;autorizzazione alla distribuzione per<span class=\"excerpt-hellip\"> [\u2026]<\/span><\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1557,1561],"tags":[],"class_list":["post-51508","post","type-post","status-publish","format-standard","hentry","category-forwarding-logistics","category-regions"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>LIP Invest lancia il quarto fondo immobiliare logistico - Loginfo24<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/loginfo24.com\/it\/2021\/08\/31\/lip-invest-lancia-il-quarto-fondo-immobiliare-logistico\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"LIP Invest lancia il quarto fondo immobiliare logistico - Loginfo24\" \/>\n<meta property=\"og:description\" content=\"LIP Invest, principale gestore di investimenti per immobili logistici in Germania, lancia il suo quarto fondo immobiliare logistico. La BaFin ha concesso l&#8217;autorizzazione alla distribuzione per [\u2026]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/loginfo24.com\/it\/2021\/08\/31\/lip-invest-lancia-il-quarto-fondo-immobiliare-logistico\/\" \/>\n<meta property=\"og:site_name\" content=\"Loginfo24\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/\" \/>\n<meta property=\"article:published_time\" content=\"2021-08-31T15:44:45+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2021\\\/08\\\/31\\\/lip-invest-lancia-il-quarto-fondo-immobiliare-logistico\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2021\\\/08\\\/31\\\/lip-invest-lancia-il-quarto-fondo-immobiliare-logistico\\\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"LIP Invest lancia il quarto fondo immobiliare logistico\",\"datePublished\":\"2021-08-31T15:44:45+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2021\\\/08\\\/31\\\/lip-invest-lancia-il-quarto-fondo-immobiliare-logistico\\\/\"},\"wordCount\":369,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#organization\"},\"articleSection\":[\"Forwarding &amp; Logistics\",\"Regions\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/it\\\/2021\\\/08\\\/31\\\/lip-invest-lancia-il-quarto-fondo-immobiliare-logistico\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2021\\\/08\\\/31\\\/lip-invest-lancia-il-quarto-fondo-immobiliare-logistico\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2021\\\/08\\\/31\\\/lip-invest-lancia-il-quarto-fondo-immobiliare-logistico\\\/\",\"name\":\"LIP Invest lancia il quarto fondo immobiliare logistico - Loginfo24\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#website\"},\"datePublished\":\"2021-08-31T15:44:45+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2021\\\/08\\\/31\\\/lip-invest-lancia-il-quarto-fondo-immobiliare-logistico\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/it\\\/2021\\\/08\\\/31\\\/lip-invest-lancia-il-quarto-fondo-immobiliare-logistico\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2021\\\/08\\\/31\\\/lip-invest-lancia-il-quarto-fondo-immobiliare-logistico\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"LIP Invest lancia il quarto fondo immobiliare logistico\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/\",\"name\":\"Loginfo24\",\"description\":\"Loginfo24 \u00e8 la piattaforma dedicata alla logistica e alle catene di fornitura con informazioni disponibili 24 ore su 24.\",\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#organization\",\"name\":\"Logismedia Group AG\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"width\":938,\"height\":351,\"caption\":\"Logismedia Group AG\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/people\\\/Loginfo24\\\/100057360583332\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/lofinfo24\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"LIP Invest lancia il quarto fondo immobiliare logistico - Loginfo24","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/loginfo24.com\/it\/2021\/08\/31\/lip-invest-lancia-il-quarto-fondo-immobiliare-logistico\/","og_locale":"it_IT","og_type":"article","og_title":"LIP Invest lancia il quarto fondo immobiliare logistico - Loginfo24","og_description":"LIP Invest, principale gestore di investimenti per immobili logistici in Germania, lancia il suo quarto fondo immobiliare logistico. La BaFin ha concesso l&#8217;autorizzazione alla distribuzione per [\u2026]","og_url":"https:\/\/loginfo24.com\/it\/2021\/08\/31\/lip-invest-lancia-il-quarto-fondo-immobiliare-logistico\/","og_site_name":"Loginfo24","article_publisher":"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","article_published_time":"2021-08-31T15:44:45+00:00","twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"2 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/loginfo24.com\/it\/2021\/08\/31\/lip-invest-lancia-il-quarto-fondo-immobiliare-logistico\/#article","isPartOf":{"@id":"https:\/\/loginfo24.com\/it\/2021\/08\/31\/lip-invest-lancia-il-quarto-fondo-immobiliare-logistico\/"},"author":{"name":"","@id":""},"headline":"LIP Invest lancia il quarto fondo immobiliare logistico","datePublished":"2021-08-31T15:44:45+00:00","mainEntityOfPage":{"@id":"https:\/\/loginfo24.com\/it\/2021\/08\/31\/lip-invest-lancia-il-quarto-fondo-immobiliare-logistico\/"},"wordCount":369,"commentCount":0,"publisher":{"@id":"https:\/\/loginfo24.com\/it\/#organization"},"articleSection":["Forwarding &amp; Logistics","Regions"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/loginfo24.com\/it\/2021\/08\/31\/lip-invest-lancia-il-quarto-fondo-immobiliare-logistico\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/loginfo24.com\/it\/2021\/08\/31\/lip-invest-lancia-il-quarto-fondo-immobiliare-logistico\/","url":"https:\/\/loginfo24.com\/it\/2021\/08\/31\/lip-invest-lancia-il-quarto-fondo-immobiliare-logistico\/","name":"LIP Invest lancia il quarto fondo immobiliare logistico - Loginfo24","isPartOf":{"@id":"https:\/\/loginfo24.com\/it\/#website"},"datePublished":"2021-08-31T15:44:45+00:00","breadcrumb":{"@id":"https:\/\/loginfo24.com\/it\/2021\/08\/31\/lip-invest-lancia-il-quarto-fondo-immobiliare-logistico\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/loginfo24.com\/it\/2021\/08\/31\/lip-invest-lancia-il-quarto-fondo-immobiliare-logistico\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/loginfo24.com\/it\/2021\/08\/31\/lip-invest-lancia-il-quarto-fondo-immobiliare-logistico\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/loginfo24.com\/it\/"},{"@type":"ListItem","position":2,"name":"LIP Invest lancia il quarto fondo immobiliare logistico"}]},{"@type":"WebSite","@id":"https:\/\/loginfo24.com\/it\/#website","url":"https:\/\/loginfo24.com\/it\/","name":"Loginfo24","description":"Loginfo24 \u00e8 la piattaforma dedicata alla logistica e alle catene di fornitura con informazioni disponibili 24 ore su 24.","publisher":{"@id":"https:\/\/loginfo24.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/loginfo24.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/loginfo24.com\/it\/#organization","name":"Logismedia Group AG","url":"https:\/\/loginfo24.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/loginfo24.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","width":938,"height":351,"caption":"Logismedia Group AG"},"image":{"@id":"https:\/\/loginfo24.com\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","https:\/\/www.linkedin.com\/company\/lofinfo24\/"]}]}},"_links":{"self":[{"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/posts\/51508","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/comments?post=51508"}],"version-history":[{"count":0,"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/posts\/51508\/revisions"}],"wp:attachment":[{"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/media?parent=51508"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/categories?post=51508"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/tags?post=51508"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}