{"id":51398,"date":"2021-08-25T18:47:33","date_gmt":"2021-08-25T16:47:33","guid":{"rendered":"https:\/\/blog.brand-architecture.at\/2021\/08\/25\/astag-sottolinea-limportanza-del-trasporto-stradale-in-svizzera\/"},"modified":"2021-08-25T18:47:33","modified_gmt":"2021-08-25T16:47:33","slug":"astag-sottolinea-limportanza-del-trasporto-stradale-in-svizzera","status":"publish","type":"post","link":"https:\/\/loginfo24.com\/it\/2021\/08\/25\/astag-sottolinea-limportanza-del-trasporto-stradale-in-svizzera\/","title":{"rendered":"ASTAG sottolinea l&#8217;importanza del trasporto stradale in Svizzera"},"content":{"rendered":"<p>Il sindacato svizzero dei veicoli commerciali ASTAG \u00e8 orgoglioso di poter impegnarsi con una politica costruttiva per un settore indispensabile. L&#8217;industria del trasporto su strada svizzera \u00e8 sistematicamente rilevante, sicura e molto pulita. Grazie ai camion, ogni giorno e soprattutto durante la crisi del Coronavirus, viene garantita la fornitura e lo smaltimento in tutto il paese. Investimenti nell&#8217;ordine di miliardi hanno portato a un rinnovamento della flotta con veicoli all&#8217;avanguardia a zero emissioni inquinanti e bassi valori di CO2.<\/p>\n<p>(Berna) Negli ultimi giorni, il sindacato svizzero dei veicoli commerciali ASTAG ha ricevuto una notevole attenzione dai media. Al centro dell&#8217;attenzione c&#8217;era quasi esclusivamente l&#8217;organizzazione. Le attivit\u00e0 e i successi dell&#8217;ASTAG e dei suoi membri a favore della fornitura e dello smaltimento, cos\u00ec come della mobilit\u00e0 in Svizzera, hanno suscitato poco interesse. Sono stati trascurati soprattutto l&#8217;alta rilevanza sistemica del trasporto merci su strada per l&#8217;intera economia e popolazione, cos\u00ec come l&#8217;impegno efficace delle aziende di trasporto e autobus turistici a favore dell&#8217;ambiente e del clima.<\/p>\n<h5><strong>I servizi dell&#8217;ASTAG e dei suoi membri:<\/strong><\/h5>\n<ul>\n<li>Per la distribuzione di beni e merci, il trasporto su strada \u00e8 indispensabile. Solo grazie ai camion gli alimenti, i beni di prima necessit\u00e0, i farmaci, ma anche i materiali da costruzione, il legno e le macchine arrivano sempre in modo affidabile e puntuale a destinazione, come ha dimostrato la crisi del Coronavirus. Ogni singolo cantiere funziona solo grazie ai trasporti in entrata e in uscita via strada. Anche lo smaltimento (rifiuti, pulizia delle fognature) \u00e8 garantito dai veicoli commerciali.<\/li>\n<li>All&#8217;inizio dei servizi di trasporto ci sono le esigenze dell&#8217;economia, del commercio e della popolazione. Il compito e l&#8217;obiettivo dei membri dell&#8217;ASTAG \u00e8 quello di soddisfare la domanda nel modo pi\u00f9 efficiente possibile, a beneficio dell&#8217;intero paese.<\/li>\n<li>Negli ultimi anni, l&#8217;industria del trasporto su strada ha rinnovato quasi l&#8217;intera flotta. Oggi, oltre il 96% di tutti i chilometri tonnellata vengono percorsi con veicoli commerciali moderni conformi agli standard EURO 5 e 6. Le emissioni inquinanti sono quindi scese a quasi zero. Inoltre, la quota del trasporto pesante sulle emissioni totali di CO2 della Svizzera \u00e8 di poco meno del 5%.<\/li>\n<li>Gi\u00e0 ora sono in uso anche veicoli commerciali con propulsione alternativa (elettrica, LNG, idrogeno). Maggiore \u00e8 l&#8217;uso di energia primaria da fonti rinnovabili, minori sono le emissioni di CO2. L&#8217;industria dei trasporti svizzera svolge un ruolo pionieristico in questo senso in tutta Europa.<\/li>\n<li>Inoltre, il settore si \u00e8 impegnato volontariamente in una risoluzione sul clima dell&#8217;ASTAG del maggio 2021 a ridurre le proprie emissioni di gas serra del 50% entro il 2030 rispetto al livello del 1990. Misure efficaci sono gi\u00e0 in fase di attuazione e ora vengono intensificate.<\/li>\n<li>Le autiste e gli autisti professionisti, come sostegno indispensabile del settore, sono obbligati a partecipare regolarmente a corsi di formazione continua. L&#8217;obbligo legale \u00e8 di 5 giorni di formazione ogni 5 anni. Ci\u00f2 include in particolare anche corsi di EcoDrive per una guida il pi\u00f9 possibile economica in termini di carburante. In media, ci\u00f2 consente di ridurre il consumo di diesel, ovvero le emissioni di CO2, di circa il 10%.<\/li>\n<li>Per rafforzare il trasporto merci su rotaia, diverse aziende membri dell&#8217;ASTAG hanno partecipato finanziariamente a SBB Cargo International e a SBB Cargo. In questo modo si contribuisce in modo significativo al trasferimento nel traffico di transito attraverso le Alpi da confine a confine. Inoltre, la ferrovia viene utilizzata sempre di pi\u00f9 nel traffico interno, quando possibile.<\/li>\n<\/ul>\n<h5><strong>Continua stretta collaborazione con le autorit\u00e0 politiche<\/strong><\/h5>\n<p>La copertura mediatica degli ultimi giorni \u00e8 quindi priva di qualsiasi fondamento. \u00c8 corretto affermare che l&#8217;ASTAG si impegna con orgoglio e convinzione per le legittime preoccupazioni e interessi del trasporto merci e passeggeri con camion, autobus turistici e taxi a favore dell&#8217;intero paese. L&#8217;obiettivo \u00e8 quello di consentire un trasporto di persone e merci il pi\u00f9 efficiente, sicuro e rispettoso dell&#8217;ambiente possibile. Gi\u00e0 anni fa, l&#8217;ASTAG si \u00e8 quindi espressa senza riserve a favore della co-modalit\u00e0, cio\u00e8 della collaborazione paritaria di tutti i mezzi di trasporto. Anche in futuro, la politica dei trasporti e quella ambientale e climatica dovrebbero essere sviluppate il pi\u00f9 possibile senza paraocchi ideologici. &#8220;L&#8217;ASTAG \u00e8 lieta di poter continuare a collaborare in modo stretto e costruttivo con il Parlamento, il Consiglio federale, l&#8217;amministrazione e le forze costruttive di tutti i partiti&#8221;, riassume il direttore dell&#8217;ASTAG Reto Jaussi.<br \/>Foto: \u00a9 Loginfo24\/Adobe Stock<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il sindacato svizzero dei veicoli commerciali ASTAG \u00e8 orgoglioso di poter impegnarsi con una politica costruttiva per un settore indispensabile. L&#8217;industria del trasporto su strada svizzera<span class=\"excerpt-hellip\"> [\u2026]<\/span><\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1557,1556,1561],"tags":[],"class_list":["post-51398","post","type-post","status-publish","format-standard","hentry","category-forwarding-logistics","category-intermodal-road","category-regions"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>ASTAG sottolinea l&#039;importanza del trasporto stradale in Svizzera - Loginfo24<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/loginfo24.com\/it\/2021\/08\/25\/astag-sottolinea-limportanza-del-trasporto-stradale-in-svizzera\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"ASTAG sottolinea l&#039;importanza del trasporto stradale in Svizzera - Loginfo24\" \/>\n<meta property=\"og:description\" content=\"Il sindacato svizzero dei veicoli commerciali ASTAG \u00e8 orgoglioso di poter impegnarsi con una politica costruttiva per un settore indispensabile. L&#8217;industria del trasporto su strada svizzera [\u2026]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/loginfo24.com\/it\/2021\/08\/25\/astag-sottolinea-limportanza-del-trasporto-stradale-in-svizzera\/\" \/>\n<meta property=\"og:site_name\" content=\"Loginfo24\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/\" \/>\n<meta property=\"article:published_time\" content=\"2021-08-25T16:47:33+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2021\\\/08\\\/25\\\/astag-sottolinea-limportanza-del-trasporto-stradale-in-svizzera\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2021\\\/08\\\/25\\\/astag-sottolinea-limportanza-del-trasporto-stradale-in-svizzera\\\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"ASTAG sottolinea l&#8217;importanza del trasporto stradale in Svizzera\",\"datePublished\":\"2021-08-25T16:47:33+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2021\\\/08\\\/25\\\/astag-sottolinea-limportanza-del-trasporto-stradale-in-svizzera\\\/\"},\"wordCount\":736,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#organization\"},\"articleSection\":[\"Forwarding &amp; Logistics\",\"Intermodal \\\/ Road\",\"Regions\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/it\\\/2021\\\/08\\\/25\\\/astag-sottolinea-limportanza-del-trasporto-stradale-in-svizzera\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2021\\\/08\\\/25\\\/astag-sottolinea-limportanza-del-trasporto-stradale-in-svizzera\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2021\\\/08\\\/25\\\/astag-sottolinea-limportanza-del-trasporto-stradale-in-svizzera\\\/\",\"name\":\"ASTAG sottolinea l'importanza del trasporto stradale in Svizzera - Loginfo24\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#website\"},\"datePublished\":\"2021-08-25T16:47:33+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2021\\\/08\\\/25\\\/astag-sottolinea-limportanza-del-trasporto-stradale-in-svizzera\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/it\\\/2021\\\/08\\\/25\\\/astag-sottolinea-limportanza-del-trasporto-stradale-in-svizzera\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2021\\\/08\\\/25\\\/astag-sottolinea-limportanza-del-trasporto-stradale-in-svizzera\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"ASTAG sottolinea l&#8217;importanza del trasporto stradale in Svizzera\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/\",\"name\":\"Loginfo24\",\"description\":\"Loginfo24 \u00e8 la piattaforma dedicata alla logistica e alle catene di fornitura con informazioni disponibili 24 ore su 24.\",\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#organization\",\"name\":\"Logismedia Group AG\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"width\":938,\"height\":351,\"caption\":\"Logismedia Group AG\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/people\\\/Loginfo24\\\/100057360583332\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/lofinfo24\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"ASTAG sottolinea l'importanza del trasporto stradale in Svizzera - Loginfo24","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/loginfo24.com\/it\/2021\/08\/25\/astag-sottolinea-limportanza-del-trasporto-stradale-in-svizzera\/","og_locale":"it_IT","og_type":"article","og_title":"ASTAG sottolinea l'importanza del trasporto stradale in Svizzera - Loginfo24","og_description":"Il sindacato svizzero dei veicoli commerciali ASTAG \u00e8 orgoglioso di poter impegnarsi con una politica costruttiva per un settore indispensabile. L&#8217;industria del trasporto su strada svizzera [\u2026]","og_url":"https:\/\/loginfo24.com\/it\/2021\/08\/25\/astag-sottolinea-limportanza-del-trasporto-stradale-in-svizzera\/","og_site_name":"Loginfo24","article_publisher":"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","article_published_time":"2021-08-25T16:47:33+00:00","twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"3 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/loginfo24.com\/it\/2021\/08\/25\/astag-sottolinea-limportanza-del-trasporto-stradale-in-svizzera\/#article","isPartOf":{"@id":"https:\/\/loginfo24.com\/it\/2021\/08\/25\/astag-sottolinea-limportanza-del-trasporto-stradale-in-svizzera\/"},"author":{"name":"","@id":""},"headline":"ASTAG sottolinea l&#8217;importanza del trasporto stradale in Svizzera","datePublished":"2021-08-25T16:47:33+00:00","mainEntityOfPage":{"@id":"https:\/\/loginfo24.com\/it\/2021\/08\/25\/astag-sottolinea-limportanza-del-trasporto-stradale-in-svizzera\/"},"wordCount":736,"commentCount":0,"publisher":{"@id":"https:\/\/loginfo24.com\/it\/#organization"},"articleSection":["Forwarding &amp; Logistics","Intermodal \/ Road","Regions"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/loginfo24.com\/it\/2021\/08\/25\/astag-sottolinea-limportanza-del-trasporto-stradale-in-svizzera\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/loginfo24.com\/it\/2021\/08\/25\/astag-sottolinea-limportanza-del-trasporto-stradale-in-svizzera\/","url":"https:\/\/loginfo24.com\/it\/2021\/08\/25\/astag-sottolinea-limportanza-del-trasporto-stradale-in-svizzera\/","name":"ASTAG sottolinea l'importanza del trasporto stradale in Svizzera - Loginfo24","isPartOf":{"@id":"https:\/\/loginfo24.com\/it\/#website"},"datePublished":"2021-08-25T16:47:33+00:00","breadcrumb":{"@id":"https:\/\/loginfo24.com\/it\/2021\/08\/25\/astag-sottolinea-limportanza-del-trasporto-stradale-in-svizzera\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/loginfo24.com\/it\/2021\/08\/25\/astag-sottolinea-limportanza-del-trasporto-stradale-in-svizzera\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/loginfo24.com\/it\/2021\/08\/25\/astag-sottolinea-limportanza-del-trasporto-stradale-in-svizzera\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/loginfo24.com\/it\/"},{"@type":"ListItem","position":2,"name":"ASTAG sottolinea l&#8217;importanza del trasporto stradale in Svizzera"}]},{"@type":"WebSite","@id":"https:\/\/loginfo24.com\/it\/#website","url":"https:\/\/loginfo24.com\/it\/","name":"Loginfo24","description":"Loginfo24 \u00e8 la piattaforma dedicata alla logistica e alle catene di fornitura con informazioni disponibili 24 ore su 24.","publisher":{"@id":"https:\/\/loginfo24.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/loginfo24.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/loginfo24.com\/it\/#organization","name":"Logismedia Group AG","url":"https:\/\/loginfo24.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/loginfo24.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","width":938,"height":351,"caption":"Logismedia Group AG"},"image":{"@id":"https:\/\/loginfo24.com\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","https:\/\/www.linkedin.com\/company\/lofinfo24\/"]}]}},"_links":{"self":[{"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/posts\/51398","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/comments?post=51398"}],"version-history":[{"count":0,"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/posts\/51398\/revisions"}],"wp:attachment":[{"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/media?parent=51398"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/categories?post=51398"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/tags?post=51398"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}