{"id":51283,"date":"2021-08-16T18:19:11","date_gmt":"2021-08-16T16:19:11","guid":{"rendered":"https:\/\/blog.brand-architecture.at\/2021\/08\/16\/dsv-panalpina-acquisisce-definitivamente-il-business-gil-di-agility\/"},"modified":"2021-08-16T18:19:11","modified_gmt":"2021-08-16T16:19:11","slug":"dsv-panalpina-acquisisce-definitivamente-il-business-gil-di-agility","status":"publish","type":"post","link":"https:\/\/loginfo24.com\/it\/2021\/08\/16\/dsv-panalpina-acquisisce-definitivamente-il-business-gil-di-agility\/","title":{"rendered":"DSV Panalpina acquisisce definitivamente il business GIL di Agility"},"content":{"rendered":"<p>Tutte le condizioni e i requisiti per l&#8217;acquisizione del Global Integrated Logistics (GIL) di Agility sono stati soddisfatti, e DSV Panalpina A\/S (DSV) acquisisce ora formalmente GIL da Agility, che ha sede in Kuwait. Con l&#8217;acquisizione di GIL, DSV diventa uno dei tre principali attori mondiali nel settore dei trasporti e della logistica e intende espandere ulteriormente l&#8217;attivit\u00e0 da questa posizione forte.<\/p>\n<p>(Hedehusene) La conclusione dell&#8217;acquisizione di GIL, prevista per oggi, rappresenta una pietra miliare importante nella strategia di crescita di DSV. Nel settore dei trasporti e della logistica, la dimensione \u00e8 fondamentale, e con l&#8217;acquisizione DSV consolida la sua posizione come una delle pi\u00f9 grandi aziende di trasporto e logistica al mondo.<\/p>\n<p>\u201cSono molto felice di dare il benvenuto ai nostri nuovi colleghi di GIL in questo giorno importante. Ci sono molte affinit\u00e0 quando si guarda alle nostre due aziende, sia in termini di modelli di business e servizi, sia, non da ultimo, per il nostro comune focus sull&#8217;empowerment locale e sul servizio clienti. DSV e GIL si integrano perfettamente. Inizieremo ora con l&#8217;integrazione e insieme espanderemo l&#8217;attivit\u00e0, portando un valore ancora maggiore ai nostri numerosi clienti, partner e azionisti rispetto a quanto potremmo fare singolarmente\u201d, afferma Jens Bj\u00f8rn Andersen, CEO di DSV.<\/p>\n<h5><strong>Valore della transazione di 30,2 miliardi di DKK<\/strong><\/h5>\n<p>Il valore aziendale della transazione \u00e8 di circa 30,2 miliardi di DKK e il valore del capitale proprio \u00e8 di circa 29,6 miliardi di DKK. La fusione tra DSV e GIL avr\u00e0 un fatturato pro forma combinato di circa 160 miliardi di DKK (basato sugli ultimi 12 mesi) e un organico comune di 75.000 dipendenti in oltre 90 paesi.<\/p>\n<p>In cambio del 100% di GIL, Agility ricever\u00e0 azioni DSV che corrispondono a circa l&#8217;8% di tutte le azioni DSV in circolazione dopo la transazione. In questo modo, Agility diventer\u00e0 il secondo maggiore azionista di DSV sulla base dell&#8217;attuale registro degli azionisti. DSV ha accettato di nominare un rappresentante di Agility nel consiglio di amministrazione di DSV dopo il completamento della transazione.<\/p>\n<h5><strong>Offerte di servizi migliorate in tutti e tre i settori<\/strong><\/h5>\n<p>GIL genera un fatturato annuale di 29 miliardi di DKK (4,6 miliardi di USD), con il trasporto aereo e marittimo che rappresenta la parte pi\u00f9 consistente. Questa azienda sar\u00e0 aggiunta alla rete globale esistente di DSV. Inoltre, l&#8217;inclusione di GIL espande la presenza di DSV sia in APAC che in Medio Oriente. Con una capacit\u00e0 di magazzino di 1,4 milioni di metri quadrati, GIL sar\u00e0 una forte integrazione per DSV Solutions, mentre le attivit\u00e0 di trasporto terrestre in Europa e Medio Oriente rafforzeranno la rete DSV Road.<\/p>\n<p>\u201cAggiungendo la rete e le competenze di GIL alla nostra rete esistente, miglioriamo la nostra competitivit\u00e0 in tutti e tre i settori: Air &amp; Sea, Road e Solutions. Questo porta sinergie commerciali e opportunit\u00e0 di cross-selling, offrendo ai nostri clienti un livello di servizio ancora pi\u00f9 elevato e un one-stop-shop per le esigenze logistiche\u201d, afferma Jens Bj\u00f8rn Andersen.<\/p>\n<h5><strong>Espandere insieme l&#8217;attivit\u00e0<\/strong><\/h5>\n<p>L&#8217;attivit\u00e0 combinata di DSV e GIL mira a sfruttare la posizione di mercato rafforzata per continuare a crescere attraverso offerte di servizi migliorate per i clienti, un&#8217;infrastruttura IT leader di mercato e vantaggi di scala.<\/p>\n<p>La strategia di acquisizione di DSV si \u00e8 dimostrata efficace sia nell&#8217;acquisizione che nell&#8217;integrazione delle aziende, l&#8217;ultima delle quali \u00e8 stata la svizzera Panalpina nel 2019 e l&#8217;americana UTi Worldwide nel 2016.<\/p>\n<p>Il focus sulla scalabilit\u00e0 rimane uno dei principali vantaggi competitivi nel settore della spedizione e offre significativi vantaggi operativi e commerciali in un mercato altamente frammentato.<\/p>\n<h5><strong>Il processo di integrazione pu\u00f2 iniziare<\/strong><\/h5>\n<p>Ora pu\u00f2 iniziare il processo di integrazione di GIL. Le due organizzazioni saranno unite in un processo specifico per paese, il che significa che per i clienti e i dipendenti in molti paesi, per il momento, sar\u00e0 business as usual, fino a quando non verr\u00e0 avviato il processo di fusione specifico per paese. Come per le precedenti acquisizioni, DSV prender\u00e0 in considerazione sia aspetti organizzativi che individuali anche in questa integrazione.<\/p>\n<p>Nonostante la conclusione della transazione prevista per oggi, in un numero limitato di paesi, dove i ricavi singoli e combinati sono trascurabili rispetto ai ricavi combinati dopo la conclusione della transazione, le approvazioni normative sono ancora in attesa.<\/p>\n<p>Foto: \u00a9 DSV<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Tutte le condizioni e i requisiti per l&#8217;acquisizione del Global Integrated Logistics (GIL) di Agility sono stati soddisfatti, e DSV Panalpina A\/S (DSV) acquisisce ora formalmente<span class=\"excerpt-hellip\"> [\u2026]<\/span><\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1557,1561],"tags":[],"class_list":["post-51283","post","type-post","status-publish","format-standard","hentry","category-forwarding-logistics","category-regions"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>DSV Panalpina acquisisce definitivamente il business GIL di Agility - Loginfo24<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/loginfo24.com\/it\/2021\/08\/16\/dsv-panalpina-acquisisce-definitivamente-il-business-gil-di-agility\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"DSV Panalpina acquisisce definitivamente il business GIL di Agility - Loginfo24\" \/>\n<meta property=\"og:description\" content=\"Tutte le condizioni e i requisiti per l&#8217;acquisizione del Global Integrated Logistics (GIL) di Agility sono stati soddisfatti, e DSV Panalpina A\/S (DSV) acquisisce ora formalmente [\u2026]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/loginfo24.com\/it\/2021\/08\/16\/dsv-panalpina-acquisisce-definitivamente-il-business-gil-di-agility\/\" \/>\n<meta property=\"og:site_name\" content=\"Loginfo24\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/\" \/>\n<meta property=\"article:published_time\" content=\"2021-08-16T16:19:11+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2021\\\/08\\\/16\\\/dsv-panalpina-acquisisce-definitivamente-il-business-gil-di-agility\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2021\\\/08\\\/16\\\/dsv-panalpina-acquisisce-definitivamente-il-business-gil-di-agility\\\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"DSV Panalpina acquisisce definitivamente il business GIL di Agility\",\"datePublished\":\"2021-08-16T16:19:11+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2021\\\/08\\\/16\\\/dsv-panalpina-acquisisce-definitivamente-il-business-gil-di-agility\\\/\"},\"wordCount\":712,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#organization\"},\"articleSection\":[\"Forwarding &amp; Logistics\",\"Regions\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/it\\\/2021\\\/08\\\/16\\\/dsv-panalpina-acquisisce-definitivamente-il-business-gil-di-agility\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2021\\\/08\\\/16\\\/dsv-panalpina-acquisisce-definitivamente-il-business-gil-di-agility\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2021\\\/08\\\/16\\\/dsv-panalpina-acquisisce-definitivamente-il-business-gil-di-agility\\\/\",\"name\":\"DSV Panalpina acquisisce definitivamente il business GIL di Agility - Loginfo24\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#website\"},\"datePublished\":\"2021-08-16T16:19:11+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2021\\\/08\\\/16\\\/dsv-panalpina-acquisisce-definitivamente-il-business-gil-di-agility\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/it\\\/2021\\\/08\\\/16\\\/dsv-panalpina-acquisisce-definitivamente-il-business-gil-di-agility\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2021\\\/08\\\/16\\\/dsv-panalpina-acquisisce-definitivamente-il-business-gil-di-agility\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"DSV Panalpina acquisisce definitivamente il business GIL di Agility\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/\",\"name\":\"Loginfo24\",\"description\":\"Loginfo24 \u00e8 la piattaforma dedicata alla logistica e alle catene di fornitura con informazioni disponibili 24 ore su 24.\",\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#organization\",\"name\":\"Logismedia Group AG\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"width\":938,\"height\":351,\"caption\":\"Logismedia Group AG\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/people\\\/Loginfo24\\\/100057360583332\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/lofinfo24\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"DSV Panalpina acquisisce definitivamente il business GIL di Agility - Loginfo24","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/loginfo24.com\/it\/2021\/08\/16\/dsv-panalpina-acquisisce-definitivamente-il-business-gil-di-agility\/","og_locale":"it_IT","og_type":"article","og_title":"DSV Panalpina acquisisce definitivamente il business GIL di Agility - Loginfo24","og_description":"Tutte le condizioni e i requisiti per l&#8217;acquisizione del Global Integrated Logistics (GIL) di Agility sono stati soddisfatti, e DSV Panalpina A\/S (DSV) acquisisce ora formalmente [\u2026]","og_url":"https:\/\/loginfo24.com\/it\/2021\/08\/16\/dsv-panalpina-acquisisce-definitivamente-il-business-gil-di-agility\/","og_site_name":"Loginfo24","article_publisher":"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","article_published_time":"2021-08-16T16:19:11+00:00","twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"3 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/loginfo24.com\/it\/2021\/08\/16\/dsv-panalpina-acquisisce-definitivamente-il-business-gil-di-agility\/#article","isPartOf":{"@id":"https:\/\/loginfo24.com\/it\/2021\/08\/16\/dsv-panalpina-acquisisce-definitivamente-il-business-gil-di-agility\/"},"author":{"name":"","@id":""},"headline":"DSV Panalpina acquisisce definitivamente il business GIL di Agility","datePublished":"2021-08-16T16:19:11+00:00","mainEntityOfPage":{"@id":"https:\/\/loginfo24.com\/it\/2021\/08\/16\/dsv-panalpina-acquisisce-definitivamente-il-business-gil-di-agility\/"},"wordCount":712,"commentCount":0,"publisher":{"@id":"https:\/\/loginfo24.com\/it\/#organization"},"articleSection":["Forwarding &amp; Logistics","Regions"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/loginfo24.com\/it\/2021\/08\/16\/dsv-panalpina-acquisisce-definitivamente-il-business-gil-di-agility\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/loginfo24.com\/it\/2021\/08\/16\/dsv-panalpina-acquisisce-definitivamente-il-business-gil-di-agility\/","url":"https:\/\/loginfo24.com\/it\/2021\/08\/16\/dsv-panalpina-acquisisce-definitivamente-il-business-gil-di-agility\/","name":"DSV Panalpina acquisisce definitivamente il business GIL di Agility - Loginfo24","isPartOf":{"@id":"https:\/\/loginfo24.com\/it\/#website"},"datePublished":"2021-08-16T16:19:11+00:00","breadcrumb":{"@id":"https:\/\/loginfo24.com\/it\/2021\/08\/16\/dsv-panalpina-acquisisce-definitivamente-il-business-gil-di-agility\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/loginfo24.com\/it\/2021\/08\/16\/dsv-panalpina-acquisisce-definitivamente-il-business-gil-di-agility\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/loginfo24.com\/it\/2021\/08\/16\/dsv-panalpina-acquisisce-definitivamente-il-business-gil-di-agility\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/loginfo24.com\/it\/"},{"@type":"ListItem","position":2,"name":"DSV Panalpina acquisisce definitivamente il business GIL di Agility"}]},{"@type":"WebSite","@id":"https:\/\/loginfo24.com\/it\/#website","url":"https:\/\/loginfo24.com\/it\/","name":"Loginfo24","description":"Loginfo24 \u00e8 la piattaforma dedicata alla logistica e alle catene di fornitura con informazioni disponibili 24 ore su 24.","publisher":{"@id":"https:\/\/loginfo24.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/loginfo24.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/loginfo24.com\/it\/#organization","name":"Logismedia Group AG","url":"https:\/\/loginfo24.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/loginfo24.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","width":938,"height":351,"caption":"Logismedia Group AG"},"image":{"@id":"https:\/\/loginfo24.com\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","https:\/\/www.linkedin.com\/company\/lofinfo24\/"]}]}},"_links":{"self":[{"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/posts\/51283","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/comments?post=51283"}],"version-history":[{"count":0,"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/posts\/51283\/revisions"}],"wp:attachment":[{"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/media?parent=51283"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/categories?post=51283"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/tags?post=51283"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}