{"id":28210,"date":"2021-08-02T18:27:51","date_gmt":"2021-08-02T16:27:51","guid":{"rendered":"https:\/\/blog.brand-architecture.at\/2021\/08\/02\/leogistics-e-quuppa-automatizzano-la-gestione-del-yard\/"},"modified":"2025-12-15T13:13:53","modified_gmt":"2025-12-15T12:13:53","slug":"leogistics-e-quuppa-automatizzano-la-gestione-del-yard","status":"publish","type":"post","link":"https:\/\/loginfo24.com\/it\/2021\/08\/02\/leogistics-e-quuppa-automatizzano-la-gestione-del-yard\/","title":{"rendered":"leogistics e Quuppa automatizzano la gestione del yard"},"content":{"rendered":"<p>La leogistics GmbH, fornitore leader nella gestione digitale e automatizzata degli yard, sviluppa con myleo \/ yard una piattaforma di gestione degli yard altamente innovativa. Grazie a una nuova partnership con Quuppa, le aziende possono ora riconoscere con precisione al metro dove si trovano le varie risorse.<\/p>\n<p>(Amburgo) &#8220;La gestione degli yard del futuro \u00e8 digitalizzata e automatizzata. Per soddisfare la nostra ambizione di rendere myleo \/ dsc la piattaforma di gestione della supply chain leader, non solo consentiamo il tracciamento degli asset tramite Quuppa, ma collaboriamo con tutti i partner commerciali e i sistemi connessi per un controllo ottimizzato di vari processi aziendali&#8221;, afferma Andr\u00e9 K\u00e4ber, CEO di leogistics GmbH.<\/p>\n<h5><strong>Dati preziosi sulle posizioni delle attrezzature<\/strong><\/h5>\n<p>Spesso non \u00e8 chiaro dove si trovino attualmente le attrezzature o i mezzi di carico all&#8217;interno dell&#8217;area aziendale o del magazzino. Il sistema di localizzazione intelligente Quuppa\u2122 \u00e8 una soluzione potente che si basa sulla tecnologia Bluetooth\u00ae Direction Finding e su algoritmi proprietari per tracciare oggetti e dispositivi in quasi tempo reale con una precisione di meno di un metro. Quuppa \u00e8 un fornitore leader di sistemi di localizzazione in tempo reale (RTLS) con oltre 2600 implementazioni in pi\u00f9 di 55 paesi e oltre 200 partner in tutto il mondo. Dalle informazioni su come si muovono gli oggetti tracciati nell&#8217;area e quanto tempo trascorrono in ciascun luogo, il Quuppa Positioning Engine crea profili di posizione dettagliati. Grazie agli strumenti e alle app intelligenti di myleo \/ yard, il modulo di gestione degli yard di myleo \/ dsc, le aziende possono utilizzarli per identificare colli di bottiglia nei processi e snellire le operazioni critiche nella logistica aziendale. &#8220;Siamo entusiasti di questa partnership e di espandere insieme a leogistics il nostro business in una variet\u00e0 di settori&#8221;, afferma Thomas Hasselman, Chief Marketing Officer di Quuppa.<\/p>\n<h5><strong>Con dati in tempo reale verso lo yard automatizzato del futuro<\/strong><\/h5>\n<p>La nuova soluzione partner consente di digitalizzare il mondo fisico. Con questo approccio, leogistics, insieme a partner come Quuppa, crea un ecosistema che consente ai clienti di comprendere, migliorare e automatizzare i propri processi in tempi rapidi. Questo \u00e8 possibile grazie a flussi di lavoro intuitivi e opzioni di controllo flessibili nella soluzione cloud. L&#8217;uso il pi\u00f9 efficiente possibile di MAFIs, veicoli di movimentazione o carrelli elevatori attraverso l&#8217;ottimizzazione continua dei percorsi e l&#8217;assegnazione degli ordini sono solo alcuni esempi delle numerose possibilit\u00e0 di ottimizzazione e automazione basate su dati in tempo reale all&#8217;interno di myleo \/ dsc. A supportare ci\u00f2 ci sono diverse app operative, l&#8217;integrazione senza soluzione di continuit\u00e0 con Quuppa e, non da ultimo, la profonda conoscenza dei processi di leogistics GmbH. La myleo \/ dsc non solo offre processi aziendali e report gi\u00e0 configurati in modo esteso, ma \u00e8 anche molto facile da integrare in paesaggi di sistema e soluzioni partner, personalizzarla o ampliarla. Ci\u00f2 consente tempi di progetto estremamente brevi - anche per requisiti complessi, l&#8217;investimento iniziale per i costi di implementazione scende al minimo.<\/p>\n<h5><strong>Tracciare e gestire attrezzature, contenitori e co.<\/strong><\/h5>\n<p>I tag Quuppa possono essere applicati a qualsiasi oggetto, come carrelli elevatori, o a vari mezzi di carico come IBC, fusti o pallet, e funzionano in modo affidabile anche in condizioni difficili. Una volta installato, il sistema di solito non richiede manutenzione fisica e invia una notifica se necessita di attenzione. In questo modo, le aziende che utilizzano contenitori riutilizzabili possono ottenere una grande trasparenza processuale e basata sulla posizione sui propri mezzi di carico grazie alla tecnologia RTLS di Quuppa e alla nuova soluzione di gestione dei contenitori myleo \/ empties. Il nuovo modulo di myleo \/ dsc offre una gestione chiara dei mezzi di carico sotto forma di conti contenitore, che possono essere bilanciati in modo trasparente tra i partner della supply chain. Sulla base di geofences e tracciamento preciso della posizione, sono possibili anche prenotazioni automatizzate nello yard.<\/p>\n<h5><strong>Gestione intelligente dei contenitori tramite sensoristica e IoT<\/strong><\/h5>\n<p>Il tracciamento degli asset e la gestione dei contenitori offrono un enorme potenziale per progetti IoT. In futuro, dispositivi o contenitori dotati di sensoristica intelligente comunicheranno autonomamente il loro contenuto, posizione e influenze ambientali, contribuendo cos\u00ec in modo significativo alla gestione della qualit\u00e0. Quando un contenitore viene riempito presso il fornitore, il sensore integrato invia dati a myleo \/ dsc. Questi includono il numero ID univoco, la posizione, il timestamp, il contenuto e il livello di riempimento, nonch\u00e9 la temperatura e l&#8217;umidit\u00e0 dell&#8217;ambiente. Se il contenitore rileva durante il trasporto di essere stato esposto a influenze ambientali dannose, emette un avviso corrispondente. In questo modo, la qualit\u00e0 delle merci durante i trasporti pu\u00f2 essere monitorata meglio. Foto: \u00a9 leogistics<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La leogistics GmbH, fornitore leader nella gestione digitale e automatizzata degli yard, sviluppa con myleo \/ yard una piattaforma di gestione degli yard altamente innovativa. Grazie<span class=\"excerpt-hellip\"> [\u2026]<\/span><\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1665,1557,1560,1561],"tags":[],"class_list":["post-28210","post","type-post","status-publish","format-standard","hentry","category-categories","category-forwarding-logistics","category-intralogistics","category-regions"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>leogistics e Quuppa automatizzano la gestione del yard - Loginfo24<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/loginfo24.com\/it\/2021\/08\/02\/leogistics-e-quuppa-automatizzano-la-gestione-del-yard\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"leogistics e Quuppa automatizzano la gestione del yard - Loginfo24\" \/>\n<meta property=\"og:description\" content=\"La leogistics GmbH, fornitore leader nella gestione digitale e automatizzata degli yard, sviluppa con myleo \/ yard una piattaforma di gestione degli yard altamente innovativa. Grazie [\u2026]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/loginfo24.com\/it\/2021\/08\/02\/leogistics-e-quuppa-automatizzano-la-gestione-del-yard\/\" \/>\n<meta property=\"og:site_name\" content=\"Loginfo24\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/\" \/>\n<meta property=\"article:published_time\" content=\"2021-08-02T16:27:51+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-12-15T12:13:53+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2021\\\/08\\\/02\\\/leogistics-e-quuppa-automatizzano-la-gestione-del-yard\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2021\\\/08\\\/02\\\/leogistics-e-quuppa-automatizzano-la-gestione-del-yard\\\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"leogistics e Quuppa automatizzano la gestione del yard\",\"datePublished\":\"2021-08-02T16:27:51+00:00\",\"dateModified\":\"2025-12-15T12:13:53+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2021\\\/08\\\/02\\\/leogistics-e-quuppa-automatizzano-la-gestione-del-yard\\\/\"},\"wordCount\":767,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#organization\"},\"articleSection\":[\"Categories\",\"Forwarding &amp; Logistics\",\"Intralogistics\",\"Regions\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/it\\\/2021\\\/08\\\/02\\\/leogistics-e-quuppa-automatizzano-la-gestione-del-yard\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2021\\\/08\\\/02\\\/leogistics-e-quuppa-automatizzano-la-gestione-del-yard\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2021\\\/08\\\/02\\\/leogistics-e-quuppa-automatizzano-la-gestione-del-yard\\\/\",\"name\":\"leogistics e Quuppa automatizzano la gestione del yard - Loginfo24\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#website\"},\"datePublished\":\"2021-08-02T16:27:51+00:00\",\"dateModified\":\"2025-12-15T12:13:53+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2021\\\/08\\\/02\\\/leogistics-e-quuppa-automatizzano-la-gestione-del-yard\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/it\\\/2021\\\/08\\\/02\\\/leogistics-e-quuppa-automatizzano-la-gestione-del-yard\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2021\\\/08\\\/02\\\/leogistics-e-quuppa-automatizzano-la-gestione-del-yard\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"leogistics e Quuppa automatizzano la gestione del yard\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/\",\"name\":\"Loginfo24\",\"description\":\"Loginfo24 \u00e8 la piattaforma dedicata alla logistica e alle catene di fornitura con informazioni disponibili 24 ore su 24.\",\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#organization\",\"name\":\"Logismedia Group AG\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"width\":938,\"height\":351,\"caption\":\"Logismedia Group AG\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/people\\\/Loginfo24\\\/100057360583332\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/lofinfo24\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"leogistics e Quuppa automatizzano la gestione del yard - Loginfo24","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/loginfo24.com\/it\/2021\/08\/02\/leogistics-e-quuppa-automatizzano-la-gestione-del-yard\/","og_locale":"it_IT","og_type":"article","og_title":"leogistics e Quuppa automatizzano la gestione del yard - Loginfo24","og_description":"La leogistics GmbH, fornitore leader nella gestione digitale e automatizzata degli yard, sviluppa con myleo \/ yard una piattaforma di gestione degli yard altamente innovativa. Grazie [\u2026]","og_url":"https:\/\/loginfo24.com\/it\/2021\/08\/02\/leogistics-e-quuppa-automatizzano-la-gestione-del-yard\/","og_site_name":"Loginfo24","article_publisher":"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","article_published_time":"2021-08-02T16:27:51+00:00","article_modified_time":"2025-12-15T12:13:53+00:00","twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"4 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/loginfo24.com\/it\/2021\/08\/02\/leogistics-e-quuppa-automatizzano-la-gestione-del-yard\/#article","isPartOf":{"@id":"https:\/\/loginfo24.com\/it\/2021\/08\/02\/leogistics-e-quuppa-automatizzano-la-gestione-del-yard\/"},"author":{"name":"","@id":""},"headline":"leogistics e Quuppa automatizzano la gestione del yard","datePublished":"2021-08-02T16:27:51+00:00","dateModified":"2025-12-15T12:13:53+00:00","mainEntityOfPage":{"@id":"https:\/\/loginfo24.com\/it\/2021\/08\/02\/leogistics-e-quuppa-automatizzano-la-gestione-del-yard\/"},"wordCount":767,"commentCount":0,"publisher":{"@id":"https:\/\/loginfo24.com\/it\/#organization"},"articleSection":["Categories","Forwarding &amp; Logistics","Intralogistics","Regions"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/loginfo24.com\/it\/2021\/08\/02\/leogistics-e-quuppa-automatizzano-la-gestione-del-yard\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/loginfo24.com\/it\/2021\/08\/02\/leogistics-e-quuppa-automatizzano-la-gestione-del-yard\/","url":"https:\/\/loginfo24.com\/it\/2021\/08\/02\/leogistics-e-quuppa-automatizzano-la-gestione-del-yard\/","name":"leogistics e Quuppa automatizzano la gestione del yard - Loginfo24","isPartOf":{"@id":"https:\/\/loginfo24.com\/it\/#website"},"datePublished":"2021-08-02T16:27:51+00:00","dateModified":"2025-12-15T12:13:53+00:00","breadcrumb":{"@id":"https:\/\/loginfo24.com\/it\/2021\/08\/02\/leogistics-e-quuppa-automatizzano-la-gestione-del-yard\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/loginfo24.com\/it\/2021\/08\/02\/leogistics-e-quuppa-automatizzano-la-gestione-del-yard\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/loginfo24.com\/it\/2021\/08\/02\/leogistics-e-quuppa-automatizzano-la-gestione-del-yard\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/loginfo24.com\/it\/"},{"@type":"ListItem","position":2,"name":"leogistics e Quuppa automatizzano la gestione del yard"}]},{"@type":"WebSite","@id":"https:\/\/loginfo24.com\/it\/#website","url":"https:\/\/loginfo24.com\/it\/","name":"Loginfo24","description":"Loginfo24 \u00e8 la piattaforma dedicata alla logistica e alle catene di fornitura con informazioni disponibili 24 ore su 24.","publisher":{"@id":"https:\/\/loginfo24.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/loginfo24.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/loginfo24.com\/it\/#organization","name":"Logismedia Group AG","url":"https:\/\/loginfo24.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/loginfo24.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","width":938,"height":351,"caption":"Logismedia Group AG"},"image":{"@id":"https:\/\/loginfo24.com\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","https:\/\/www.linkedin.com\/company\/lofinfo24\/"]}]}},"_links":{"self":[{"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/posts\/28210","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/comments?post=28210"}],"version-history":[{"count":1,"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/posts\/28210\/revisions"}],"predecessor-version":[{"id":50675,"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/posts\/28210\/revisions\/50675"}],"wp:attachment":[{"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/media?parent=28210"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/categories?post=28210"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/tags?post=28210"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}