{"id":28204,"date":"2021-08-02T18:14:33","date_gmt":"2021-08-02T16:14:33","guid":{"rendered":"https:\/\/blog.brand-architecture.at\/2021\/08\/02\/biek-accoglie-la-nuova-legge-sulla-guida-autonoma\/"},"modified":"2025-12-15T13:13:52","modified_gmt":"2025-12-15T12:13:52","slug":"biek-accoglie-la-nuova-legge-sulla-guida-autonoma","status":"publish","type":"post","link":"https:\/\/loginfo24.com\/it\/2021\/08\/02\/biek-accoglie-la-nuova-legge-sulla-guida-autonoma\/","title":{"rendered":"BIEK accoglie la nuova legge sulla guida autonoma"},"content":{"rendered":"<p>Il Bundesverband Paket und Expresslogistik (BIEK) accoglie con favore la nuova legge sulla guida autonoma, entrata in vigore la scorsa settimana. In futuro, i veicoli di consegna a guida autonoma potrebbero svolgere un ruolo importante nella consegna dei pacchi. Uno scenario: possono supportare i fattorini durante il loro percorso, ad esempio dirigendosi autonomamente verso zone di carico predefinite.<\/p>\n<p>(Berlino) &#8220;La legge rappresenta un buon punto di partenza per testare la tecnologia innovativa della guida autonoma in condizioni reali di traffico stradale&#8221;, spiega Marten Bosselmann, presidente del BIEK. &#8220;Inoltre, accogliamo con favore il fatto che nei casi d&#8217;uso previsti dalla legge non siano menzionati solo il trasporto pubblico e privato di persone, ma anche la logistica e il trasporto merci.&#8221;<\/p>\n<h5><strong>Ridurre i percorsi dei fattorini<\/strong><\/h5>\n<p>In futuro, i veicoli di consegna a guida autonoma potrebbero svolgere un ruolo importante nella consegna dei pacchi. Uno scenario: possono supportare i fattorini durante il loro percorso, ad esempio dirigendosi autonomamente verso zone di carico predefinite. In questo modo, da un lato si riducono i percorsi dei fattorini, dall&#8217;altro si elimina la ricerca di parcheggi. Grazie all&#8217;uso mirato di veicoli di consegna autonomi, il processo di consegna potrebbe diventare ancora pi\u00f9 efficiente in futuro - e la forza lavoro umana potrebbe concentrarsi ancora di pi\u00f9 sulla reale consegna dei pacchi. &#8220;Quando parliamo di un futuro con veicoli autonomi, \u00e8 fondamentale che, oltre alle normative legali sulla protezione dei dati e sulla responsabilit\u00e0, sia presente anche un&#8217;infrastruttura digitale adeguata. A medio e lungo termine, l&#8217;uso di veicoli autonomi o almeno semi-autonomi nella consegna dei pacchi \u00e8 assolutamente concepibile - a condizione che ci sia una connessione Internet mobile a banda larga disponibile in modo capillare e sicuro&#8221;, afferma Marten Bosselmann. Foto: \u00a9 BIEK\/Adobe Stock<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il Bundesverband Paket und Expresslogistik (BIEK) accoglie con favore la nuova legge sulla guida autonoma, entrata in vigore la scorsa settimana. In futuro, i veicoli di<span class=\"excerpt-hellip\"> [\u2026]<\/span><\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1557,1556,1561],"tags":[],"class_list":["post-28204","post","type-post","status-publish","format-standard","hentry","category-forwarding-logistics","category-intermodal-road","category-regions"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>BIEK accoglie la nuova legge sulla guida autonoma - Loginfo24<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/loginfo24.com\/it\/2021\/08\/02\/biek-accoglie-la-nuova-legge-sulla-guida-autonoma\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"BIEK accoglie la nuova legge sulla guida autonoma - Loginfo24\" \/>\n<meta property=\"og:description\" content=\"Il Bundesverband Paket und Expresslogistik (BIEK) accoglie con favore la nuova legge sulla guida autonoma, entrata in vigore la scorsa settimana. In futuro, i veicoli di [\u2026]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/loginfo24.com\/it\/2021\/08\/02\/biek-accoglie-la-nuova-legge-sulla-guida-autonoma\/\" \/>\n<meta property=\"og:site_name\" content=\"Loginfo24\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/\" \/>\n<meta property=\"article:published_time\" content=\"2021-08-02T16:14:33+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-12-15T12:13:52+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2021\\\/08\\\/02\\\/biek-accoglie-la-nuova-legge-sulla-guida-autonoma\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2021\\\/08\\\/02\\\/biek-accoglie-la-nuova-legge-sulla-guida-autonoma\\\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"BIEK accoglie la nuova legge sulla guida autonoma\",\"datePublished\":\"2021-08-02T16:14:33+00:00\",\"dateModified\":\"2025-12-15T12:13:52+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2021\\\/08\\\/02\\\/biek-accoglie-la-nuova-legge-sulla-guida-autonoma\\\/\"},\"wordCount\":299,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#organization\"},\"articleSection\":[\"Forwarding &amp; Logistics\",\"Intermodal \\\/ Road\",\"Regions\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/it\\\/2021\\\/08\\\/02\\\/biek-accoglie-la-nuova-legge-sulla-guida-autonoma\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2021\\\/08\\\/02\\\/biek-accoglie-la-nuova-legge-sulla-guida-autonoma\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2021\\\/08\\\/02\\\/biek-accoglie-la-nuova-legge-sulla-guida-autonoma\\\/\",\"name\":\"BIEK accoglie la nuova legge sulla guida autonoma - Loginfo24\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#website\"},\"datePublished\":\"2021-08-02T16:14:33+00:00\",\"dateModified\":\"2025-12-15T12:13:52+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2021\\\/08\\\/02\\\/biek-accoglie-la-nuova-legge-sulla-guida-autonoma\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/it\\\/2021\\\/08\\\/02\\\/biek-accoglie-la-nuova-legge-sulla-guida-autonoma\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2021\\\/08\\\/02\\\/biek-accoglie-la-nuova-legge-sulla-guida-autonoma\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"BIEK accoglie la nuova legge sulla guida autonoma\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/\",\"name\":\"Loginfo24\",\"description\":\"Loginfo24 \u00e8 la piattaforma dedicata alla logistica e alle catene di fornitura con informazioni disponibili 24 ore su 24.\",\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#organization\",\"name\":\"Logismedia Group AG\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"width\":938,\"height\":351,\"caption\":\"Logismedia Group AG\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/people\\\/Loginfo24\\\/100057360583332\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/lofinfo24\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"BIEK accoglie la nuova legge sulla guida autonoma - Loginfo24","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/loginfo24.com\/it\/2021\/08\/02\/biek-accoglie-la-nuova-legge-sulla-guida-autonoma\/","og_locale":"it_IT","og_type":"article","og_title":"BIEK accoglie la nuova legge sulla guida autonoma - Loginfo24","og_description":"Il Bundesverband Paket und Expresslogistik (BIEK) accoglie con favore la nuova legge sulla guida autonoma, entrata in vigore la scorsa settimana. In futuro, i veicoli di [\u2026]","og_url":"https:\/\/loginfo24.com\/it\/2021\/08\/02\/biek-accoglie-la-nuova-legge-sulla-guida-autonoma\/","og_site_name":"Loginfo24","article_publisher":"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","article_published_time":"2021-08-02T16:14:33+00:00","article_modified_time":"2025-12-15T12:13:52+00:00","twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/loginfo24.com\/it\/2021\/08\/02\/biek-accoglie-la-nuova-legge-sulla-guida-autonoma\/#article","isPartOf":{"@id":"https:\/\/loginfo24.com\/it\/2021\/08\/02\/biek-accoglie-la-nuova-legge-sulla-guida-autonoma\/"},"author":{"name":"","@id":""},"headline":"BIEK accoglie la nuova legge sulla guida autonoma","datePublished":"2021-08-02T16:14:33+00:00","dateModified":"2025-12-15T12:13:52+00:00","mainEntityOfPage":{"@id":"https:\/\/loginfo24.com\/it\/2021\/08\/02\/biek-accoglie-la-nuova-legge-sulla-guida-autonoma\/"},"wordCount":299,"commentCount":0,"publisher":{"@id":"https:\/\/loginfo24.com\/it\/#organization"},"articleSection":["Forwarding &amp; Logistics","Intermodal \/ Road","Regions"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/loginfo24.com\/it\/2021\/08\/02\/biek-accoglie-la-nuova-legge-sulla-guida-autonoma\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/loginfo24.com\/it\/2021\/08\/02\/biek-accoglie-la-nuova-legge-sulla-guida-autonoma\/","url":"https:\/\/loginfo24.com\/it\/2021\/08\/02\/biek-accoglie-la-nuova-legge-sulla-guida-autonoma\/","name":"BIEK accoglie la nuova legge sulla guida autonoma - Loginfo24","isPartOf":{"@id":"https:\/\/loginfo24.com\/it\/#website"},"datePublished":"2021-08-02T16:14:33+00:00","dateModified":"2025-12-15T12:13:52+00:00","breadcrumb":{"@id":"https:\/\/loginfo24.com\/it\/2021\/08\/02\/biek-accoglie-la-nuova-legge-sulla-guida-autonoma\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/loginfo24.com\/it\/2021\/08\/02\/biek-accoglie-la-nuova-legge-sulla-guida-autonoma\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/loginfo24.com\/it\/2021\/08\/02\/biek-accoglie-la-nuova-legge-sulla-guida-autonoma\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/loginfo24.com\/it\/"},{"@type":"ListItem","position":2,"name":"BIEK accoglie la nuova legge sulla guida autonoma"}]},{"@type":"WebSite","@id":"https:\/\/loginfo24.com\/it\/#website","url":"https:\/\/loginfo24.com\/it\/","name":"Loginfo24","description":"Loginfo24 \u00e8 la piattaforma dedicata alla logistica e alle catene di fornitura con informazioni disponibili 24 ore su 24.","publisher":{"@id":"https:\/\/loginfo24.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/loginfo24.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/loginfo24.com\/it\/#organization","name":"Logismedia Group AG","url":"https:\/\/loginfo24.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/loginfo24.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","width":938,"height":351,"caption":"Logismedia Group AG"},"image":{"@id":"https:\/\/loginfo24.com\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","https:\/\/www.linkedin.com\/company\/lofinfo24\/"]}]}},"_links":{"self":[{"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/posts\/28204","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/comments?post=28204"}],"version-history":[{"count":1,"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/posts\/28204\/revisions"}],"predecessor-version":[{"id":50663,"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/posts\/28204\/revisions\/50663"}],"wp:attachment":[{"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/media?parent=28204"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/categories?post=28204"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/tags?post=28204"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}