{"id":28168,"date":"2021-07-30T19:40:37","date_gmt":"2021-07-30T17:40:37","guid":{"rendered":"https:\/\/blog.brand-architecture.at\/2021\/07\/30\/logwin-logistics-registra-un-notevole-aumento-nel-primo-semestre-del-2021\/"},"modified":"2025-12-15T13:13:41","modified_gmt":"2025-12-15T12:13:41","slug":"logwin-logistics-registra-un-notevole-aumento-nel-primo-semestre-del-2021","status":"publish","type":"post","link":"https:\/\/loginfo24.com\/it\/2021\/07\/30\/logwin-logistics-registra-un-notevole-aumento-nel-primo-semestre-del-2021\/","title":{"rendered":"Logwin Logistics registra un notevole aumento nel primo semestre del 2021"},"content":{"rendered":"<p><p>Il gruppo Logwin ha registrato nei primi sei mesi dell&#8217;anno un fatturato di 771,1 milioni di euro, superiore del 43,4% rispetto al fatturato dell&#8217;anno precedente di 537,7 milioni di euro. Questo sviluppo \u00e8 stato ottenuto grazie a un volume significativamente aumentato nel trasporto aereo e marittimo, nonch\u00e9 all&#8217;aumento delle tariffe rispetto allo stesso periodo dell&#8217;anno precedente nel trasporto marittimo.<\/p>\n<p>(Grevenmacher) Sulla base del forte aumento del fatturato, il gruppo Logwin \u00e8 riuscito, nonostante la situazione di capacit\u00e0 molto tesa durante tutto il primo semestre del 2021 e le continue pressioni dovute alla pandemia di Covid-19, a migliorare significativamente il proprio risultato operativo (EBITA) e il margine operativo al 4,7% (2020: 3,4%).<\/p>\n<p>Il risultato operativo (EBITA) del gruppo Logwin \u00e8 aumentato nel primo semestre del 2021 da 18,2 milioni di euro nello stesso periodo dell&#8217;anno precedente a 36,6 milioni di euro. Nel settore Air + Ocean, il risultato operativo \u00e8 aumentato di 18,8 milioni di euro a 38,7 milioni di euro (2020: 19,9 milioni di euro). Anche nel settore Solutions si \u00e8 registrato un aumento del risultato da 1,8 milioni di euro a 3,8 milioni di euro. Nel settore Solutions, il miglioramento \u00e8 stato ottenuto nonostante le continue pressioni sulle attivit\u00e0 nel settore retail a causa delle misure di contenimento della pandemia. Il risultato del periodo \u00e8 stato di 27,7 milioni di euro, molto superiore rispetto all&#8217;anno precedente (12,6 milioni di euro) grazie all&#8217;ottima evoluzione del risultato operativo.<\/p>\n<h5><strong>Previsione per il 2021 adeguata<\/strong><\/h5>\n<p>Nei primi due trimestri dell&#8217;anno in corso, il gruppo Logwin ha registrato un free cash flow di 13,7 milioni di euro (2020: -16,1 milioni di euro). La liquidit\u00e0 netta ammontava al 30 giugno 2021 a 86,5 milioni di euro, superiore rispetto al livello di fine anno precedente (2020: 77,5 milioni di euro).<\/p>\n<p>Rispetto alle informazioni contenute nel rapporto finanziario annuale 2020, il gruppo Logwin ha adeguato la previsione per lo sviluppo del fatturato e del risultato 2021 con il comunicato Ad Hoc del 23 luglio 2021, a causa dello sviluppo commerciale significativamente superiore alle aspettative nel primo semestre del 2021. Sulla base degli sviluppi del primo semestre, il gruppo Logwin prevede ora una crescita significativa del fatturato a circa 1,5 miliardi di euro. L&#8217;entit\u00e0 dell&#8217;aumento del fatturato dipende ancora in modo sostanziale dall&#8217;ulteriore evoluzione delle tariffe di trasporto e dei volumi.<\/p>\n<h5><strong>Settore Air + Ocean registra un notevole aumento<\/strong><\/h5>\n<p>Il settore Air + Ocean superer\u00e0 significativamente il livello dell&#8217;anno precedente, mentre nel settore Solutions si prevede un leggero aumento del fatturato. Il risultato operativo (EBITA) del gruppo Logwin aumenter\u00e0 anch&#8217;esso in modo significativo rispetto all&#8217;anno precedente, e si prevede che si attesti intorno ai 65 milioni di euro. Anche il risultato del periodo dovrebbe aumentare significativamente sulla base dell&#8217;attesa evoluzione del risultato operativo (EBITA).<\/p>\n<p>La previsione rimane comunque soggetta a una forte incertezza a causa dello sviluppo particolare del mercato e dell&#8217;ambiente competitivo e delle possibili conseguenze delle misure di contenimento della pandemia a livello globale.<\/p>\n<p>Le suddette grandezze di controllo centrali (KPI) fanno parte del sistema di indicatori utilizzato nel gruppo Logwin e vengono spiegate e definite nella sezione &#8220;Gestione aziendale finanziaria&#8221; della relazione di gestione del gruppo nel rapporto finanziario annuale 2020, in conformit\u00e0 con le linee guida per indicatori di performance alternativi dell&#8217;Autorit\u00e0 europea degli strumenti finanziari e dei mercati (ESMA) del 5 ottobre 2015.<\/p>\n<p>Foto: \u00a9 Logwin<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il gruppo Logwin ha registrato nei primi sei mesi dell&#8217;anno un fatturato di 771,1 milioni di euro, superiore del 43,4% rispetto al fatturato dell&#8217;anno precedente di<span class=\"excerpt-hellip\"> [\u2026]<\/span><\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1557,1560,1561],"tags":[],"class_list":["post-28168","post","type-post","status-publish","format-standard","hentry","category-forwarding-logistics","category-intralogistics","category-regions"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Logwin Logistics registra un notevole aumento nel primo semestre del 2021 - Loginfo24<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/loginfo24.com\/it\/2021\/07\/30\/logwin-logistics-registra-un-notevole-aumento-nel-primo-semestre-del-2021\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Logwin Logistics registra un notevole aumento nel primo semestre del 2021 - Loginfo24\" \/>\n<meta property=\"og:description\" content=\"Il gruppo Logwin ha registrato nei primi sei mesi dell&#8217;anno un fatturato di 771,1 milioni di euro, superiore del 43,4% rispetto al fatturato dell&#8217;anno precedente di [\u2026]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/loginfo24.com\/it\/2021\/07\/30\/logwin-logistics-registra-un-notevole-aumento-nel-primo-semestre-del-2021\/\" \/>\n<meta property=\"og:site_name\" content=\"Loginfo24\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/\" \/>\n<meta property=\"article:published_time\" content=\"2021-07-30T17:40:37+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-12-15T12:13:41+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2021\\\/07\\\/30\\\/logwin-logistics-registra-un-notevole-aumento-nel-primo-semestre-del-2021\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2021\\\/07\\\/30\\\/logwin-logistics-registra-un-notevole-aumento-nel-primo-semestre-del-2021\\\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Logwin Logistics registra un notevole aumento nel primo semestre del 2021\",\"datePublished\":\"2021-07-30T17:40:37+00:00\",\"dateModified\":\"2025-12-15T12:13:41+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2021\\\/07\\\/30\\\/logwin-logistics-registra-un-notevole-aumento-nel-primo-semestre-del-2021\\\/\"},\"wordCount\":533,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#organization\"},\"articleSection\":[\"Forwarding &amp; Logistics\",\"Intralogistics\",\"Regions\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/it\\\/2021\\\/07\\\/30\\\/logwin-logistics-registra-un-notevole-aumento-nel-primo-semestre-del-2021\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2021\\\/07\\\/30\\\/logwin-logistics-registra-un-notevole-aumento-nel-primo-semestre-del-2021\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2021\\\/07\\\/30\\\/logwin-logistics-registra-un-notevole-aumento-nel-primo-semestre-del-2021\\\/\",\"name\":\"Logwin Logistics registra un notevole aumento nel primo semestre del 2021 - Loginfo24\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#website\"},\"datePublished\":\"2021-07-30T17:40:37+00:00\",\"dateModified\":\"2025-12-15T12:13:41+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2021\\\/07\\\/30\\\/logwin-logistics-registra-un-notevole-aumento-nel-primo-semestre-del-2021\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/it\\\/2021\\\/07\\\/30\\\/logwin-logistics-registra-un-notevole-aumento-nel-primo-semestre-del-2021\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2021\\\/07\\\/30\\\/logwin-logistics-registra-un-notevole-aumento-nel-primo-semestre-del-2021\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Logwin Logistics registra un notevole aumento nel primo semestre del 2021\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/\",\"name\":\"Loginfo24\",\"description\":\"Loginfo24 \u00e8 la piattaforma dedicata alla logistica e alle catene di fornitura con informazioni disponibili 24 ore su 24.\",\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#organization\",\"name\":\"Logismedia Group AG\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"width\":938,\"height\":351,\"caption\":\"Logismedia Group AG\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/people\\\/Loginfo24\\\/100057360583332\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/lofinfo24\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Logwin Logistics registra un notevole aumento nel primo semestre del 2021 - Loginfo24","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/loginfo24.com\/it\/2021\/07\/30\/logwin-logistics-registra-un-notevole-aumento-nel-primo-semestre-del-2021\/","og_locale":"it_IT","og_type":"article","og_title":"Logwin Logistics registra un notevole aumento nel primo semestre del 2021 - Loginfo24","og_description":"Il gruppo Logwin ha registrato nei primi sei mesi dell&#8217;anno un fatturato di 771,1 milioni di euro, superiore del 43,4% rispetto al fatturato dell&#8217;anno precedente di [\u2026]","og_url":"https:\/\/loginfo24.com\/it\/2021\/07\/30\/logwin-logistics-registra-un-notevole-aumento-nel-primo-semestre-del-2021\/","og_site_name":"Loginfo24","article_publisher":"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","article_published_time":"2021-07-30T17:40:37+00:00","article_modified_time":"2025-12-15T12:13:41+00:00","twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"3 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/loginfo24.com\/it\/2021\/07\/30\/logwin-logistics-registra-un-notevole-aumento-nel-primo-semestre-del-2021\/#article","isPartOf":{"@id":"https:\/\/loginfo24.com\/it\/2021\/07\/30\/logwin-logistics-registra-un-notevole-aumento-nel-primo-semestre-del-2021\/"},"author":{"name":"","@id":""},"headline":"Logwin Logistics registra un notevole aumento nel primo semestre del 2021","datePublished":"2021-07-30T17:40:37+00:00","dateModified":"2025-12-15T12:13:41+00:00","mainEntityOfPage":{"@id":"https:\/\/loginfo24.com\/it\/2021\/07\/30\/logwin-logistics-registra-un-notevole-aumento-nel-primo-semestre-del-2021\/"},"wordCount":533,"commentCount":0,"publisher":{"@id":"https:\/\/loginfo24.com\/it\/#organization"},"articleSection":["Forwarding &amp; Logistics","Intralogistics","Regions"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/loginfo24.com\/it\/2021\/07\/30\/logwin-logistics-registra-un-notevole-aumento-nel-primo-semestre-del-2021\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/loginfo24.com\/it\/2021\/07\/30\/logwin-logistics-registra-un-notevole-aumento-nel-primo-semestre-del-2021\/","url":"https:\/\/loginfo24.com\/it\/2021\/07\/30\/logwin-logistics-registra-un-notevole-aumento-nel-primo-semestre-del-2021\/","name":"Logwin Logistics registra un notevole aumento nel primo semestre del 2021 - Loginfo24","isPartOf":{"@id":"https:\/\/loginfo24.com\/it\/#website"},"datePublished":"2021-07-30T17:40:37+00:00","dateModified":"2025-12-15T12:13:41+00:00","breadcrumb":{"@id":"https:\/\/loginfo24.com\/it\/2021\/07\/30\/logwin-logistics-registra-un-notevole-aumento-nel-primo-semestre-del-2021\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/loginfo24.com\/it\/2021\/07\/30\/logwin-logistics-registra-un-notevole-aumento-nel-primo-semestre-del-2021\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/loginfo24.com\/it\/2021\/07\/30\/logwin-logistics-registra-un-notevole-aumento-nel-primo-semestre-del-2021\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/loginfo24.com\/it\/"},{"@type":"ListItem","position":2,"name":"Logwin Logistics registra un notevole aumento nel primo semestre del 2021"}]},{"@type":"WebSite","@id":"https:\/\/loginfo24.com\/it\/#website","url":"https:\/\/loginfo24.com\/it\/","name":"Loginfo24","description":"Loginfo24 \u00e8 la piattaforma dedicata alla logistica e alle catene di fornitura con informazioni disponibili 24 ore su 24.","publisher":{"@id":"https:\/\/loginfo24.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/loginfo24.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/loginfo24.com\/it\/#organization","name":"Logismedia Group AG","url":"https:\/\/loginfo24.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/loginfo24.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","width":938,"height":351,"caption":"Logismedia Group AG"},"image":{"@id":"https:\/\/loginfo24.com\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","https:\/\/www.linkedin.com\/company\/lofinfo24\/"]}]}},"_links":{"self":[{"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/posts\/28168","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/comments?post=28168"}],"version-history":[{"count":1,"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/posts\/28168\/revisions"}],"predecessor-version":[{"id":50591,"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/posts\/28168\/revisions\/50591"}],"wp:attachment":[{"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/media?parent=28168"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/categories?post=28168"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/tags?post=28168"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}