{"id":27545,"date":"2021-07-07T16:01:30","date_gmt":"2021-07-07T14:01:30","guid":{"rendered":"https:\/\/blog.brand-architecture.at\/2021\/07\/07\/sebastian-betz-diventa-secondo-amministratore-delegato-di-lip-invest\/"},"modified":"2025-12-15T13:10:33","modified_gmt":"2025-12-15T12:10:33","slug":"sebastian-betz-diventa-secondo-amministratore-delegato-di-lip-invest","status":"publish","type":"post","link":"https:\/\/loginfo24.com\/it\/2021\/07\/07\/sebastian-betz-diventa-secondo-amministratore-delegato-di-lip-invest\/","title":{"rendered":"Sebastian Betz diventa secondo amministratore delegato di LIP Invest"},"content":{"rendered":"<p>LIP Invest, principale societ\u00e0 di investimento nella classe di attivo immobili logistici in Germania, amplia la sua direzione a causa della sua forte crescita. Dal 1\u00b0 luglio 2021, Sebastian Betz (33 anni) \u00e8 il secondo amministratore delegato della societ\u00e0 di investimento di Monaco LIP, accanto al fondatore Bodo Hollung (61 anni). Betz continuer\u00e0 a guidare operativamente la gestione dei fondi e del portafoglio e sar\u00e0 anche responsabile della gestione degli asset.<\/p>\n<p>(Monaco) Hollung continuer\u00e0 a occuparsi delle aree strategia e sviluppo aziendale, nonch\u00e9 comunicazione, e gestir\u00e0 operativamente l&#8217;acquisizione. Hollung e Betz collaborano con successo nella gestione di fondi immobiliari logistici istituzionali da oltre otto anni. Presso LIP, che hanno fondato insieme nel 2017, Sebastian Betz \u00e8 gi\u00e0 dal 2019 un procuratore nella direzione aziendale. &#8220;Con la promozione di Sebastian a amministratore delegato, stiamo orientando il nostro azienda in forte crescita \u2013 gi\u00e0 con un portafoglio immobiliare logistico di oltre 1,2 miliardi di euro \u2013 verso il futuro e distribuendo la responsabilit\u00e0 su pi\u00f9 spalle&#8221;, spiega Bodo Hollung, fondatore e amministratore delegato di LIP Invest, aggiungendo: &#8220;Lavoro a stretto contatto con Sebastian da tanti anni, in modo fidato e collaborativo, ora persino alla sesta emissione di fondi. Pertanto, sono ancora pi\u00f9 felice di poter plasmare il futuro di LIP insieme a lui in una posizione di leadership.&#8221;<\/p>\n<h5><strong>Gi\u00e0 collaborato in precedenza<\/strong><\/h5>\n<p>Sebastian Betz ha studiato geografia e economia aziendale e ha conseguito nel 2012 all&#8217;Universit\u00e0 di Treviri un Master of Arts in geografia applicata con specializzazione in economia immobiliare. Attualmente, Betz sta ancora completando uno studio part-time presso l&#8217;IRE|BS, che terminer\u00e0 con successo nel 2021 con il titolo di economista immobiliare (IRE|BS). Dopo esperienze professionali presso Colliers e Realogis, Betz ha fondato insieme a Hollung RLI Investors \u2013 recentemente venduta a DIC \u2013 come societ\u00e0 di investimento, prima di avviare entrambi LIP. <\/p>\n<h5>LIP con un&#8217;attivit\u00e0 di fondi in forte crescita<\/h5>\n<p> L&#8217;attuale ampliamento della direzione era una conseguenza logica della forte crescita dell&#8217;attivit\u00e0 di fondi. Dal 2017, LIP ha acquisito 43 immobili con un volume di investimento di oltre 1,2 miliardi di euro e oltre 880.000 metri quadrati di superficie affittabile con tre fondi immobiliari logistici. Nel frattempo, oltre 50 investitori istituzionali provenienti da assicurazioni, fondi pensione, casse di previdenza, banche, fondazioni e grandi family office hanno partecipato ai fondi LIP. &#8220;L&#8217;interesse per i nostri fondi e immobili logistici \u00e8 inarrestabile, quindi presto lanceremo un ulteriore fondo con una strategia simile. La nostra disponibilit\u00e0 di prodotto rimane molto stabile e il nostro pipeline \u00e8 ben riempito. Pertanto, pianifichiamo investimenti di oltre 200 milioni di euro nel secondo semestre&#8221;, riporta Hollung.<\/p>\n<h5><strong>Su LIP<\/strong><\/h5>\n<p>LIP Invest \u00e8 la principale societ\u00e0 di investimento nella classe di attivo immobili logistici in Germania. L&#8217;azienda \u00e8 stata fondata nel 2017 da manager esperti ed esperti del settore. Attualmente, LIP gestisce immobili logistici con una superficie totale affittabile di circa 880.000 metri quadrati e un volume di circa 1,2 miliardi di euro. Con tre fondi finora, LIP offre agli investitori istituzionali accesso alla classe di attivo attraente degli immobili logistici.<\/p>\n<p class=\"Default\"><span style=\"font-family: 'Cambria',serif\">Foto: \u00a9 LIP<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>LIP Invest, principale societ\u00e0 di investimento nella classe di attivo immobili logistici in Germania, amplia la sua direzione a causa della sua forte crescita. Dal 1\u00b0<span class=\"excerpt-hellip\"> [\u2026]<\/span><\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1557,1561],"tags":[],"class_list":["post-27545","post","type-post","status-publish","format-standard","hentry","category-forwarding-logistics","category-regions"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Sebastian Betz diventa secondo amministratore delegato di LIP Invest - Loginfo24<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/loginfo24.com\/it\/2021\/07\/07\/sebastian-betz-diventa-secondo-amministratore-delegato-di-lip-invest\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Sebastian Betz diventa secondo amministratore delegato di LIP Invest - Loginfo24\" \/>\n<meta property=\"og:description\" content=\"LIP Invest, principale societ\u00e0 di investimento nella classe di attivo immobili logistici in Germania, amplia la sua direzione a causa della sua forte crescita. Dal 1\u00b0 [\u2026]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/loginfo24.com\/it\/2021\/07\/07\/sebastian-betz-diventa-secondo-amministratore-delegato-di-lip-invest\/\" \/>\n<meta property=\"og:site_name\" content=\"Loginfo24\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/\" \/>\n<meta property=\"article:published_time\" content=\"2021-07-07T14:01:30+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-12-15T12:10:33+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2021\\\/07\\\/07\\\/sebastian-betz-diventa-secondo-amministratore-delegato-di-lip-invest\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2021\\\/07\\\/07\\\/sebastian-betz-diventa-secondo-amministratore-delegato-di-lip-invest\\\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Sebastian Betz diventa secondo amministratore delegato di LIP Invest\",\"datePublished\":\"2021-07-07T14:01:30+00:00\",\"dateModified\":\"2025-12-15T12:10:33+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2021\\\/07\\\/07\\\/sebastian-betz-diventa-secondo-amministratore-delegato-di-lip-invest\\\/\"},\"wordCount\":494,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#organization\"},\"articleSection\":[\"Forwarding &amp; Logistics\",\"Regions\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/it\\\/2021\\\/07\\\/07\\\/sebastian-betz-diventa-secondo-amministratore-delegato-di-lip-invest\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2021\\\/07\\\/07\\\/sebastian-betz-diventa-secondo-amministratore-delegato-di-lip-invest\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2021\\\/07\\\/07\\\/sebastian-betz-diventa-secondo-amministratore-delegato-di-lip-invest\\\/\",\"name\":\"Sebastian Betz diventa secondo amministratore delegato di LIP Invest - Loginfo24\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#website\"},\"datePublished\":\"2021-07-07T14:01:30+00:00\",\"dateModified\":\"2025-12-15T12:10:33+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2021\\\/07\\\/07\\\/sebastian-betz-diventa-secondo-amministratore-delegato-di-lip-invest\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/it\\\/2021\\\/07\\\/07\\\/sebastian-betz-diventa-secondo-amministratore-delegato-di-lip-invest\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2021\\\/07\\\/07\\\/sebastian-betz-diventa-secondo-amministratore-delegato-di-lip-invest\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Sebastian Betz diventa secondo amministratore delegato di LIP Invest\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/\",\"name\":\"Loginfo24\",\"description\":\"Loginfo24 \u00e8 la piattaforma dedicata alla logistica e alle catene di fornitura con informazioni disponibili 24 ore su 24.\",\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#organization\",\"name\":\"Logismedia Group AG\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"width\":938,\"height\":351,\"caption\":\"Logismedia Group AG\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/people\\\/Loginfo24\\\/100057360583332\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/lofinfo24\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Sebastian Betz diventa secondo amministratore delegato di LIP Invest - Loginfo24","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/loginfo24.com\/it\/2021\/07\/07\/sebastian-betz-diventa-secondo-amministratore-delegato-di-lip-invest\/","og_locale":"it_IT","og_type":"article","og_title":"Sebastian Betz diventa secondo amministratore delegato di LIP Invest - Loginfo24","og_description":"LIP Invest, principale societ\u00e0 di investimento nella classe di attivo immobili logistici in Germania, amplia la sua direzione a causa della sua forte crescita. Dal 1\u00b0 [\u2026]","og_url":"https:\/\/loginfo24.com\/it\/2021\/07\/07\/sebastian-betz-diventa-secondo-amministratore-delegato-di-lip-invest\/","og_site_name":"Loginfo24","article_publisher":"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","article_published_time":"2021-07-07T14:01:30+00:00","article_modified_time":"2025-12-15T12:10:33+00:00","twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"2 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/loginfo24.com\/it\/2021\/07\/07\/sebastian-betz-diventa-secondo-amministratore-delegato-di-lip-invest\/#article","isPartOf":{"@id":"https:\/\/loginfo24.com\/it\/2021\/07\/07\/sebastian-betz-diventa-secondo-amministratore-delegato-di-lip-invest\/"},"author":{"name":"","@id":""},"headline":"Sebastian Betz diventa secondo amministratore delegato di LIP Invest","datePublished":"2021-07-07T14:01:30+00:00","dateModified":"2025-12-15T12:10:33+00:00","mainEntityOfPage":{"@id":"https:\/\/loginfo24.com\/it\/2021\/07\/07\/sebastian-betz-diventa-secondo-amministratore-delegato-di-lip-invest\/"},"wordCount":494,"commentCount":0,"publisher":{"@id":"https:\/\/loginfo24.com\/it\/#organization"},"articleSection":["Forwarding &amp; Logistics","Regions"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/loginfo24.com\/it\/2021\/07\/07\/sebastian-betz-diventa-secondo-amministratore-delegato-di-lip-invest\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/loginfo24.com\/it\/2021\/07\/07\/sebastian-betz-diventa-secondo-amministratore-delegato-di-lip-invest\/","url":"https:\/\/loginfo24.com\/it\/2021\/07\/07\/sebastian-betz-diventa-secondo-amministratore-delegato-di-lip-invest\/","name":"Sebastian Betz diventa secondo amministratore delegato di LIP Invest - Loginfo24","isPartOf":{"@id":"https:\/\/loginfo24.com\/it\/#website"},"datePublished":"2021-07-07T14:01:30+00:00","dateModified":"2025-12-15T12:10:33+00:00","breadcrumb":{"@id":"https:\/\/loginfo24.com\/it\/2021\/07\/07\/sebastian-betz-diventa-secondo-amministratore-delegato-di-lip-invest\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/loginfo24.com\/it\/2021\/07\/07\/sebastian-betz-diventa-secondo-amministratore-delegato-di-lip-invest\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/loginfo24.com\/it\/2021\/07\/07\/sebastian-betz-diventa-secondo-amministratore-delegato-di-lip-invest\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/loginfo24.com\/it\/"},{"@type":"ListItem","position":2,"name":"Sebastian Betz diventa secondo amministratore delegato di LIP Invest"}]},{"@type":"WebSite","@id":"https:\/\/loginfo24.com\/it\/#website","url":"https:\/\/loginfo24.com\/it\/","name":"Loginfo24","description":"Loginfo24 \u00e8 la piattaforma dedicata alla logistica e alle catene di fornitura con informazioni disponibili 24 ore su 24.","publisher":{"@id":"https:\/\/loginfo24.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/loginfo24.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/loginfo24.com\/it\/#organization","name":"Logismedia Group AG","url":"https:\/\/loginfo24.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/loginfo24.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","width":938,"height":351,"caption":"Logismedia Group AG"},"image":{"@id":"https:\/\/loginfo24.com\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","https:\/\/www.linkedin.com\/company\/lofinfo24\/"]}]}},"_links":{"self":[{"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/posts\/27545","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/comments?post=27545"}],"version-history":[{"count":1,"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/posts\/27545\/revisions"}],"predecessor-version":[{"id":49350,"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/posts\/27545\/revisions\/49350"}],"wp:attachment":[{"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/media?parent=27545"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/categories?post=27545"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/tags?post=27545"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}