{"id":27102,"date":"2021-06-18T12:28:07","date_gmt":"2021-06-18T10:28:07","guid":{"rendered":"https:\/\/blog.brand-architecture.at\/2021\/06\/18\/carsten-norland-succede-a-soren-poulsgaard-jensen-come-ceo-di-scandlines\/"},"modified":"2025-12-15T13:08:21","modified_gmt":"2025-12-15T12:08:21","slug":"carsten-norland-succede-a-soren-poulsgaard-jensen-come-ceo-di-scandlines","status":"publish","type":"post","link":"https:\/\/loginfo24.com\/it\/2021\/06\/18\/carsten-norland-succede-a-soren-poulsgaard-jensen-come-ceo-di-scandlines\/","title":{"rendered":"Carsten N\u00f8rland succede a S\u00f8ren Poulsgaard Jensen come CEO di Scandlines"},"content":{"rendered":"<p>Dopo oltre dieci anni di successo alla guida di Scandlines, S\u00f8ren Poulsgaard Jensen ha informato il consiglio di sorveglianza che \u00e8 giunto il momento di passare il testimone. Il consiglio di sorveglianza ha nominato Carsten N\u00f8rland, Senior Vice President International presso la birreria Royal Unibrew, come successore di S\u00f8ren Poulsgaard Jensen come CEO.<\/p>\n<p><span style=\"font-family: 'Cambria',serif\">(Copenaghen\/Hamburgo) \u201eS\u00f8ren Poulsgaard Jensen ha svolto un lavoro eccellente e ha posizionato Scandlines come fornitore verde e competitivo di infrastrutture critiche, che collega Europa e Scandinavia, in modo molto forte per il futuro. Carsten N\u00f8rland porter\u00e0 le giuste competenze e esperienze economiche e internazionali per continuare i buoni risultati nei prossimi anni fino e, non da ultimo, dopo l&#8217;apertura del collegamento fisso del Fehmarnbelt\u201c, ha dichiarato Vagn S\u00f8rensen, presidente del consiglio di sorveglianza di Scandlines.<\/span><\/p>\n<p><span style=\"font-family: 'Cambria',serif\">Carsten N\u00f8rland ha 52 anni e ha conseguito una laurea in economia presso l&#8217;Universit\u00e0 di Copenaghen (Copenhagen Business School). Prima dei suoi sette anni in Royal Unibrew, ha ricoperto posizioni dirigenziali ed \u00e8 stato responsabile delle attivit\u00e0 internazionali presso Copenhagen Airports, Fl\u00fcgger e Masterfoods\/MARS Inc.<\/span><\/p>\n<p><span style=\"font-family: 'Cambria',serif\">Carsten N\u00f8rland assumer\u00e0 il suo incarico il 1\u00b0 settembre 2021. Fino ad allora, S\u00f8ren Poulsgaard Jensen continuer\u00e0 il suo lavoro per Scandlines e contribuir\u00e0 anche a garantire una transizione fluida per il nuovo CEO entro met\u00e0 settembre.<\/span><\/p>\n<p><span style=\"font-family: 'Cambria',serif\">Foto: \u00a9 Scandlines<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dopo oltre dieci anni di successo alla guida di Scandlines, S\u00f8ren Poulsgaard Jensen ha informato il consiglio di sorveglianza che \u00e8 giunto il momento di passare<span class=\"excerpt-hellip\"> [\u2026]<\/span><\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1557,1561,1559],"tags":[],"class_list":["post-27102","post","type-post","status-publish","format-standard","hentry","category-forwarding-logistics","category-regions","category-shipping-ports"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Carsten N\u00f8rland succede a S\u00f8ren Poulsgaard Jensen come CEO di Scandlines - Loginfo24<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/loginfo24.com\/it\/2021\/06\/18\/carsten-norland-succede-a-soren-poulsgaard-jensen-come-ceo-di-scandlines\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Carsten N\u00f8rland succede a S\u00f8ren Poulsgaard Jensen come CEO di Scandlines - Loginfo24\" \/>\n<meta property=\"og:description\" content=\"Dopo oltre dieci anni di successo alla guida di Scandlines, S\u00f8ren Poulsgaard Jensen ha informato il consiglio di sorveglianza che \u00e8 giunto il momento di passare [\u2026]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/loginfo24.com\/it\/2021\/06\/18\/carsten-norland-succede-a-soren-poulsgaard-jensen-come-ceo-di-scandlines\/\" \/>\n<meta property=\"og:site_name\" content=\"Loginfo24\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/\" \/>\n<meta property=\"article:published_time\" content=\"2021-06-18T10:28:07+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-12-15T12:08:21+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2021\\\/06\\\/18\\\/carsten-norland-succede-a-soren-poulsgaard-jensen-come-ceo-di-scandlines\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2021\\\/06\\\/18\\\/carsten-norland-succede-a-soren-poulsgaard-jensen-come-ceo-di-scandlines\\\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Carsten N\u00f8rland succede a S\u00f8ren Poulsgaard Jensen come CEO di Scandlines\",\"datePublished\":\"2021-06-18T10:28:07+00:00\",\"dateModified\":\"2025-12-15T12:08:21+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2021\\\/06\\\/18\\\/carsten-norland-succede-a-soren-poulsgaard-jensen-come-ceo-di-scandlines\\\/\"},\"wordCount\":234,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#organization\"},\"articleSection\":[\"Forwarding &amp; Logistics\",\"Regions\",\"Shipping &amp; Ports\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/it\\\/2021\\\/06\\\/18\\\/carsten-norland-succede-a-soren-poulsgaard-jensen-come-ceo-di-scandlines\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2021\\\/06\\\/18\\\/carsten-norland-succede-a-soren-poulsgaard-jensen-come-ceo-di-scandlines\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2021\\\/06\\\/18\\\/carsten-norland-succede-a-soren-poulsgaard-jensen-come-ceo-di-scandlines\\\/\",\"name\":\"Carsten N\u00f8rland succede a S\u00f8ren Poulsgaard Jensen come CEO di Scandlines - Loginfo24\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#website\"},\"datePublished\":\"2021-06-18T10:28:07+00:00\",\"dateModified\":\"2025-12-15T12:08:21+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2021\\\/06\\\/18\\\/carsten-norland-succede-a-soren-poulsgaard-jensen-come-ceo-di-scandlines\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/it\\\/2021\\\/06\\\/18\\\/carsten-norland-succede-a-soren-poulsgaard-jensen-come-ceo-di-scandlines\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2021\\\/06\\\/18\\\/carsten-norland-succede-a-soren-poulsgaard-jensen-come-ceo-di-scandlines\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Carsten N\u00f8rland succede a S\u00f8ren Poulsgaard Jensen come CEO di Scandlines\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/\",\"name\":\"Loginfo24\",\"description\":\"Loginfo24 \u00e8 la piattaforma dedicata alla logistica e alle catene di fornitura con informazioni disponibili 24 ore su 24.\",\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#organization\",\"name\":\"Logismedia Group AG\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"width\":938,\"height\":351,\"caption\":\"Logismedia Group AG\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/people\\\/Loginfo24\\\/100057360583332\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/lofinfo24\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Carsten N\u00f8rland succede a S\u00f8ren Poulsgaard Jensen come CEO di Scandlines - Loginfo24","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/loginfo24.com\/it\/2021\/06\/18\/carsten-norland-succede-a-soren-poulsgaard-jensen-come-ceo-di-scandlines\/","og_locale":"it_IT","og_type":"article","og_title":"Carsten N\u00f8rland succede a S\u00f8ren Poulsgaard Jensen come CEO di Scandlines - Loginfo24","og_description":"Dopo oltre dieci anni di successo alla guida di Scandlines, S\u00f8ren Poulsgaard Jensen ha informato il consiglio di sorveglianza che \u00e8 giunto il momento di passare [\u2026]","og_url":"https:\/\/loginfo24.com\/it\/2021\/06\/18\/carsten-norland-succede-a-soren-poulsgaard-jensen-come-ceo-di-scandlines\/","og_site_name":"Loginfo24","article_publisher":"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","article_published_time":"2021-06-18T10:28:07+00:00","article_modified_time":"2025-12-15T12:08:21+00:00","twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/loginfo24.com\/it\/2021\/06\/18\/carsten-norland-succede-a-soren-poulsgaard-jensen-come-ceo-di-scandlines\/#article","isPartOf":{"@id":"https:\/\/loginfo24.com\/it\/2021\/06\/18\/carsten-norland-succede-a-soren-poulsgaard-jensen-come-ceo-di-scandlines\/"},"author":{"name":"","@id":""},"headline":"Carsten N\u00f8rland succede a S\u00f8ren Poulsgaard Jensen come CEO di Scandlines","datePublished":"2021-06-18T10:28:07+00:00","dateModified":"2025-12-15T12:08:21+00:00","mainEntityOfPage":{"@id":"https:\/\/loginfo24.com\/it\/2021\/06\/18\/carsten-norland-succede-a-soren-poulsgaard-jensen-come-ceo-di-scandlines\/"},"wordCount":234,"commentCount":0,"publisher":{"@id":"https:\/\/loginfo24.com\/it\/#organization"},"articleSection":["Forwarding &amp; Logistics","Regions","Shipping &amp; Ports"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/loginfo24.com\/it\/2021\/06\/18\/carsten-norland-succede-a-soren-poulsgaard-jensen-come-ceo-di-scandlines\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/loginfo24.com\/it\/2021\/06\/18\/carsten-norland-succede-a-soren-poulsgaard-jensen-come-ceo-di-scandlines\/","url":"https:\/\/loginfo24.com\/it\/2021\/06\/18\/carsten-norland-succede-a-soren-poulsgaard-jensen-come-ceo-di-scandlines\/","name":"Carsten N\u00f8rland succede a S\u00f8ren Poulsgaard Jensen come CEO di Scandlines - Loginfo24","isPartOf":{"@id":"https:\/\/loginfo24.com\/it\/#website"},"datePublished":"2021-06-18T10:28:07+00:00","dateModified":"2025-12-15T12:08:21+00:00","breadcrumb":{"@id":"https:\/\/loginfo24.com\/it\/2021\/06\/18\/carsten-norland-succede-a-soren-poulsgaard-jensen-come-ceo-di-scandlines\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/loginfo24.com\/it\/2021\/06\/18\/carsten-norland-succede-a-soren-poulsgaard-jensen-come-ceo-di-scandlines\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/loginfo24.com\/it\/2021\/06\/18\/carsten-norland-succede-a-soren-poulsgaard-jensen-come-ceo-di-scandlines\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/loginfo24.com\/it\/"},{"@type":"ListItem","position":2,"name":"Carsten N\u00f8rland succede a S\u00f8ren Poulsgaard Jensen come CEO di Scandlines"}]},{"@type":"WebSite","@id":"https:\/\/loginfo24.com\/it\/#website","url":"https:\/\/loginfo24.com\/it\/","name":"Loginfo24","description":"Loginfo24 \u00e8 la piattaforma dedicata alla logistica e alle catene di fornitura con informazioni disponibili 24 ore su 24.","publisher":{"@id":"https:\/\/loginfo24.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/loginfo24.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/loginfo24.com\/it\/#organization","name":"Logismedia Group AG","url":"https:\/\/loginfo24.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/loginfo24.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","width":938,"height":351,"caption":"Logismedia Group AG"},"image":{"@id":"https:\/\/loginfo24.com\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","https:\/\/www.linkedin.com\/company\/lofinfo24\/"]}]}},"_links":{"self":[{"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/posts\/27102","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/comments?post=27102"}],"version-history":[{"count":1,"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/posts\/27102\/revisions"}],"predecessor-version":[{"id":48472,"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/posts\/27102\/revisions\/48472"}],"wp:attachment":[{"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/media?parent=27102"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/categories?post=27102"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/tags?post=27102"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}