{"id":26332,"date":"2022-01-07T15:03:41","date_gmt":"2022-01-07T14:03:41","guid":{"rendered":"https:\/\/blog.brand-architecture.at\/2022\/01\/07\/element-logic-nuovamente-certificato-come-datore-di-lavoro-attraente\/"},"modified":"2022-01-07T15:03:41","modified_gmt":"2022-01-07T14:03:41","slug":"element-logic-nuovamente-certificato-come-datore-di-lavoro-attraente","status":"publish","type":"post","link":"https:\/\/loginfo24.com\/it\/2022\/01\/07\/element-logic-nuovamente-certificato-come-datore-di-lavoro-attraente\/","title":{"rendered":"Element Logic nuovamente certificato come datore di lavoro attraente"},"content":{"rendered":"<h5><strong>L&#8217;istituto di ricerca e consulenza Great Place to Work\u00ae ha premiato il system integrator Element Logic per la seconda volta consecutiva in un processo di certificazione internazionale come datore di lavoro attraente. La certificazione si basa sul giudizio dei dipendenti e riconosce una leadership credibile e giusta.<\/strong><\/h5>\n<p>(Bad Friedrichshall) La promozione attiva dei dipendenti e una cultura aziendale caratterizzata da rispetto, fiducia, orgoglio e spirito di squadra sono le caratteristiche distintive dell&#8217;attrattiva del datore di lavoro di Element Logic. Ora, il distributore AutoStore di maggior successo al mondo del 2020 \u00e8 stato nuovamente certificato per la seconda volta consecutiva con il marchio di qualit\u00e0 secondo lo standard globale di Great Place to Work. Il riconoscimento si basa su un&#8217;indagine rappresentativa e anonima tra i dipendenti e costituisce la base per un branding del datore di lavoro autentico ed efficace. &#8220;Siamo molto orgogliosi di essere certificati per il secondo anno consecutivo sia internamente che esternamente dai nostri dipendenti e da Great Place to Work&#8221;, afferma Manfred W. Schleicher, amministratore delegato di Element Logic Germania. &#8220;Credibilit\u00e0, rispetto, equit\u00e0, orgoglio e comunit\u00e0 sono le cinque dimensioni che vengono misurate. Questa certificazione fornisce importanti indicazioni su quanto siamo riusciti come azienda a prenderci cura dei nostri dipendenti e della nostra cultura.&#8221;<\/p>\n<p>In effetti, il system integrator internazionale chiude il 2021 come un anno commerciale estremamente di successo. Sono stati aperti quattro nuovi mercati e il personale \u00e8 quasi raddoppiato, passando da 140 a 225 dipendenti. &#8220;I migliori posti di lavoro hanno in comune il fatto di riuscire a creare una cultura e una leadership basate sulla fiducia&#8221;, spiega Jannik Krohn Falck, CEO di Great Place to Work Germania, la certificazione. &#8220;Il loro focus strategico su tutti i dipendenti significa che sono stati in grado di affrontare il periodo difficile che stiamo attraversando e ora sono ben posizionati nella crescente competizione per i talenti. Congratulazioni a Element Logic per la certificazione per il secondo anno consecutivo.&#8221;<\/p>\n<h5><strong>Meglio posizionati in termini di turnover e assenteismo<\/strong><\/h5>\n<p>Diverse metriche aziendali dimostrano che i migliori datori di lavoro in Germania sono significativamente meglio posizionati rispetto alla media delle aziende in temi come turnover e assenteismo, ma anche in termini di successo economico e capacit\u00e0 di innovazione. I datori di lavoro premiati ricevono inoltre pi\u00f9 del doppio delle candidature rispetto alle aziende senza riconoscimento. &#8220;Ci impegniamo costantemente a offrire ai dipendenti in ogni sede del mondo un ambiente di lavoro in cui si lavora volentieri&#8221;, riassume Manfred Schleicher. &#8220;Il riconoscimento di Great Place to Work dimostra ancora una volta che Element Logic, con i suoi fantastici dipendenti, pu\u00f2 affrontare qualsiasi sfida. Insieme affrontiamo nuove sfide con un sorriso e dimostriamo che il lavoro di squadra pu\u00f2 realizzare ogni sogno.&#8221;<\/p>\n<p>Foto: \u00a9 Element Logic<\/p>\n","protected":false},"excerpt":{"rendered":"<p>L&#8217;istituto di ricerca e consulenza Great Place to Work\u00ae ha premiato il system integrator Element Logic per la seconda volta consecutiva in un processo di certificazione<span class=\"excerpt-hellip\"> [\u2026]<\/span><\/p>\n","protected":false},"author":0,"featured_media":11371,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1557,1560,1561],"tags":[],"class_list":["post-26332","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-forwarding-logistics","category-intralogistics","category-regions"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Element Logic nuovamente certificato come datore di lavoro attraente - Loginfo24<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/loginfo24.com\/it\/2022\/01\/07\/element-logic-nuovamente-certificato-come-datore-di-lavoro-attraente\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Element Logic nuovamente certificato come datore di lavoro attraente - Loginfo24\" \/>\n<meta property=\"og:description\" content=\"L&#8217;istituto di ricerca e consulenza Great Place to Work\u00ae ha premiato il system integrator Element Logic per la seconda volta consecutiva in un processo di certificazione [\u2026]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/loginfo24.com\/it\/2022\/01\/07\/element-logic-nuovamente-certificato-come-datore-di-lavoro-attraente\/\" \/>\n<meta property=\"og:site_name\" content=\"Loginfo24\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/\" \/>\n<meta property=\"article:published_time\" content=\"2022-01-07T14:03:41+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Element_Logic_7.1.22.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1209\" \/>\n\t<meta property=\"og:image:height\" content=\"731\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2022\\\/01\\\/07\\\/element-logic-nuovamente-certificato-come-datore-di-lavoro-attraente\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2022\\\/01\\\/07\\\/element-logic-nuovamente-certificato-come-datore-di-lavoro-attraente\\\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Element Logic nuovamente certificato come datore di lavoro attraente\",\"datePublished\":\"2022-01-07T14:03:41+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2022\\\/01\\\/07\\\/element-logic-nuovamente-certificato-come-datore-di-lavoro-attraente\\\/\"},\"wordCount\":458,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2022\\\/01\\\/07\\\/element-logic-nuovamente-certificato-come-datore-di-lavoro-attraente\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/Element_Logic_7.1.22.jpg\",\"articleSection\":[\"Forwarding &amp; Logistics\",\"Intralogistics\",\"Regions\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/it\\\/2022\\\/01\\\/07\\\/element-logic-nuovamente-certificato-come-datore-di-lavoro-attraente\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2022\\\/01\\\/07\\\/element-logic-nuovamente-certificato-come-datore-di-lavoro-attraente\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2022\\\/01\\\/07\\\/element-logic-nuovamente-certificato-come-datore-di-lavoro-attraente\\\/\",\"name\":\"Element Logic nuovamente certificato come datore di lavoro attraente - Loginfo24\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2022\\\/01\\\/07\\\/element-logic-nuovamente-certificato-come-datore-di-lavoro-attraente\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2022\\\/01\\\/07\\\/element-logic-nuovamente-certificato-come-datore-di-lavoro-attraente\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/Element_Logic_7.1.22.jpg\",\"datePublished\":\"2022-01-07T14:03:41+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2022\\\/01\\\/07\\\/element-logic-nuovamente-certificato-come-datore-di-lavoro-attraente\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/it\\\/2022\\\/01\\\/07\\\/element-logic-nuovamente-certificato-come-datore-di-lavoro-attraente\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2022\\\/01\\\/07\\\/element-logic-nuovamente-certificato-come-datore-di-lavoro-attraente\\\/#primaryimage\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/Element_Logic_7.1.22.jpg\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/Element_Logic_7.1.22.jpg\",\"width\":1209,\"height\":731},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2022\\\/01\\\/07\\\/element-logic-nuovamente-certificato-come-datore-di-lavoro-attraente\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Element Logic nuovamente certificato come datore di lavoro attraente\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/\",\"name\":\"Loginfo24\",\"description\":\"Loginfo24 \u00e8 la piattaforma dedicata alla logistica e alle catene di fornitura con informazioni disponibili 24 ore su 24.\",\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#organization\",\"name\":\"Logismedia Group AG\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"width\":938,\"height\":351,\"caption\":\"Logismedia Group AG\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/people\\\/Loginfo24\\\/100057360583332\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/lofinfo24\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Element Logic nuovamente certificato come datore di lavoro attraente - Loginfo24","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/loginfo24.com\/it\/2022\/01\/07\/element-logic-nuovamente-certificato-come-datore-di-lavoro-attraente\/","og_locale":"it_IT","og_type":"article","og_title":"Element Logic nuovamente certificato come datore di lavoro attraente - Loginfo24","og_description":"L&#8217;istituto di ricerca e consulenza Great Place to Work\u00ae ha premiato il system integrator Element Logic per la seconda volta consecutiva in un processo di certificazione [\u2026]","og_url":"https:\/\/loginfo24.com\/it\/2022\/01\/07\/element-logic-nuovamente-certificato-come-datore-di-lavoro-attraente\/","og_site_name":"Loginfo24","article_publisher":"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","article_published_time":"2022-01-07T14:03:41+00:00","og_image":[{"width":1209,"height":731,"url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Element_Logic_7.1.22.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"2 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/loginfo24.com\/it\/2022\/01\/07\/element-logic-nuovamente-certificato-come-datore-di-lavoro-attraente\/#article","isPartOf":{"@id":"https:\/\/loginfo24.com\/it\/2022\/01\/07\/element-logic-nuovamente-certificato-come-datore-di-lavoro-attraente\/"},"author":{"name":"","@id":""},"headline":"Element Logic nuovamente certificato come datore di lavoro attraente","datePublished":"2022-01-07T14:03:41+00:00","mainEntityOfPage":{"@id":"https:\/\/loginfo24.com\/it\/2022\/01\/07\/element-logic-nuovamente-certificato-come-datore-di-lavoro-attraente\/"},"wordCount":458,"commentCount":0,"publisher":{"@id":"https:\/\/loginfo24.com\/it\/#organization"},"image":{"@id":"https:\/\/loginfo24.com\/it\/2022\/01\/07\/element-logic-nuovamente-certificato-come-datore-di-lavoro-attraente\/#primaryimage"},"thumbnailUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Element_Logic_7.1.22.jpg","articleSection":["Forwarding &amp; Logistics","Intralogistics","Regions"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/loginfo24.com\/it\/2022\/01\/07\/element-logic-nuovamente-certificato-come-datore-di-lavoro-attraente\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/loginfo24.com\/it\/2022\/01\/07\/element-logic-nuovamente-certificato-come-datore-di-lavoro-attraente\/","url":"https:\/\/loginfo24.com\/it\/2022\/01\/07\/element-logic-nuovamente-certificato-come-datore-di-lavoro-attraente\/","name":"Element Logic nuovamente certificato come datore di lavoro attraente - Loginfo24","isPartOf":{"@id":"https:\/\/loginfo24.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/loginfo24.com\/it\/2022\/01\/07\/element-logic-nuovamente-certificato-come-datore-di-lavoro-attraente\/#primaryimage"},"image":{"@id":"https:\/\/loginfo24.com\/it\/2022\/01\/07\/element-logic-nuovamente-certificato-come-datore-di-lavoro-attraente\/#primaryimage"},"thumbnailUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Element_Logic_7.1.22.jpg","datePublished":"2022-01-07T14:03:41+00:00","breadcrumb":{"@id":"https:\/\/loginfo24.com\/it\/2022\/01\/07\/element-logic-nuovamente-certificato-come-datore-di-lavoro-attraente\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/loginfo24.com\/it\/2022\/01\/07\/element-logic-nuovamente-certificato-come-datore-di-lavoro-attraente\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/loginfo24.com\/it\/2022\/01\/07\/element-logic-nuovamente-certificato-come-datore-di-lavoro-attraente\/#primaryimage","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Element_Logic_7.1.22.jpg","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Element_Logic_7.1.22.jpg","width":1209,"height":731},{"@type":"BreadcrumbList","@id":"https:\/\/loginfo24.com\/it\/2022\/01\/07\/element-logic-nuovamente-certificato-come-datore-di-lavoro-attraente\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/loginfo24.com\/it\/"},{"@type":"ListItem","position":2,"name":"Element Logic nuovamente certificato come datore di lavoro attraente"}]},{"@type":"WebSite","@id":"https:\/\/loginfo24.com\/it\/#website","url":"https:\/\/loginfo24.com\/it\/","name":"Loginfo24","description":"Loginfo24 \u00e8 la piattaforma dedicata alla logistica e alle catene di fornitura con informazioni disponibili 24 ore su 24.","publisher":{"@id":"https:\/\/loginfo24.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/loginfo24.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/loginfo24.com\/it\/#organization","name":"Logismedia Group AG","url":"https:\/\/loginfo24.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/loginfo24.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","width":938,"height":351,"caption":"Logismedia Group AG"},"image":{"@id":"https:\/\/loginfo24.com\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","https:\/\/www.linkedin.com\/company\/lofinfo24\/"]}]}},"_links":{"self":[{"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/posts\/26332","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/comments?post=26332"}],"version-history":[{"count":0,"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/posts\/26332\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/media\/11371"}],"wp:attachment":[{"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/media?parent=26332"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/categories?post=26332"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/tags?post=26332"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}