{"id":25431,"date":"2021-05-12T17:57:35","date_gmt":"2021-05-12T15:57:35","guid":{"rendered":"https:\/\/blog.brand-architecture.at\/2021\/05\/12\/la-piattaforma-mydhli-aumenta-le-prenotazioni-online-del-56-percento\/"},"modified":"2025-12-15T13:02:21","modified_gmt":"2025-12-15T12:02:21","slug":"la-piattaforma-mydhli-aumenta-le-prenotazioni-online-del-56-percento","status":"publish","type":"post","link":"https:\/\/loginfo24.com\/it\/2021\/05\/12\/la-piattaforma-mydhli-aumenta-le-prenotazioni-online-del-56-percento\/","title":{"rendered":"La piattaforma myDHLi aumenta le prenotazioni online del 56 percento"},"content":{"rendered":"<p>Dopo il lancio di successo di myDHLi, l&#8217;esperto logistico DHL ha ampliato la disponibilit\u00e0 globale della piattaforma da otto a 62 paesi. Tutte le espansioni seguono i principi guida dello sviluppo continuo di myDHLi. La piattaforma per i clienti \u00e8 ora disponibile anche per i trasporti su strada di DHL Freight. Nuove funzionalit\u00e0 e caratteristiche sono state presentate al primo myDHLi Digital Summit.<\/p>\n<p>(Bonn) DHL Global Forwarding, Freight, il principale specialista internazionale delle spedizioni del Deutsche Post DHL Group, ha presentato oggi nuove funzionalit\u00e0 e miglioramenti per la piattaforma digitale per i clienti <a href=\"https:\/\/www.mydhli.com\/\">myDHLi<\/a>, che festeggia il primo anniversario della sua esistenza. Dopo il lancio di successo di myDHLi, l&#8217;esperto logistico ha ampliato la disponibilit\u00e0 globale della piattaforma da otto a 62 paesi. Allo stesso tempo, le prenotazioni online sono aumentate del 56 percento (Q1\/2021 rispetto a Q1\/2020). Questa espansione \u00e8 accompagnata da funzionalit\u00e0 migliorate come l&#8217;opzione integrata &#8220;Salva e Modifica&#8221; per salvare e modificare successivamente le offerte di trasporto, oltre a nuovi servizi come myDHLi Reports per una maggiore trasparenza delle spedizioni. Inoltre, la piattaforma \u00e8 ora disponibile per la prima volta anche per i clienti nel settore delle spedizioni su strada. Il rollout \u00e8 attualmente in corso in Turchia. Per mettere in evidenza lo sviluppo rapido della piattaforma myDHLi, in particolare le innovazioni lungo la trasformazione digitale nella logistica, \u00e8 stato istituito il &#8220;myDHLi Digital Summit&#8221;, che si terr\u00e0 una volta all&#8217;anno. La prima edizione di questo formato si \u00e8 svolta oggi presso il DHL Innovation Center di Troisdorf.<\/p>\n<h5><strong>Traduzione della digitalizzazione in orientamento al cliente<\/strong><\/h5>\n<p>&#8220;myDHLi traduce la digitalizzazione in orientamento al cliente. Per questo motivo investiamo molto tempo e impegno nel rollout della piattaforma. I clienti possono prenotare spedizioni in modo molto comodo attraverso la piattaforma, che segue i principi di design pi\u00f9 moderni. \u00c8 garantita una trasparenza a 360\u00b0 riguardo alle proprie spedizioni e offerte di trasporto. Alla fine del 2020, 1.000 clienti utilizzavano la piattaforma. Solo quattro mesi dopo, abbiamo gi\u00e0 contato circa 3.000 utenti in 62 paesi tra i nostri clienti myDHLi&#8221;, afferma Tim Scharwath, CEO Global Forwarding, Freight. &#8220;Data l&#8217;enorme successo del lancio sul mercato, espanderemo progressivamente la piattaforma, ad esempio aggiungendo ulteriori lingue.&#8221;<\/p>\n<p>La funzione Quote + Book offre, basata su un&#8217;analisi del comportamento degli utenti e su un design applicativo moderno, una maggiore facilit\u00e0 d&#8217;uso. I clienti possono salvare le operazioni di prenotazione in qualsiasi momento e richiamarle e continuare durante il periodo di offerta. In questo modo, informazioni importanti che non erano disponibili all&#8217;inizio della prenotazione possono essere facilmente aggiunte in un secondo momento. Inoltre, la piattaforma \u00e8 dotata di una nuova funzionalit\u00e0 tramite myDHLi Reports, che offre al cliente piena trasparenza sui dati delle spedizioni passate e attuali, consentendo ulteriori analisi.<\/p>\n<h5><strong><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-large wp-image-11347\" src=\"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/DHL_12.5.21.jpg\" alt=\"\" width=\"1024\" height=\"592\" \/><\/strong><\/h5>\n<p>Approccio Multi-Channel<\/p>\n<p>Tutte le espansioni seguono i principi guida dello sviluppo continuo di myDHLi. Questo include, ad esempio, una completa trasparenza delle spedizioni con le informazioni end-to-end dalla raccolta alla consegna finale. L&#8217;approccio multi-channel assicura che tutte le informazioni siano disponibili in un unico posto, indipendentemente dai canali utilizzati dal cliente. Inoltre, una funzione di avviso segnala quale operazione richiede particolare attenzione da parte del cliente. Funzionalit\u00e0 integrate di social media come &#8220;Segui&#8221; e &#8220;Condividi&#8221; consentono ai clienti di scambiare informazioni con i propri clienti, colleghi e fornitori, semplificando cos\u00ec la comunicazione lungo l&#8217;intera catena di approvvigionamento.<\/p>\n<p>&#8220;In myDHLi, le esigenze di trasporto dei nostri clienti e l&#8217;esperienza del cliente sono al centro dell&#8217;attenzione&#8221;, afferma Uwe Brinks, CEO DHL Freight. &#8220;A causa dell&#8217;alta domanda e del feedback positivo degli utenti di myDHLi, abbiamo deciso di aprire la piattaforma anche ai nostri clienti nel settore del trasporto terrestre, affinch\u00e9 possano beneficiare delle funzionalit\u00e0 e dei servizi che finora erano disponibili solo per i nostri clienti nel settore aereo e marittimo con myDHLi.&#8221;<\/p>\n<h5><strong>Struttura modulare<\/strong><\/h5>\n<p>Il portale clienti myDHLi, lanciato con successo un anno fa, ha stabilito nuovi standard in un settore ancora poco digitalizzato. Si distingue per una struttura modulare che consente agli utenti di personalizzare completamente il portale. I clienti possono scegliere se utilizzare esclusivamente la funzione Quote + Book per confrontare le opzioni di trasporto disponibili e poi prenotare direttamente una delle offerte logistiche. Inoltre, possono anche utilizzare servizi aggiuntivi come il tracciamento delle spedizioni, la gestione dei documenti, myDHLi Reports e myDHLi Analytics, e ora, grazie al nuovo aggiornamento, ottenere anche informazioni sui tempi di transito e sui costi per unit\u00e0. Poich\u00e9 il portale \u00e8 ora disponibile anche per il trasporto terrestre, myDHLi diventa una piattaforma one-stop per tutti i clienti di DHL Global Forwarding, Freight. Allo stesso tempo, myDHLi contribuisce alla strategia di sostenibilit\u00e0 di DHL: dal gennaio 2021, DHL Global Forwarding neutralizza le emissioni di anidride carbonica di tutte le spedizioni marittime LCL utilizzando biocarburanti sostenibili - senza costi aggiuntivi per il cliente. Per tutti gli altri tipi di trasporto, su richiesta, \u00e8 possibile scegliere un compenso per le emissioni o una neutralizzazione delle emissioni di CO2 tramite biocarburanti.<\/p>\n<p>La digitalizzazione \u00e8 uno dei pilastri strategici di DHL Global Forwarding. Per continuare a promuovere gli sviluppi in questo settore dell&#8217;industria logistica, da oggi viene istituito il &#8220;myDHLi Digital Summit&#8221;, che si terr\u00e0 una volta all&#8217;anno. L&#8217;evento ha l&#8217;obiettivo di presentare innovazioni relative al portale clienti myDHLi e discutere e promuovere attivamente i progressi della trasformazione digitale nella logistica, in linea con la strategia del gruppo Deutsche Post DHL - &#8220;Eccellenza in un mondo digitale&#8221;.<\/p>\n<p>Foto: \u00a9 DHL \/ <strong><em>Didascalia dell&#8217;immagine di copertura:<\/em><\/strong><em> da sinistra: Uwe Brinks, CEO DHL Freight, e Tim Scharwath, CEO Global Forwarding, Freight<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dopo il lancio di successo di myDHLi, l&#8217;esperto logistico DHL ha ampliato la disponibilit\u00e0 globale della piattaforma da otto a 62 paesi. Tutte le espansioni seguono<span class=\"excerpt-hellip\"> [\u2026]<\/span><\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1665,1557,1561],"tags":[],"class_list":["post-25431","post","type-post","status-publish","format-standard","hentry","category-categories","category-forwarding-logistics","category-regions"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La piattaforma myDHLi aumenta le prenotazioni online del 56 percento - Loginfo24<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/loginfo24.com\/it\/2021\/05\/12\/la-piattaforma-mydhli-aumenta-le-prenotazioni-online-del-56-percento\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La piattaforma myDHLi aumenta le prenotazioni online del 56 percento - Loginfo24\" \/>\n<meta property=\"og:description\" content=\"Dopo il lancio di successo di myDHLi, l&#8217;esperto logistico DHL ha ampliato la disponibilit\u00e0 globale della piattaforma da otto a 62 paesi. Tutte le espansioni seguono [\u2026]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/loginfo24.com\/it\/2021\/05\/12\/la-piattaforma-mydhli-aumenta-le-prenotazioni-online-del-56-percento\/\" \/>\n<meta property=\"og:site_name\" content=\"Loginfo24\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/\" \/>\n<meta property=\"article:published_time\" content=\"2021-05-12T15:57:35+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-12-15T12:02:21+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/DHL_12.5.21.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2021\\\/05\\\/12\\\/la-piattaforma-mydhli-aumenta-le-prenotazioni-online-del-56-percento\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2021\\\/05\\\/12\\\/la-piattaforma-mydhli-aumenta-le-prenotazioni-online-del-56-percento\\\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"La piattaforma myDHLi aumenta le prenotazioni online del 56 percento\",\"datePublished\":\"2021-05-12T15:57:35+00:00\",\"dateModified\":\"2025-12-15T12:02:21+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2021\\\/05\\\/12\\\/la-piattaforma-mydhli-aumenta-le-prenotazioni-online-del-56-percento\\\/\"},\"wordCount\":916,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2021\\\/05\\\/12\\\/la-piattaforma-mydhli-aumenta-le-prenotazioni-online-del-56-percento\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/DHL_12.5.21.jpg\",\"articleSection\":[\"Categories\",\"Forwarding &amp; Logistics\",\"Regions\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/it\\\/2021\\\/05\\\/12\\\/la-piattaforma-mydhli-aumenta-le-prenotazioni-online-del-56-percento\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2021\\\/05\\\/12\\\/la-piattaforma-mydhli-aumenta-le-prenotazioni-online-del-56-percento\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2021\\\/05\\\/12\\\/la-piattaforma-mydhli-aumenta-le-prenotazioni-online-del-56-percento\\\/\",\"name\":\"La piattaforma myDHLi aumenta le prenotazioni online del 56 percento - Loginfo24\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2021\\\/05\\\/12\\\/la-piattaforma-mydhli-aumenta-le-prenotazioni-online-del-56-percento\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2021\\\/05\\\/12\\\/la-piattaforma-mydhli-aumenta-le-prenotazioni-online-del-56-percento\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/DHL_12.5.21.jpg\",\"datePublished\":\"2021-05-12T15:57:35+00:00\",\"dateModified\":\"2025-12-15T12:02:21+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2021\\\/05\\\/12\\\/la-piattaforma-mydhli-aumenta-le-prenotazioni-online-del-56-percento\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/it\\\/2021\\\/05\\\/12\\\/la-piattaforma-mydhli-aumenta-le-prenotazioni-online-del-56-percento\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2021\\\/05\\\/12\\\/la-piattaforma-mydhli-aumenta-le-prenotazioni-online-del-56-percento\\\/#primaryimage\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/DHL_12.5.21.jpg\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/DHL_12.5.21.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2021\\\/05\\\/12\\\/la-piattaforma-mydhli-aumenta-le-prenotazioni-online-del-56-percento\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La piattaforma myDHLi aumenta le prenotazioni online del 56 percento\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/\",\"name\":\"Loginfo24\",\"description\":\"Loginfo24 \u00e8 la piattaforma dedicata alla logistica e alle catene di fornitura con informazioni disponibili 24 ore su 24.\",\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#organization\",\"name\":\"Logismedia Group AG\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"width\":938,\"height\":351,\"caption\":\"Logismedia Group AG\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/people\\\/Loginfo24\\\/100057360583332\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/lofinfo24\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La piattaforma myDHLi aumenta le prenotazioni online del 56 percento - Loginfo24","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/loginfo24.com\/it\/2021\/05\/12\/la-piattaforma-mydhli-aumenta-le-prenotazioni-online-del-56-percento\/","og_locale":"it_IT","og_type":"article","og_title":"La piattaforma myDHLi aumenta le prenotazioni online del 56 percento - Loginfo24","og_description":"Dopo il lancio di successo di myDHLi, l&#8217;esperto logistico DHL ha ampliato la disponibilit\u00e0 globale della piattaforma da otto a 62 paesi. Tutte le espansioni seguono [\u2026]","og_url":"https:\/\/loginfo24.com\/it\/2021\/05\/12\/la-piattaforma-mydhli-aumenta-le-prenotazioni-online-del-56-percento\/","og_site_name":"Loginfo24","article_publisher":"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","article_published_time":"2021-05-12T15:57:35+00:00","article_modified_time":"2025-12-15T12:02:21+00:00","og_image":[{"url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/DHL_12.5.21.jpg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"4 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/loginfo24.com\/it\/2021\/05\/12\/la-piattaforma-mydhli-aumenta-le-prenotazioni-online-del-56-percento\/#article","isPartOf":{"@id":"https:\/\/loginfo24.com\/it\/2021\/05\/12\/la-piattaforma-mydhli-aumenta-le-prenotazioni-online-del-56-percento\/"},"author":{"name":"","@id":""},"headline":"La piattaforma myDHLi aumenta le prenotazioni online del 56 percento","datePublished":"2021-05-12T15:57:35+00:00","dateModified":"2025-12-15T12:02:21+00:00","mainEntityOfPage":{"@id":"https:\/\/loginfo24.com\/it\/2021\/05\/12\/la-piattaforma-mydhli-aumenta-le-prenotazioni-online-del-56-percento\/"},"wordCount":916,"commentCount":0,"publisher":{"@id":"https:\/\/loginfo24.com\/it\/#organization"},"image":{"@id":"https:\/\/loginfo24.com\/it\/2021\/05\/12\/la-piattaforma-mydhli-aumenta-le-prenotazioni-online-del-56-percento\/#primaryimage"},"thumbnailUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/DHL_12.5.21.jpg","articleSection":["Categories","Forwarding &amp; Logistics","Regions"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/loginfo24.com\/it\/2021\/05\/12\/la-piattaforma-mydhli-aumenta-le-prenotazioni-online-del-56-percento\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/loginfo24.com\/it\/2021\/05\/12\/la-piattaforma-mydhli-aumenta-le-prenotazioni-online-del-56-percento\/","url":"https:\/\/loginfo24.com\/it\/2021\/05\/12\/la-piattaforma-mydhli-aumenta-le-prenotazioni-online-del-56-percento\/","name":"La piattaforma myDHLi aumenta le prenotazioni online del 56 percento - Loginfo24","isPartOf":{"@id":"https:\/\/loginfo24.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/loginfo24.com\/it\/2021\/05\/12\/la-piattaforma-mydhli-aumenta-le-prenotazioni-online-del-56-percento\/#primaryimage"},"image":{"@id":"https:\/\/loginfo24.com\/it\/2021\/05\/12\/la-piattaforma-mydhli-aumenta-le-prenotazioni-online-del-56-percento\/#primaryimage"},"thumbnailUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/DHL_12.5.21.jpg","datePublished":"2021-05-12T15:57:35+00:00","dateModified":"2025-12-15T12:02:21+00:00","breadcrumb":{"@id":"https:\/\/loginfo24.com\/it\/2021\/05\/12\/la-piattaforma-mydhli-aumenta-le-prenotazioni-online-del-56-percento\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/loginfo24.com\/it\/2021\/05\/12\/la-piattaforma-mydhli-aumenta-le-prenotazioni-online-del-56-percento\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/loginfo24.com\/it\/2021\/05\/12\/la-piattaforma-mydhli-aumenta-le-prenotazioni-online-del-56-percento\/#primaryimage","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/DHL_12.5.21.jpg","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/DHL_12.5.21.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/loginfo24.com\/it\/2021\/05\/12\/la-piattaforma-mydhli-aumenta-le-prenotazioni-online-del-56-percento\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/loginfo24.com\/it\/"},{"@type":"ListItem","position":2,"name":"La piattaforma myDHLi aumenta le prenotazioni online del 56 percento"}]},{"@type":"WebSite","@id":"https:\/\/loginfo24.com\/it\/#website","url":"https:\/\/loginfo24.com\/it\/","name":"Loginfo24","description":"Loginfo24 \u00e8 la piattaforma dedicata alla logistica e alle catene di fornitura con informazioni disponibili 24 ore su 24.","publisher":{"@id":"https:\/\/loginfo24.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/loginfo24.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/loginfo24.com\/it\/#organization","name":"Logismedia Group AG","url":"https:\/\/loginfo24.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/loginfo24.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","width":938,"height":351,"caption":"Logismedia Group AG"},"image":{"@id":"https:\/\/loginfo24.com\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","https:\/\/www.linkedin.com\/company\/lofinfo24\/"]}]}},"_links":{"self":[{"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/posts\/25431","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/comments?post=25431"}],"version-history":[{"count":1,"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/posts\/25431\/revisions"}],"predecessor-version":[{"id":46564,"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/posts\/25431\/revisions\/46564"}],"wp:attachment":[{"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/media?parent=25431"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/categories?post=25431"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/tags?post=25431"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}