{"id":25000,"date":"2021-04-26T17:23:21","date_gmt":"2021-04-26T15:23:21","guid":{"rendered":"https:\/\/blog.brand-architecture.at\/2021\/04\/26\/rhenus-con-offerta-virtuale-alla-transport-logistic-online\/"},"modified":"2025-12-15T13:00:15","modified_gmt":"2025-12-15T12:00:15","slug":"rhenus-con-offerta-virtuale-alla-transport-logistic-online","status":"publish","type":"post","link":"https:\/\/loginfo24.com\/it\/2021\/04\/26\/rhenus-con-offerta-virtuale-alla-transport-logistic-online\/","title":{"rendered":"Rhenus con offerta virtuale alla transport logistic Online"},"content":{"rendered":"<p>Anche se la situazione pandemica continua a non permettere incontri fisici e networking a Monaco durante la fiera internazionale transport logistic di quest&#8217;anno, il gruppo Rhenus offre ai suoi clienti e interessati la possibilit\u00e0 di prendere appuntamenti virtuali con il proprio referente personale. Questi possono essere prenotati da subito attraverso il sito web della fiera Rhenus. Inoltre, il fornitore di servizi logistici \u00e8 presente nel programma conferenze della fiera con sei interessanti panel.<\/p>\n<p>(Holzwickede) L&#8217;alternativa online all&#8217;incontro fisico in fiera si svolger\u00e0 durante tutta la settimana dal 3 al 7 maggio. Attraverso il sito www.rhenus.group\/de\/tl2021 \u00e8 possibile prenotare appuntamenti con vari referenti delle rispettive unit\u00e0 aziendali e su temi specifici.<\/p>\n<p>\u201e\u00c8 importante per noi mantenere la vicinanza e lo scambio con i nostri clienti, partner e interessati anche in tempi di pandemia. Puntiamo sul fatto che con la nostra offerta di colloqui possiamo offrire un&#8217;alternativa al networking allo stand fieristico, che sar\u00e0 utilizzata da molti interessati\u201c, spiega il Dr. Stephan Peters, membro del consiglio di amministrazione di Rhenus, il formato di dialogo di quest&#8217;anno.<\/p>\n<h5><strong>Partecipazione al programma conferenze <\/strong><\/h5>\n<p>Rhenus non solo \u00e8 presente con colloqui individuali alla transport logistic, ma partecipa quest&#8217;anno in modo particolarmente intenso al programma conferenze. Cos\u00ec, Jan Harnisch, COO Global di Rhenus Air &amp; Ocean, discuter\u00e0 il 4 maggio alle 13:00 dello sviluppo della navigazione marittima dei container dopo il Corona, mentre Andr\u00e9 Delarue, COO Airfreight Rhenus Asia Pacific, parler\u00e0 contemporaneamente di carenze di capacit\u00e0 e dell&#8217;aumento delle tariffe aeree.<\/p>\n<p>Anche il tema della sostenibilit\u00e0 sar\u00e0 affrontato: Sascha H\u00e4hnke, amministratore delegato di Rhenus Transport, terr\u00e0 il 4 maggio alle 14:30 una conferenza sui motori alternativi nella pratica, mentre la responsabile della sostenibilit\u00e0 Isa Kohn fornir\u00e0 il 5 maggio alle 10:00 informazioni sui risparmi di CO2 nella logistica. Il Dr. Stephan Peters relazioner\u00e0 lo stesso giorno a partire dalle 11:30 sulle sfide della pandemia di Covid-19 e sulla gestione della crisi presso Rhenus. Nell&#8217;ultimo giorno della fiera si parler\u00e0, tra l&#8217;altro, con Sascha H\u00e4hnke di processi di carico pi\u00f9 efficienti.<\/p>\n<p>Foto: \u00a9 Rhenus<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Anche se la situazione pandemica continua a non permettere incontri fisici e networking a Monaco durante la fiera internazionale transport logistic di quest&#8217;anno, il gruppo Rhenus<span class=\"excerpt-hellip\"> [\u2026]<\/span><\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1557,1561],"tags":[],"class_list":["post-25000","post","type-post","status-publish","format-standard","hentry","category-forwarding-logistics","category-regions"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Rhenus con offerta virtuale alla transport logistic Online - Loginfo24<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/loginfo24.com\/it\/2021\/04\/26\/rhenus-con-offerta-virtuale-alla-transport-logistic-online\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Rhenus con offerta virtuale alla transport logistic Online - Loginfo24\" \/>\n<meta property=\"og:description\" content=\"Anche se la situazione pandemica continua a non permettere incontri fisici e networking a Monaco durante la fiera internazionale transport logistic di quest&#8217;anno, il gruppo Rhenus [\u2026]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/loginfo24.com\/it\/2021\/04\/26\/rhenus-con-offerta-virtuale-alla-transport-logistic-online\/\" \/>\n<meta property=\"og:site_name\" content=\"Loginfo24\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/\" \/>\n<meta property=\"article:published_time\" content=\"2021-04-26T15:23:21+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-12-15T12:00:15+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2021\\\/04\\\/26\\\/rhenus-con-offerta-virtuale-alla-transport-logistic-online\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2021\\\/04\\\/26\\\/rhenus-con-offerta-virtuale-alla-transport-logistic-online\\\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Rhenus con offerta virtuale alla transport logistic Online\",\"datePublished\":\"2021-04-26T15:23:21+00:00\",\"dateModified\":\"2025-12-15T12:00:15+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2021\\\/04\\\/26\\\/rhenus-con-offerta-virtuale-alla-transport-logistic-online\\\/\"},\"wordCount\":345,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#organization\"},\"articleSection\":[\"Forwarding &amp; Logistics\",\"Regions\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/it\\\/2021\\\/04\\\/26\\\/rhenus-con-offerta-virtuale-alla-transport-logistic-online\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2021\\\/04\\\/26\\\/rhenus-con-offerta-virtuale-alla-transport-logistic-online\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2021\\\/04\\\/26\\\/rhenus-con-offerta-virtuale-alla-transport-logistic-online\\\/\",\"name\":\"Rhenus con offerta virtuale alla transport logistic Online - Loginfo24\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#website\"},\"datePublished\":\"2021-04-26T15:23:21+00:00\",\"dateModified\":\"2025-12-15T12:00:15+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2021\\\/04\\\/26\\\/rhenus-con-offerta-virtuale-alla-transport-logistic-online\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/it\\\/2021\\\/04\\\/26\\\/rhenus-con-offerta-virtuale-alla-transport-logistic-online\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2021\\\/04\\\/26\\\/rhenus-con-offerta-virtuale-alla-transport-logistic-online\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Rhenus con offerta virtuale alla transport logistic Online\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/\",\"name\":\"Loginfo24\",\"description\":\"Loginfo24 \u00e8 la piattaforma dedicata alla logistica e alle catene di fornitura con informazioni disponibili 24 ore su 24.\",\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#organization\",\"name\":\"Logismedia Group AG\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"width\":938,\"height\":351,\"caption\":\"Logismedia Group AG\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/people\\\/Loginfo24\\\/100057360583332\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/lofinfo24\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Rhenus con offerta virtuale alla transport logistic Online - Loginfo24","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/loginfo24.com\/it\/2021\/04\/26\/rhenus-con-offerta-virtuale-alla-transport-logistic-online\/","og_locale":"it_IT","og_type":"article","og_title":"Rhenus con offerta virtuale alla transport logistic Online - Loginfo24","og_description":"Anche se la situazione pandemica continua a non permettere incontri fisici e networking a Monaco durante la fiera internazionale transport logistic di quest&#8217;anno, il gruppo Rhenus [\u2026]","og_url":"https:\/\/loginfo24.com\/it\/2021\/04\/26\/rhenus-con-offerta-virtuale-alla-transport-logistic-online\/","og_site_name":"Loginfo24","article_publisher":"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","article_published_time":"2021-04-26T15:23:21+00:00","article_modified_time":"2025-12-15T12:00:15+00:00","twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"2 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/loginfo24.com\/it\/2021\/04\/26\/rhenus-con-offerta-virtuale-alla-transport-logistic-online\/#article","isPartOf":{"@id":"https:\/\/loginfo24.com\/it\/2021\/04\/26\/rhenus-con-offerta-virtuale-alla-transport-logistic-online\/"},"author":{"name":"","@id":""},"headline":"Rhenus con offerta virtuale alla transport logistic Online","datePublished":"2021-04-26T15:23:21+00:00","dateModified":"2025-12-15T12:00:15+00:00","mainEntityOfPage":{"@id":"https:\/\/loginfo24.com\/it\/2021\/04\/26\/rhenus-con-offerta-virtuale-alla-transport-logistic-online\/"},"wordCount":345,"commentCount":0,"publisher":{"@id":"https:\/\/loginfo24.com\/it\/#organization"},"articleSection":["Forwarding &amp; Logistics","Regions"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/loginfo24.com\/it\/2021\/04\/26\/rhenus-con-offerta-virtuale-alla-transport-logistic-online\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/loginfo24.com\/it\/2021\/04\/26\/rhenus-con-offerta-virtuale-alla-transport-logistic-online\/","url":"https:\/\/loginfo24.com\/it\/2021\/04\/26\/rhenus-con-offerta-virtuale-alla-transport-logistic-online\/","name":"Rhenus con offerta virtuale alla transport logistic Online - Loginfo24","isPartOf":{"@id":"https:\/\/loginfo24.com\/it\/#website"},"datePublished":"2021-04-26T15:23:21+00:00","dateModified":"2025-12-15T12:00:15+00:00","breadcrumb":{"@id":"https:\/\/loginfo24.com\/it\/2021\/04\/26\/rhenus-con-offerta-virtuale-alla-transport-logistic-online\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/loginfo24.com\/it\/2021\/04\/26\/rhenus-con-offerta-virtuale-alla-transport-logistic-online\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/loginfo24.com\/it\/2021\/04\/26\/rhenus-con-offerta-virtuale-alla-transport-logistic-online\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/loginfo24.com\/it\/"},{"@type":"ListItem","position":2,"name":"Rhenus con offerta virtuale alla transport logistic Online"}]},{"@type":"WebSite","@id":"https:\/\/loginfo24.com\/it\/#website","url":"https:\/\/loginfo24.com\/it\/","name":"Loginfo24","description":"Loginfo24 \u00e8 la piattaforma dedicata alla logistica e alle catene di fornitura con informazioni disponibili 24 ore su 24.","publisher":{"@id":"https:\/\/loginfo24.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/loginfo24.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/loginfo24.com\/it\/#organization","name":"Logismedia Group AG","url":"https:\/\/loginfo24.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/loginfo24.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","width":938,"height":351,"caption":"Logismedia Group AG"},"image":{"@id":"https:\/\/loginfo24.com\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","https:\/\/www.linkedin.com\/company\/lofinfo24\/"]}]}},"_links":{"self":[{"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/posts\/25000","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/comments?post=25000"}],"version-history":[{"count":1,"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/posts\/25000\/revisions"}],"predecessor-version":[{"id":45706,"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/posts\/25000\/revisions\/45706"}],"wp:attachment":[{"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/media?parent=25000"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/categories?post=25000"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/tags?post=25000"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}