{"id":24868,"date":"2021-04-21T18:26:46","date_gmt":"2021-04-21T16:26:46","guid":{"rendered":"https:\/\/blog.brand-architecture.at\/2021\/04\/21\/nexxiot-supporta-jaeger-bernburg-nelluso-ecologico-dei-veicoli\/"},"modified":"2025-12-15T12:59:39","modified_gmt":"2025-12-15T11:59:39","slug":"nexxiot-supporta-jaeger-bernburg-nelluso-ecologico-dei-veicoli","status":"publish","type":"post","link":"https:\/\/loginfo24.com\/it\/2021\/04\/21\/nexxiot-supporta-jaeger-bernburg-nelluso-ecologico-dei-veicoli\/","title":{"rendered":"Nexxiot supporta Jaeger Bernburg nell&#8217;uso ecologico dei veicoli"},"content":{"rendered":"<p>Jaeger Bernburg utilizza la tecnologia Nexxiot nella sua azienda ferroviaria per digitalizzare la propria flotta e rendere l&#8217;uso dei veicoli ferroviari pi\u00f9 economico ed ecologico. Al centro della collaborazione c&#8217;\u00e8 l&#8217;equipaggiamento dei dispositivi su rotaia con tecnologia IoT, per garantire un monitoraggio efficace delle prestazioni grazie alla trasmissione di dati in tempo reale.<\/p>\n<p>(Zurigo\/Bernburg) Dall&#8217;aprile 2020, Nexxiot fornisce a Jaeger Bernburg i propri sensori sviluppati internamente, chiamati Globehopper. L&#8217;equipaggiamento dell&#8217;intera flotta \u00e8 stato recentemente completato.<\/p>\n<p>Christian Koch, responsabile operativo locale, spiega i motivi della collaborazione: &#8220;La nostra azienda persegue una strategia di digitalizzazione ambiziosa. Per questo era importante per noi adottare un sistema che fosse privo di manutenzione e autonomo dal punto di vista energetico, e che consentisse un monitoraggio preciso delle prestazioni della nostra flotta. I Globehopper di Nexxiot combinano queste caratteristiche. La tecnologia ci consente di garantire la manutenzione della nostra flotta secondo le attuali normative europee sulla manutenzione dei veicoli, in modo da avere sempre sotto controllo quali veicoli hanno quanta prestazione operativa. Questo ci permette di ottimizzare i nostri processi e automatizzare l&#8217;analisi dei dati.&#8221;<\/p>\n<h5><strong>Risparmiare percorsi ed emissioni<\/strong><\/h5>\n<p>La Jaeger Bernburg Group, attiva principalmente nella costruzione ferroviaria, gestisce una vasta gamma di veicoli, in particolare veicoli standard, secondari e a doppia via. L&#8217;intera flotta \u00e8 stata ora completamente equipaggiata con Globehopper, consentendo una pianificazione migliore della disposizione della flotta. &#8220;Possiamo indirizzare i nostri veicoli ai cantieri in modo pi\u00f9 efficiente, poich\u00e9 sappiamo sempre dove si trovano. Questo riduce percorsi e emissioni inutili. Inoltre, supportiamo i nostri dipendenti nelle loro operazioni lavorative e forniamo loro informazioni trasparenti su cui possono basare le loro decisioni&#8221;, continua Koch.<\/p>\n<p>Dalla fondazione di Nexxiot nel 2015, sono stati messi in funzione pi\u00f9 di 122.000 Globehopper, che hanno gi\u00e0 percorso insieme oltre 4 miliardi di chilometri. &#8220;Il nostro obiettivo \u00e8 ridurre le emissioni globali di anidride carbonica del cinque percento spostando il traffico dalla strada alla ferrovia. Ogni chilometro risparmiato, reso possibile dalla nostra tecnologia, contribuisce a questo obiettivo&#8221;, afferma il CEO di Nexxiot, Stefan Kalmund.<\/p>\n<h5><strong>Su Jaeger Bernburg<\/strong><\/h5>\n<p>Come gruppo di medie dimensioni, Jaeger Bernburg offre una vasta gamma di servizi nel settore delle costruzioni, con un focus sulla costruzione di infrastrutture e ingegneria civile. I complessi progetti di costruzione vengono realizzati con personale interno. Le aree di attivit\u00e0 spaziano dalla costruzione ferroviaria e dei binari, costruzione stradale e ingegneria civile, fino a costruzione di terreni e scavi, costruzione di canali e tubazioni, fino al disassemblaggio ingegneristico.<\/p>\n<h5><strong>Su Nexxiot AG<\/strong><\/h5>\n<p>Nexxiot AG, con sede a Zurigo, Svizzera, \u00e8 leader di settore nello sviluppo e nella fornitura di soluzioni digitali per la gestione della supply chain. L&#8217;azienda \u00e8 un punto di riferimento nei settori degli algoritmi Big Data, intelligenza artificiale e apprendimento automatico, geofencing e tecnologia dei sensori embedded a ultra-basso consumo. Nexxiot utilizza la digitalizzazione per portare fiducia, sicurezza ed efficienza nel settore della logistica. I dati su oltre 4 miliardi di chilometri di trasporto percorsi sono memorizzati nella cloud logistica sviluppata appositamente da Nexxiot. Dipendenti provenienti da oltre 19 paesi contribuiscono al successo dell&#8217;azienda. Oltre alla sede principale in Svizzera, l&#8217;azienda opera in Germania e negli Stati Uniti e persegue una strategia di crescita globale.<\/p>\n<p>Foto: \u00a9 Jaeger<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Jaeger Bernburg utilizza la tecnologia Nexxiot nella sua azienda ferroviaria per digitalizzare la propria flotta e rendere l&#8217;uso dei veicoli ferroviari pi\u00f9 economico ed ecologico. Al<span class=\"excerpt-hellip\"> [\u2026]<\/span><\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1665,1557,1561],"tags":[],"class_list":["post-24868","post","type-post","status-publish","format-standard","hentry","category-categories","category-forwarding-logistics","category-regions"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Nexxiot supporta Jaeger Bernburg nell&#039;uso ecologico dei veicoli - Loginfo24<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/loginfo24.com\/it\/2021\/04\/21\/nexxiot-supporta-jaeger-bernburg-nelluso-ecologico-dei-veicoli\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Nexxiot supporta Jaeger Bernburg nell&#039;uso ecologico dei veicoli - Loginfo24\" \/>\n<meta property=\"og:description\" content=\"Jaeger Bernburg utilizza la tecnologia Nexxiot nella sua azienda ferroviaria per digitalizzare la propria flotta e rendere l&#8217;uso dei veicoli ferroviari pi\u00f9 economico ed ecologico. Al [\u2026]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/loginfo24.com\/it\/2021\/04\/21\/nexxiot-supporta-jaeger-bernburg-nelluso-ecologico-dei-veicoli\/\" \/>\n<meta property=\"og:site_name\" content=\"Loginfo24\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/\" \/>\n<meta property=\"article:published_time\" content=\"2021-04-21T16:26:46+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-12-15T11:59:39+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2021\\\/04\\\/21\\\/nexxiot-supporta-jaeger-bernburg-nelluso-ecologico-dei-veicoli\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2021\\\/04\\\/21\\\/nexxiot-supporta-jaeger-bernburg-nelluso-ecologico-dei-veicoli\\\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Nexxiot supporta Jaeger Bernburg nell&#8217;uso ecologico dei veicoli\",\"datePublished\":\"2021-04-21T16:26:46+00:00\",\"dateModified\":\"2025-12-15T11:59:39+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2021\\\/04\\\/21\\\/nexxiot-supporta-jaeger-bernburg-nelluso-ecologico-dei-veicoli\\\/\"},\"wordCount\":537,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#organization\"},\"articleSection\":[\"Categories\",\"Forwarding &amp; Logistics\",\"Regions\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/it\\\/2021\\\/04\\\/21\\\/nexxiot-supporta-jaeger-bernburg-nelluso-ecologico-dei-veicoli\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2021\\\/04\\\/21\\\/nexxiot-supporta-jaeger-bernburg-nelluso-ecologico-dei-veicoli\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2021\\\/04\\\/21\\\/nexxiot-supporta-jaeger-bernburg-nelluso-ecologico-dei-veicoli\\\/\",\"name\":\"Nexxiot supporta Jaeger Bernburg nell'uso ecologico dei veicoli - Loginfo24\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#website\"},\"datePublished\":\"2021-04-21T16:26:46+00:00\",\"dateModified\":\"2025-12-15T11:59:39+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2021\\\/04\\\/21\\\/nexxiot-supporta-jaeger-bernburg-nelluso-ecologico-dei-veicoli\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/it\\\/2021\\\/04\\\/21\\\/nexxiot-supporta-jaeger-bernburg-nelluso-ecologico-dei-veicoli\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2021\\\/04\\\/21\\\/nexxiot-supporta-jaeger-bernburg-nelluso-ecologico-dei-veicoli\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Nexxiot supporta Jaeger Bernburg nell&#8217;uso ecologico dei veicoli\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/\",\"name\":\"Loginfo24\",\"description\":\"Loginfo24 \u00e8 la piattaforma dedicata alla logistica e alle catene di fornitura con informazioni disponibili 24 ore su 24.\",\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#organization\",\"name\":\"Logismedia Group AG\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"width\":938,\"height\":351,\"caption\":\"Logismedia Group AG\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/people\\\/Loginfo24\\\/100057360583332\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/lofinfo24\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Nexxiot supporta Jaeger Bernburg nell'uso ecologico dei veicoli - Loginfo24","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/loginfo24.com\/it\/2021\/04\/21\/nexxiot-supporta-jaeger-bernburg-nelluso-ecologico-dei-veicoli\/","og_locale":"it_IT","og_type":"article","og_title":"Nexxiot supporta Jaeger Bernburg nell'uso ecologico dei veicoli - Loginfo24","og_description":"Jaeger Bernburg utilizza la tecnologia Nexxiot nella sua azienda ferroviaria per digitalizzare la propria flotta e rendere l&#8217;uso dei veicoli ferroviari pi\u00f9 economico ed ecologico. Al [\u2026]","og_url":"https:\/\/loginfo24.com\/it\/2021\/04\/21\/nexxiot-supporta-jaeger-bernburg-nelluso-ecologico-dei-veicoli\/","og_site_name":"Loginfo24","article_publisher":"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","article_published_time":"2021-04-21T16:26:46+00:00","article_modified_time":"2025-12-15T11:59:39+00:00","twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"3 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/loginfo24.com\/it\/2021\/04\/21\/nexxiot-supporta-jaeger-bernburg-nelluso-ecologico-dei-veicoli\/#article","isPartOf":{"@id":"https:\/\/loginfo24.com\/it\/2021\/04\/21\/nexxiot-supporta-jaeger-bernburg-nelluso-ecologico-dei-veicoli\/"},"author":{"name":"","@id":""},"headline":"Nexxiot supporta Jaeger Bernburg nell&#8217;uso ecologico dei veicoli","datePublished":"2021-04-21T16:26:46+00:00","dateModified":"2025-12-15T11:59:39+00:00","mainEntityOfPage":{"@id":"https:\/\/loginfo24.com\/it\/2021\/04\/21\/nexxiot-supporta-jaeger-bernburg-nelluso-ecologico-dei-veicoli\/"},"wordCount":537,"commentCount":0,"publisher":{"@id":"https:\/\/loginfo24.com\/it\/#organization"},"articleSection":["Categories","Forwarding &amp; Logistics","Regions"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/loginfo24.com\/it\/2021\/04\/21\/nexxiot-supporta-jaeger-bernburg-nelluso-ecologico-dei-veicoli\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/loginfo24.com\/it\/2021\/04\/21\/nexxiot-supporta-jaeger-bernburg-nelluso-ecologico-dei-veicoli\/","url":"https:\/\/loginfo24.com\/it\/2021\/04\/21\/nexxiot-supporta-jaeger-bernburg-nelluso-ecologico-dei-veicoli\/","name":"Nexxiot supporta Jaeger Bernburg nell'uso ecologico dei veicoli - Loginfo24","isPartOf":{"@id":"https:\/\/loginfo24.com\/it\/#website"},"datePublished":"2021-04-21T16:26:46+00:00","dateModified":"2025-12-15T11:59:39+00:00","breadcrumb":{"@id":"https:\/\/loginfo24.com\/it\/2021\/04\/21\/nexxiot-supporta-jaeger-bernburg-nelluso-ecologico-dei-veicoli\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/loginfo24.com\/it\/2021\/04\/21\/nexxiot-supporta-jaeger-bernburg-nelluso-ecologico-dei-veicoli\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/loginfo24.com\/it\/2021\/04\/21\/nexxiot-supporta-jaeger-bernburg-nelluso-ecologico-dei-veicoli\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/loginfo24.com\/it\/"},{"@type":"ListItem","position":2,"name":"Nexxiot supporta Jaeger Bernburg nell&#8217;uso ecologico dei veicoli"}]},{"@type":"WebSite","@id":"https:\/\/loginfo24.com\/it\/#website","url":"https:\/\/loginfo24.com\/it\/","name":"Loginfo24","description":"Loginfo24 \u00e8 la piattaforma dedicata alla logistica e alle catene di fornitura con informazioni disponibili 24 ore su 24.","publisher":{"@id":"https:\/\/loginfo24.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/loginfo24.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/loginfo24.com\/it\/#organization","name":"Logismedia Group AG","url":"https:\/\/loginfo24.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/loginfo24.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","width":938,"height":351,"caption":"Logismedia Group AG"},"image":{"@id":"https:\/\/loginfo24.com\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","https:\/\/www.linkedin.com\/company\/lofinfo24\/"]}]}},"_links":{"self":[{"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/posts\/24868","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/comments?post=24868"}],"version-history":[{"count":1,"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/posts\/24868\/revisions"}],"predecessor-version":[{"id":45448,"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/posts\/24868\/revisions\/45448"}],"wp:attachment":[{"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/media?parent=24868"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/categories?post=24868"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/tags?post=24868"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}