{"id":24531,"date":"2021-04-08T18:44:11","date_gmt":"2021-04-08T16:44:11","guid":{"rendered":"https:\/\/blog.brand-architecture.at\/2021\/04\/08\/witron-presenta-buoni-risultati-per-lanno-fiscale-2020\/"},"modified":"2025-12-15T12:58:04","modified_gmt":"2025-12-15T11:58:04","slug":"witron-presenta-buoni-risultati-per-lanno-fiscale-2020","status":"publish","type":"post","link":"https:\/\/loginfo24.com\/it\/2021\/04\/08\/witron-presenta-buoni-risultati-per-lanno-fiscale-2020\/","title":{"rendered":"WITRON presenta buoni risultati per l&#8217;anno fiscale 2020"},"content":{"rendered":"<p>WITRON compie 50 anni e ha creato, nonostante la pandemia globale di Corona, una solida base per il 2021 nell&#8217;anno fiscale 2020: nuovi progetti, 110 milioni di euro in pi\u00f9 di fatturato, 500 nuovi dipendenti, 106 nuovi apprendisti e un raddoppio della superficie produttiva fanno s\u00ec che l&#8217;appaltatore generale di Parkstein guardi ancora con fiducia al futuro.<\/p>\n<p>(Parkstein) I concetti innovativi di soluzioni e gestione di WITRON hanno un ottimo nome anche in tempi economici difficili nel mercato della logistica. Questo \u00e8 dimostrato dagli ordini ricevuti, che nell&#8217;anno fiscale passato hanno superato il miliardo di euro. A questo hanno contribuito le firme di contratti con importanti aziende commerciali in Europa e Nord America, che si fidano delle strategie omnicanale di WITRON nei loro centri di logistica alimentare e non alimentare. La decisione di puntare su settori resistenti alle crisi e rilevanti per il sistema si \u00e8 rivelata a lungo termine corretta, poich\u00e9 attualmente circa il 90% del fatturato viene generato con clienti nei settori del commercio e della distribuzione.<\/p>\n<h5><strong>Premio dal Ministero dello Stato bavarese<\/strong><\/h5>\n<p>Il fatturato \u00e8 stato aumentato da 600 milioni di euro a 710 milioni di euro, il che ha comportato l&#8217;assunzione di 500 nuovi dipendenti. Attualmente, 4.500 dipendenti lavorano in tutto il mondo per il gruppo WITRON, circa 2.000 di questi sono impiegati nella sede centrale nella parte settentrionale della Baviera. Grazie allo sviluppo commerciale costantemente positivo sin dalla fondazione dell&#8217;azienda, l&#8217;azienda familiare \u00e8 stata premiata dal Ministero bavarese per l&#8217;Economia, lo Sviluppo Regionale e l&#8217;Energia con il premio &#8220;Bayerns Best 50&#8221; \u2013 conferito per la crescita superiore alla media nelle PMI. &#8220;Questo premio \u00e8 un segnale positivo non solo per noi come azienda e datore di lavoro, ma anche per la nostra regione. Siamo molto orgogliosi di essere tra le migliori PMI della Baviera \u2013 questo \u00e8 un chiaro segnale che il duro lavoro e l&#8217;impegno di anni vengono premiati&#8221;, si rallegrano il fondatore dell&#8217;azienda Walter Winkler.<\/p>\n<h5><strong>Oltre 100 nuovi apprendisti iniziano la carriera professionale<\/strong><\/h5>\n<p>WITRON continua a dare grande importanza alla formazione dei propri dipendenti. Questo si riflette nel fatto che per la seconda volta consecutiva sono stati assunti oltre 100 apprendisti per iniziare la loro carriera professionale in uno dei 17 diversi indirizzi di formazione tecnica e commerciale. Attualmente, WITRON impiega quasi 300 apprendisti, il tasso di assunzione dopo la formazione \u00e8 vicino al 100%. L&#8217;alto impegno degli apprendisti e dei formatori \u00e8 dimostrato ogni anno da numerosi vincitori di camere e campionati regionali.<\/p>\n<h5><strong>Johannes Schweiger rafforza la direzione aziendale<\/strong><\/h5>\n<p>Un mercato di crescita significativo \u00e8 ancora il business dei servizi in continua espansione, poich\u00e9 sempre pi\u00f9 clienti affidano a WITRON la responsabilit\u00e0 delle loro strutture logistiche come partner a lungo termine. Questo settore comprende ormai pi\u00f9 della met\u00e0 del personale di WITRON. Per coprire in modo ottimale la variet\u00e0 di temi e l&#8217;internazionalit\u00e0 che ne derivano, sia a livello personale, funzionale che culturale, Johannes Schweiger ha rafforzato la direzione del servizio WITRON da maggio 2020. Condivide compiti e responsabilit\u00e0 con il direttore Christian Dietl. Il 33enne laureato in economia J. Schweiger lavora gi\u00e0 in WITRON dal 2013 e ha implementato con successo diversi progetti nel settore delle risorse umane nazionali e internazionali. A livello di gruppo, Helmut Prieschenk, Johannes Mei\u00dfner e Martin Stich fanno parte del team di direzione di cinque membri:<\/p>\n<h5><strong>Prossimo passo evolutivo: piattaforma Retail Omni Channel Machinery<\/strong><\/h5>\n<p>Dopo che la soluzione OPM nella sua quarta generazione si \u00e8 praticamente sviluppata in uno standard nella logistica alimentare automatizzata, i Parksteiner stanno ora facendo un passo avanti. Anche se attualmente la maggior parte del volume nel commercio al dettaglio alimentare continua a essere gestita tramite filiali, quasi tutti i rivenditori in Europa e Nord America stanno cercando soluzioni omnicanale ragionevoli \u2013 con approcci talvolta diversi. L&#8217;obiettivo \u00e8 chiaro: soddisfare con successo tutti i canali dei clienti come ad esempio il commercio al dettaglio, Click &amp; Collect, consegna a domicilio, drive e convenience store \u2013 e allo stesso tempo garantire l&#8217;integrazione end-to-end di tutti i collegamenti nella catena di approvvigionamento come fornitori, centri logistici e trasporti. Il successo si riferisce in particolare a quattro temi chiave: massimo servizio al cliente finale, ottimizzazione economica complessiva, flessibilit\u00e0 operativa e strategica e sostenibilit\u00e0. Proprio queste quattro dimensioni sono nel mirino dei Parksteiner. Con quasi due decenni di utilizzo pratico dell&#8217;OPM e la fornitura quotidiana di circa 35.000 filiali e 100 milioni di clienti finali da oltre 80 centri di distribuzione OPM, WITRON dispone di enormi esperienze e know-how in merito alle reti nel settore del commercio alimentare. Su questa base \u00e8 stata sviluppata l&#8217;Omni Channel Machinery (OCM), che affronta in modo coerente il tema della distribuzione multicanale come piattaforma logistica. In particolare, per quanto riguarda l&#8217;economicit\u00e0 della rete, sono stati implementati i seguenti principi fondamentali: \u2022 Integrazione invece di mondi paralleli e complessa atomizzazione \u2022 Utilizzo di sinergie invece di moltiplicare gli stessi processi per canali diversi \u2022 Focus su un&#8217;economicit\u00e0 complessiva della rete invece di ottimizzare i silos. I progetti con la soluzione OCM sono gi\u00e0 in fase di realizzazione, come ad esempio presso Axfood (Svezia) e Migros (Svizzera) \u2013 e sono in fase di pianificazione concreta con ulteriori clienti<\/p>\n<h5><strong>Nuova costruzione per la produzione di tecnologia di trasporto in perfetto tempo<\/strong><\/h5>\n<p>Ci sono grandi progressi dal cantiere di Parkstein. La nuova costruzione di 120.000 m\u00b2, iniziata alla fine del 2019, in cui oltre a capacit\u00e0 produttive aggiuntive per la produzione meccanica di WITRON verranno creati anche molti uffici per sviluppatori di software e ingegneri, sta procedendo secondo i tempi previsti. L&#8217;investimento ammonta a circa 160 milioni di euro. Dopo la prevista conclusione \u2013 puntuale per il 50\u00b0 anniversario dell&#8217;azienda quest&#8217;anno \u2013 l&#8217;intera superficie produttiva di WITRON superer\u00e0 i 212.000 m\u00b2. Foto: \u00a9 WITRON \/ <strong><em>Didascalia dell&#8217;immagine:<\/em><\/strong><em> Inaugurato nell&#8217;anno del giubileo: un nuovo stabilimento di produzione di 120.000 m\u00b2 a Parkstein (tutto a destra)<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>WITRON compie 50 anni e ha creato, nonostante la pandemia globale di Corona, una solida base per il 2021 nell&#8217;anno fiscale 2020: nuovi progetti, 110 milioni<span class=\"excerpt-hellip\"> [\u2026]<\/span><\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1557,1560,1561],"tags":[],"class_list":["post-24531","post","type-post","status-publish","format-standard","hentry","category-forwarding-logistics","category-intralogistics","category-regions"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>WITRON presenta buoni risultati per l&#039;anno fiscale 2020 - Loginfo24<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/loginfo24.com\/it\/2021\/04\/08\/witron-presenta-buoni-risultati-per-lanno-fiscale-2020\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"WITRON presenta buoni risultati per l&#039;anno fiscale 2020 - Loginfo24\" \/>\n<meta property=\"og:description\" content=\"WITRON compie 50 anni e ha creato, nonostante la pandemia globale di Corona, una solida base per il 2021 nell&#8217;anno fiscale 2020: nuovi progetti, 110 milioni [\u2026]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/loginfo24.com\/it\/2021\/04\/08\/witron-presenta-buoni-risultati-per-lanno-fiscale-2020\/\" \/>\n<meta property=\"og:site_name\" content=\"Loginfo24\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/\" \/>\n<meta property=\"article:published_time\" content=\"2021-04-08T16:44:11+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-12-15T11:58:04+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"5 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2021\\\/04\\\/08\\\/witron-presenta-buoni-risultati-per-lanno-fiscale-2020\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2021\\\/04\\\/08\\\/witron-presenta-buoni-risultati-per-lanno-fiscale-2020\\\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"WITRON presenta buoni risultati per l&#8217;anno fiscale 2020\",\"datePublished\":\"2021-04-08T16:44:11+00:00\",\"dateModified\":\"2025-12-15T11:58:04+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2021\\\/04\\\/08\\\/witron-presenta-buoni-risultati-per-lanno-fiscale-2020\\\/\"},\"wordCount\":950,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#organization\"},\"articleSection\":[\"Forwarding &amp; Logistics\",\"Intralogistics\",\"Regions\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/it\\\/2021\\\/04\\\/08\\\/witron-presenta-buoni-risultati-per-lanno-fiscale-2020\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2021\\\/04\\\/08\\\/witron-presenta-buoni-risultati-per-lanno-fiscale-2020\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2021\\\/04\\\/08\\\/witron-presenta-buoni-risultati-per-lanno-fiscale-2020\\\/\",\"name\":\"WITRON presenta buoni risultati per l'anno fiscale 2020 - Loginfo24\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#website\"},\"datePublished\":\"2021-04-08T16:44:11+00:00\",\"dateModified\":\"2025-12-15T11:58:04+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2021\\\/04\\\/08\\\/witron-presenta-buoni-risultati-per-lanno-fiscale-2020\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/it\\\/2021\\\/04\\\/08\\\/witron-presenta-buoni-risultati-per-lanno-fiscale-2020\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2021\\\/04\\\/08\\\/witron-presenta-buoni-risultati-per-lanno-fiscale-2020\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"WITRON presenta buoni risultati per l&#8217;anno fiscale 2020\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/\",\"name\":\"Loginfo24\",\"description\":\"Loginfo24 \u00e8 la piattaforma dedicata alla logistica e alle catene di fornitura con informazioni disponibili 24 ore su 24.\",\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#organization\",\"name\":\"Logismedia Group AG\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"width\":938,\"height\":351,\"caption\":\"Logismedia Group AG\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/people\\\/Loginfo24\\\/100057360583332\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/lofinfo24\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"WITRON presenta buoni risultati per l'anno fiscale 2020 - Loginfo24","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/loginfo24.com\/it\/2021\/04\/08\/witron-presenta-buoni-risultati-per-lanno-fiscale-2020\/","og_locale":"it_IT","og_type":"article","og_title":"WITRON presenta buoni risultati per l'anno fiscale 2020 - Loginfo24","og_description":"WITRON compie 50 anni e ha creato, nonostante la pandemia globale di Corona, una solida base per il 2021 nell&#8217;anno fiscale 2020: nuovi progetti, 110 milioni [\u2026]","og_url":"https:\/\/loginfo24.com\/it\/2021\/04\/08\/witron-presenta-buoni-risultati-per-lanno-fiscale-2020\/","og_site_name":"Loginfo24","article_publisher":"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","article_published_time":"2021-04-08T16:44:11+00:00","article_modified_time":"2025-12-15T11:58:04+00:00","twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"5 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/loginfo24.com\/it\/2021\/04\/08\/witron-presenta-buoni-risultati-per-lanno-fiscale-2020\/#article","isPartOf":{"@id":"https:\/\/loginfo24.com\/it\/2021\/04\/08\/witron-presenta-buoni-risultati-per-lanno-fiscale-2020\/"},"author":{"name":"","@id":""},"headline":"WITRON presenta buoni risultati per l&#8217;anno fiscale 2020","datePublished":"2021-04-08T16:44:11+00:00","dateModified":"2025-12-15T11:58:04+00:00","mainEntityOfPage":{"@id":"https:\/\/loginfo24.com\/it\/2021\/04\/08\/witron-presenta-buoni-risultati-per-lanno-fiscale-2020\/"},"wordCount":950,"commentCount":0,"publisher":{"@id":"https:\/\/loginfo24.com\/it\/#organization"},"articleSection":["Forwarding &amp; Logistics","Intralogistics","Regions"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/loginfo24.com\/it\/2021\/04\/08\/witron-presenta-buoni-risultati-per-lanno-fiscale-2020\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/loginfo24.com\/it\/2021\/04\/08\/witron-presenta-buoni-risultati-per-lanno-fiscale-2020\/","url":"https:\/\/loginfo24.com\/it\/2021\/04\/08\/witron-presenta-buoni-risultati-per-lanno-fiscale-2020\/","name":"WITRON presenta buoni risultati per l'anno fiscale 2020 - Loginfo24","isPartOf":{"@id":"https:\/\/loginfo24.com\/it\/#website"},"datePublished":"2021-04-08T16:44:11+00:00","dateModified":"2025-12-15T11:58:04+00:00","breadcrumb":{"@id":"https:\/\/loginfo24.com\/it\/2021\/04\/08\/witron-presenta-buoni-risultati-per-lanno-fiscale-2020\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/loginfo24.com\/it\/2021\/04\/08\/witron-presenta-buoni-risultati-per-lanno-fiscale-2020\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/loginfo24.com\/it\/2021\/04\/08\/witron-presenta-buoni-risultati-per-lanno-fiscale-2020\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/loginfo24.com\/it\/"},{"@type":"ListItem","position":2,"name":"WITRON presenta buoni risultati per l&#8217;anno fiscale 2020"}]},{"@type":"WebSite","@id":"https:\/\/loginfo24.com\/it\/#website","url":"https:\/\/loginfo24.com\/it\/","name":"Loginfo24","description":"Loginfo24 \u00e8 la piattaforma dedicata alla logistica e alle catene di fornitura con informazioni disponibili 24 ore su 24.","publisher":{"@id":"https:\/\/loginfo24.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/loginfo24.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/loginfo24.com\/it\/#organization","name":"Logismedia Group AG","url":"https:\/\/loginfo24.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/loginfo24.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","width":938,"height":351,"caption":"Logismedia Group AG"},"image":{"@id":"https:\/\/loginfo24.com\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","https:\/\/www.linkedin.com\/company\/lofinfo24\/"]}]}},"_links":{"self":[{"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/posts\/24531","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/comments?post=24531"}],"version-history":[{"count":1,"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/posts\/24531\/revisions"}],"predecessor-version":[{"id":44780,"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/posts\/24531\/revisions\/44780"}],"wp:attachment":[{"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/media?parent=24531"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/categories?post=24531"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/tags?post=24531"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}