{"id":23075,"date":"2021-02-04T18:51:42","date_gmt":"2021-02-04T17:51:42","guid":{"rendered":"https:\/\/blog.brand-architecture.at\/2021\/02\/04\/il-sviluppatore-software-lis-ag-avvia-un-nuovo-centro-dati\/"},"modified":"2025-12-15T12:51:25","modified_gmt":"2025-12-15T11:51:25","slug":"il-sviluppatore-software-lis-ag-avvia-un-nuovo-centro-dati","status":"publish","type":"post","link":"https:\/\/loginfo24.com\/it\/2021\/02\/04\/il-sviluppatore-software-lis-ag-avvia-un-nuovo-centro-dati\/","title":{"rendered":"Il sviluppatore software LIS AG avvia un nuovo centro dati"},"content":{"rendered":"<p>Il sviluppatore software LIS AG registra un aumento dell&#8217;interesse per il sistema di gestione dei trasporti basato su cloud TMS WinSped. Una nuova infrastruttura IT aumenta le capacit\u00e0 per utenti aggiuntivi. La nuova sala server \u00e8 stata progettata e costruita secondo la norma DIN EN 50600.<\/p>\n<p>(Greven) La LIS Logistische Informationssysteme AG ha completato i lavori di costruzione del suo nuovo centro dati. Con la nuova e pi\u00f9 grande sala server presso la sede centrale di Greven, il sviluppatore software risponde alla crescente domanda dei clienti per un&#8217;applicazione online del suo sistema di gestione dei trasporti (TMS) WinSped. Grazie alla soluzione cloud, i trasportatori e i caricatori possono pianificare e monitorare le loro rotte in modo indipendente dalla posizione. Gi\u00e0 64 aziende utilizzano la variante supportata da server.<\/p>\n<h5>Strutture IT moderne sono rilevanti<\/h5>\n<p> &#8220;In particolare, i mesi passati in smart working hanno dimostrato quanto siano rilevanti le strutture IT moderne. Con l&#8217;accesso a WinSped tramite una semplice connessione Internet, aiutiamo le aziende di logistica ad agire in modo flessibile e indipendente&#8221;, afferma Rolf Hansmann, membro del consiglio di amministrazione della LIS Logistische Informationssysteme AG. &#8220;In questo modo diventano pi\u00f9 resilienti contro tali influenze esterne come una pandemia&#8221;, aggiunge Hansmann. Oltre alla maggiore capacit\u00e0 di adattamento e resilienza, gli utenti del centro dati beneficiano di ulteriori vantaggi. I servizi di backup e aggiornamento, ad esempio, vengono eseguiti automaticamente. Inoltre, grazie all&#8217;utilizzo dei server LIS, non ci sono costi per hardware e manutenzione altrimenti necessari. Ci\u00f2 elimina anche il lavoro aggiuntivo per l&#8217;implementazione e il personale per il backup dei dati. \u00c8 anche possibile collegare ulteriori dispositivi e postazioni di lavoro senza problemi. La sala con un totale di dieci nuovi server presso la sede centrale di Greven \u00e8 stata progettata e costruita secondo la norma DIN EN 50600, e una certificazione \u00e8 prevista per il primo trimestre di quest&#8217;anno. Insieme, dispongono di 7,5 terabyte di memoria RAM, oltre 100 terabyte di spazio di archiviazione e 240 core CPU (Central Processing Unit). C&#8217;\u00e8 anche spazio sufficiente per future espansioni, poich\u00e9 attualmente cinque armadi server sono occupati solo per met\u00e0.<\/p>\n<h5><strong>Sistema antincendio e alimentazione di emergenza<\/strong><\/h5>\n<p> La sicurezza \u00e8 garantita da sistemi di allerta contro le intrusioni e gli incendi. Inoltre, il sistema dispone di un&#8217;alimentazione elettrica ininterrotta (UPS), che pu\u00f2 fornire energia ai nostri sistemi per oltre un&#8217;ora in caso di interruzione di corrente. In questo modo rimane operativo anche durante un blackout. Nel caso improbabile di un blackout, entra in funzione un generatore di emergenza. Oltre all&#8217;alimentazione, anche il raffreddamento \u00e8 progettato in modo ridondante. Due sistemi indipendenti raffreddano il corridoio freddo. Inoltre, i server sono dimensionati in modo tale da poter sopportare anche il guasto di due macchine: in una seconda sala server in un edificio separato, LIS fornisce una potenza server simile per poter ripristinare l&#8217;ambiente in caso di perdita della sala server principale. Questo scenario viene provato una volta al mese. Foto: \u00a9 LIS <a href=\"https:\/\/www.lis.eu\" target=\"_blank\" rel=\"noopener noreferrer\">www.lis.eu<\/a>\u00a0\u00a0\u00a0\u00a0\u00a0 <a href=\"https:\/\/www.lis.eu\/service\/lis-cloud-services\/\" target=\"_blank\" rel=\"noopener noreferrer\">www.lis.eu\/service\/lis-cloud-services\/<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il sviluppatore software LIS AG registra un aumento dell&#8217;interesse per il sistema di gestione dei trasporti basato su cloud TMS WinSped. Una nuova infrastruttura IT aumenta<span class=\"excerpt-hellip\"> [\u2026]<\/span><\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1665,1557,1561],"tags":[],"class_list":["post-23075","post","type-post","status-publish","format-standard","hentry","category-categories","category-forwarding-logistics","category-regions"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Il sviluppatore software LIS AG avvia un nuovo centro dati - Loginfo24<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/loginfo24.com\/it\/2021\/02\/04\/il-sviluppatore-software-lis-ag-avvia-un-nuovo-centro-dati\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Il sviluppatore software LIS AG avvia un nuovo centro dati - Loginfo24\" \/>\n<meta property=\"og:description\" content=\"Il sviluppatore software LIS AG registra un aumento dell&#8217;interesse per il sistema di gestione dei trasporti basato su cloud TMS WinSped. Una nuova infrastruttura IT aumenta [\u2026]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/loginfo24.com\/it\/2021\/02\/04\/il-sviluppatore-software-lis-ag-avvia-un-nuovo-centro-dati\/\" \/>\n<meta property=\"og:site_name\" content=\"Loginfo24\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/\" \/>\n<meta property=\"article:published_time\" content=\"2021-02-04T17:51:42+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-12-15T11:51:25+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2021\\\/02\\\/04\\\/il-sviluppatore-software-lis-ag-avvia-un-nuovo-centro-dati\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2021\\\/02\\\/04\\\/il-sviluppatore-software-lis-ag-avvia-un-nuovo-centro-dati\\\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Il sviluppatore software LIS AG avvia un nuovo centro dati\",\"datePublished\":\"2021-02-04T17:51:42+00:00\",\"dateModified\":\"2025-12-15T11:51:25+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2021\\\/02\\\/04\\\/il-sviluppatore-software-lis-ag-avvia-un-nuovo-centro-dati\\\/\"},\"wordCount\":501,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#organization\"},\"articleSection\":[\"Categories\",\"Forwarding &amp; Logistics\",\"Regions\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/it\\\/2021\\\/02\\\/04\\\/il-sviluppatore-software-lis-ag-avvia-un-nuovo-centro-dati\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2021\\\/02\\\/04\\\/il-sviluppatore-software-lis-ag-avvia-un-nuovo-centro-dati\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2021\\\/02\\\/04\\\/il-sviluppatore-software-lis-ag-avvia-un-nuovo-centro-dati\\\/\",\"name\":\"Il sviluppatore software LIS AG avvia un nuovo centro dati - Loginfo24\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#website\"},\"datePublished\":\"2021-02-04T17:51:42+00:00\",\"dateModified\":\"2025-12-15T11:51:25+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2021\\\/02\\\/04\\\/il-sviluppatore-software-lis-ag-avvia-un-nuovo-centro-dati\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/it\\\/2021\\\/02\\\/04\\\/il-sviluppatore-software-lis-ag-avvia-un-nuovo-centro-dati\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2021\\\/02\\\/04\\\/il-sviluppatore-software-lis-ag-avvia-un-nuovo-centro-dati\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Il sviluppatore software LIS AG avvia un nuovo centro dati\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/\",\"name\":\"Loginfo24\",\"description\":\"Loginfo24 \u00e8 la piattaforma dedicata alla logistica e alle catene di fornitura con informazioni disponibili 24 ore su 24.\",\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#organization\",\"name\":\"Logismedia Group AG\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"width\":938,\"height\":351,\"caption\":\"Logismedia Group AG\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/people\\\/Loginfo24\\\/100057360583332\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/lofinfo24\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Il sviluppatore software LIS AG avvia un nuovo centro dati - Loginfo24","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/loginfo24.com\/it\/2021\/02\/04\/il-sviluppatore-software-lis-ag-avvia-un-nuovo-centro-dati\/","og_locale":"it_IT","og_type":"article","og_title":"Il sviluppatore software LIS AG avvia un nuovo centro dati - Loginfo24","og_description":"Il sviluppatore software LIS AG registra un aumento dell&#8217;interesse per il sistema di gestione dei trasporti basato su cloud TMS WinSped. Una nuova infrastruttura IT aumenta [\u2026]","og_url":"https:\/\/loginfo24.com\/it\/2021\/02\/04\/il-sviluppatore-software-lis-ag-avvia-un-nuovo-centro-dati\/","og_site_name":"Loginfo24","article_publisher":"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","article_published_time":"2021-02-04T17:51:42+00:00","article_modified_time":"2025-12-15T11:51:25+00:00","twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"2 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/loginfo24.com\/it\/2021\/02\/04\/il-sviluppatore-software-lis-ag-avvia-un-nuovo-centro-dati\/#article","isPartOf":{"@id":"https:\/\/loginfo24.com\/it\/2021\/02\/04\/il-sviluppatore-software-lis-ag-avvia-un-nuovo-centro-dati\/"},"author":{"name":"","@id":""},"headline":"Il sviluppatore software LIS AG avvia un nuovo centro dati","datePublished":"2021-02-04T17:51:42+00:00","dateModified":"2025-12-15T11:51:25+00:00","mainEntityOfPage":{"@id":"https:\/\/loginfo24.com\/it\/2021\/02\/04\/il-sviluppatore-software-lis-ag-avvia-un-nuovo-centro-dati\/"},"wordCount":501,"commentCount":0,"publisher":{"@id":"https:\/\/loginfo24.com\/it\/#organization"},"articleSection":["Categories","Forwarding &amp; Logistics","Regions"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/loginfo24.com\/it\/2021\/02\/04\/il-sviluppatore-software-lis-ag-avvia-un-nuovo-centro-dati\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/loginfo24.com\/it\/2021\/02\/04\/il-sviluppatore-software-lis-ag-avvia-un-nuovo-centro-dati\/","url":"https:\/\/loginfo24.com\/it\/2021\/02\/04\/il-sviluppatore-software-lis-ag-avvia-un-nuovo-centro-dati\/","name":"Il sviluppatore software LIS AG avvia un nuovo centro dati - Loginfo24","isPartOf":{"@id":"https:\/\/loginfo24.com\/it\/#website"},"datePublished":"2021-02-04T17:51:42+00:00","dateModified":"2025-12-15T11:51:25+00:00","breadcrumb":{"@id":"https:\/\/loginfo24.com\/it\/2021\/02\/04\/il-sviluppatore-software-lis-ag-avvia-un-nuovo-centro-dati\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/loginfo24.com\/it\/2021\/02\/04\/il-sviluppatore-software-lis-ag-avvia-un-nuovo-centro-dati\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/loginfo24.com\/it\/2021\/02\/04\/il-sviluppatore-software-lis-ag-avvia-un-nuovo-centro-dati\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/loginfo24.com\/it\/"},{"@type":"ListItem","position":2,"name":"Il sviluppatore software LIS AG avvia un nuovo centro dati"}]},{"@type":"WebSite","@id":"https:\/\/loginfo24.com\/it\/#website","url":"https:\/\/loginfo24.com\/it\/","name":"Loginfo24","description":"Loginfo24 \u00e8 la piattaforma dedicata alla logistica e alle catene di fornitura con informazioni disponibili 24 ore su 24.","publisher":{"@id":"https:\/\/loginfo24.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/loginfo24.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/loginfo24.com\/it\/#organization","name":"Logismedia Group AG","url":"https:\/\/loginfo24.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/loginfo24.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","width":938,"height":351,"caption":"Logismedia Group AG"},"image":{"@id":"https:\/\/loginfo24.com\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","https:\/\/www.linkedin.com\/company\/lofinfo24\/"]}]}},"_links":{"self":[{"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/posts\/23075","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/comments?post=23075"}],"version-history":[{"count":1,"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/posts\/23075\/revisions"}],"predecessor-version":[{"id":41876,"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/posts\/23075\/revisions\/41876"}],"wp:attachment":[{"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/media?parent=23075"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/categories?post=23075"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/tags?post=23075"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}