{"id":22994,"date":"2021-02-01T17:56:21","date_gmt":"2021-02-01T16:56:21","guid":{"rendered":"https:\/\/blog.brand-architecture.at\/2021\/02\/01\/astag-vede-dopo-20-anni-di-lsva-le-emissioni-inquinanti-a-zero\/"},"modified":"2025-12-15T12:50:59","modified_gmt":"2025-12-15T11:50:59","slug":"astag-vede-dopo-20-anni-di-lsva-le-emissioni-inquinanti-a-zero","status":"publish","type":"post","link":"https:\/\/loginfo24.com\/it\/2021\/02\/01\/astag-vede-dopo-20-anni-di-lsva-le-emissioni-inquinanti-a-zero\/","title":{"rendered":"ASTAG vede dopo 20 anni di LSVA le emissioni inquinanti a zero"},"content":{"rendered":"<p>L&#8217;associazione svizzera dei veicoli commerciali ASTAG sottolinea che da esattamente 20 anni il settore del trasporto su strada contribuisce in modo efficace alla politica di trasferimento con pagamenti LSVA per un totale di oltre 25 miliardi di franchi. In relazione alla riforma annunciata del sistema tariffario, l&#8217;ASTAG \u00e8 pronta a discussioni, ma richiede sicurezza nella pianificazione e negli investimenti per il trasporto su strada. Gli obiettivi ambientali della LSVA sono stati raggiunti. Ora le regole del gioco non devono essere cambiate.<\/p>\n<p>(Berna) L&#8217;imposta sul traffico pesante dipendente dalle prestazioni (LSVA) \u00e8 il fattore principale nel carico di costi statali nel settore del trasporto su strada svizzero. Esattamente 20 anni fa, il 31 gennaio 2001, \u00e8 stata la data di inizio del primo periodo di fatturazione. Da allora, \u00e8 dovuto circa 1 franco per ogni singolo chilometro percorso da un camion da 40 tonnellate. Questo comporta, a seconda della prestazione di guida e della categoria di emissioni*, fino a 100&#8217;000 franchi all&#8217;anno per veicolo commerciale \u2013 a favore delle casse federali, prima che le aziende di trasporto guadagnino anche solo un centesimo. In nessun altro paese la tassa \u00e8 cos\u00ec alta. Nel frattempo, ogni anno si accumulano 1,5 miliardi di franchi, e dal 2001 sono oltre 25 miliardi di franchi. Due terzi vengono utilizzati per legge direttamente per finanziare l&#8217;infrastruttura ferroviaria. Il trasporto su strada contribuisce quindi attivamente e in modo efficace alla politica di trasferimento.<\/p>\n<h5><strong>Un tema emotivo \u2013 massiccia distruzione di valore<\/strong><\/h5>\n<p> Tuttavia, l&#8217;associazione svizzera dei veicoli commerciali ASTAG guarda pi\u00f9 avanti che indietro a una storia della LSVA estremamente variabile ed emotiva. Troppo spesso, le giuste preoccupazioni e argomentazioni del settore del trasporto su strada non sono state considerate dalla politica in passato \u2013 in particolare fino al 2010. Le conseguenze negative sono state massicci aumenti delle tariffe LSVA e cambiamenti arbitrari e prematuri delle categorie di imposta (\u201cdeclassamenti\u201d). Il valore di acquisto dei veicoli \u00e8 stato cos\u00ec pi\u00f9 di una volta ridotto drammaticamente o addirittura completamente annullato. &#8220;Capisco molto bene l&#8217;amarezza e le emozioni che molti dei nostri membri provano riguardo alla LSVA&#8221;, afferma il consigliere agli Stati e presidente centrale dell&#8217;ASTAG Thierry Burkart: &#8220;Non da ultimo a causa della LSVA, molte piccole e medie imprese sono scomparse dal mercato!&#8221;<br \/> \u00c8 quindi ancora pi\u00f9 importante che l&#8217;equit\u00e0, la proporzionalit\u00e0 e &#8220;l&#8217;effetto sull&#8217;obiettivo&#8221; siano rispettati nello sviluppo annunciato della LSVA. L&#8217;ASTAG prende atto con piacere che il Consiglio federale apparentemente \u2013 allontanandosi dalla pratica precedente \u2013 non intende procedere con il &#8220;martello di legno&#8221;, ma in dialogo con il settore. Con l&#8217;aumento dei veicoli a propulsione alternativa (elettrico, CNG\/LNG, idrogeno), le discussioni su sistematica e tariffe sono senza dubbio necessarie. Tuttavia, \u00e8 fondamentale che la sicurezza degli investimenti e la pianificazione anticipata siano sempre garantite.<\/p>\n<h5><strong>Nessun declassamento anticipato della norma EURO VI<\/strong><\/h5>\n<p> Con la riduzione delle emissioni inquinanti (monossido di carbonio, ossido di azoto, ecc.) a quasi zero, raggiunta attraverso una rapida modernizzazione della flotta, gli obiettivi ambientali della LSVA sono stati raggiunti da tempo. Sarebbe fatale o un colpo inaccettabile per il settore cambiare fondamentalmente le regole del gioco ora e rendere la LSVA, ad esempio, principalmente dipendente dalle emissioni di CO2. Un declassamento dei veicoli della norma EURO VI, finora la pi\u00f9 moderna, deve quindi avvenire solo quando una eventuale nuova norma EURO VII \u00e8 disponibile in serie in tutta Europa per ogni ambito di applicazione. &#8220;Tuttavia, l&#8217;ASTAG \u00e8 pronta a partecipare in modo costruttivo alle discussioni in corso&#8221;, sottolinea Thierry Burkart.<br \/>*La prestazione media di un camion in Svizzera \u00e8 compresa tra 70&#8217;000 e 90&#8217;000 chilometri. Informazioni dettagliate sul calcolo della LSVA possono essere trovate sul calcolatore LSVA dell&#8217;ASTAG (<a href=\"https:\/\/www.astag.ch\/wissen\/betriebswirtschaft\/lsva-rechner\/\" target=\"_blank\" rel=\"noopener noreferrer\">www.astag.ch\/wissen\/betriebswirtschaft\/lsva-rechner<\/a> o <a href=\"https:\/\/www.lsva.ch)\" target=\"_blank\" rel=\"noopener noreferrer\">www.lsva.ch)<\/a>.<br \/>Foto: \u00a9 Adobe Stock<br \/><a href=\"https:\/\/www.post.ch\" target=\"_blank\" rel=\"noopener noreferrer\">www.astag.ch<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>L&#8217;associazione svizzera dei veicoli commerciali ASTAG sottolinea che da esattamente 20 anni il settore del trasporto su strada contribuisce in modo efficace alla politica di trasferimento<span class=\"excerpt-hellip\"> [\u2026]<\/span><\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1557,1556,1561],"tags":[],"class_list":["post-22994","post","type-post","status-publish","format-standard","hentry","category-forwarding-logistics","category-intermodal-road","category-regions"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>ASTAG vede dopo 20 anni di LSVA le emissioni inquinanti a zero - Loginfo24<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/loginfo24.com\/it\/2021\/02\/01\/astag-vede-dopo-20-anni-di-lsva-le-emissioni-inquinanti-a-zero\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"ASTAG vede dopo 20 anni di LSVA le emissioni inquinanti a zero - Loginfo24\" \/>\n<meta property=\"og:description\" content=\"L&#8217;associazione svizzera dei veicoli commerciali ASTAG sottolinea che da esattamente 20 anni il settore del trasporto su strada contribuisce in modo efficace alla politica di trasferimento [\u2026]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/loginfo24.com\/it\/2021\/02\/01\/astag-vede-dopo-20-anni-di-lsva-le-emissioni-inquinanti-a-zero\/\" \/>\n<meta property=\"og:site_name\" content=\"Loginfo24\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/\" \/>\n<meta property=\"article:published_time\" content=\"2021-02-01T16:56:21+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-12-15T11:50:59+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2021\\\/02\\\/01\\\/astag-vede-dopo-20-anni-di-lsva-le-emissioni-inquinanti-a-zero\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2021\\\/02\\\/01\\\/astag-vede-dopo-20-anni-di-lsva-le-emissioni-inquinanti-a-zero\\\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"ASTAG vede dopo 20 anni di LSVA le emissioni inquinanti a zero\",\"datePublished\":\"2021-02-01T16:56:21+00:00\",\"dateModified\":\"2025-12-15T11:50:59+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2021\\\/02\\\/01\\\/astag-vede-dopo-20-anni-di-lsva-le-emissioni-inquinanti-a-zero\\\/\"},\"wordCount\":617,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#organization\"},\"articleSection\":[\"Forwarding &amp; Logistics\",\"Intermodal \\\/ Road\",\"Regions\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/it\\\/2021\\\/02\\\/01\\\/astag-vede-dopo-20-anni-di-lsva-le-emissioni-inquinanti-a-zero\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2021\\\/02\\\/01\\\/astag-vede-dopo-20-anni-di-lsva-le-emissioni-inquinanti-a-zero\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2021\\\/02\\\/01\\\/astag-vede-dopo-20-anni-di-lsva-le-emissioni-inquinanti-a-zero\\\/\",\"name\":\"ASTAG vede dopo 20 anni di LSVA le emissioni inquinanti a zero - Loginfo24\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#website\"},\"datePublished\":\"2021-02-01T16:56:21+00:00\",\"dateModified\":\"2025-12-15T11:50:59+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2021\\\/02\\\/01\\\/astag-vede-dopo-20-anni-di-lsva-le-emissioni-inquinanti-a-zero\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/it\\\/2021\\\/02\\\/01\\\/astag-vede-dopo-20-anni-di-lsva-le-emissioni-inquinanti-a-zero\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2021\\\/02\\\/01\\\/astag-vede-dopo-20-anni-di-lsva-le-emissioni-inquinanti-a-zero\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"ASTAG vede dopo 20 anni di LSVA le emissioni inquinanti a zero\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/\",\"name\":\"Loginfo24\",\"description\":\"Loginfo24 \u00e8 la piattaforma dedicata alla logistica e alle catene di fornitura con informazioni disponibili 24 ore su 24.\",\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#organization\",\"name\":\"Logismedia Group AG\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"width\":938,\"height\":351,\"caption\":\"Logismedia Group AG\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/people\\\/Loginfo24\\\/100057360583332\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/lofinfo24\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"ASTAG vede dopo 20 anni di LSVA le emissioni inquinanti a zero - Loginfo24","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/loginfo24.com\/it\/2021\/02\/01\/astag-vede-dopo-20-anni-di-lsva-le-emissioni-inquinanti-a-zero\/","og_locale":"it_IT","og_type":"article","og_title":"ASTAG vede dopo 20 anni di LSVA le emissioni inquinanti a zero - Loginfo24","og_description":"L&#8217;associazione svizzera dei veicoli commerciali ASTAG sottolinea che da esattamente 20 anni il settore del trasporto su strada contribuisce in modo efficace alla politica di trasferimento [\u2026]","og_url":"https:\/\/loginfo24.com\/it\/2021\/02\/01\/astag-vede-dopo-20-anni-di-lsva-le-emissioni-inquinanti-a-zero\/","og_site_name":"Loginfo24","article_publisher":"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","article_published_time":"2021-02-01T16:56:21+00:00","article_modified_time":"2025-12-15T11:50:59+00:00","twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"3 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/loginfo24.com\/it\/2021\/02\/01\/astag-vede-dopo-20-anni-di-lsva-le-emissioni-inquinanti-a-zero\/#article","isPartOf":{"@id":"https:\/\/loginfo24.com\/it\/2021\/02\/01\/astag-vede-dopo-20-anni-di-lsva-le-emissioni-inquinanti-a-zero\/"},"author":{"name":"","@id":""},"headline":"ASTAG vede dopo 20 anni di LSVA le emissioni inquinanti a zero","datePublished":"2021-02-01T16:56:21+00:00","dateModified":"2025-12-15T11:50:59+00:00","mainEntityOfPage":{"@id":"https:\/\/loginfo24.com\/it\/2021\/02\/01\/astag-vede-dopo-20-anni-di-lsva-le-emissioni-inquinanti-a-zero\/"},"wordCount":617,"commentCount":0,"publisher":{"@id":"https:\/\/loginfo24.com\/it\/#organization"},"articleSection":["Forwarding &amp; Logistics","Intermodal \/ Road","Regions"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/loginfo24.com\/it\/2021\/02\/01\/astag-vede-dopo-20-anni-di-lsva-le-emissioni-inquinanti-a-zero\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/loginfo24.com\/it\/2021\/02\/01\/astag-vede-dopo-20-anni-di-lsva-le-emissioni-inquinanti-a-zero\/","url":"https:\/\/loginfo24.com\/it\/2021\/02\/01\/astag-vede-dopo-20-anni-di-lsva-le-emissioni-inquinanti-a-zero\/","name":"ASTAG vede dopo 20 anni di LSVA le emissioni inquinanti a zero - Loginfo24","isPartOf":{"@id":"https:\/\/loginfo24.com\/it\/#website"},"datePublished":"2021-02-01T16:56:21+00:00","dateModified":"2025-12-15T11:50:59+00:00","breadcrumb":{"@id":"https:\/\/loginfo24.com\/it\/2021\/02\/01\/astag-vede-dopo-20-anni-di-lsva-le-emissioni-inquinanti-a-zero\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/loginfo24.com\/it\/2021\/02\/01\/astag-vede-dopo-20-anni-di-lsva-le-emissioni-inquinanti-a-zero\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/loginfo24.com\/it\/2021\/02\/01\/astag-vede-dopo-20-anni-di-lsva-le-emissioni-inquinanti-a-zero\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/loginfo24.com\/it\/"},{"@type":"ListItem","position":2,"name":"ASTAG vede dopo 20 anni di LSVA le emissioni inquinanti a zero"}]},{"@type":"WebSite","@id":"https:\/\/loginfo24.com\/it\/#website","url":"https:\/\/loginfo24.com\/it\/","name":"Loginfo24","description":"Loginfo24 \u00e8 la piattaforma dedicata alla logistica e alle catene di fornitura con informazioni disponibili 24 ore su 24.","publisher":{"@id":"https:\/\/loginfo24.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/loginfo24.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/loginfo24.com\/it\/#organization","name":"Logismedia Group AG","url":"https:\/\/loginfo24.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/loginfo24.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","width":938,"height":351,"caption":"Logismedia Group AG"},"image":{"@id":"https:\/\/loginfo24.com\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","https:\/\/www.linkedin.com\/company\/lofinfo24\/"]}]}},"_links":{"self":[{"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/posts\/22994","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/comments?post=22994"}],"version-history":[{"count":1,"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/posts\/22994\/revisions"}],"predecessor-version":[{"id":41714,"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/posts\/22994\/revisions\/41714"}],"wp:attachment":[{"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/media?parent=22994"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/categories?post=22994"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/tags?post=22994"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}