{"id":22909,"date":"2021-01-28T16:12:26","date_gmt":"2021-01-28T15:12:26","guid":{"rendered":"https:\/\/blog.brand-architecture.at\/2021\/01\/28\/kardex-mlog-punta-sulla-manutenzione-remota-e-offre-questo-servizio-anche-per-terzi\/"},"modified":"2025-12-15T12:50:29","modified_gmt":"2025-12-15T11:50:29","slug":"kardex-mlog-punta-sulla-manutenzione-remota-e-offre-questo-servizio-anche-per-terzi","status":"publish","type":"post","link":"https:\/\/loginfo24.com\/it\/2021\/01\/28\/kardex-mlog-punta-sulla-manutenzione-remota-e-offre-questo-servizio-anche-per-terzi\/","title":{"rendered":"Kardex Mlog punta sulla manutenzione remota e offre questo servizio anche per terzi"},"content":{"rendered":"<p>L&#8217;intralogista Kardex Mlog ha ulteriormente ottimizzato la manutenzione e la riparazione dei magazzini automatizzati, puntando pi\u00f9 che mai sulla procedura remota. In oltre il 96% dei casi, la manutenzione a distanza con il concetto adottato da Kardex Mlog ha successo e la disponibilit\u00e0 degli impianti aumenta. Il concetto di Life Cycle Service, composto da sei moduli di servizio, \u00e8 offerto dall&#8217;azienda con sede a Neuenstadt anche per gli impianti di fornitori esterni.<\/p>\n<p>(Neuenstadt)Il Life Cycle Service accompagna gli impianti logistici durante l&#8217;intero ciclo di vita, garantendo la massima affidabilit\u00e0 e mantenendo la tecnologia aggiornata. I clienti possono configurare un concetto di manutenzione su misura scegliendo tra sei moduli di servizio. Nel modulo Support Services, Kardex Mlog offre riparazioni in loco o tramite diagnosi remota, supportate dalla realt\u00e0 aumentata. Un servizio di reperibilit\u00e0 e una hotline attiva 24 ore su 24 completano l&#8217;offerta. Altri moduli di servizio si concentrano su aree come ricambi, formazione e consulenza, manutenzione predittiva, contratti di servizio e sicurezza. Questi includono non solo le ispezioni UVV, l&#8217;ispezione DGUV-V3, il rispetto delle normative di prevenzione degli infortuni e le istruzioni di sicurezza, ma anche le ispezioni annuali delle scaffalature secondo la norma EN 15635. Durante l&#8217;ispezione delle scaffalature, spesso emergono difetti che devono essere corretti immediatamente. In caso di danni, i responsabili del magazzino rischiano pesanti multe e conseguenze penali se persone vengono ferite a causa di scaffalature insufficientemente sicure. &#8220;Offriamo ai nostri clienti un servizio completo con un unico referente centrale per l&#8217;intero impianto&#8221;, sottolinea Rainer Busch, responsabile del settore Life Cycle Service e membro della direzione di Kardex Mlog. In questo contesto e a causa del feedback positivo dei clienti, il suo team si occupa anche del servizio tecnico per impianti non realizzati da Kardex Mlog.<\/p>\n<h5>Potenziale della procedura remota<\/h5>\n<p>Il potenziale della procedura remota \u00e8 stato riconosciuto da Kardex Mlog come uno dei primi fornitori di sistemi integrati di flusso di materiali e magazzini a scaffale alto, e da allora \u00e8 stato costantemente ampliato e sviluppato. L&#8217;automazione del magazzino ha gi\u00e0 realizzato diverse centinaia di soluzioni per la manutenzione remota dal 1997. Oggi, gi\u00e0 il 75% dei servizi di supporto per magazzini automatizzati viene effettuato tramite procedura remota. &#8220;In futuro, questa percentuale potrebbe salire all&#8217;80-90%&#8221;, \u00e8 convinto Busch. La presenza di tecnici di servizio esterni nel proprio magazzino \u00e8 quindi necessaria solo in rari casi. Tra i fattori che guidano questo sviluppo c&#8217;\u00e8 la crescente interconnessione degli impianti, in particolare in relazione all&#8217;Industria 4.0 e alle soluzioni Smart Service associate di Kardex Mlog. Lo sviluppo dipende anche dalla qualificazione del personale presso l&#8217;operatore dell&#8217;impianto. Se durante la manutenzione remota viene diagnosticato un difetto hardware, alcune parti possono essere sostituite dal cliente stesso, in stretta collaborazione con la hotline e con l&#8217;aiuto della realt\u00e0 aumentata, se dispone delle conoscenze di base necessarie. Grazie al contributo fornito, i costi di manutenzione dei magazzini automatizzati possono essere sensibilmente ridotti, un aspetto che Kardex Mlog promuove attivamente con il modulo di servizio &#8220;Formazione \/ Ottimizzazione \/ Consulenza&#8221;. Oltre alla formazione degli operatori, l&#8217;azienda offre anche corsi di formazione per i manutentori e corsi di sistema per la gestione della logistica.<\/p>\n<h5>Su Kardex Mlog<\/h5>\n<p>Kardex Mlog, con sede a Neuenstadt am Kocher, \u00e8 uno dei principali fornitori di sistemi integrati di flusso di materiali e magazzini a scaffale alto. L&#8217;azienda vanta oltre 50 anni di esperienza nella progettazione, realizzazione e manutenzione di soluzioni logistiche completamente automatizzate. I tre settori aziendali di nuovi impianti, modernizzazione e servizio clienti si basano sulla propria produzione a Neuenstadt. Kardex Mlog fa parte del gruppo Kardex e impiega 300 persone, con un fatturato di 79 milioni di euro nel 2019. Foto: \u00a9 Kardex Mlog \/ <em>Didascalia:<\/em><em> In oltre il 96% dei casi, la manutenzione a distanza con il concetto adottato da Kardex Mlog ha successo.<\/em> <a href=\"https:\/\/www.kardex.com\" target=\"_blank\" rel=\"noopener noreferrer\">www.kardex.com<\/a> \u00a0\u00a0\u00a0\u00a0\u00a0<a href=\"https:\/\/www.kardex-mlog.de\" target=\"_blank\" rel=\"noopener noreferrer\">www.kardex-mlog.de<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>L&#8217;intralogista Kardex Mlog ha ulteriormente ottimizzato la manutenzione e la riparazione dei magazzini automatizzati, puntando pi\u00f9 che mai sulla procedura remota. In oltre il 96% dei<span class=\"excerpt-hellip\"> [\u2026]<\/span><\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1665,1557,1560,1561],"tags":[],"class_list":["post-22909","post","type-post","status-publish","format-standard","hentry","category-categories","category-forwarding-logistics","category-intralogistics","category-regions"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Kardex Mlog punta sulla manutenzione remota e offre questo servizio anche per terzi - Loginfo24<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/loginfo24.com\/it\/2021\/01\/28\/kardex-mlog-punta-sulla-manutenzione-remota-e-offre-questo-servizio-anche-per-terzi\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Kardex Mlog punta sulla manutenzione remota e offre questo servizio anche per terzi - Loginfo24\" \/>\n<meta property=\"og:description\" content=\"L&#8217;intralogista Kardex Mlog ha ulteriormente ottimizzato la manutenzione e la riparazione dei magazzini automatizzati, puntando pi\u00f9 che mai sulla procedura remota. In oltre il 96% dei [\u2026]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/loginfo24.com\/it\/2021\/01\/28\/kardex-mlog-punta-sulla-manutenzione-remota-e-offre-questo-servizio-anche-per-terzi\/\" \/>\n<meta property=\"og:site_name\" content=\"Loginfo24\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/\" \/>\n<meta property=\"article:published_time\" content=\"2021-01-28T15:12:26+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-12-15T11:50:29+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2021\\\/01\\\/28\\\/kardex-mlog-punta-sulla-manutenzione-remota-e-offre-questo-servizio-anche-per-terzi\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2021\\\/01\\\/28\\\/kardex-mlog-punta-sulla-manutenzione-remota-e-offre-questo-servizio-anche-per-terzi\\\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Kardex Mlog punta sulla manutenzione remota e offre questo servizio anche per terzi\",\"datePublished\":\"2021-01-28T15:12:26+00:00\",\"dateModified\":\"2025-12-15T11:50:29+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2021\\\/01\\\/28\\\/kardex-mlog-punta-sulla-manutenzione-remota-e-offre-questo-servizio-anche-per-terzi\\\/\"},\"wordCount\":641,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#organization\"},\"articleSection\":[\"Categories\",\"Forwarding &amp; Logistics\",\"Intralogistics\",\"Regions\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/it\\\/2021\\\/01\\\/28\\\/kardex-mlog-punta-sulla-manutenzione-remota-e-offre-questo-servizio-anche-per-terzi\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2021\\\/01\\\/28\\\/kardex-mlog-punta-sulla-manutenzione-remota-e-offre-questo-servizio-anche-per-terzi\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2021\\\/01\\\/28\\\/kardex-mlog-punta-sulla-manutenzione-remota-e-offre-questo-servizio-anche-per-terzi\\\/\",\"name\":\"Kardex Mlog punta sulla manutenzione remota e offre questo servizio anche per terzi - Loginfo24\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#website\"},\"datePublished\":\"2021-01-28T15:12:26+00:00\",\"dateModified\":\"2025-12-15T11:50:29+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2021\\\/01\\\/28\\\/kardex-mlog-punta-sulla-manutenzione-remota-e-offre-questo-servizio-anche-per-terzi\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/it\\\/2021\\\/01\\\/28\\\/kardex-mlog-punta-sulla-manutenzione-remota-e-offre-questo-servizio-anche-per-terzi\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2021\\\/01\\\/28\\\/kardex-mlog-punta-sulla-manutenzione-remota-e-offre-questo-servizio-anche-per-terzi\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Kardex Mlog punta sulla manutenzione remota e offre questo servizio anche per terzi\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/\",\"name\":\"Loginfo24\",\"description\":\"Loginfo24 \u00e8 la piattaforma dedicata alla logistica e alle catene di fornitura con informazioni disponibili 24 ore su 24.\",\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#organization\",\"name\":\"Logismedia Group AG\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"width\":938,\"height\":351,\"caption\":\"Logismedia Group AG\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/people\\\/Loginfo24\\\/100057360583332\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/lofinfo24\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Kardex Mlog punta sulla manutenzione remota e offre questo servizio anche per terzi - Loginfo24","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/loginfo24.com\/it\/2021\/01\/28\/kardex-mlog-punta-sulla-manutenzione-remota-e-offre-questo-servizio-anche-per-terzi\/","og_locale":"it_IT","og_type":"article","og_title":"Kardex Mlog punta sulla manutenzione remota e offre questo servizio anche per terzi - Loginfo24","og_description":"L&#8217;intralogista Kardex Mlog ha ulteriormente ottimizzato la manutenzione e la riparazione dei magazzini automatizzati, puntando pi\u00f9 che mai sulla procedura remota. In oltre il 96% dei [\u2026]","og_url":"https:\/\/loginfo24.com\/it\/2021\/01\/28\/kardex-mlog-punta-sulla-manutenzione-remota-e-offre-questo-servizio-anche-per-terzi\/","og_site_name":"Loginfo24","article_publisher":"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","article_published_time":"2021-01-28T15:12:26+00:00","article_modified_time":"2025-12-15T11:50:29+00:00","twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"3 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/loginfo24.com\/it\/2021\/01\/28\/kardex-mlog-punta-sulla-manutenzione-remota-e-offre-questo-servizio-anche-per-terzi\/#article","isPartOf":{"@id":"https:\/\/loginfo24.com\/it\/2021\/01\/28\/kardex-mlog-punta-sulla-manutenzione-remota-e-offre-questo-servizio-anche-per-terzi\/"},"author":{"name":"","@id":""},"headline":"Kardex Mlog punta sulla manutenzione remota e offre questo servizio anche per terzi","datePublished":"2021-01-28T15:12:26+00:00","dateModified":"2025-12-15T11:50:29+00:00","mainEntityOfPage":{"@id":"https:\/\/loginfo24.com\/it\/2021\/01\/28\/kardex-mlog-punta-sulla-manutenzione-remota-e-offre-questo-servizio-anche-per-terzi\/"},"wordCount":641,"commentCount":0,"publisher":{"@id":"https:\/\/loginfo24.com\/it\/#organization"},"articleSection":["Categories","Forwarding &amp; Logistics","Intralogistics","Regions"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/loginfo24.com\/it\/2021\/01\/28\/kardex-mlog-punta-sulla-manutenzione-remota-e-offre-questo-servizio-anche-per-terzi\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/loginfo24.com\/it\/2021\/01\/28\/kardex-mlog-punta-sulla-manutenzione-remota-e-offre-questo-servizio-anche-per-terzi\/","url":"https:\/\/loginfo24.com\/it\/2021\/01\/28\/kardex-mlog-punta-sulla-manutenzione-remota-e-offre-questo-servizio-anche-per-terzi\/","name":"Kardex Mlog punta sulla manutenzione remota e offre questo servizio anche per terzi - Loginfo24","isPartOf":{"@id":"https:\/\/loginfo24.com\/it\/#website"},"datePublished":"2021-01-28T15:12:26+00:00","dateModified":"2025-12-15T11:50:29+00:00","breadcrumb":{"@id":"https:\/\/loginfo24.com\/it\/2021\/01\/28\/kardex-mlog-punta-sulla-manutenzione-remota-e-offre-questo-servizio-anche-per-terzi\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/loginfo24.com\/it\/2021\/01\/28\/kardex-mlog-punta-sulla-manutenzione-remota-e-offre-questo-servizio-anche-per-terzi\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/loginfo24.com\/it\/2021\/01\/28\/kardex-mlog-punta-sulla-manutenzione-remota-e-offre-questo-servizio-anche-per-terzi\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/loginfo24.com\/it\/"},{"@type":"ListItem","position":2,"name":"Kardex Mlog punta sulla manutenzione remota e offre questo servizio anche per terzi"}]},{"@type":"WebSite","@id":"https:\/\/loginfo24.com\/it\/#website","url":"https:\/\/loginfo24.com\/it\/","name":"Loginfo24","description":"Loginfo24 \u00e8 la piattaforma dedicata alla logistica e alle catene di fornitura con informazioni disponibili 24 ore su 24.","publisher":{"@id":"https:\/\/loginfo24.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/loginfo24.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/loginfo24.com\/it\/#organization","name":"Logismedia Group AG","url":"https:\/\/loginfo24.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/loginfo24.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","width":938,"height":351,"caption":"Logismedia Group AG"},"image":{"@id":"https:\/\/loginfo24.com\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","https:\/\/www.linkedin.com\/company\/lofinfo24\/"]}]}},"_links":{"self":[{"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/posts\/22909","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/comments?post=22909"}],"version-history":[{"count":1,"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/posts\/22909\/revisions"}],"predecessor-version":[{"id":41544,"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/posts\/22909\/revisions\/41544"}],"wp:attachment":[{"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/media?parent=22909"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/categories?post=22909"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/tags?post=22909"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}