{"id":22232,"date":"2020-12-16T19:12:04","date_gmt":"2020-12-16T18:12:04","guid":{"rendered":"https:\/\/blog.brand-architecture.at\/2020\/12\/16\/db-cargo-lancia-il-veloce-scandinavian-rail-shuttle\/"},"modified":"2025-12-15T12:47:39","modified_gmt":"2025-12-15T11:47:39","slug":"db-cargo-lancia-il-veloce-scandinavian-rail-shuttle","status":"publish","type":"post","link":"https:\/\/loginfo24.com\/it\/2020\/12\/16\/db-cargo-lancia-il-veloce-scandinavian-rail-shuttle\/","title":{"rendered":"DB Cargo lancia il veloce Scandinavian Rail Shuttle"},"content":{"rendered":"<p>DB Cargo installa lo Scandinavian Rail Shuttle tra Taulov in Danimarca (Jutlandia) e Katrineholm in Svezia (Stoccolma). DB Cargo Scandinavia \u00e8 l&#8217;operatore transfrontaliero e coordina tutto da un&#8217;unica fonte. I treni circolano tre volte a settimana in entrambe le direzioni.<\/p>\n<p>(Magonza) Ecologico e veloce, non possono andare insieme? Certo! In mezza giornata, la famiglia DB Cargo fornisce beni di consumo, carta e acciaio in Danimarca e Svezia. Da novembre \u00e8 disponibile la nuova soluzione di trasporto ferroviario diretto Scandinavian Rail Shuttle, con DB Cargo Scandinavia che funge da operatore transfrontaliero.<\/p>\n<p>Con lo <em>Scandinavian Rail Shuttle<\/em>, il portafoglio prodotti della famiglia DB Cargo si arricchisce di un&#8217;offerta. Dall&#8217;inizio di novembre, lo shuttle opera tra il centro di carico danese Taulov in Jutlandia e Katrineholm vicino a Stoccolma. La soluzione di trasporto ferroviario \u00e8 stata avviata dalla filiale scandinava DB Cargo Scandinavia, che diventa cos\u00ec il primo fornitore a offrire trasporti intermodali diretti e regolari tra Danimarca e Svezia. La particolarit\u00e0 \u00e8 che DB Cargo Scandinavia assume il ruolo di operatore, gestendo quindi prenotazioni, utilizzo e realizzazione da un&#8217;unica fonte \u2013 anche transfrontaliera.<\/p>\n<h5><strong>Un tempo di transito di 14 ore<\/strong><\/h5>\n<p>In sole 14 ore, durante la notte e con una capacit\u00e0 di fino a 38 unit\u00e0 di carico, lo <strong>Scandinavian Rail Shuttle<\/strong> trasporta rimorchi, container e casse mobili tra i principali centri economici in Danimarca e Svezia. Il punto di partenza e di arrivo dei tre giri settimanali \u00e8 Taulov in Jutlandia (Danimarca) e Katrineholm, vicino alla capitale svedese Stoccolma. Vengono trasportati beni di consumo verso la Svezia e da l\u00ec carta e acciaio di ritorno in Danimarca. La connessione diretta intermodale non solo \u00e8 veloce, ma \u00e8 anche rispettosa dell&#8217;ambiente. Per ogni rimorchio e tratta vengono risparmiate 1,2 milioni di tonnellate di CO<sub>2<\/sub> \u2013 circa l&#8217;80% in meno rispetto a un trasporto su strada.<\/p>\n<p>&#8220;La ferrovia offre una &#8216;soluzione di trasporto verde&#8217; attraente, per la quale rilasciamo al cliente un cosiddetto &#8216;Carbon Footprint Certificate&#8217;, in modo che il contributo dato dal risparmio di CO<sub>2<\/sub> per la protezione dell&#8217;ambiente venga documentato&#8221;, afferma Maarten de Ridder, responsabile delle vendite internazionali di DB Cargo.<\/p>\n<h5><strong>Trasporti prenotabili online dal 2021<\/strong><\/h5>\n<p>Lo <em>Scandinavian Rail Shuttle<\/em> \u00e8 ideale per le aziende che desiderano spostare i trasporti dalla strada alla ferrovia, rendendo cos\u00ec il trasporto pi\u00f9 ecologico ed economico. I trasporti possono essere facilmente prenotati ad hoc e online. \u00c8 previsto di offrire il prodotto shuttle a partire dall&#8217;autunno 2021 con cinque giri a settimana.<\/p>\n<p>&#8220;\u00c8 un trasporto che abbiamo avviato con grande impegno e passione, e ora \u00e8 partito. E questo in questo periodo particolarmente difficile di Corona&#8221;, afferma Oliver Gesche, CFO di DB Cargo Scandinavia. &#8220;Grazie al collegamento con la nostra rete europea fino in Cina, vedo un grande potenziale per il nostro <em>Scandinavian Rail Shuttle<\/em>.&#8221;<\/p>\n<p>Foto: \u00a9 DB Cargo<\/p>\n<p><a href=\"https:\/\/www.dbcargo.com\" target=\"_blank\" rel=\"noopener noreferrer\">www.dbcargo.com<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>DB Cargo installa lo Scandinavian Rail Shuttle tra Taulov in Danimarca (Jutlandia) e Katrineholm in Svezia (Stoccolma). DB Cargo Scandinavia \u00e8 l&#8217;operatore transfrontaliero e coordina tutto<span class=\"excerpt-hellip\"> [\u2026]<\/span><\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1557,1561],"tags":[],"class_list":["post-22232","post","type-post","status-publish","format-standard","hentry","category-forwarding-logistics","category-regions"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>DB Cargo lancia il veloce Scandinavian Rail Shuttle - Loginfo24<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/loginfo24.com\/it\/2020\/12\/16\/db-cargo-lancia-il-veloce-scandinavian-rail-shuttle\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"DB Cargo lancia il veloce Scandinavian Rail Shuttle - Loginfo24\" \/>\n<meta property=\"og:description\" content=\"DB Cargo installa lo Scandinavian Rail Shuttle tra Taulov in Danimarca (Jutlandia) e Katrineholm in Svezia (Stoccolma). DB Cargo Scandinavia \u00e8 l&#8217;operatore transfrontaliero e coordina tutto [\u2026]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/loginfo24.com\/it\/2020\/12\/16\/db-cargo-lancia-il-veloce-scandinavian-rail-shuttle\/\" \/>\n<meta property=\"og:site_name\" content=\"Loginfo24\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/\" \/>\n<meta property=\"article:published_time\" content=\"2020-12-16T18:12:04+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-12-15T11:47:39+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2020\\\/12\\\/16\\\/db-cargo-lancia-il-veloce-scandinavian-rail-shuttle\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2020\\\/12\\\/16\\\/db-cargo-lancia-il-veloce-scandinavian-rail-shuttle\\\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"DB Cargo lancia il veloce Scandinavian Rail Shuttle\",\"datePublished\":\"2020-12-16T18:12:04+00:00\",\"dateModified\":\"2025-12-15T11:47:39+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2020\\\/12\\\/16\\\/db-cargo-lancia-il-veloce-scandinavian-rail-shuttle\\\/\"},\"wordCount\":463,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#organization\"},\"articleSection\":[\"Forwarding &amp; Logistics\",\"Regions\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/it\\\/2020\\\/12\\\/16\\\/db-cargo-lancia-il-veloce-scandinavian-rail-shuttle\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2020\\\/12\\\/16\\\/db-cargo-lancia-il-veloce-scandinavian-rail-shuttle\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2020\\\/12\\\/16\\\/db-cargo-lancia-il-veloce-scandinavian-rail-shuttle\\\/\",\"name\":\"DB Cargo lancia il veloce Scandinavian Rail Shuttle - Loginfo24\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#website\"},\"datePublished\":\"2020-12-16T18:12:04+00:00\",\"dateModified\":\"2025-12-15T11:47:39+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2020\\\/12\\\/16\\\/db-cargo-lancia-il-veloce-scandinavian-rail-shuttle\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/it\\\/2020\\\/12\\\/16\\\/db-cargo-lancia-il-veloce-scandinavian-rail-shuttle\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2020\\\/12\\\/16\\\/db-cargo-lancia-il-veloce-scandinavian-rail-shuttle\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"DB Cargo lancia il veloce Scandinavian Rail Shuttle\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/\",\"name\":\"Loginfo24\",\"description\":\"Loginfo24 \u00e8 la piattaforma dedicata alla logistica e alle catene di fornitura con informazioni disponibili 24 ore su 24.\",\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#organization\",\"name\":\"Logismedia Group AG\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"width\":938,\"height\":351,\"caption\":\"Logismedia Group AG\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/people\\\/Loginfo24\\\/100057360583332\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/lofinfo24\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"DB Cargo lancia il veloce Scandinavian Rail Shuttle - Loginfo24","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/loginfo24.com\/it\/2020\/12\/16\/db-cargo-lancia-il-veloce-scandinavian-rail-shuttle\/","og_locale":"it_IT","og_type":"article","og_title":"DB Cargo lancia il veloce Scandinavian Rail Shuttle - Loginfo24","og_description":"DB Cargo installa lo Scandinavian Rail Shuttle tra Taulov in Danimarca (Jutlandia) e Katrineholm in Svezia (Stoccolma). DB Cargo Scandinavia \u00e8 l&#8217;operatore transfrontaliero e coordina tutto [\u2026]","og_url":"https:\/\/loginfo24.com\/it\/2020\/12\/16\/db-cargo-lancia-il-veloce-scandinavian-rail-shuttle\/","og_site_name":"Loginfo24","article_publisher":"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","article_published_time":"2020-12-16T18:12:04+00:00","article_modified_time":"2025-12-15T11:47:39+00:00","twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"2 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/loginfo24.com\/it\/2020\/12\/16\/db-cargo-lancia-il-veloce-scandinavian-rail-shuttle\/#article","isPartOf":{"@id":"https:\/\/loginfo24.com\/it\/2020\/12\/16\/db-cargo-lancia-il-veloce-scandinavian-rail-shuttle\/"},"author":{"name":"","@id":""},"headline":"DB Cargo lancia il veloce Scandinavian Rail Shuttle","datePublished":"2020-12-16T18:12:04+00:00","dateModified":"2025-12-15T11:47:39+00:00","mainEntityOfPage":{"@id":"https:\/\/loginfo24.com\/it\/2020\/12\/16\/db-cargo-lancia-il-veloce-scandinavian-rail-shuttle\/"},"wordCount":463,"commentCount":0,"publisher":{"@id":"https:\/\/loginfo24.com\/it\/#organization"},"articleSection":["Forwarding &amp; Logistics","Regions"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/loginfo24.com\/it\/2020\/12\/16\/db-cargo-lancia-il-veloce-scandinavian-rail-shuttle\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/loginfo24.com\/it\/2020\/12\/16\/db-cargo-lancia-il-veloce-scandinavian-rail-shuttle\/","url":"https:\/\/loginfo24.com\/it\/2020\/12\/16\/db-cargo-lancia-il-veloce-scandinavian-rail-shuttle\/","name":"DB Cargo lancia il veloce Scandinavian Rail Shuttle - Loginfo24","isPartOf":{"@id":"https:\/\/loginfo24.com\/it\/#website"},"datePublished":"2020-12-16T18:12:04+00:00","dateModified":"2025-12-15T11:47:39+00:00","breadcrumb":{"@id":"https:\/\/loginfo24.com\/it\/2020\/12\/16\/db-cargo-lancia-il-veloce-scandinavian-rail-shuttle\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/loginfo24.com\/it\/2020\/12\/16\/db-cargo-lancia-il-veloce-scandinavian-rail-shuttle\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/loginfo24.com\/it\/2020\/12\/16\/db-cargo-lancia-il-veloce-scandinavian-rail-shuttle\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/loginfo24.com\/it\/"},{"@type":"ListItem","position":2,"name":"DB Cargo lancia il veloce Scandinavian Rail Shuttle"}]},{"@type":"WebSite","@id":"https:\/\/loginfo24.com\/it\/#website","url":"https:\/\/loginfo24.com\/it\/","name":"Loginfo24","description":"Loginfo24 \u00e8 la piattaforma dedicata alla logistica e alle catene di fornitura con informazioni disponibili 24 ore su 24.","publisher":{"@id":"https:\/\/loginfo24.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/loginfo24.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/loginfo24.com\/it\/#organization","name":"Logismedia Group AG","url":"https:\/\/loginfo24.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/loginfo24.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","width":938,"height":351,"caption":"Logismedia Group AG"},"image":{"@id":"https:\/\/loginfo24.com\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","https:\/\/www.linkedin.com\/company\/lofinfo24\/"]}]}},"_links":{"self":[{"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/posts\/22232","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/comments?post=22232"}],"version-history":[{"count":1,"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/posts\/22232\/revisions"}],"predecessor-version":[{"id":40650,"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/posts\/22232\/revisions\/40650"}],"wp:attachment":[{"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/media?parent=22232"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/categories?post=22232"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/tags?post=22232"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}