{"id":21380,"date":"2020-11-18T12:00:33","date_gmt":"2020-11-18T11:00:33","guid":{"rendered":"https:\/\/blog.brand-architecture.at\/2020\/11\/18\/a-p-moller-maersk-migliora-la-redditivita-nel-terzo-trimestre\/"},"modified":"2025-12-15T12:43:53","modified_gmt":"2025-12-15T11:43:53","slug":"a-p-moller-maersk-migliora-la-redditivita-nel-terzo-trimestre","status":"publish","type":"post","link":"https:\/\/loginfo24.com\/it\/2020\/11\/18\/a-p-moller-maersk-migliora-la-redditivita-nel-terzo-trimestre\/","title":{"rendered":"A.P. Moller - Maersk migliora la redditivit\u00e0 nel terzo trimestre"},"content":{"rendered":"<p>La compagnia di navigazione A.P. Moller - Maersk presenta buoni risultati per il terzo trimestre del 2020. Il risultato operativo (EBITDA) \u00e8 aumentato del 39% a 2,3 miliardi di USD, nonostante un calo del fatturato dell&#8217;1,4%. Questo \u00e8 dovuto a un rigoroso controllo dei costi.<\/p>\n<p>(Copenaghen) Nel terzo trimestre, A.P. Moller - Maersk ha migliorato la redditivit\u00e0 dell&#8217;intera azienda e ha generato un forte flusso di cassa libero, nonostante gli effetti negativi della pandemia di COVID-19 sull&#8217;economia globale. L&#8217;azienda ha aumentato il risultato prima di interessi, tasse e ammortamenti (EBITDA) del 39% a 2,3 miliardi di dollari, mentre il fatturato \u00e8 diminuito dell&#8217;1,4% a 9,9 miliardi di dollari. Il miglioramento delle prestazioni si basa su un rigoroso controllo dei costi, una gestione agile della capacit\u00e0, una forte focalizzazione sulle offerte ai clienti con ulteriore trazione nell&#8217;utilizzo dei servizi digitali e alcuni segnali di ripresa della domanda rispetto al secondo trimestre.<\/p>\n<h5><strong>Implementazione disciplinata della strategia<\/strong><\/h5>\n<p>&#8220;Sebbene il COVID-19 abbia avuto un impatto negativo sulle attivit\u00e0 nella maggior parte dei nostri settori, la nostra implementazione disciplinata della strategia nel terzo trimestre ha portato a una solida crescita del risultato e del flusso di cassa. Allo stesso tempo, siamo riusciti a integrare e semplificare ulteriormente l&#8217;organizzazione in Ocean &amp; Logistics, abbiamo completato l&#8217;acquisizione di KGH Customs Services e abbiamo continuato l&#8217;integrazione del team delle prestazioni per supportare le nostre forti performance finanziarie nella logistica &amp; servizi&#8221;, afferma S\u00e9ren Skou, CEO di A.P. Moller - Maersk.<\/p>\n<h5><strong>Driver di prestazione Ocean<\/strong><\/h5>\n<p>Il principale driver di prestazione in questo trimestre \u00e8 stato Ocean, che nonostante un calo dei volumi del 3,6% ha migliorato la redditivit\u00e0 di 511 milioni di dollari a 1,8 miliardi di dollari, raggiungendo un margine EBITDA del 25,4%, grazie a un utilizzo della capacit\u00e0 ancora agile, costi pi\u00f9 bassi e un temporaneo aumento delle tariffe di trasporto a breve termine a causa di una ripresa improvvisa della domanda su alcune rotte.<\/p>\n<p>Le prestazioni sono state fortemente supportate da Logistics &amp; Services, che hanno beneficiato di una domanda significativa nella gestione della catena di approvvigionamento, intermodale e dal team delle prestazioni acquisito. Nel terzo trimestre, il fatturato in Logistics &amp; Services \u00e8 aumentato dell&#8217;11% e la redditivit\u00e0 \u00e8 aumentata del 44%, raggiungendo un EBITDA di 131 milioni di dollari rispetto ai 91 milioni di dollari del 2019, nonostante i costi di ristrutturazione di 40 milioni di dollari. Nei terminal &amp; rimorchio, siamo riusciti a migliorare ulteriormente i margini e il risultato nonostante volumi e ricavi inferiori.<\/p>\n<h5><strong>Rendimento aumentato<\/strong><\/h5>\n<p>Il rendimento del capitale investito (CROIC) \u00e8 aumentato negli ultimi dodici mesi grazie a un flusso di cassa operativo pi\u00f9 forte e a un CAPEX lordo inferiore, passando da 9,9 a 13,9 punti. Il rendimento del capitale investito (ROIC), che era di 3 punti negli ultimi dodici mesi, \u00e8 aumentato a 5,9 punti, poich\u00e9 il risultato \u00e8 migliorato e il capitale investito \u00e8 diminuito leggermente.<\/p>\n<p>La generazione di flusso di cassa libero di 3 miliardi di dollari nei primi nove mesi del 2020 ha permesso all&#8217;azienda di restituire liquidit\u00e0 agli azionisti, finanziare acquisizioni e ridurre il debito, con il debito netto che \u00e8 sceso ulteriormente a 10,8 miliardi di dollari entro la fine del terzo trimestre, rispetto a 11,7 miliardi di dollari a fine 2019.<\/p>\n<h5><strong>Fidelizzazione dei dipendenti<\/strong><\/h5>\n<p>Saren Skou aggiunge: &#8220;Durante la pandemia, le nostre principali priorit\u00e0 sono state mantenere i nostri dipendenti al sicuro, mantenere la nostra rete globale e i nostri porti per servire i nostri clienti e supportare le comunit\u00e0 in cui operiamo. Questo rimane il nostro focus, poich\u00e9 la domanda si \u00e8 parzialmente ripresa.<\/p>\n<p>I nostri progressi nei risultati e la nostra trasformazione ci consentono di guardare con fiducia oltre l&#8217;eccezionale anno 2020, ma siamo ben consapevoli dell&#8217;elevata incertezza che la pandemia e i relativi lockdown continueranno a rappresentare nei prossimi trimestri.&#8221;<\/p>\n<h5><strong>Programma di riacquisto azioni<\/strong><\/h5>\n<p>In considerazione delle forti prestazioni e della generazione di cassa, il consiglio di amministrazione ha deciso di avviare un nuovo programma di riacquisto azioni di 10 miliardi di DKK (circa 1,6 miliardi di USD) su un periodo di fino a 15 mesi, la cui prima tranche (500 milioni di USD) dovrebbe iniziare a dicembre. La parte rimanente del riacquisto delle azioni \u00e8 soggetta all&#8217;approvazione degli azionisti nella prossima assemblea generale di marzo 2021.<\/p>\n<h5><strong>Linee guida per il 2020 e CAPEX<\/strong><\/h5>\n<p>Alla luce della dinamica attuale in tutto il business, A.P. Moller - Maersk prevede, come annunciato il 17 novembre 2020, un EBITDA prima dei costi di ristrutturazione e integrazione nell&#8217;intervallo di 8-8,5 miliardi di USD, rispetto ai precedenti 7,5-8 miliardi di USD, come annunciato il 13 ottobre 2020.<\/p>\n<p>La crescita della domanda globale di contenitori \u00e8 prevista in calo del 4-5% nel 2020 a causa del COVID-19.<\/p>\n<p>La crescita organica del volume in Ocean dovrebbe ora essere leggermente al di sotto della crescita media del mercato, che finora \u00e8 stata in linea con il mercato o leggermente al di sotto del mercato.<\/p>\n<p>Per il 2020, si prevede un investimento (CAPEX) di 1,5 miliardi di USD, con un&#8217;alta conversione di liquidit\u00e0 (flusso di cassa dalle operazioni rispetto all&#8217;EBITDA).<\/p>\n<p>Per il 2021-2022, si prevede che la previsione cumulativa per le spese in conto capitale sar\u00e0 tra 4,5 e 5,5 miliardi di USD con un&#8217;alta conversione di liquidit\u00e0.<\/p>\n<p>Foto: \u00a9 Moller - Maersk<\/p>\n<h3><strong><a href=\"https:\/\/www.maersk.com\/news\/articles\/2020\/11\/18\/strong-performance-by-ap-moller-maersk-q3\" target=\"_blank\" rel=\"noopener noreferrer\">Dettagli sulla chiusura<\/a> <\/strong><\/h3>\n","protected":false},"excerpt":{"rendered":"<p>La compagnia di navigazione A.P. Moller - Maersk presenta buoni risultati per il terzo trimestre del 2020. Il risultato operativo (EBITDA) \u00e8 aumentato del 39% a<span class=\"excerpt-hellip\"> [\u2026]<\/span><\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1557,1561,1559],"tags":[],"class_list":["post-21380","post","type-post","status-publish","format-standard","hentry","category-forwarding-logistics","category-regions","category-shipping-ports"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>A.P. Moller - Maersk migliora la redditivit\u00e0 nel terzo trimestre - Loginfo24<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/loginfo24.com\/it\/2020\/11\/18\/a-p-moller-maersk-migliora-la-redditivita-nel-terzo-trimestre\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"A.P. Moller - Maersk migliora la redditivit\u00e0 nel terzo trimestre - Loginfo24\" \/>\n<meta property=\"og:description\" content=\"La compagnia di navigazione A.P. Moller - Maersk presenta buoni risultati per il terzo trimestre del 2020. Il risultato operativo (EBITDA) \u00e8 aumentato del 39% a [\u2026]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/loginfo24.com\/it\/2020\/11\/18\/a-p-moller-maersk-migliora-la-redditivita-nel-terzo-trimestre\/\" \/>\n<meta property=\"og:site_name\" content=\"Loginfo24\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/\" \/>\n<meta property=\"article:published_time\" content=\"2020-11-18T11:00:33+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-12-15T11:43:53+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2020\\\/11\\\/18\\\/a-p-moller-maersk-migliora-la-redditivita-nel-terzo-trimestre\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2020\\\/11\\\/18\\\/a-p-moller-maersk-migliora-la-redditivita-nel-terzo-trimestre\\\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"A.P. Moller - Maersk migliora la redditivit\u00e0 nel terzo trimestre\",\"datePublished\":\"2020-11-18T11:00:33+00:00\",\"dateModified\":\"2025-12-15T11:43:53+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2020\\\/11\\\/18\\\/a-p-moller-maersk-migliora-la-redditivita-nel-terzo-trimestre\\\/\"},\"wordCount\":853,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#organization\"},\"articleSection\":[\"Forwarding &amp; Logistics\",\"Regions\",\"Shipping &amp; Ports\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/it\\\/2020\\\/11\\\/18\\\/a-p-moller-maersk-migliora-la-redditivita-nel-terzo-trimestre\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2020\\\/11\\\/18\\\/a-p-moller-maersk-migliora-la-redditivita-nel-terzo-trimestre\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2020\\\/11\\\/18\\\/a-p-moller-maersk-migliora-la-redditivita-nel-terzo-trimestre\\\/\",\"name\":\"A.P. Moller - Maersk migliora la redditivit\u00e0 nel terzo trimestre - Loginfo24\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#website\"},\"datePublished\":\"2020-11-18T11:00:33+00:00\",\"dateModified\":\"2025-12-15T11:43:53+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2020\\\/11\\\/18\\\/a-p-moller-maersk-migliora-la-redditivita-nel-terzo-trimestre\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/it\\\/2020\\\/11\\\/18\\\/a-p-moller-maersk-migliora-la-redditivita-nel-terzo-trimestre\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2020\\\/11\\\/18\\\/a-p-moller-maersk-migliora-la-redditivita-nel-terzo-trimestre\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"A.P. Moller &#8211; Maersk migliora la redditivit\u00e0 nel terzo trimestre\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/\",\"name\":\"Loginfo24\",\"description\":\"Loginfo24 \u00e8 la piattaforma dedicata alla logistica e alle catene di fornitura con informazioni disponibili 24 ore su 24.\",\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#organization\",\"name\":\"Logismedia Group AG\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"width\":938,\"height\":351,\"caption\":\"Logismedia Group AG\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/people\\\/Loginfo24\\\/100057360583332\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/lofinfo24\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"A.P. Moller - Maersk migliora la redditivit\u00e0 nel terzo trimestre - Loginfo24","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/loginfo24.com\/it\/2020\/11\/18\/a-p-moller-maersk-migliora-la-redditivita-nel-terzo-trimestre\/","og_locale":"it_IT","og_type":"article","og_title":"A.P. Moller - Maersk migliora la redditivit\u00e0 nel terzo trimestre - Loginfo24","og_description":"La compagnia di navigazione A.P. Moller - Maersk presenta buoni risultati per il terzo trimestre del 2020. Il risultato operativo (EBITDA) \u00e8 aumentato del 39% a [\u2026]","og_url":"https:\/\/loginfo24.com\/it\/2020\/11\/18\/a-p-moller-maersk-migliora-la-redditivita-nel-terzo-trimestre\/","og_site_name":"Loginfo24","article_publisher":"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","article_published_time":"2020-11-18T11:00:33+00:00","article_modified_time":"2025-12-15T11:43:53+00:00","twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"4 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/loginfo24.com\/it\/2020\/11\/18\/a-p-moller-maersk-migliora-la-redditivita-nel-terzo-trimestre\/#article","isPartOf":{"@id":"https:\/\/loginfo24.com\/it\/2020\/11\/18\/a-p-moller-maersk-migliora-la-redditivita-nel-terzo-trimestre\/"},"author":{"name":"","@id":""},"headline":"A.P. Moller - Maersk migliora la redditivit\u00e0 nel terzo trimestre","datePublished":"2020-11-18T11:00:33+00:00","dateModified":"2025-12-15T11:43:53+00:00","mainEntityOfPage":{"@id":"https:\/\/loginfo24.com\/it\/2020\/11\/18\/a-p-moller-maersk-migliora-la-redditivita-nel-terzo-trimestre\/"},"wordCount":853,"commentCount":0,"publisher":{"@id":"https:\/\/loginfo24.com\/it\/#organization"},"articleSection":["Forwarding &amp; Logistics","Regions","Shipping &amp; Ports"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/loginfo24.com\/it\/2020\/11\/18\/a-p-moller-maersk-migliora-la-redditivita-nel-terzo-trimestre\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/loginfo24.com\/it\/2020\/11\/18\/a-p-moller-maersk-migliora-la-redditivita-nel-terzo-trimestre\/","url":"https:\/\/loginfo24.com\/it\/2020\/11\/18\/a-p-moller-maersk-migliora-la-redditivita-nel-terzo-trimestre\/","name":"A.P. Moller - Maersk migliora la redditivit\u00e0 nel terzo trimestre - Loginfo24","isPartOf":{"@id":"https:\/\/loginfo24.com\/it\/#website"},"datePublished":"2020-11-18T11:00:33+00:00","dateModified":"2025-12-15T11:43:53+00:00","breadcrumb":{"@id":"https:\/\/loginfo24.com\/it\/2020\/11\/18\/a-p-moller-maersk-migliora-la-redditivita-nel-terzo-trimestre\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/loginfo24.com\/it\/2020\/11\/18\/a-p-moller-maersk-migliora-la-redditivita-nel-terzo-trimestre\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/loginfo24.com\/it\/2020\/11\/18\/a-p-moller-maersk-migliora-la-redditivita-nel-terzo-trimestre\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/loginfo24.com\/it\/"},{"@type":"ListItem","position":2,"name":"A.P. Moller &#8211; Maersk migliora la redditivit\u00e0 nel terzo trimestre"}]},{"@type":"WebSite","@id":"https:\/\/loginfo24.com\/it\/#website","url":"https:\/\/loginfo24.com\/it\/","name":"Loginfo24","description":"Loginfo24 \u00e8 la piattaforma dedicata alla logistica e alle catene di fornitura con informazioni disponibili 24 ore su 24.","publisher":{"@id":"https:\/\/loginfo24.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/loginfo24.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/loginfo24.com\/it\/#organization","name":"Logismedia Group AG","url":"https:\/\/loginfo24.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/loginfo24.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","width":938,"height":351,"caption":"Logismedia Group AG"},"image":{"@id":"https:\/\/loginfo24.com\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","https:\/\/www.linkedin.com\/company\/lofinfo24\/"]}]}},"_links":{"self":[{"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/posts\/21380","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/comments?post=21380"}],"version-history":[{"count":1,"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/posts\/21380\/revisions"}],"predecessor-version":[{"id":38954,"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/posts\/21380\/revisions\/38954"}],"wp:attachment":[{"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/media?parent=21380"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/categories?post=21380"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/tags?post=21380"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}