{"id":20054,"date":"2020-09-26T19:37:27","date_gmt":"2020-09-26T17:37:27","guid":{"rendered":"https:\/\/blog.brand-architecture.at\/2020\/09\/26\/ssi-schafer-espone-un-magazzino-per-piccoli-pezzi-al-museo-dei-trasporti-della-svizzera\/"},"modified":"2025-12-15T12:37:55","modified_gmt":"2025-12-15T11:37:55","slug":"ssi-schafer-espone-un-magazzino-per-piccoli-pezzi-al-museo-dei-trasporti-della-svizzera","status":"publish","type":"post","link":"https:\/\/loginfo24.com\/it\/2020\/09\/26\/ssi-schafer-espone-un-magazzino-per-piccoli-pezzi-al-museo-dei-trasporti-della-svizzera\/","title":{"rendered":"SSI Sch\u00e4fer espone un magazzino per piccoli pezzi al Museo dei Trasporti della Svizzera"},"content":{"rendered":"<p>L&#8217;intralogista SSI Sch\u00e4fer contribuisce all&#8217;esposizione tematica &#8216;Vivere la logistica&#8217; presso il Museo dei Trasporti della Svizzera a Lucerna. \u00c8 stato scelto un pezzo espositivo ben visibile, il magazzino automatico per piccoli pezzi alto 14 metri.<\/p>\n<p>(Neunkirchen\/Sieg) Gli ultimi mesi hanno insegnato quanto siano importanti i flussi di materiali e le catene di approvvigionamento funzionanti nella vita quotidiana. Con il magazzino automatico per piccoli pezzi (AKL) alto 14 m, SSI Sch\u00e4fer offre ai visitatori uno sguardo dietro le quinte dell&#8217;intralogistica, promuovendo cos\u00ec la comprensione di processi altrimenti spesso invisibili.<\/p>\n<p>Lo spazio economico e abitativo della Svizzera funziona grazie a sistemi di logistica, comunicazione e trasporto efficienti; a livello globale, nazionale e locale. Illustrare questo in modo impressionante \u00e8 l&#8217;obiettivo dell&#8217;esposizione tematica &#8216;Vivere la logistica!&#8217;, che \u00e8 stata avviata dal Museo dei Trasporti della Svizzera insieme alla Fondazione Logistica Svizzera e vari partner di spicco del settore. In qualit\u00e0 di fornitore leader di soluzioni per sistemi di magazzino e logistica, SSI Sch\u00e4fer supporta il progetto con un magazzino automatico per piccoli pezzi in dimensioni reali.<\/p>\n<h5><strong>1.824 posti per contenitori<\/strong><\/h5>\n<p>15 tonnellate di acciaio costituiscono la struttura portante dell&#8217;AKL. La scaffalatura alta 14 m \u00e8 stata zincata a caldo per l&#8217;uso esterno presso il Museo dei Trasporti, rendendola resistente alle intemperie. Nei tre corridoi sono disponibili 1.824 posti per contenitori.<\/p>\n<p>I magazzini automatici per piccoli pezzi sono gestiti da dispositivi di movimentazione (RBG), che si muovono automaticamente nei corridoi del magazzino, controllati centralmente da software di logistica, e caricano e scaricano i contenitori. Gli RBG non sono adatti per l&#8217;uso all&#8217;aperto e sono stati quindi stampati in dimensioni reali come visualizzazioni ad alta risoluzione (rendering) e inseriti nei corridoi. In questo modo, ai visitatori viene fornita un&#8217;immagine realistica delle dimensioni effettive di un magazzino automatico per piccoli pezzi.<\/p>\n<h5><strong>Contenitori Euro di produzione propria<\/strong><\/h5>\n<p>L&#8217;AKL \u00e8 stato dotato di contenitori Euro gialli e rossi in plastica. I contenitori, prodotti internamente, con dimensioni di 600x400x220 mm, corrispondono a quelli utilizzati nella pratica, ma sono stati resi stabili ai raggi UV per l&#8217;uso esterno e presentano un fondo con fori, in modo che la pioggia e l&#8217;acqua di fusione della neve possano defluire.<\/p>\n<h5><strong>Montaggio efficiente in collaborazione con Atlas Montagen<\/strong><\/h5>\n<p>Il montaggio dell&#8217;AKL \u00e8 stato realizzato da SSI Sch\u00e4fer in collaborazione con il partner di lunga data Atlas Montagen della Svizzera. I montaggi nel campo della tecnologia di magazzino sono una questione di fiducia e soggetti a normative legali. Pertanto, il personale deve avere formazione specifica, che prepara al lavoro in altezza e quindi legalmente consentito. L&#8217;uso esterno presso il Museo dei Trasporti \u00e8 stato anche eccezionale per il team di montaggio ed \u00e8 stato eseguito con impegno e precisione.<\/p>\n<p>L&#8217;AKL di SSI Sch\u00e4fer pu\u00f2 essere visitato nell&#8217;ambito della mostra speciale &#8216;Vivere la logistica!&#8217; fino ad agosto 2022 presso il Museo dei Trasporti.<\/p>\n<h4><a href=\"https:\/\/www.verkehrshaus.ch\/besuchen\/museum\/logistik-erleben.html\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>Mostra Vivere la logistica<\/strong><\/a><\/h4>\n<p>Foto: \u00a9 SSI Sch\u00e4fer<\/p>\n<p><a href=\"https:\/\/www.ssi-schaefer.com\" target=\"_blank\" rel=\"noopener noreferrer\">www.ssi-schaefer.com<\/a>\u00a0\u00a0\u00a0 <a href=\"https:\/\/www.pressebox.de\/redirect\/ext?tu=http%3A%2F%2Fwww.atlas-personal.ch&amp;rp=w6FG8OVT-gwDXLQsVxInMWrZlvcFY_9isybdPZHlz8U\" target=\"_blank\" rel=\"noopener noreferrer\">www.atlas-personal.ch<\/a>\u00a0\u00a0\u00a0 <a href=\"https:\/\/www.verkehrshaus.ch\" target=\"_blank\" rel=\"noopener noreferrer\">www.verkehrshaus.ch<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>L&#8217;intralogista SSI Sch\u00e4fer contribuisce all&#8217;esposizione tematica &#8216;Vivere la logistica&#8217; presso il Museo dei Trasporti della Svizzera a Lucerna. \u00c8 stato scelto un pezzo espositivo ben visibile,<span class=\"excerpt-hellip\"> [\u2026]<\/span><\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1557,1560,1561],"tags":[],"class_list":["post-20054","post","type-post","status-publish","format-standard","hentry","category-forwarding-logistics","category-intralogistics","category-regions"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>SSI Sch\u00e4fer espone un magazzino per piccoli pezzi al Museo dei Trasporti della Svizzera - Loginfo24<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/loginfo24.com\/it\/2020\/09\/26\/ssi-schafer-espone-un-magazzino-per-piccoli-pezzi-al-museo-dei-trasporti-della-svizzera\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"SSI Sch\u00e4fer espone un magazzino per piccoli pezzi al Museo dei Trasporti della Svizzera - Loginfo24\" \/>\n<meta property=\"og:description\" content=\"L&#8217;intralogista SSI Sch\u00e4fer contribuisce all&#8217;esposizione tematica &#8216;Vivere la logistica&#8217; presso il Museo dei Trasporti della Svizzera a Lucerna. \u00c8 stato scelto un pezzo espositivo ben visibile, [\u2026]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/loginfo24.com\/it\/2020\/09\/26\/ssi-schafer-espone-un-magazzino-per-piccoli-pezzi-al-museo-dei-trasporti-della-svizzera\/\" \/>\n<meta property=\"og:site_name\" content=\"Loginfo24\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/\" \/>\n<meta property=\"article:published_time\" content=\"2020-09-26T17:37:27+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-12-15T11:37:55+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2020\\\/09\\\/26\\\/ssi-schafer-espone-un-magazzino-per-piccoli-pezzi-al-museo-dei-trasporti-della-svizzera\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2020\\\/09\\\/26\\\/ssi-schafer-espone-un-magazzino-per-piccoli-pezzi-al-museo-dei-trasporti-della-svizzera\\\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"SSI Sch\u00e4fer espone un magazzino per piccoli pezzi al Museo dei Trasporti della Svizzera\",\"datePublished\":\"2020-09-26T17:37:27+00:00\",\"dateModified\":\"2025-12-15T11:37:55+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2020\\\/09\\\/26\\\/ssi-schafer-espone-un-magazzino-per-piccoli-pezzi-al-museo-dei-trasporti-della-svizzera\\\/\"},\"wordCount\":508,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#organization\"},\"articleSection\":[\"Forwarding &amp; Logistics\",\"Intralogistics\",\"Regions\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/it\\\/2020\\\/09\\\/26\\\/ssi-schafer-espone-un-magazzino-per-piccoli-pezzi-al-museo-dei-trasporti-della-svizzera\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2020\\\/09\\\/26\\\/ssi-schafer-espone-un-magazzino-per-piccoli-pezzi-al-museo-dei-trasporti-della-svizzera\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2020\\\/09\\\/26\\\/ssi-schafer-espone-un-magazzino-per-piccoli-pezzi-al-museo-dei-trasporti-della-svizzera\\\/\",\"name\":\"SSI Sch\u00e4fer espone un magazzino per piccoli pezzi al Museo dei Trasporti della Svizzera - Loginfo24\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#website\"},\"datePublished\":\"2020-09-26T17:37:27+00:00\",\"dateModified\":\"2025-12-15T11:37:55+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2020\\\/09\\\/26\\\/ssi-schafer-espone-un-magazzino-per-piccoli-pezzi-al-museo-dei-trasporti-della-svizzera\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/it\\\/2020\\\/09\\\/26\\\/ssi-schafer-espone-un-magazzino-per-piccoli-pezzi-al-museo-dei-trasporti-della-svizzera\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2020\\\/09\\\/26\\\/ssi-schafer-espone-un-magazzino-per-piccoli-pezzi-al-museo-dei-trasporti-della-svizzera\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"SSI Sch\u00e4fer espone un magazzino per piccoli pezzi al Museo dei Trasporti della Svizzera\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/\",\"name\":\"Loginfo24\",\"description\":\"Loginfo24 \u00e8 la piattaforma dedicata alla logistica e alle catene di fornitura con informazioni disponibili 24 ore su 24.\",\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#organization\",\"name\":\"Logismedia Group AG\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"width\":938,\"height\":351,\"caption\":\"Logismedia Group AG\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/people\\\/Loginfo24\\\/100057360583332\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/lofinfo24\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"SSI Sch\u00e4fer espone un magazzino per piccoli pezzi al Museo dei Trasporti della Svizzera - Loginfo24","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/loginfo24.com\/it\/2020\/09\/26\/ssi-schafer-espone-un-magazzino-per-piccoli-pezzi-al-museo-dei-trasporti-della-svizzera\/","og_locale":"it_IT","og_type":"article","og_title":"SSI Sch\u00e4fer espone un magazzino per piccoli pezzi al Museo dei Trasporti della Svizzera - Loginfo24","og_description":"L&#8217;intralogista SSI Sch\u00e4fer contribuisce all&#8217;esposizione tematica &#8216;Vivere la logistica&#8217; presso il Museo dei Trasporti della Svizzera a Lucerna. \u00c8 stato scelto un pezzo espositivo ben visibile, [\u2026]","og_url":"https:\/\/loginfo24.com\/it\/2020\/09\/26\/ssi-schafer-espone-un-magazzino-per-piccoli-pezzi-al-museo-dei-trasporti-della-svizzera\/","og_site_name":"Loginfo24","article_publisher":"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","article_published_time":"2020-09-26T17:37:27+00:00","article_modified_time":"2025-12-15T11:37:55+00:00","twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"2 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/loginfo24.com\/it\/2020\/09\/26\/ssi-schafer-espone-un-magazzino-per-piccoli-pezzi-al-museo-dei-trasporti-della-svizzera\/#article","isPartOf":{"@id":"https:\/\/loginfo24.com\/it\/2020\/09\/26\/ssi-schafer-espone-un-magazzino-per-piccoli-pezzi-al-museo-dei-trasporti-della-svizzera\/"},"author":{"name":"","@id":""},"headline":"SSI Sch\u00e4fer espone un magazzino per piccoli pezzi al Museo dei Trasporti della Svizzera","datePublished":"2020-09-26T17:37:27+00:00","dateModified":"2025-12-15T11:37:55+00:00","mainEntityOfPage":{"@id":"https:\/\/loginfo24.com\/it\/2020\/09\/26\/ssi-schafer-espone-un-magazzino-per-piccoli-pezzi-al-museo-dei-trasporti-della-svizzera\/"},"wordCount":508,"commentCount":0,"publisher":{"@id":"https:\/\/loginfo24.com\/it\/#organization"},"articleSection":["Forwarding &amp; Logistics","Intralogistics","Regions"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/loginfo24.com\/it\/2020\/09\/26\/ssi-schafer-espone-un-magazzino-per-piccoli-pezzi-al-museo-dei-trasporti-della-svizzera\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/loginfo24.com\/it\/2020\/09\/26\/ssi-schafer-espone-un-magazzino-per-piccoli-pezzi-al-museo-dei-trasporti-della-svizzera\/","url":"https:\/\/loginfo24.com\/it\/2020\/09\/26\/ssi-schafer-espone-un-magazzino-per-piccoli-pezzi-al-museo-dei-trasporti-della-svizzera\/","name":"SSI Sch\u00e4fer espone un magazzino per piccoli pezzi al Museo dei Trasporti della Svizzera - Loginfo24","isPartOf":{"@id":"https:\/\/loginfo24.com\/it\/#website"},"datePublished":"2020-09-26T17:37:27+00:00","dateModified":"2025-12-15T11:37:55+00:00","breadcrumb":{"@id":"https:\/\/loginfo24.com\/it\/2020\/09\/26\/ssi-schafer-espone-un-magazzino-per-piccoli-pezzi-al-museo-dei-trasporti-della-svizzera\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/loginfo24.com\/it\/2020\/09\/26\/ssi-schafer-espone-un-magazzino-per-piccoli-pezzi-al-museo-dei-trasporti-della-svizzera\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/loginfo24.com\/it\/2020\/09\/26\/ssi-schafer-espone-un-magazzino-per-piccoli-pezzi-al-museo-dei-trasporti-della-svizzera\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/loginfo24.com\/it\/"},{"@type":"ListItem","position":2,"name":"SSI Sch\u00e4fer espone un magazzino per piccoli pezzi al Museo dei Trasporti della Svizzera"}]},{"@type":"WebSite","@id":"https:\/\/loginfo24.com\/it\/#website","url":"https:\/\/loginfo24.com\/it\/","name":"Loginfo24","description":"Loginfo24 \u00e8 la piattaforma dedicata alla logistica e alle catene di fornitura con informazioni disponibili 24 ore su 24.","publisher":{"@id":"https:\/\/loginfo24.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/loginfo24.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/loginfo24.com\/it\/#organization","name":"Logismedia Group AG","url":"https:\/\/loginfo24.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/loginfo24.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","width":938,"height":351,"caption":"Logismedia Group AG"},"image":{"@id":"https:\/\/loginfo24.com\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","https:\/\/www.linkedin.com\/company\/lofinfo24\/"]}]}},"_links":{"self":[{"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/posts\/20054","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/comments?post=20054"}],"version-history":[{"count":1,"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/posts\/20054\/revisions"}],"predecessor-version":[{"id":36312,"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/posts\/20054\/revisions\/36312"}],"wp:attachment":[{"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/media?parent=20054"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/categories?post=20054"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/tags?post=20054"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}