{"id":19731,"date":"2020-07-07T06:04:48","date_gmt":"2020-07-07T04:04:48","guid":{"rendered":"https:\/\/blog.brand-architecture.at\/2020\/07\/07\/il-gruppo-bertschi-svizzero-e-ben-attrezzato-per-il-futuro\/"},"modified":"2025-12-15T12:36:38","modified_gmt":"2025-12-15T11:36:38","slug":"il-gruppo-bertschi-svizzero-e-ben-attrezzato-per-il-futuro","status":"publish","type":"post","link":"https:\/\/loginfo24.com\/it\/2020\/07\/07\/il-gruppo-bertschi-svizzero-e-ben-attrezzato-per-il-futuro\/","title":{"rendered":"Il Gruppo Bertschi svizzero \u00e8 ben attrezzato per il futuro"},"content":{"rendered":"<p>Durante l&#8217;assemblea generale del Gruppo Bertschi del 4 luglio 2020, gli azionisti sono stati informati sull&#8217;attuale sviluppo. L&#8217;azienda ha affrontato bene la prima ondata di Corona, anche grazie all&#8217;avanzata trasformazione digitale. Il consiglio di amministrazione \u00e8 stato ampliato con Kurt Haerri e J\u00f6rg Berner.<\/p>\n<p>(D\u00fcrren\u00e4sch) Il Gruppo Bertschi, attivo a livello mondiale nella logistica chimica, ha finora affrontato bene la crisi del Corona. La gestione precoce e di successo della sfida da parte di Bertschi China ha contribuito a questo. Anche i consistenti investimenti degli ultimi due anni nella trasformazione digitale hanno permesso di trasferire l&#8217;80% dei posti di lavoro d&#8217;ufficio in home office senza perdita di qualit\u00e0 in pochi giorni. La digitalizzazione \u00e8 attualmente in fase di ulteriore accelerazione. Il focus sul trasporto combinato ha consentito trasporti senza interruzioni durante la fase di chiusura delle frontiere in Europa.<\/p>\n<p>La salute e la sicurezza dei dipendenti hanno sempre la massima priorit\u00e0 per Bertschi, soprattutto durante il periodo del Corona. &#8220;Grazie a misure organizzative, a una grande sensibilizzazione e alla diligenza di tutti i dipendenti, nonch\u00e9 a una struttura di home office completa e a turni separati nei processi operativi, abbiamo affrontato la crisi fino ad oggi senza casi di infezione nel gruppo&#8221;, ha dichiarato Jan Arnet, CEO del Gruppo Bertschi.<\/p>\n<p>Inoltre, la direzione del gruppo e il consiglio di amministrazione hanno garantito la liquidit\u00e0 a lungo termine del gruppo sulla base di scenari finanziari per il 2020 e il 2021 con prestiti bancari aggiuntivi. La base finanziaria molto robusta e l&#8217;eccellente rating dell&#8217;azienda da parte delle banche hanno reso possibile ottenere buone condizioni. &#8220;Abbiamo raggiunto il nostro obiettivo di garantirci sufficiente margine di manovra per poter cogliere proattivamente le opportunit\u00e0 offerte dal mercato anche durante la crisi&#8221;, ha affermato Hans-J\u00f6rg Bertschi, presidente esecutivo dell&#8217;azienda.<\/p>\n<h5><strong>Traffico europeo diminuito del 20 percento<\/strong><\/h5>\n<p>A causa della crisi del Corona, il volume d&#8217;affari di Bertschi nel principale traffico europeo \u00e8 diminuito di quasi il 20 percento da aprile. Questo \u00e8 stato principalmente causato dal crollo della domanda nei due settori automobilistico e beni di consumo durevoli, che utilizzano molti prodotti chimici. La ripresa di questi due settori richieder\u00e0 pi\u00f9 tempo, forse fino alla fine del 2021. La crisi del Corona apre anche nuove opportunit\u00e0. Molti clienti vogliono diversificare e rendere pi\u00f9 robusta la loro catena di approvvigionamento a causa delle esperienze fatte, e la sostenibilit\u00e0 sta diventando sempre pi\u00f9 importante per loro. Con nuove offerte, Bertschi intende cogliere queste opportunit\u00e0 e compensare le perdite di traffico. Jan Arnet ha sottolineato: &#8220;Bertschi si impegna anche in crisi a cogliere proattivamente nuove opportunit\u00e0 nel mercato e a investire in soluzioni clienti innovative e sostenibili. Questo vale sia per il mercato europeo che per i nostri servizi globali, nei quali vediamo un notevole potenziale di crescita per il futuro.&#8221;<\/p>\n<p>L&#8217;andamento degli affari del Gruppo Bertschi nei primi cinque mesi del 2020 \u00e8 soddisfacente, considerando le grandi sfide. Tuttavia, il ritorno alla normalit\u00e0 richieder\u00e0 del tempo e ci sono anche rischi di ulteriori battute d&#8217;arresto. &#8220;Ci aspettiamo che la domanda chimica globale raggiunga nuovamente il livello pre-crisi solo alla fine del 2021. Tuttavia, vediamo anche opportunit\u00e0 a breve termine nel mercato e possiamo attuare rapidamente gli investimenti necessari grazie alla nostra solida situazione finanziaria&#8221;, afferma Hans-J\u00f6rg Bertschi.<\/p>\n<h5><strong>Due nuovi membri del consiglio di amministrazione<\/strong><\/h5>\n<p>In vista del futuro, gli azionisti hanno deciso, durante l&#8217;assemblea generale del 4 luglio 2020, di ampliare il consiglio di amministrazione del gruppo con Kurt Haerri e J\u00f6rg Berner.<\/p>\n<p>Kurt Haerri lavora presso Schindler dal 1987, attualmente come Senior Vice President. Dal 1996 al 2003 e dal 2017 al 2019 ha lavorato per l&#8217;azienda in Cina, dove ha gestito, tra l&#8217;altro, il business delle nuove installazioni. Nel 1996 ha conseguito un Executive MBA presso l&#8217;Universit\u00e0 di San Gallo. \u00c8 stato presidente della Swiss-Chinese Chamber of Commerce (SCCC) dal 2006 al 2014 ed \u00e8 attualmente membro del consiglio. Kurt Haerri ha insegnato dal 2004 al 2019 come docente a contratto presso l&#8217;ETH di Zurigo nel programma Executive MBA per la gestione della catena di approvvigionamento internazionale. Ha 58 anni e vive a Birrwil (AG). La sua lunga esperienza nel mercato cinese e nella gestione globale della catena di approvvigionamento pu\u00f2 fornire nuovi impulsi al Gruppo Bertschi.<\/p>\n<p>Con J\u00f6rg Berner, il consiglio di amministrazione viene ampliato per la prima volta da un membro della terza generazione della famiglia Bertschi. Ha conseguito un master presso l&#8217;Universit\u00e0 di San Gallo nel 2013 ed \u00e8 stato Investment Manager presso l&#8217;azienda Invision a Zug dal 2013 al 2016. Dal 2016 \u00e8 Project Manager per il Gruppo Bertschi in progetti strategici. Nel 2018 ha contribuito alla creazione della nuova sede aziendale di Elite International Logistics a Houston (USA). L&#8217;ingresso di J\u00f6rg Berner nel consiglio di amministrazione \u00e8 conforme al concetto di successione e alla costituzione della famiglia Bertschi del 2009, che mira a facilitare il passaggio dalla seconda alla terza generazione con una fase di transizione pluriennale tra le generazioni.<\/p>\n<p>Con questa espansione, il consiglio di amministrazione continua a essere composto per la maggior parte da membri esterni alla famiglia. Gli attuali membri esterni del consiglio di amministrazione Alexander Krebs, Boy Litjens e Bruno Sidler, insieme ai membri della famiglia Brigitta Berner e Hans-J\u00f6rg Bertschi, sono stati rieletti per un ulteriore mandato di due anni durante l&#8217;assemblea generale.<\/p>\n<h5><strong><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-3946 size-large\" src=\"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Bertschi_1.jpg\" alt=\"\" width=\"1024\" height=\"678\" \/><\/strong><\/h5>\n<h5><strong>Informazioni sul Gruppo Bertschi<\/strong><\/h5>\n<p>Bertschi \u00e8 un fornitore di servizi logistici globale specializzato nella logistica di prodotti liquidi e sfusi per l&#8217;industria chimica. L&#8217;azienda familiare con sede in Svizzera \u00e8 stata fondata nel 1956 e genera un fatturato annuale di circa 988 milioni di franchi svizzeri. 3.100 dipendenti forniscono servizi logistici di alta qualit\u00e0 in 77 sedi in 38 paesi e supportano i clienti in loco.<\/p>\n<p>Bertschi possiede 37.100 serbatoi e container silos, 1.100 camion e 30 terminal container. L&#8217;azienda \u00e8 leader di mercato in Europa nel trasporto chimico intermodale su rotaia, strada e acqua, nonch\u00e9 un fornitore globale di traffico di container cisterna e servizi logistici a valore aggiunto per l&#8217;industria chimica. Siti importanti al di fuori dell&#8217;Europa includono Shanghai, Singapore, Houston, Mosca, San Paolo, Dubai, Al-Jubail (Arabia Saudita) e Istanbul.<\/p>\n<p>Foto: \u00a9 Gruppo Bertschi<\/p>\n<p><a href=\"https:\/\/www.bertschi.com\" target=\"_blank\" rel=\"noopener noreferrer\">www.bertschi.com<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Durante l&#8217;assemblea generale del Gruppo Bertschi del 4 luglio 2020, gli azionisti sono stati informati sull&#8217;attuale sviluppo. L&#8217;azienda ha affrontato bene la prima ondata di Corona,<span class=\"excerpt-hellip\"> [\u2026]<\/span><\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1665,1557,1556,1561],"tags":[],"class_list":["post-19731","post","type-post","status-publish","format-standard","hentry","category-categories","category-forwarding-logistics","category-intermodal-road","category-regions"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Il Gruppo Bertschi svizzero \u00e8 ben attrezzato per il futuro - Loginfo24<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/loginfo24.com\/it\/2020\/07\/07\/il-gruppo-bertschi-svizzero-e-ben-attrezzato-per-il-futuro\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Il Gruppo Bertschi svizzero \u00e8 ben attrezzato per il futuro - Loginfo24\" \/>\n<meta property=\"og:description\" content=\"Durante l&#8217;assemblea generale del Gruppo Bertschi del 4 luglio 2020, gli azionisti sono stati informati sull&#8217;attuale sviluppo. L&#8217;azienda ha affrontato bene la prima ondata di Corona, [\u2026]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/loginfo24.com\/it\/2020\/07\/07\/il-gruppo-bertschi-svizzero-e-ben-attrezzato-per-il-futuro\/\" \/>\n<meta property=\"og:site_name\" content=\"Loginfo24\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/\" \/>\n<meta property=\"article:published_time\" content=\"2020-07-07T04:04:48+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-12-15T11:36:38+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Bertschi_1.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"5 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2020\\\/07\\\/07\\\/il-gruppo-bertschi-svizzero-e-ben-attrezzato-per-il-futuro\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2020\\\/07\\\/07\\\/il-gruppo-bertschi-svizzero-e-ben-attrezzato-per-il-futuro\\\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Il Gruppo Bertschi svizzero \u00e8 ben attrezzato per il futuro\",\"datePublished\":\"2020-07-07T04:04:48+00:00\",\"dateModified\":\"2025-12-15T11:36:38+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2020\\\/07\\\/07\\\/il-gruppo-bertschi-svizzero-e-ben-attrezzato-per-il-futuro\\\/\"},\"wordCount\":1009,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2020\\\/07\\\/07\\\/il-gruppo-bertschi-svizzero-e-ben-attrezzato-per-il-futuro\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/Bertschi_1.jpg\",\"articleSection\":[\"Categories\",\"Forwarding &amp; Logistics\",\"Intermodal \\\/ Road\",\"Regions\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/it\\\/2020\\\/07\\\/07\\\/il-gruppo-bertschi-svizzero-e-ben-attrezzato-per-il-futuro\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2020\\\/07\\\/07\\\/il-gruppo-bertschi-svizzero-e-ben-attrezzato-per-il-futuro\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2020\\\/07\\\/07\\\/il-gruppo-bertschi-svizzero-e-ben-attrezzato-per-il-futuro\\\/\",\"name\":\"Il Gruppo Bertschi svizzero \u00e8 ben attrezzato per il futuro - Loginfo24\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2020\\\/07\\\/07\\\/il-gruppo-bertschi-svizzero-e-ben-attrezzato-per-il-futuro\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2020\\\/07\\\/07\\\/il-gruppo-bertschi-svizzero-e-ben-attrezzato-per-il-futuro\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/Bertschi_1.jpg\",\"datePublished\":\"2020-07-07T04:04:48+00:00\",\"dateModified\":\"2025-12-15T11:36:38+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2020\\\/07\\\/07\\\/il-gruppo-bertschi-svizzero-e-ben-attrezzato-per-il-futuro\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/it\\\/2020\\\/07\\\/07\\\/il-gruppo-bertschi-svizzero-e-ben-attrezzato-per-il-futuro\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2020\\\/07\\\/07\\\/il-gruppo-bertschi-svizzero-e-ben-attrezzato-per-il-futuro\\\/#primaryimage\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/Bertschi_1.jpg\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/Bertschi_1.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2020\\\/07\\\/07\\\/il-gruppo-bertschi-svizzero-e-ben-attrezzato-per-il-futuro\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Il Gruppo Bertschi svizzero \u00e8 ben attrezzato per il futuro\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/\",\"name\":\"Loginfo24\",\"description\":\"Loginfo24 \u00e8 la piattaforma dedicata alla logistica e alle catene di fornitura con informazioni disponibili 24 ore su 24.\",\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#organization\",\"name\":\"Logismedia Group AG\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"width\":938,\"height\":351,\"caption\":\"Logismedia Group AG\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/people\\\/Loginfo24\\\/100057360583332\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/lofinfo24\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Il Gruppo Bertschi svizzero \u00e8 ben attrezzato per il futuro - Loginfo24","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/loginfo24.com\/it\/2020\/07\/07\/il-gruppo-bertschi-svizzero-e-ben-attrezzato-per-il-futuro\/","og_locale":"it_IT","og_type":"article","og_title":"Il Gruppo Bertschi svizzero \u00e8 ben attrezzato per il futuro - Loginfo24","og_description":"Durante l&#8217;assemblea generale del Gruppo Bertschi del 4 luglio 2020, gli azionisti sono stati informati sull&#8217;attuale sviluppo. L&#8217;azienda ha affrontato bene la prima ondata di Corona, [\u2026]","og_url":"https:\/\/loginfo24.com\/it\/2020\/07\/07\/il-gruppo-bertschi-svizzero-e-ben-attrezzato-per-il-futuro\/","og_site_name":"Loginfo24","article_publisher":"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","article_published_time":"2020-07-07T04:04:48+00:00","article_modified_time":"2025-12-15T11:36:38+00:00","og_image":[{"url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Bertschi_1.jpg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"5 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/loginfo24.com\/it\/2020\/07\/07\/il-gruppo-bertschi-svizzero-e-ben-attrezzato-per-il-futuro\/#article","isPartOf":{"@id":"https:\/\/loginfo24.com\/it\/2020\/07\/07\/il-gruppo-bertschi-svizzero-e-ben-attrezzato-per-il-futuro\/"},"author":{"name":"","@id":""},"headline":"Il Gruppo Bertschi svizzero \u00e8 ben attrezzato per il futuro","datePublished":"2020-07-07T04:04:48+00:00","dateModified":"2025-12-15T11:36:38+00:00","mainEntityOfPage":{"@id":"https:\/\/loginfo24.com\/it\/2020\/07\/07\/il-gruppo-bertschi-svizzero-e-ben-attrezzato-per-il-futuro\/"},"wordCount":1009,"commentCount":0,"publisher":{"@id":"https:\/\/loginfo24.com\/it\/#organization"},"image":{"@id":"https:\/\/loginfo24.com\/it\/2020\/07\/07\/il-gruppo-bertschi-svizzero-e-ben-attrezzato-per-il-futuro\/#primaryimage"},"thumbnailUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Bertschi_1.jpg","articleSection":["Categories","Forwarding &amp; Logistics","Intermodal \/ Road","Regions"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/loginfo24.com\/it\/2020\/07\/07\/il-gruppo-bertschi-svizzero-e-ben-attrezzato-per-il-futuro\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/loginfo24.com\/it\/2020\/07\/07\/il-gruppo-bertschi-svizzero-e-ben-attrezzato-per-il-futuro\/","url":"https:\/\/loginfo24.com\/it\/2020\/07\/07\/il-gruppo-bertschi-svizzero-e-ben-attrezzato-per-il-futuro\/","name":"Il Gruppo Bertschi svizzero \u00e8 ben attrezzato per il futuro - Loginfo24","isPartOf":{"@id":"https:\/\/loginfo24.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/loginfo24.com\/it\/2020\/07\/07\/il-gruppo-bertschi-svizzero-e-ben-attrezzato-per-il-futuro\/#primaryimage"},"image":{"@id":"https:\/\/loginfo24.com\/it\/2020\/07\/07\/il-gruppo-bertschi-svizzero-e-ben-attrezzato-per-il-futuro\/#primaryimage"},"thumbnailUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Bertschi_1.jpg","datePublished":"2020-07-07T04:04:48+00:00","dateModified":"2025-12-15T11:36:38+00:00","breadcrumb":{"@id":"https:\/\/loginfo24.com\/it\/2020\/07\/07\/il-gruppo-bertschi-svizzero-e-ben-attrezzato-per-il-futuro\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/loginfo24.com\/it\/2020\/07\/07\/il-gruppo-bertschi-svizzero-e-ben-attrezzato-per-il-futuro\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/loginfo24.com\/it\/2020\/07\/07\/il-gruppo-bertschi-svizzero-e-ben-attrezzato-per-il-futuro\/#primaryimage","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Bertschi_1.jpg","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Bertschi_1.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/loginfo24.com\/it\/2020\/07\/07\/il-gruppo-bertschi-svizzero-e-ben-attrezzato-per-il-futuro\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/loginfo24.com\/it\/"},{"@type":"ListItem","position":2,"name":"Il Gruppo Bertschi svizzero \u00e8 ben attrezzato per il futuro"}]},{"@type":"WebSite","@id":"https:\/\/loginfo24.com\/it\/#website","url":"https:\/\/loginfo24.com\/it\/","name":"Loginfo24","description":"Loginfo24 \u00e8 la piattaforma dedicata alla logistica e alle catene di fornitura con informazioni disponibili 24 ore su 24.","publisher":{"@id":"https:\/\/loginfo24.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/loginfo24.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/loginfo24.com\/it\/#organization","name":"Logismedia Group AG","url":"https:\/\/loginfo24.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/loginfo24.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","width":938,"height":351,"caption":"Logismedia Group AG"},"image":{"@id":"https:\/\/loginfo24.com\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","https:\/\/www.linkedin.com\/company\/lofinfo24\/"]}]}},"_links":{"self":[{"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/posts\/19731","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/comments?post=19731"}],"version-history":[{"count":1,"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/posts\/19731\/revisions"}],"predecessor-version":[{"id":35726,"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/posts\/19731\/revisions\/35726"}],"wp:attachment":[{"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/media?parent=19731"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/categories?post=19731"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/tags?post=19731"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}